{"id":1664,"date":"2005-11-07T13:41:00","date_gmt":"2005-11-07T12:41:00","guid":{"rendered":""},"modified":"2015-09-04T11:40:44","modified_gmt":"2015-09-04T09:40:44","slug":"marc-aug-i-rischi-della-tolleranza","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/","title":{"rendered":"Marc Aug&egrave;: i rischi della tolleranza"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-26764\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg\" alt=\"Marc_Aug\u00e8\" width=\"250\" height=\"182\" \/><\/a>Articolo pubblicato su <strong>La Repubblica<\/strong><\/div>\n<div style=\"text-align: center;\">del 23 ottobre 2003<\/div>\n<p style=\"text-align: justify;\"><em>Il\u00a0mito del \u201cbuon selvaggio\u201d \u00e8 duro a morire, ricordando che una riflessione sul potere s\u2019impone ad ogni latitudine.\u00a0 <\/em><em>\u00abTemi come cultura, identit\u00e0, potere e ideologia sono ancora di grandissima attualit\u00e0, specie in una societ\u00e0 come la nostra che oggi si di batte tra locale e globale\u00bb<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Fabio Gambero<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Dalle trib\u00f9 africane ai non luoghi della moderna societ\u00e0 occidentale. E\u2019 questo l\u2019atipico percorso di Marc Aug\u00e9, il celebre antropologo francese che insegna all\u2019Ecole des Hautes Etudes en Sciences\u00a0 Sociales di Parigi. L\u2019autore di <em>Un etnologo nel metr\u00f2<\/em>, <em>Il senso degli altri e Finzioni di fine secolo<\/em> discuter\u00e0 a Roma, domani, al Salone del libro storico, di \u00abGlobalizzazione e identit\u00e0\u00bb, con Giacomo Marramao<\/div>\n<p style=\"text-align: justify;\">Il viaggio in Italia gli consente anche di presentare <em>Poteri di vita, poteri di morte<\/em> (Raffaello Cortina, pagg. 180, euro 19,50), un libro di molti anni fa ma tradotto da noi soltanto oggi. Si tratta di un denso saggio che polemizza\u00a0 contro il mito duro a morire del \u201cbuon selvaggio\u201d, ricordando che una riflessione sul potere s\u2019impone ad ogni latitudine.<\/p>\n<p style=\"text-align: justify;\">\u00abCerto, questo libro \u00e8 nato da una discussione tipica degli anni Settanta\u00bb, ammette lo studioso francese, \u00abma temi come cultura, identit\u00e0, potere e ideologia sono ancora di grandissima attualit\u00e0, specie in una societ\u00e0 come la nostra che oggi si di batte tra locale e globale. Secondo me, \u00e8 sempre necessario interrogarsi sul potere e sulle sue forme di repressione pi\u00f9 o meno simboliche, che da noi oltretutto sono spesso subdole e mascherate. nelle societ\u00e0 democratiche, il potere, sfruttando l\u2019immagine e la comunicazione, pi\u00f9 che alla repressione diretta mira a condizionare le nostre vite\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Lei afferma che tutte le societ\u00e0, in un modo o nell\u2019altro, sono sempre repressive<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abLe logiche del potere trascendono le forme istituzionali, sono le stesse dappertutto. Quando ho scritto il libro molti pensavano \u2013e qualcuno lo pensa ancora oggi \u2013 che nelle cosiddette societ\u00e0 primitive i rapporti di potere non esistessero. In realt\u00e0, il potere si manifesta anche l\u00ec, e talvolta con forme repressive molto marcate. Insomma i paradisi primitivi sono miti che non esistono. Ma in quegli anni la valorizzazione delle differenze era molto forte, tanto e vero che ne paghiamo le conseguenze ancora oggi\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Cosa vuol dire?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abL\u2019esasperazione del diritto alla differenza ha prodotto un culturalismo i cui effetti perversi sono oggi percepibili da tutti. In nome del rispetto degli altri a qualsiasi costo, c\u2019\u00e8 chi giustifica l\u2019ingiustificabile. Nelle altre culture \u2013 ad esempio quella islamica \u2013 tolleriamo valori e pratiche che non ammetteremmo mai nella nostra. Questo atteggiamento nasconde una forma di razzismo capovolto, perch\u00e9 nel nome della differenza, accettiamo nell\u2019altro ci\u00f2 che non tolleriamo in noi, considerandolo di fatto a un livello inferiore al nostro. Questa vittoria del <em>politically correct<\/em> finisce pure per intimidire il pensiero democratico. In realt\u00e0 si pu\u00f2 essere benissimo tolleranti e contemporaneamente molto fermi sui principi. la tolleranza non deve mai tollerare l\u2019intollerabile, come ad esempio la disuguaglianza dei sessi o la repressione della libert\u00e0 religiosa\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Nel suo libro si parla molto di ideologia.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abPersonalmente non credo alla fine delle ideologie. Proprio quando si crede che queste non esistano pi\u00f9, esse sono in realt\u00e0 ancora pi\u00f9 efficaci. Su questo terreno, Althusser aveva ragione quando sosteneva che coloro che sono le prime vittime di un\u2019ideologia sono spesso coloro che la difendono. Infatti, una delle caratteristiche proprie dell\u2019Illusione ideologica \u00e8 di persuadere coloro che ne sono le vittime. Oggi purtroppo l\u2019attualit\u00e0 ci mostra molti drammatici esempi di tale funzionamento ideologico\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sarebbero le ideologie che dominano la societ\u00e0 contemporanea?<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abL\u2019ideologia del consumismo, come pure l\u2019ideologia della fine della storia. Quest\u2019ultima \u00e8 un mito che rappresenta bene la posizione della nazione che domina lo scacchiere mondiale. Gli Usa, infatti, difendono un sistema che combina democrazia rappresentativa, liberalismo economico e leggi del mercato, presentandolo come un orizzonte definitivo e insuperabile. Nulla potr\u00e0 pi\u00f9 rimetterlo in discussione. Da questa mancanza di prospettive deriva anche quell\u2019ideologia del presente che mi sembra il dato pi\u00f9 caratteristico dei nostri tempi. Noi tutti viviamo sotto la dittatura del presente immediato: dimentichiamo il passato e non ci proiettiamo nel futuro\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su La Repubblica del 23 ottobre 2003 Il\u00a0mito del \u201cbuon selvaggio\u201d \u00e8 duro a morire, ricordando che una riflessione sul potere s\u2019impone ad ogni latitudine.\u00a0 \u00abTemi come cultura, identit\u00e0, potere e ideologia sono ancora di grandissima attualit\u00e0, specie in una societ\u00e0 come la nostra che oggi si di batte tra locale e globale\u00bb &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":26764,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[1116,755],"class_list":["post-1664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-buon-selvaggio","tag-potere","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-11-07T12:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-04T09:40:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"263\" \/>\n\t<meta property=\"og:image:height\" content=\"191\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Marc Aug&egrave;: i rischi della tolleranza\",\"datePublished\":\"2005-11-07T12:41:00+00:00\",\"dateModified\":\"2015-09-04T09:40:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/\"},\"wordCount\":696,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Marc_Aug\u00e8.jpg\",\"keywords\":[\"buon selvaggio\",\"potere\"],\"articleSection\":[\"Politica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/\",\"name\":\"Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Marc_Aug\u00e8.jpg\",\"datePublished\":\"2005-11-07T12:41:00+00:00\",\"dateModified\":\"2015-09-04T09:40:44+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Marc_Aug\u00e8.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Marc_Aug\u00e8.jpg\",\"width\":263,\"height\":191},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/marc-aug-i-rischi-della-tolleranza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marc Aug&egrave;: i rischi della tolleranza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/","og_locale":"it_IT","og_type":"article","og_title":"Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-11-07T12:41:00+00:00","article_modified_time":"2015-09-04T09:40:44+00:00","og_image":[{"width":263,"height":191,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Marc Aug&egrave;: i rischi della tolleranza","datePublished":"2005-11-07T12:41:00+00:00","dateModified":"2015-09-04T09:40:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/"},"wordCount":696,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg","keywords":["buon selvaggio","potere"],"articleSection":["Politica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/","name":"Marc Aug&egrave;: i rischi della tolleranza - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg","datePublished":"2005-11-07T12:41:00+00:00","dateModified":"2015-09-04T09:40:44+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Marc_Aug\u00e8.jpg","width":263,"height":191},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/marc-aug-i-rischi-della-tolleranza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Marc Aug&egrave;: i rischi della tolleranza"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1664\/revisions"}],"predecessor-version":[{"id":26765,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1664\/revisions\/26765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26764"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}