{"id":16619,"date":"2015-01-15T00:00:49","date_gmt":"2015-01-14T23:00:49","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=16619"},"modified":"2015-01-12T13:05:29","modified_gmt":"2015-01-12T12:05:29","slug":"leuropa-al-buio-con-la-testa-sotto-la-sabbia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/","title":{"rendered":"L&#8217;Europa al buio con la testa sotto la sabbia"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16620\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris-300x156.jpg\" alt=\"hebdo_Paris\" width=\"250\" height=\"130\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris-300x156.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg 311w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>l Mattino<\/strong><strong>, <\/strong>8 gennaio 2015<\/p>\n<p style=\"text-align: center;\">di <strong>Massimo Introvigne<\/strong><\/p>\n<p style=\"text-align: justify;\">Il 7 gennaio 2015 si \u00e8 spenta a Parigi una luce sull&#8217;Europa, e Dio solo sa quando mai sar\u00e0 riaccesa. I terroristi &#8211; qualunque sia la congrega di tagliagole cui davvero appartengono &#8211; hanno mostrato di poter colpire non solo in Iraq o in Siria, non solo nei luoghi nomadi dove si viaggia in aereo o in metropolitana, ma di giorno, in una grande citt\u00e0, nella sede di un giornale, cio\u00e8 in uno di quei luoghi che ci sembrava potessero godere di un qualche statuto di zona franca. Ma non esistono pi\u00f9 zone franche: ogni luogo, ogni uomo, ogni donna \u00e8 un obiettivo di questa guerra maledetta.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">S\u00ec, la luce si \u00e8 spenta. Si \u00e8 spenta sui sogni di Hollande,di Obama, dell&#8217;Unione Europea, delle Nazioni Unite, e anche dei nostri politici italiani di potersi permettere di non occuparsi dell&#8217;ISIS, del califfo, di al-Qa&#8217;ida che si riorganizza e che forse, a un anno dalla rottura con il Califfato, sta riannodando le fila di un grande cartello del Male che raduni tutti i terroristi dell&#8217;ultra-fondamentalismo islamico.<\/p>\n<p style=\"text-align: justify;\">Ci si illudeva in Francia, ci si illude anche da noi che, se non ci occupiamo dei terroristi, se non mandiamo neppure un soldato a combattere in Medio Oriente o a difendere i cristiani massacrati e crocefissi o le donne della minoranza yazida violentate e vendute come schiave &#8211; perch\u00e9 ogni soldato che torna a casa in una bara fa perdere voti al governo che lo ha mandato a combattere &#8211; i terroristi ci lasceranno in pace. Ma se noi non ci occupiamo dei terroristi, i terroristi si occupano di noi, e torna a casa in una bara chi \u00e8 semplicemente andato a lavorare nel centro di una delle nostre capitali.<\/p>\n<p style=\"text-align: justify;\">Possiamo condannare, deprecare, firmare appelli, ma le chiacchiere stanno a zero e si combatte il terrorismo solo andandolo a estirpare nei suoi santuari, con gli stivali delle truppe sul terreno e non con la semplice propaganda o i droni di Obama. Altrimenti diamo ragione a Osama bin Laden, il quale sosteneva che tra chi non vuole\u00a0 rischiare di morire e chi ama la morte vince sempre il secondo &#8211; e il primo muore comunque.<\/p>\n<p style=\"text-align: justify;\">S\u00ec, la luce si \u00e8 spenta. Si \u00e8 spenta su chi non ha capito la lezione di Benedetto XVI a Ratisbona e oltre Ratisbona, che non offendeva affatto l&#8217;Islam &#8211; chi ha risposto alla satira di \u00abCharlie Hebdo\u00bb con gli omicidi \u00e8 un miserabile farabutto, e tuttavia i discorsi di Papa Ratzinger e le vignette non sono sullo stesso piano &#8211; ma lo invitava a riannodare le fila di un dialogo fra fede e ragione partendo dalla sua stessa tradizione, senza rinnegarla ma nello stesso tempo senza rifiutare di vederne gli aspetti oscuri e problematici.<\/p>\n<p style=\"text-align: justify;\">Non hanno capito quella lezione i buonisti per cui tutti i musulmani sono amanti della pace, gentili e magari amici degli animali e dei fiori. Ma non l&#8217;hanno capita neanche i \u00abcattivisti\u00bb che oggi se la prendono con Papa Francesco perch\u00e9 non hanno mai letto Papa Benedetto, il quale affermava anche, il 28 novembre 2006, che il dialogo con i musulmani \u00abnon pu\u00f2 essere ridotto ad un extra opzionale: al contrario, esso \u00e8 una necessit\u00e0 vitale, dalla quale dipende in larga misura il nostro futuro\u00bb.<\/p>\n<p style=\"text-align: justify;\">S\u00ec, la luce si \u00e8 spenta. Si \u00e8 spenta sui politicanti estremisti e sciacalli di tutte le risme, i quali sperano di lucrare su queste tragedie per fare i martiri con il sangue degli altri alla ricerca di un miserabile tornaconto elettorale, o per arruolare anche i poveri morti di Parigi in rese dei conti ecclesiastiche che oggi hanno di mira Papa Francesco, accusato di inventare un dialogo con l&#8217;islam che invece gi\u00e0 Benedetto XVI definiva \u00abnon opzionale\u00bb, cio\u00e8 obbligatorio.<\/p>\n<p style=\"text-align: justify;\">Mantenere i nervi saldi quando la luce si spegne \u00e8 molto difficile. Ma chi sa vedere nel buio comprende che la \u00abstrategia Francesco\u00bb che Papa Bergoglio ha pi\u00f9 volte proposto di fronte alle stragi dell&#8217;ISIS \u00e8 l&#8217;unico modo ragionevole di rispondere a questa criminale follia. Non \u00e8 delegando a qualche generale medio-orientale con gli stivali sporchi di sangue la repressione insieme dell&#8217;islam politico e dei diritti umani nel suo Paese, e non \u00e8 strillando in piazza che tutti i musulmani sono terroristi che si disinnesca l&#8217;ultra-fondamentalismo assassino.<\/p>\n<p style=\"text-align: justify;\">Al contrario, lo si alimenta, e si spengono altre luci. Oriana Fallaci, poco prima di morire, aveva riferito che Benedetto XVI in un colloquio privato con lei aveva definito il dialogo con il mondo islamico \u00abimpossibile ma obbligatorio\u00bb. In giornate come quella di oggi il dialogo sembra davvero impossibile. Ma \u00e8 solo trovando interlocutori islamici disposti non a rinnegare la propria storia e la propria identit\u00e0 ma a cercare con fatica al loro interno le ragioni per condannare e isolare i terroristi che questi assassini potranno essere davvero sconfitti. \u00c8 la strategia di Papa Francesco, era la vera strategia di Papa Benedetto. \u00c8 la strategia pi\u00f9 difficile. Ma non ce ne sono altre.<\/p>\n<p style=\"text-align: justify;\">Benedetto XVI ama ricordare un proverbio della sua terra, la Baviera. Quando la luce si spegne si possono fare due cose: maledire l\u2019oscurit\u00e0, che non serve a nulla, o accendere una fiammella. Oggi ci sembra che anche la fiammella serva a poco. Ma se ognuno di noi accende la sua fiammella, alla fine torner\u00e0 la luce. Alla fine non avremo pi\u00f9 paura del buio, e potr\u00e0 perfino capitare che sia il buio ad avere paura di noi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l Mattino, 8 gennaio 2015 di Massimo Introvigne Il 7 gennaio 2015 si \u00e8 spenta a Parigi una luce sull&#8217;Europa, e Dio solo sa quando mai sar\u00e0 riaccesa. I terroristi &#8211; qualunque sia la congrega di tagliagole cui davvero appartengono &#8211; hanno mostrato di poter colpire non solo in Iraq o in Siria, non solo &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":16620,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[2408],"class_list":["post-16619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam-in-europa","tag-islam-in-europa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T23:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"311\" \/>\n\t<meta property=\"og:image:height\" content=\"162\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;Europa al buio con la testa sotto la sabbia\",\"datePublished\":\"2015-01-14T23:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/\"},\"wordCount\":904,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/hebdo_Paris.jpg\",\"keywords\":[\"Islam in Europa\"],\"articleSection\":[\"Islam in Europa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/\",\"name\":\"L'Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/hebdo_Paris.jpg\",\"datePublished\":\"2015-01-14T23:00:49+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/hebdo_Paris.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/hebdo_Paris.jpg\",\"width\":311,\"height\":162},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Europa al buio con la testa sotto la sabbia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/","og_locale":"it_IT","og_type":"article","og_title":"L'Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-01-14T23:00:49+00:00","og_image":[{"width":311,"height":162,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;Europa al buio con la testa sotto la sabbia","datePublished":"2015-01-14T23:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/"},"wordCount":904,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg","keywords":["Islam in Europa"],"articleSection":["Islam in Europa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/","name":"L'Europa al buio con la testa sotto la sabbia - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg","datePublished":"2015-01-14T23:00:49+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/hebdo_Paris.jpg","width":311,"height":162},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/leuropa-al-buio-con-la-testa-sotto-la-sabbia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Europa al buio con la testa sotto la sabbia"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=16619"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16619\/revisions"}],"predecessor-version":[{"id":16621,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16619\/revisions\/16621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/16620"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=16619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=16619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=16619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}