{"id":16319,"date":"2015-01-15T00:00:53","date_gmt":"2015-01-14T23:00:53","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=16319"},"modified":"2015-01-15T11:21:33","modified_gmt":"2015-01-15T10:21:33","slug":"laborto-si-puo-combattere-il-caso-pennsylvania","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/","title":{"rendered":"L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16320 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg\" alt=\"pro life\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg 200w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><a href=\"http:\/\/www.lacrocequotidiano.it\/\" target=\"_blank\">La Croce\u00a0on line<\/a><\/strong> 2 gennaio 2015<\/p>\n<p style=\"text-align: center;\"><em>L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Giuseppe Brienza<\/strong><\/p>\n<p style=\"text-align: justify;\">Augusto Del Noce, a partire dal suo libro Il suicidio della Rivoluzione (1978), ci ha spiegato quello sbocco paradossale, quella particolare eterogenesi dei fini per cui \u00abil compimento della rivoluzione coincide con il suo suicidio\u00bb.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Nel marzo del 2010 il presidente Obama aveva firmato un executive order con il quale, in attuazione della sua riforma sanitaria (l\u2019Obamacare), finanziava fra l\u2019altro nello Stato della Pennsylvania un programma di \u201cassicurazione ad alto rischio\u201d, pari a 16 milioni federali, con il quale si sarebbe dovuto coprire anche l\u2019aborto. Pare proprio non sia andata cos\u00ec (l\u2019eterogenesi dei fini\u2026).<\/p>\n<p style=\"text-align: justify;\">Stando almeno a quanto riporta su <em>LifeNews.com <\/em>il giornalista Steven Ertelt, dalle statistiche recentemente pubblicate dal Dipartimento della Salute, in Pennsylvania \u00abgli aborti sono scesi ormai ai minimi storici\u00bb. Nel 2013, infatti, la percentuale degli aborti sul numero totale d\u00a0delle nascite \u00e8 diminuita del 7 per cento. \u00abNello stesso momento in cui le informazioni e gli aiuti in favore delle nascite sono resi disponibili &#8211; ha commentato Micaiah Bilger, dirigente della Pennsylvania Pro-Life Federation -, i centri che praticano aborti iniziano a chiudere e sempre pi\u00f9 donne sono accompagnate a scegliere la vita\u00bb.<\/p>\n<p style=\"text-align: justify;\">Le tecnologie stanno infatti rendendo sempre pi\u00f9 evidente a tutte le donne che, anche nelle prime settimane, e fino comunque dal momento del concepimento, quella vita che portano in grembo non \u00e8 affatto un \u201cgrumo di cellule\u201d, come vorrebbero i medici abortisti ed i militanti prochoice.<\/p>\n<p style=\"text-align: justify;\">Le ultime machine ad ultrasuoni, ad esempio, permettono sempre meglio a madri e padri di rendersi conto come quel loro \u201cprodotto del concepimento\u201d sorrida, salti o si succhi allegramente il pollice. Eppoi nonostante le campagne pro-aborto, in Pennsylvania nel 2013 le complicazioni relative all\u2019intervento ipocritamente detto di \u201cinterruzione volontaria della gravidanza\u201d sono balzata a quasi il 22 per cento, stando al Rapporto del Dipartimento della Salute.<\/p>\n<p style=\"text-align: justify;\">Le donne hanno tutto il diritto di conoscere fino in fondo i rischi legati all\u2019aborto ed agli interventi abortivi, compresa quella sindrome post-abortiva che \u00e8 persino censurata nei manuali medici. Inoltre, come lo stesso Bilger ha rivendicato, ad ogni gestante vanno presentate le reali alternative che, il Sistema pubblico offre loro e, \u00abgrazie ai centri per la gravidanza della Pennsylvania ed ai \u201cProgrammi Alternativi all\u2019Aborto\u201d resi disponibili nel nostro Stato, sempre pi\u00f9 donne in cinta e genitori hanno accesso a informazioni corrette e supporto\u00bb.<\/p>\n<p style=\"text-align: justify;\">Chi segue le vicende pro life degli Stati Uniti ricorda che, la Pennsylvania, \u00e8 quello Stato nel quale un medico abortista venne assassinato nel 2009 durante una funzione nella chiesa luterana che frequentava. Oppure nel quale \u00e8 stato condannato, nel 2013, per tre omicidi di primo grado, un omicidio preterintenzionale e oltre duecento infrazioni della legge che regola l\u2019aborto in Pennsylvania, il medico Kermit Gosnell, della cui mostruosa vicenda \u00e8 stato tratto anche un best seller, intitolato \u201cGosnell\u2019s Babies\u201d.<\/p>\n<p style=\"text-align: justify;\">La legge attualmente vigente in Pennsylvania prevede che l\u2019aborto sia permesso fino alla ventiquattresima settimana di gravidanza ma, un minuto dopo, come visto, non si va per la leggera. Forse non \u00e8 un caso che, l\u2019attuale presidente della Conferenza Episcopale americana , l&#8217;Arcivescovo Joseph Kurtz, sia proprio nativo della Pennsylvania.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 vescovo di Louisville, venuto a Roma come delegato nel Sinodo dei Vescovi sulla Famiglia, ha esplicitato la prima delle sue speranze ed aspettative: ristabilire fiducia e confidenza con il popolo americano affinch\u00e9 tutti possano avere un matrimonio fecondo e una famiglia unita. E, senza farsi troppe illusioni sui numeri degli aborti, ha aggiunto rispondendo ad un\u2019intervista all\u2019agenzia Zenit: \u00abSpero che la gente non diventi oggetto e strumento delle statistiche che possono essere manipolate qua e l\u00e0. Le persone sono pi\u00f9 importanti delle statistiche. E la gente ha bisogno di recuperare la speranza\u00bb.<\/p>\n<p style=\"text-align: justify;\">L\u2019Arcivescovo, dalla sua pluriennale esperienza di consulente famigliare, ha quindi concluso con una frase che, ci pare, sia il miglior commento alla notizia (naturalmente non data dai nostri media) degli aborti ai minimi storici in Pennsylvania: \u00able famiglie sono benedette dalla nascita dei bambini. I genitori amano i loro figli e vogliono ci\u00f2 che \u00e8 meglio per loro. Dobbiamo lavorare e costruire su questo amore. Quindi ci sono cose molto positive gi\u00e0 l\u00e0 fuori. Spero che la gente afferri questo messaggio\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Croce\u00a0on line 2 gennaio 2015 L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania Giuseppe Brienza Augusto Del Noce, a partire dal suo libro Il suicidio della Rivoluzione (1978), ci ha spiegato quello sbocco paradossale, quella particolare eterogenesi dei fini per cui \u00abil compimento della rivoluzione coincide con il suo suicidio\u00bb.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":16320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1336],"class_list":["post-16319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-pro-life","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-14T23:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-15T10:21:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania\",\"datePublished\":\"2015-01-14T23:00:53+00:00\",\"dateModified\":\"2015-01-15T10:21:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pro-life.jpg\",\"keywords\":[\"pro life\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/\",\"name\":\"L'aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pro-life.jpg\",\"datePublished\":\"2015-01-14T23:00:53+00:00\",\"dateModified\":\"2015-01-15T10:21:33+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pro-life.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pro-life.jpg\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/laborto-si-puo-combattere-il-caso-pennsylvania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/","og_locale":"it_IT","og_type":"article","og_title":"L'aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-01-14T23:00:53+00:00","article_modified_time":"2015-01-15T10:21:33+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania","datePublished":"2015-01-14T23:00:53+00:00","dateModified":"2015-01-15T10:21:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/"},"wordCount":708,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg","keywords":["pro life"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/","name":"L'aborto si pu\u00f2 combattere, Il caso Pennsylvania - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg","datePublished":"2015-01-14T23:00:53+00:00","dateModified":"2015-01-15T10:21:33+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/01\/pro-life.jpg","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/laborto-si-puo-combattere-il-caso-pennsylvania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;aborto si pu\u00f2 combattere, Il caso Pennsylvania"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=16319"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16319\/revisions"}],"predecessor-version":[{"id":16871,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/16319\/revisions\/16871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/16320"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=16319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=16319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=16319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}