{"id":1619,"date":"2005-10-20T17:43:25","date_gmt":"2005-10-20T15:43:25","guid":{"rendered":""},"modified":"2015-12-21T16:32:04","modified_gmt":"2015-12-21T15:32:04","slug":"la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/","title":{"rendered":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29026\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg\" alt=\"fisco\" width=\"250\" height=\"140\" \/><\/a>Cristianit\u00e0<\/strong> n. 189 (1991)<\/div>\n<p style=\"text-align: justify;\"><em>il problema della fiscalit\u00e0 non \u00e8 soltanto un fatto economico e che, pertanto, non \u00e8 risolvibile con modifiche puramente tecniche della normativa fiscale, ma investe sia il complesso dei rapporti tra lo Stato e i cittadini, sia la concezione delle funzioni e dei limiti dell\u2019attivit\u00e0 di governo: quindi, si tratta di un problema che pu\u00f2 essere correttamente qualificato come politico in senso proprio.<\/em><\/p>\n<p style=\"text-align: center;\">di<strong> Ferdinando Leotta<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>Un problema purtroppo sempre attuale<\/strong><\/div>\n<p style=\"text-align: justify;\"><em>&#8220;<\/em>[&#8230;]<em> ritengo che gli argomenti importanti meritano di essere ripetuti instancabilmente, almeno fino a quando la comprensione generale non ne riduca l\u2019importanza&#8221;<\/em>: cos\u00ec si legge nella <em>Premessa<\/em> al volume <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, <em>Premessa<\/em> in cui l\u2019autore, Antonio Martino, avverte che \u2014 al fine di spiegare le motivazioni della protesta fiscale in Italia e di individuare le soluzioni per rispondere all\u2019esigenza di una fiscalit\u00e0 diversa e meno vessatoria \u2014 riprende non solo argomentazioni da lui stesso formulate alcuni anni addietro ma ripropone anche argomenti gi\u00e0 sostenuti da altri, convinto che la riproposizione di questi argomenti rafforzi la credibilit\u00e0 di quelli esposti (1).<\/p>\n<p style=\"text-align: justify;\">Professore ordinario di Storia e Politica Monetaria alla Facolt\u00e0 di Scienze Politiche dell\u2019Universit\u00e0 La Sapienza di Roma e Direttore Scientifico del Centro di Ricerche Economiche Applicate, il CREA, Antonio Martino ricerca, insieme a Gianni Marongiu e Sergio Ricossa, le ragioni della protesta fiscale in Italia, che \u2014 per esempio \u2014 nella manifestazione svoltasi a Torino il 23 novembre del 1986, ha mobilitato oltre trentamila cittadini (2). L\u2019anno precedente lo studioso aveva pubblicato sullo stesso argomento, presso il CREA, un saggio intitolato <em>Fisco: anarchia o legalit\u00e0 costituzionale?<\/em> (3).<\/p>\n<p style=\"text-align: justify;\">La tesi di fondo di <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em> \u00e8 che il problema della fiscalit\u00e0 non \u00e8 soltanto un fatto economico e che, pertanto, non \u00e8 risolvibile con modifiche puramente tecniche della normativa fiscale, ma investe sia il complesso dei rapporti tra lo Stato e i cittadini, sia la concezione delle funzioni e dei limiti dell\u2019attivit\u00e0 di governo: quindi, si tratta di un problema che pu\u00f2 essere correttamente qualificato come politico in senso proprio.<\/p>\n<p style=\"text-align: justify;\">L\u2019opera si propone di illustrare l\u2019origine della crescita incontrollata della fiscalit\u00e0, di richiamare l\u2019attenzione sulle conseguenze di tale processo e di far comprendere la necessit\u00e0 di una soluzione costituzionale del problema.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019arco di tempo intercorso dalla data di pubblicazione \u2014 cio\u00e8 dal 1987 \u2014 a oggi, tutti i problemi della fiscalit\u00e0 italiana, elencati da Victor Uckmar nell\u2019<em>Introduzione<\/em> (4), sono rimasti irrisolti: le dimensioni enormi della spesa pubblica; la carenza di garanzie per il cittadino di fronte al legislatore, all\u2019amministrazione finanziaria e al giudice; la proliferazione di provvedimenti legislativi in materia fiscale; la debolezza dell\u2019amministrazione finanziaria non adeguatamente fornita di mezzi e di funzionari; l\u2019inadeguata tutela del cittadino dinanzi alle commissioni tributarie, espressa, in particolare, dal mantenimento del <em>solve et repete<\/em>, del &#8220;paga e ricorri&#8221;; l\u2019introduzione del nuovo sistema penale tributario, sono tutti esempi che mostrano come, in sostanza, nulla sia mutato in meglio, mentre nuove e delicate problematiche sono sorte, come quelle relative all\u2019elusione e al passaggio dalla tassazione del reddito effettivo a quella del reddito &#8220;normale&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>La libert\u00e0 e le tasse, la protesta fiscale e il senso dello Stato<\/strong><\/p>\n<p style=\"text-align: justify;\">Esordendo in modo volutamente paradossale l\u2019autore fa propria l\u2019osservazione del filosofo di Harward Robert Nosick, secondo cui <em>&#8220;la tassazione del reddito da lavoro configura una sorta di lavoro forzato&#8221;<\/em> (5). Infatti lo Stato, prelevando al cittadino una parte di reddito equivalente al profitto di un certo numero di ore lavorative, lo costringe a lavorare <em>gratis<\/em> per quelle ore e, quindi, lo rende di fatto temporaneamente schiavo.<\/p>\n<p style=\"text-align: justify;\">Dunque la fiscalit\u00e0 determina un costo, in termini di libert\u00e0 personale, che, se \u00e8 accettabile quando \u00e8 attinente ad attivit\u00e0 propriamente pubbliche, risulta odioso quando \u00e8 causato da un\u2019inefficiente ingerenza dello Stato in ambiti in cui potrebbe operare con successo la societ\u00e0 civile.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec non tardano a delinearsi le ragioni della protesta fiscale: invece di scandalizzarsi perch\u00e9 i contribuenti, nel 1986, si permisero di &#8220;parlar male di Garibaldi&#8221;, Antonio Martino sostiene che i benpensanti dovrebbero <em>&#8220;<\/em>[&#8230;]<em> rendersi conto non solo che la protesta fiscale \u00e8 legittima<\/em> [&#8230;]<em>, ma che essa costituisce caratteristica tipica ed ineliminabile della democrazia&#8221;<\/em>, e che se vi \u00e8 <em>&#8220;<\/em>[&#8230;]<em> qualcosa di strano nella protesta fiscale in Italia, non \u00e8 certo il fatto che abbia avuto luogo, ma che non abbia avuto luogo prima&#8221;<\/em> (6).<\/p>\n<p style=\"text-align: justify;\">Oltre all\u2019eccessivit\u00e0 del prelievo, gli italiani devono subire una legislazione fiscale <em>&#8220;complessa, contorta, farraginosa, contraddittoria e spesso incomprensibile&#8221;<\/em> (7), per cui neanche contribuenti con titoli di studio avanzati e di buona cultura possono adempiere ai loro obblighi fiscali senza l\u2019ausilio di esperti. Come se ci\u00f2 non bastasse, vengono comminate <em>&#8220;<\/em>[&#8230;]<em> pene enormi ai contribuenti che adempiono i loro obblighi fiscali anche solo con un giorno di ritardo&#8221;<\/em>: dinanzi a simili episodi <em>&#8220;a me sembra<\/em> \u2014 giunge ad affermare Antonio Martino \u2014<em> che questo terrorismo fiscale sia indegno di un Paese civile&#8221;<\/em> (8).<\/p>\n<p style=\"text-align: justify;\">Ciononostante, alcuni ritengono che interrogarsi sulla legittimit\u00e0 della pretesa fiscale sia segno di mancanza di senso dello Stato; ma, se il senso dello Stato \u00e8 la consapevolezza dell\u2019importanza delle sue funzioni, \u00e8 lecito indagare quali siano le attivit\u00e0 di sua competenza e quali no, quali da finanziare e quali da lasciare invece alla libera iniziativa, ponendo in questo modo le premesse per una fiscalit\u00e0 equa.<\/p>\n<p style=\"text-align: justify;\">Il problema \u00e8 ulteriormente complicato da <em>&#8220;<\/em>[&#8230;]<em> coloro che parlano della necessit\u00e0 di perseguire la &#8220;giustizia distributiva&#8221;&#8221;<\/em> (9) attraverso la fiscalit\u00e0 e da una mentalit\u00e0 corrente, secondo cui le imposte sarebbero <em>&#8220;<\/em>[&#8230;]<em> fine a se stesse, una sorta di meritata punizione da infliggere a chi produce e guadagna un reddito&#8221;<\/em> (10).<\/p>\n<p style=\"text-align: justify;\">Anche questo aspetto va tenuto presente per comprendere come la spesa pubblica e la fiscalit\u00e0 abbiano potuto raggiungere, negli ultimi venticinque anni, i livelli denunciati dall\u2019autore e perch\u00e9, fra le cause che rendono difficile la soluzione dei problemi della spesa pubblica, dell\u2019imposizione e dell\u2019evasione, occupi un posto non secondario un diffuso sentimento, conscio o inconscio, di invidia sociale.<\/p>\n<p style=\"text-align: justify;\"><strong>La misura della fiscalit\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Secondo l\u2019autore, la misura effettiva della fiscalit\u00e0 non \u00e8 data dal totale delle entrate \u2014 fiscalit\u00e0 esplicita \u2014, ma dall\u2019ammontare complessivo della spesa pubblica \u2014 fiscalit\u00e0 implicita. Di questa fa parte anche il disavanzo pubblico, che, a tutti gli effetti, \u00e8 un\u2019<em>&#8220;imposta diffusa&#8221;<\/em>, <em>&#8220;invisibile&#8221;<\/em> agli occhi dei pi\u00f9, e <em>&#8220;<\/em>[&#8230;]<em> &#8220;a scoppio ritardato&#8221;, nel senso che l\u2019effettivo pagamento del disavanzo viene spostato avanti nel tempo e grava sui contribuenti futuri&#8221;<\/em> (11).<\/p>\n<p style=\"text-align: justify;\">Negli anni che vanno dal 1960 al 1985, la spesa pubblica \u00e8 aumentata da 7.588 miliardi \u2014 pari a 77.634 se comparati al diminuito potere d\u2019acquisto della lira \u2014 a 425.263, con un incremento reale del 448%. In questa condizione parossistica, il settore pubblico, nel 1985, impiegava mediamente, per spendere un miliardo, soltanto poco pi\u00f9 di un minuto; tale esborso \u00e8 costato, nello stesso periodo, quasi sette milioni e mezzo ad ogni italiano.<\/p>\n<p style=\"text-align: justify;\">Queste prime cifre mostrano anche che, sempre negli ultimi venticinque anni, l\u2019inflazione \u00e8 stata superiore al 1.000%, un dato rilevantissimo, anche sotto il profilo fiscale, per valutare gli effetti del cosiddetto <em>fiscal drag<\/em>, del &#8220;drenaggio fiscale&#8221;, e la dinamica della fiscalit\u00e0 occulta.<\/p>\n<p style=\"text-align: justify;\">Al finanziamento della spesa nell\u2019anno 1985 hanno concorso, accanto alle imposte dirette (24,8%) e a quelle indirette (17,5%), i contributi sociali (25,4%) e altre entrate (8,1%), oltre ovviamente a un indebitamento netto pari al 24,3%.<\/p>\n<p style=\"text-align: justify;\"><strong>Il <em>&#8220;giorno dell\u2019indipendenza personale&#8221;<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Se si confronta l\u2019ammontare complessivo dei costi pubblici con il reddito nazionale si ottiene la percentuale di reddito prodotto dagli italiani e da questi, consapevolmente o inconsapevolmente, consegnata all\u2019erario. Tale percentuale pu\u00f2 essere espressa anche con il numero di giornate lavorative che l\u2019italiano medio deve dedicare al <em>&#8220;leviatano pubblico&#8221;<\/em> (12) per la fornitura dei mezzi richiesti.<\/p>\n<p style=\"text-align: justify;\">Nel 1974 l\u2019economista americano Milton Friedman ha proposto l\u2019istituzione di <em>&#8220;a new holiday&#8221;<\/em>, di &#8220;una nuova festa&#8221; celebrativa del giorno in cui il contribuente medio smette di lavorare per il settore pubblico e inizia a destinare a s\u00e9 e ai suoi i frutti del proprio lavoro (13).<\/p>\n<p style=\"text-align: justify;\">In Italia questa nuova festivit\u00e0, che Antonio Martino propone di intitolare <em>&#8220;il giorno dell\u2019indipendenza personale&#8221;<\/em>, \u00e8 mobile e &#8220;progressiva&#8221;: infatti, se nel 1960 si sarebbe potuta celebrare il 29 aprile, nel 1980 si sarebbe dovuto attendere il 27 giugno e, nel 1985, addirittura Ferragosto: a suo avviso, il rapporto fra la spesa pubblica e il PIL, il prodotto interno lordo, <em>&#8220;<\/em>[&#8230;]<em> costituisce la misura pi\u00f9 evidente dell\u2019abuso del potere politico ai danni della collettivit\u00e0&#8221;<\/em>, mentre \u00e8 <em>&#8220;<\/em>[&#8230;]<em> illusorio ritenere che la libert\u00e0 individuale sia tutelata e abbia un futuro quando la macchina politico-burocratica assorbe<\/em> [&#8230;]<em> oltre il 60 % del reddito nazionale&#8221;<\/em> (14).<\/p>\n<p style=\"text-align: justify;\">D\u2019altra parte, i difensori dello statalismo bollano queste argomentazioni qualificandole come &#8220;qualunquistiche&#8221; e &#8220;poujadistiche&#8221; e cercano di confutarle tecnicamente sostenendo che, per effetto dell\u2019economia sommersa, il PIL \u00e8 sottostimato e che, di conseguenza, le dimensioni del disavanzo devono essere ritenute meno preoccupanti, che la spesa pubblica non pu\u00f2 essere considerata eccessiva e che l\u2019imposizione pu\u00f2 ancora aumentare (15).<\/p>\n<p style=\"text-align: justify;\"><strong>&#8220;Il tesoro nascosto&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Il direttore del CREA si interessa al problema dell\u2019economia sommersa fin dal 1978, studiando le serie monetarie dei vent\u2019anni precedenti relative a un certo numero di paesi industrializzati. In quell\u2019occasione <em>&#8220;<\/em>[&#8230;]<em> notai<\/em> \u2014 ricorda l\u2019autore \u2014<em> un\u2019inspiegabile anomalia: la quantit\u00e0 di moneta in rapporto al prodotto interno lordo era molto maggiore in Italia che nella media degli altri Paesi<\/em> [&#8230;]<em>. Nel tentativo di spiegare il fenomeno avanzai<\/em> [&#8230;]<em> la congettura che il denominatore della frazione, cio\u00e8 il P.I.L., fosse in Italia superiore a quello rilevato&#8221;<\/em> (16). Ipotizzando una sottostima del reddito nazionale del 28%, egli si premurava per\u00f2 di avvertire che <em>&#8220;queste cifre sono solo il risultato di un semplicistico esercizio aritmetico, e non vanno prese alla lettera&#8221;<\/em> (17).<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019ipotesi, avanzata per sostenere che l\u2019economia italiana sopravviveva nonostante lo statalismo, venne da diversi osservatori <em>&#8220;<\/em>[&#8230;]<em> citata come la &#8220;stima&#8221; (<\/em>sic<em>) pi\u00f9 alta del contributo dell\u2019economia sommersa al reddito nazionale&#8221;<\/em> (18).<\/p>\n<p style=\"text-align: justify;\">A causa di quella strumentalizzazione, Antonio Martino confessa di essersi ben presto pentito di aver formulato quella congettura; infatti, le stime della sommersione economica vengono preferite ai veri rimedi per curare il malessere economico del paese, poich\u00e9 <em>&#8220;una robusta rivalutazione del reddito nazionale consente di gestire con minore affanno la politica di bilancio. Non solo diventa possibile porsi l\u2019obiettivo di accrescere di qualche punto il prelievo fiscale, ma diventa anche pi\u00f9 facile contenere la spesa. Un Paese che si scopre pi\u00f9 ricco protesta di meno se si elimina un sussidio di troppo&#8221;<\/em> (19).<\/p>\n<p style=\"text-align: justify;\">Se cos\u00ec fosse, <em>&#8220;<\/em>[&#8230;]<em> per risolvere i problemi italiani<\/em> \u2014 commenta Antonio Martino \u2014<em> basterebbe una &#8220;robusta&#8221; rivalutazione del 100 per cento, che riporterebbe l\u2019incidenza del disavanzo ai valori dei primi anni Settanta, alta ma meno assurda, quelli della spesa pubblica ai livelli dei primi anni Sessanta, e la pressione tributaria scenderebbe al di sotto di quella di Stati Uniti e Giappone. Come se non bastasse, l\u2019Italia si collocherebbe ai vertici della prosperit\u00e0 mondiale. Purtroppo, non \u00e8 cos\u00ec semplice&#8221;<\/em> (20).<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 \u2014 prosegue \u2014 non abbiamo nessuna indicazione certa che l\u2019incidenza dell\u2019economia sommersa sia aumentata negli ultimi anni; anzi, i dati monetari suggeriscono che essa sia diminuita: &#8220;[&#8230;]<em> il rapporto fra quantit\u00e0 di moneta<\/em> [&#8230;]<em> e P.I.L., che nel 1978 era 0,55, \u00e8 andato diminuendo ed \u00e8 stato pari a 0,44 nel 1985&#8243;<\/em> (21) e, se \u00e8 vero, come da pi\u00f9 parti si sostiene, che l\u2019economia sommersa \u00e8 collegata a fenomeni di evasione fiscale, <em>&#8220;<\/em>[&#8230;]<em> la crescita accelerata delle entrate tributarie che ha caratterizzato l\u2019ultimo decennio dovrebbe suggerire una diminuzione drastica dell\u2019economia sommersa&#8221;<\/em> (22).<\/p>\n<p style=\"text-align: justify;\">Ciononostante la convinzione che esista un <em>&#8220;tesoro nascosto&#8221;<\/em> \u00e8 radicata anche nelle pi\u00f9 alte autorit\u00e0 finanziarie dello Stato: nel febbraio del 1987, il Governatore della Banca d\u2019Italia ha, fra l\u2019altro, preso esplicitamente in considerazione l\u2019ipotesi di una rivalutazione dei conti nazionali dell\u2019ordine del 13-15%, sostenendo, nella sua relazione annuale, che <em>&#8220;la necessit\u00e0 di affidare il riequilibrio della finanza pubblica anche all\u2019innalzamento della pressione fiscale \u00e8 confermata dal permanere di aree di elusione, di evasione e di erosione degli imponibili&#8221;<\/em>, la cui <em>&#8220;<\/em>[&#8230;]<em> ampiezza \u00e8 resa oggi pi\u00f9 evidente dalla rivalutazione del reddito nazionale&#8221;<\/em> (23).<\/p>\n<p style=\"text-align: justify;\">E Antonio Martino contesta la giustezza della soluzione che, per contrastare la tendenza alla sommersione di una parte dei contribuenti italiani, propone un innalzamento della pressione fiscale per tutti.<\/p>\n<p style=\"text-align: justify;\"><strong>Non per volont\u00e0 della maggioranza<\/strong><\/p>\n<p style=\"text-align: justify;\">Antonio Martino \u00e8 decisamente convinto che, nonostante tutte le operazioni d\u2019ingegneria contabile, la spesa pubblica abbia veramente raggiunto dimensioni esorbitanti, anche se la sua crescita non \u00e8 stata probabilmente voluta dalla maggioranza e non \u00e8 stata il risultato intenzionale di una cosciente deliberazione politica, avendo ripetutamente tutti i governi ribadito il proposito di un controllo della spesa e di una riduzione della sua incidenza sul reddito nazionale. Tale proposito, forse sincero, era quindi sicuramente velleitario.<\/p>\n<p style=\"text-align: justify;\">Escludendo dunque la volont\u00e0 politica, la causa effettiva del fenomeno va ricercata nella congiuntura di <em>&#8220;anarchia costituzionale&#8221;<\/em> (24), di cui soffre il procedimento di formazione delle decisioni di spesa. Esemplificando, l\u2019autore sostiene che <em>&#8220;<\/em>[&#8230;] <em>in una democrazia &#8220;illimitata&#8221; (cio\u00e8 priva di una costituzione fiscale operante)&#8221;<\/em> (25) il processo di formazione della spesa pubblica \u00e8 analogo a quello dell\u2019inquinamento ecologico, dal momento che la posizione del soggetto che la propone \u00e8 molto simile a quella dell\u2019ipotetico utente di un corso d\u2019acqua: per entrambi i soggetti, il costo del comportamento \u00e8 esterno rispetto a chi lo realizza, il danno sociale derivante dal singolo atto contribuisce in modo quantitativamente trascurabile alle dimensioni globali del problema, mentre l\u2019eventuale astensione dal comportamento dannoso non produce alcun rilevabile vantaggio alla comunit\u00e0 e favorisce soltanto la concorrenza meno scrupolosa; il risultato \u00e8 che chi ne ha l\u2019interesse e la possibilit\u00e0 abusa del bilancio pubblico, esattamente come altri abusano dell\u2019ambiente: tanti singoli atti dannosi realizzano una situazione finale disastrosa per tutti.<\/p>\n<p style=\"text-align: justify;\">La soluzione al problema del disavanzo pubblico \u2014 che secondo l\u2019autore \u00e8 una componente rilevante della fiscalit\u00e0 implicita \u2014 <em>&#8220;<\/em>[&#8230;]<em> va ricercata in un insieme di regole che disciplini il comportamento dei singoli fautori di nuove o maggiori spese, cio\u00e8 in una Costituzione fiscale&#8221;<\/em> (26), e che elimini quelle asimmetrie nella percezione dei costi e dei benefici della spesa pubblica, che, a loro volta, favoriscono la denunciata anarchia.<\/p>\n<p style=\"text-align: justify;\">Un\u2019asimmetria \u00e8 costituita dal <em>&#8220;<\/em>[&#8230;]<em> contrasto nella percezione di benefici concentrati, che vanno cio\u00e8 ad un numero ridotto di persone, e costi diffusi, ripartiti su un gran numero di contribuenti&#8221;<\/em> (27): per esempio, un contributo complessivo a fondo perduto di 570 miliardi a cento imprese di un determinato settore produttivo coster\u00e0 solo 10.000 lire a ciascuno dei 57 milioni di italiani; mentre i beneficiari si organizzeranno in gruppo di pressione, gli altri non avranno n\u00e9 la percezione del costo n\u00e9 l\u2019interesse a contrastare la relativa spesa; perci\u00f2 la conclusione \u00e8 scontata: <em>&#8220;come previsto da Pareto nel lontano 1896: in queste circostanze, l\u2019esito \u00e8 fuori dubbio: gli sfruttatori avranno una vittoria schiacciante&#8221;<\/em> (28).<\/p>\n<p style=\"text-align: justify;\">Un\u2019altra asimmetria consiste nel contrasto fra i benefici immediati, anche se modesti, e i costi futuri, anche se rilevanti; questa asimmetria ha un rilievo particolarissimo in Italia, i cui governi, negli ultimi quarant\u2019anni, hanno avuto una durata media di circa dieci mesi! Un\u2019esistenza politica tendente all\u2019effimero \u00e8 un evidente incentivo <em>&#8220;ad adottare decisioni che producono benefici immediati, il cui merito viene attribuito al<\/em> <em>Governo in carica, finanziandoli con costi futuri, che verranno affrontati da governi successivi&#8221;<\/em> (29) e da contribuenti a venire.<\/p>\n<p style=\"text-align: justify;\"><strong>Spesa pubblica fra anarchia e legittimit\u00e0 costituzionale<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019anarchia costituzionale nel procedimento di formazione della spesa pubblica ha prodotto un disavanzo che, dal 1960 al 1985, \u00e8 aumentato del 32.000% in termini nominali, e di 31 volte in termini reali e la cui incidenza sul PIL \u00e8 passata dall\u20191,8% al 17,7%.<\/p>\n<p style=\"text-align: justify;\">Un effettivo freno all\u2019aumento del <em>deficit<\/em> pubblico si ha nel decennio 1951-1960. Nel periodo del &#8220;centrismo&#8221; i governi si ispiravano alla convinzione che il dettato costituzionale, contenuto nell\u2019ultimo comma dell\u2019articolo 81 \u2014 <em>&#8220;Ogni altra legge che importi nuove o maggiori spese deve indicare i mezzi per farvi fronte&#8221;<\/em> \u2014, imponesse la tendenza al pareggio del bilancio, ed <em>&#8220;erano altres\u00ec convinti che la copertura finanziaria delle leggi di spesa, oltre che obbligatoria sul piano costituzionale, fosse opportuna sotto il profilo della responsabilit\u00e0 nella gestione della cosa pubblica&#8221;<\/em> (30).<\/p>\n<p style=\"text-align: justify;\">Nel periodo precedente l\u2019&#8221;apertura a sinistra&#8221; si hanno dodici rinvii alle Camere di leggi di spesa prive di copertura finanziaria, ma successivamente, con l\u2019avvento del &#8220;centro sinistra&#8221;, si afferma sempre pi\u00f9 la filosofia del <em>deficit spending<\/em>, del &#8220;<em>deficit<\/em> da spesa&#8221;, e viene di fatto abbandonato il principio ritenuto arcaico del pareggio di bilancio. La possibilit\u00e0 di adottare decisioni di spesa prive di copertura finanziaria ha prodotto, secondo l\u2019autore, non soltanto l\u2019aumento del livello complessivo di spesa, ma anche, in ragione del perseguimento &#8220;sfrenato&#8221; dello scopo prefisso, <em>&#8220;il mancato rispetto di una scala di priorit\u00e0&#8221;<\/em> (31); l\u2019attenzione \u00e8 demagogicamente attratta soltanto dai benefici connessi alla decisione particolare e quest\u2019ultima viene adottata indipendentemente dalla considerazione della sua economicit\u00e0.<\/p>\n<p style=\"text-align: justify;\">In questo modo si \u00e8 passati dal principio di copertura alla <em>&#8220;legge della futilit\u00e0 marginale crescente&#8221;<\/em>, per cui <em>&#8220;<\/em>[&#8230;] <em>le esigenze che la spesa si propone di soddisfare diventano via via sempre pi\u00f9 futili&#8221;<\/em> (32); vengono quindi trascurati i servizi pubblici essenziali; l\u2019assistenza e la previdenza pubbliche sono insoddisfacenti e i cittadini ricorrono con sempre maggiore frequenza a cure e a coperture assicurative private; la difesa del loro patrimonio \u00e8 affidata ad agenzie private di sicurezza; alla giustizia dei tribunali si preferiscono arbitrati e transazioni e si ricorre sempre pi\u00f9 spesso a imprese private di recapito della corrispondenza.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, tutto questo non \u00e8 l\u2019esito di una cosciente scelta politica, <em>&#8220;<\/em>[&#8230;]<em> ma la conseguenza non intenzionale dell\u2019operare del sistema di incentivi politici tipico di qualsiasi sistema democratico&#8221;<\/em> (33).<\/p>\n<p style=\"text-align: justify;\">Partendo dal presupposto che le maggioranze che si formano in Parlamento non rappresentano necessariamente la maggioranza degli elettori, ma spesso sono soltanto la somma di diverse minoranze, Antonio Martino descrive un fenomeno, denominato dagli americani <em>logrolling<\/em>, ben noto agli studiosi di <em>&#8220;economia della politica&#8221;<\/em>: <em>&#8220;lo scambio di favori&#8221;<\/em> fra parlamentari o partiti politici diversi; attraverso il vicendevole sostegno, <em>&#8220;si sommano<\/em> [&#8230;]<em> due (o pi\u00f9) minoranze che, coalizzandosi, realizzano la maggioranza necessaria all\u2019approvazione di tutte le decisioni di spesa cui ognuna di esse \u00e8 interessata&#8221;<\/em> (34).<\/p>\n<p style=\"text-align: justify;\">In questo modo vengono approvate dalla maggioranza parlamentare, con un procedimento poco rispettoso di una vera democrazia, decisioni che avvantaggiano esigue minoranze di cittadini e che non sarebbero mai accettate dalla maggioranza degli elettori.<\/p>\n<p style=\"text-align: justify;\">D\u2019altro lato, secondo l\u2019autore \u2014 che dichiara di non voler formulare una critica al metodo democratico in genere, ma al funzionamento attuale dei meccanismi decisionali \u2014 \u00e8 lecito dubitare che il solo requisito di una maggioranza, anche reale, dei cittadini, configuri pienamente la condizione di legittimit\u00e0 di una decisone di spesa, non potendosi escludere che una maggioranza abusi sistematicamente del suo potere per sfruttare la minoranza.<\/p>\n<p style=\"text-align: justify;\">Dunque, se non \u00e8 sufficiente la legge del numero a garantire la richiesta legittimit\u00e0, \u00e8 necessario che si trovi un accordo su criteri obbiettivi minimi di giustificazione delle decisioni di spesa, che, essendo <em>&#8220;inevitabilmente finanziata con denaro proveniente da tasche private&#8221;<\/em>, si sostanzia in una sorta di <em>&#8220;confisca&#8221;<\/em> di risorse e limitazione della libert\u00e0 a danno di qualcuno (35).<\/p>\n<p style=\"text-align: justify;\">Se <em>&#8220;<\/em>[&#8230;]<em> il finanziamento della spesa pubblica costituisce, per chi ne sopporta il costo, niente altro che un esproprio&#8221;<\/em> (36), in quanto l\u2019erario preleva coattivamente una parte del reddito di propriet\u00e0 del contribuente, si pu\u00f2 sostenere che i criteri di legittimit\u00e0 dell\u2019esproprio della propriet\u00e0, previsti dall\u2019articolo 42 della Costituzione, possano valere analogamente anche nel caso dell\u2019esproprio del reddito. In questo modo, si possono individuare i requisiti di legittimit\u00e0 delle decisioni di spesa nel conseguimento dell\u2019interesse generale e nell\u2019indennizzo del contribuente mediante la fornitura di servizi pubblici di valore pari alle imposte pagate.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2, poich\u00e9 questo meccanismo limita pur sempre la libert\u00e0 del cittadino di disporre autonomamente della ricchezza prodotta, l\u2019entit\u00e0 della spesa e del conseguente prelievo andranno oggettivamente contenuti per non ridurre il soggetto in una condizione di tutela statale.<\/p>\n<p style=\"text-align: justify;\"><strong>Una fiscalit\u00e0 eccessiva \u00e8 antisociale<\/strong><\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 facilmente immaginare che la soluzione appena prospettata non sar\u00e0 condivisa dai difensori dello Stato assistenziale, i quali sostengono che le dimensioni della spesa pubblica sono determinate anche dalla necessaria soddisfazione dell\u2019<em>&#8220;adempimento dei doveri inderogabili di solidariet\u00e0 politica, economica e sociale&#8221;<\/em>, richiamati dall\u2019articolo 2 della Costituzione, e accusano i critici dello statalismo di scarsa sensibilit\u00e0 sociale.<\/p>\n<p style=\"text-align: justify;\">Molti di loro ignorano che <em>&#8220;<\/em>[&#8230;] <em>la spesa per &#8220;prestazioni sociali&#8221; rappresenta circa un terzo delle spese totali del settore pubblico consolidato&#8221;<\/em>, e che nel decennio 1975-1985, a fronte di un reddito reale <em>&#8220;enormemente pi\u00f9 alto e pi\u00f9 uniformemente distribuito che in passato&#8221;<\/em> (37), essa \u00e8 aumentata di circa sette volte.<\/p>\n<p style=\"text-align: justify;\">Se i 133.782 miliardi spesi nel 1985 per prestazioni sociali fossero stati distribuiti al 20% della popolazione, supponendo per assurdo che tale sia la percentuale di povert\u00e0 nel paese, gli italiani sarebbero stati trasformati in una nazione di soli benestanti; invece, i soldi dei contribuenti sono stati assorbiti dai costi e dagli sprechi burocratici che hanno reso costosissimi i servizi.<\/p>\n<p style=\"text-align: justify;\">Antonio Martino ricorda il caso esemplare del Comune di Roma, che, qualche anno fa, spendeva 77 miliardi all\u2019anno per gestire asili nido in cui si accoglievano 4.000 bambini; se il Municipio della Capitale, invece di gestire in proprio il servizio, avesse pagato le relative rette presso i pi\u00f9 esclusivi asili della citt\u00e0, avrebbe risparmiato almeno 15 milioni all\u2019anno per ogni ospite.<\/p>\n<p style=\"text-align: justify;\">Simili episodi legittimano il sospetto che <em>&#8220;<\/em>[&#8230;]<em> i veri beneficiari dell\u2019assistenzialismo non sono i destinatari dichiarati dell\u2019aiuto, ma i politici e i burocrati legati all\u2019&#8221;industria dell\u2019assistenza&#8221;&#8221;<\/em> (38).<\/p>\n<p style=\"text-align: justify;\">Gli statalisti ritengono inoltre che le esigenze di socialit\u00e0 non sarebbero comunque pienamente soddisfatte neppure in uno Stato assistenziale ben funzionante, se non si provvedesse nel contempo a ridistribuire la ricchezza attraverso provvedimenti di politica economica; a questi sostenitori dell\u2019ugualitarismo e della spesa pubblica, secondo l\u2019autore, non interessa tanto <em>&#8220;dare a chi ha<\/em> <em>&#8220;poco<\/em>&#8220;<em>&#8220;<\/em>, ma soprattutto <em>&#8220;punire chi ha &#8220;troppo&#8221;&#8221;<\/em> (39) attraverso una progressiva imposizione tributaria, accompagnata non di rado dall\u2019enfatizzazione dell\u2019evasione e dallo stimolo dell\u2019invidia sociale, senza preoccuparsi se il concorso di questi fattori determini una graduale disgregazione della societ\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>&#8220;Pagare tutti per pagare meno&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Se i tributi, che <em>&#8220;non dovrebbero mai essere visti come strumento di soddisfazione dell\u2019invidia&#8221;<\/em> (40), sono diventati un pericoloso strumento di dialettica, ci\u00f2 accade proprio a causa dell\u2019invidia sociale, che \u00e8 <em>&#8220;l\u2019ultima speranza degli orfani dello statalismo&#8221;<\/em> (41). A motivo di ci\u00f2, secondo l\u2019autore, si \u00e8 affermata nell\u2019opinione pubblica l\u2019idea che <em>&#8220;<\/em>[&#8230;]<em> i contribuenti italiani si dividerebbero in due categorie, &#8220;evasori e tartassati&#8221;<\/em> [&#8230;]<em> e i tartassati lo sarebbero soltanto per via del fatto che i malvagi evasori si rifiuterebbero di fare il loro dovere&#8221;<\/em>, per cui, se si riuscisse a far pagare agli evasori il dovuto, ritengono alcuni che <em>&#8220;tutto funzionerebbe nel migliore dei modi&#8221;<\/em> (42).<\/p>\n<p style=\"text-align: justify;\">L\u2019enfasi \u00e8 ulteriormente aumentata da quegli organi di informazione che definiscono sarcasticamente l\u2019evasione come lo &#8220;sport nazionale&#8221;, mentre in realt\u00e0 essa <em>&#8220;<\/em>[&#8230;]<em> non costituisce<\/em> [&#8230;] <em>un\u2019invenzione italiana, ma \u00e8 un fenomeno universale&#8221;<\/em> (43).<\/p>\n<p style=\"text-align: justify;\">Il legislatore \u00e8 talmente consapevole dell\u2019universalit\u00e0 e dell\u2019invincibilit\u00e0 residuale dell\u2019evasione, che <em>&#8220;<\/em>[&#8230;]<em> la nostra legislazione tributaria \u00e8 basata su una stima spesso implicita della sue dimensioni. Le nostre imposte, in altri termini, vengono introdotte nella consapevolezza del fatto che verranno in parte evase e sono, quindi, maggiori di quanto non sarebbero se il legislatore fosse convinto che l\u2019evasione sia assente&#8221;<\/em> (44).<\/p>\n<p style=\"text-align: justify;\">Lo stesso Governatore della Banca d\u2019Italia, nella relazione gi\u00e0 citata, si dice convinto che l\u2019ampiezza delle aree di elusione, di evasione e di erosione renderebbe necessario un innalzamento della pressione fiscale.<\/p>\n<p style=\"text-align: justify;\">In questo senso \u00e8 vero che l\u2019evasione si traduce in imposte pi\u00f9 alte per i contribuenti onesti, ma l\u2019affermazione va corretta denunciando l\u2019ingiusto comportamento del legislatore e dell\u2019esecutivo: infatti, <em>&#8220;se esistono<\/em> <em>contribuenti che non fanno il loro &#8220;dovere civico&#8221; e si rifiutano di pagare le imposte dovute, la soluzione non sembra proprio quella di accrescere il carico complessivo su tutti i contribuenti, anche quelli onesti&#8221;<\/em> (45).<\/p>\n<p style=\"text-align: justify;\">Il problema dell\u2019evasione non si risolve aumentando le imposte o praticando il terrorismo fiscale; esso <em>&#8220;<\/em>[&#8230;]<em> pu\u00f2 essere risolto solo grazie all\u2019azione di &#8220;un corpo numeroso di accertatori onesti, tecnicamente preparati ed adeguatamente remunerati&#8221;, come sosteneva un predecessore dell\u2019attuale Governatore che si chiamava Luigi Einaudi&#8221;<\/em> (46).<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda, infine, lo <em>slogan &#8220;pagare tutti per pagare meno&#8221;<\/em> (47), si tratta appunto di un puro <em>slogan<\/em> perch\u00e9 <em>&#8220;<\/em>[&#8230;]<em> non \u00e8 certo che dalla lotta all\u2019evasione possono venire i mezzi per una riduzione cospicua delle imposte&#8221;<\/em> (48); anzi l\u2019esperienza mostra che <em>&#8220;<\/em>[&#8230;]<em> quando aumentano le entrate del settore pubblico le spese aumentano in misura ancora maggiore&#8221;<\/em> (49).<\/p>\n<p style=\"text-align: justify;\"><strong>La crescita della fiscalit\u00e0 visibile e di quella occulta<\/strong><\/p>\n<p style=\"text-align: justify;\">Dal 1974 al 1986 le entrate totali del settore pubblico sono aumentate di quasi nove volte in termini nominali (+785%) e dell\u201987,5% in termini reali \u2014 tenendo cio\u00e8 conto dell\u2019inflazione \u2014, passando dal 32,8% al 47,1% del PIL. Alla spesa pubblica, che nel 1975 era finanziata per il 14,6% dalle imposte dirette \u2014 8.440 miliardi \u2014, l\u2019imposizione diretta nel 1985 ha fornito un contributo del 24,8%, pari a 105.471 miliardi. La crescita delle imposte dirette dal 1975 al 1985 \u00e8 stata impressionante: essa \u00e8 aumentata di dodici volte in termini nominali (+1.150%) e di otto volte in termini reali (+705%).<\/p>\n<p style=\"text-align: justify;\">Tuttavia, un incremento di queste dimensioni non corrisponde a un reale aumento della base imponibile, ma \u00e8 collegato al fenomeno del <em>fiscal drag<\/em>, che rappresenta una modalit\u00e0 extralegale e nascosta per dilatare l\u2019imposizione.<\/p>\n<p style=\"text-align: justify;\">Il fenomeno fa riferimento a un particolare effetto dovuto all\u2019azione congiunta della progressivit\u00e0 delle aliquote d\u2019imposta e dell\u2019inflazione, per cui gli imponibili dei contribuenti vengono spinti verso scaglioni di reddito gravati da aliquote maggiori.<\/p>\n<p style=\"text-align: justify;\">Il risultato \u00e8 che, <em>&#8220;<\/em>[&#8230;]<em> anche se il reddito reale \u00e8 invariato, i contribuenti sopportano una pressione tributaria crescente&#8221;<\/em> (50). Il fenomeno ha assunto proporzioni enormi, l\u2019autore cita le stime di altri economisti, secondo i quali <em>&#8220;il gettito complessivo da<\/em> fiscal drag<em>, maturato dal 1976, sarebbe risultato, nel 1984, pari a circa 24.300 miliardi, il 45 per cento del gettito totale dell\u2019IRPEF di quell\u2019anno&#8221;<\/em> (51).<\/p>\n<p style=\"text-align: justify;\">In tale contesto i provvedimenti, adottati periodicamente dai nostri governanti, di ritocco delle aliquote si mostrano puramente apparenti, perch\u00e9 danno l\u2019impressione di concedere sgravi fiscali, mentre in realt\u00e0 le imposte continuano a crescere.<\/p>\n<p style=\"text-align: justify;\">Un meccanismo, che di fatto e surrettiziamente introduce nuove imposte, non soltanto \u00e8 contrario all\u2019articolo 23 della Costituzione, ma \u00e8 anche radicalmente iniquo. La soluzione \u2014 suggerita originariamente da Vito Tanzi e condivisa in seguito anche dal sindacato socialcomunista \u2014 consiste nell\u2019indicizzazione degli scaglioni di reddito ai fini della determinazione dell\u2019imposta: accolta dal legislatore nel 1989, decorre dal periodo d\u2019imposta 1990, quindi non se ne conosce ancora la reale efficacia.<\/p>\n<p style=\"text-align: justify;\">Nonostante le <em>&#8220;troppe imposte sui redditi&#8221;<\/em> (52), l\u2019imposizione diretta rappresenta solo un quarto del finanziamento della spesa pubblica; al resto si provvede con la <em>&#8220;fiscalit\u00e0 occulta&#8221;<\/em> (53), costituita da imposte indirette (17,5%), contributi sociali (25,4%), indebitamento netto (24,2%). Sommando questi dati emerge chiaramente che <em>&#8220;<\/em>[&#8230;]<em> circa l\u201980<\/em> <em>per cento delle imposte in Italia sono invisibili, pagate cio\u00e8 da contribuenti inconsapevoli&#8221;<\/em> (54).<\/p>\n<p style=\"text-align: justify;\">Un tale sistema \u00e8 <em>&#8220;fraudolento e antidemocratico&#8221;<\/em> (55), e non certo soltanto perch\u00e9 il prezzo della benzina \u00e8 costituito per quattro quinti da tasse, ma per il sistematico e progressivo ricorso al <em>deficit<\/em>, che, finanziato con la monetizzazione del debito e con l\u2019inflazione, \u00e8 la peggiore delle imposte: infatti, secondo Luigi Einaudi, \u00e8 <em>&#8220;peggiore perch\u00e9 inavvertita, gravante assai pi\u00f9 sui poveri che sui ricchi, cagione di arricchimento per i pochi e di impoverimento per i pi\u00f9, lievito di malcontento per ogni classe contro ogni classe sociale e di disordine sociale&#8221;<\/em> (56).<\/p>\n<p style=\"text-align: justify;\">Anche se l\u2019indebitamento netto e le imposte indirette hanno finanziato circa il 42% delle spesa pubblica, il sistema non cessa di dichiararsi informato a <em>&#8220;criteri di progressivit\u00e0&#8221;<\/em>, e ci\u00f2 \u00e8 malauguratamente vero perch\u00e9 in effetti coniuga <em>&#8220;<\/em>[&#8230;] <em>il peggio di entrambe le alternative, in quanto accoppia una insensata progressivit\u00e0 nell\u2019imposizione sul reddito, con il massiccio ricorso a fonti di gettito chiaramente regressive o di segno incerto&#8221;<\/em> (57).<\/p>\n<p style=\"text-align: justify;\">Antonio Martino ripetutamente insiste per l\u2019abbassamento delle aliquote marginali, convinto che un simile provvedimento <em>&#8220;<\/em>[&#8230;]<em> riduce l\u2019incentivo all\u2019elusione delle imposte ed accresce l\u2019incentivo alla produzione del reddito&#8221;<\/em> (58), e favorisce anche un ampliamento della base imponibile e del gettito. Il convincimento dell\u2019economista si fonda, oltre che sull\u2019insegnamento di Luigi Einaudi, sull\u2019esperienza degli Stati Uniti d\u2019America, ove, nel triennio dal 1982 al 1984, nonostante la riduzione dell\u2019aliquota marginale massima dal 70 al 50%, sono aumentati sia l\u2019imponibile che il gettito.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019alternativa costituzionale<\/strong><\/p>\n<p style=\"text-align: justify;\">Comunque, un\u2019efficace soluzione del problema della fiscalit\u00e0 italiana deve essere ricercata a livello costituzionale. Allo scopo non \u00e8 necessaria una riforma della Costituzione, ma \u00e8 sufficiente una corretta applicazione del gi\u00e0 citato ultimo comma dell\u2019articolo 81, che \u2014 come riteneva Ezio Vanoni \u2014 <em>&#8220;<\/em>[&#8230;] <em>\u00e8 una garanzia della tendenza al pareggio del bilancio&#8221;<\/em> (59).<\/p>\n<p style=\"text-align: justify;\">Sono trascorsi pi\u00f9 di venticinque anni da quando la prospettiva discrezionale di tipo keynesiano \u00e8 stata preferita al principio <em>&#8220;neutrale&#8221;<\/em> (60) del pareggio di bilancio e <em>&#8220;<\/em>[&#8230;]<em> le conseguenze che ne sono seguite hanno indotto un numero crescente di personalit\u00e0 politiche ed accademiche a suggerire il ripristino di una Costituzione fiscale funzionante&#8221;<\/em> (61), e fra esse il Governatore della Banca d\u2019Italia nella relazione del 1983.<\/p>\n<p style=\"text-align: justify;\">Anche senza pretendere la soluzione pi\u00f9 radicale, consistente nel privare i membri delle due Camere dell\u2019iniziativa in materia di bilancio \u2014 soluzione condivisa da Luigi Einaudi per il motivo che <em>&#8220;<\/em>[&#8230;]<em> proprio i deputati, per rendersi popolari, hanno proposto spese senza nemmeno rendersi conto dei mezzi necessari per fronteggiarle&#8221;<\/em> (62) \u2014 \u00e8 possibile per altre vie <em>&#8220;<\/em>[&#8230;]<em> sottrarre le decisioni di spesa alla miriade di centri decisionali operanti in condizioni di irresponsabilit\u00e0&#8221;<\/em> (63).<\/p>\n<p style=\"text-align: justify;\">In primo luogo va ripristinato il principio dell\u2019ultimo comma dell\u2019articolo 81, quale principio generale di responsabilit\u00e0 nelle decisioni di spesa. L\u2019obbligo del pareggio effettivo va rispettato da tutte le decisioni di spesa del settore pubblico, comprese le amministrazioni locali, e la copertura finanziaria deve riguardare l\u2019intera durata dell\u2019impegno di spesa che viene assunto e non basta che sia limitata alla frazione del primo anno di vigenza.<\/p>\n<p style=\"text-align: justify;\">Quindi occorre individuare tassativamente i mezzi costituzionalmente accettabili per far fronte a nuove o maggiori spese. Tali mezzi sono: la riduzione di altre spese, l\u2019introduzione di nuove imposte <em>ad hoc<\/em>, e, eccezionalmente, l\u2019indebitamento sul mercato.<\/p>\n<p style=\"text-align: justify;\">Antonio Martino \u00e8 convinto che <em>&#8220;se si riuscisse a sottoporre il processo di formazione delle decisioni di spesa a regole costituzionali, la soluzione del problema dell\u2019iperfiscalit\u00e0 sarebbe in larga misura realizzata&#8221;<\/em> (64).<\/p>\n<p style=\"text-align: justify;\">L\u2019unica modifica della Costituzione auspicata dall\u2019autore \u00e8 l\u2019abolizione del divieto di <em>referendum<\/em> abrogativo in materia tributaria, sancito dall\u2019articolo 75, al fine di consentire ai cittadini un effettivo controllo popolare diretto sull\u2019attivit\u00e0 fiscale.<\/p>\n<p style=\"text-align: justify;\">E, per finire, il rispetto effettivo del dettato costituzionale potr\u00e0 dirsi realizzato solo a condizione che venga perseguito l\u2019obbiettivo della trasparenza in materia fiscale, <em>&#8220;<\/em>[&#8230;]<em> un obiettivo da porsi senza la pretesa di poterlo raggiungere immediatamente&#8221;<\/em> (65), ma adoperandosi con continuit\u00e0 <em>&#8220;<\/em>[&#8230;]<em> perch\u00e9 il grado di trasparenza della fiscalit\u00e0 aumenti, perch\u00e9 l\u2019imposizione sia in misura sempre maggiore consapevole, perch\u00e9 i contribuenti sappiano sempre meglio quanta parte del carico fiscale grava direttamente su di loro&#8221;<\/em> (66): infatti, <em>&#8220;<\/em>[&#8230;]<em> la fiscalit\u00e0 onesta \u00e8 quella che consente ai contribuenti di apprezzare per intero la penosit\u00e0 dell\u2019imposizione: il fisco &#8220;indolore&#8221; \u00e8, quasi sempre, disonesto&#8221;<\/em> (67).<\/p>\n<p style=\"text-align: justify;\"><em><strong>&#8220;Perch\u00e9 non noi?&#8221;<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Non \u00e8 mai politica attuale la parola dei profeti disarmati. Ma in un popolo ci vogliono i politici attuali e quelli inattuali; e, se i primi sono giudicati savi ed i secondi matti, ci vogliono i savi e i matti. E guai ai popoli che hanno solo i savi, perch\u00e9 spetta di solito ai matti porre e coltivare i germi della politica avvenire&#8221;<\/em>: con questa citazione di Benedetto Croce posta in epigrafe del capitolo conclusivo (68), l\u2019autore fa intendere che sa che le denunce e le proposte formulate nel suo studio provocano spesso una reazione scettica in chi, pur condividendole, le reputa tuttavia utopistiche o velleitarie, in quanto irrealizzabili politicamente.<\/p>\n<p style=\"text-align: justify;\">Ma lo studioso non accetta la concezione della politica come <em>&#8220;l\u2019arte del possibile&#8221;<\/em>; al contrario, ritiene che <em>&#8220;<\/em>[&#8230;]<em> scopo della politica sia quello di rendere possibile ci\u00f2 che \u00e8 desiderabile&#8221;<\/em> e che l\u2019obiezione del <em>&#8220;politicamente impossibile&#8221;<\/em> in molti casi \u00e8 solo <em>&#8220;una razionalizzazione dell\u2019inazione, una giustificazione del conservatorismo, una difesa ad oltranza dello <\/em>statu quo<em>&#8220;<\/em> (69).<\/p>\n<p style=\"text-align: justify;\">La sua critica alla fiscalit\u00e0, non condizionata dal bisogno di un compromesso a tutti i costi, n\u00e9 intimidita dalla mitologia socialista, mette coerentemente in discussione lo Stato &#8220;sociale&#8221;, che, nel suo assetto attuale, deve essere abbandonato.<\/p>\n<p style=\"text-align: justify;\">Una sua difesa non ha argomenti, non pu\u00f2 invocare n\u00e9 nobili intenzioni originarie, n\u00e9 risultati positivi; infatti l\u2019assistenzialismo di Stato <em>&#8220;<\/em>[&#8230;]<em> venne introdotto in forma sistematica da Bismark nel 1881 per svuotare di significato la posizione politica dei socialdemocratici&#8221;<\/em> (70), e, di conseguenza, <em>&#8220;<\/em>[&#8230;]<em> il problema della lotta alla miseria \u00e8 stato affrontato dallo Stato sociale bismarkiano su base paternalistica: lo &#8220;Stato-pap\u00e0&#8221; ha individuato una serie di bisogni &#8220;essenziali&#8221;, ha reperito i mezzi con la pressione tributaria, l\u2019indebitamento e l\u2019inflazione, si \u00e8 dato alla produzione dei servizi relativi in proprio \u2014 spesso in condizioni di monopolio \u2014 e li ha distribuiti indiscriminatamente sotto costo o &#8220;gratis&#8221;. Questo sistema \u00e8 fallito miseramente, anche se in misura diversa, ovunque&#8221;<\/em> (71).<\/p>\n<p style=\"text-align: justify;\">Il rifiuto di un simile modello di Stato non comporta l\u2019abbandono degli indigenti, dal momento che <em>&#8220;<\/em>[&#8230;]<em> lo Stato assistenziale costa pi\u00f9 di quanto rende&#8221;<\/em> e che <em>&#8220;<\/em>[&#8230;]<em> solo le briciole dell\u2019assistenzialismo sono arrivate ai beneficiari dichiarati&#8221;<\/em>, mentre <em>&#8220;<\/em>[&#8230;]<em> il pi\u00f9 \u00e8 stato dilapidato in costi burocratici (inclusivi della corruzione, degli sprechi, delle frodi e delle clientele)&#8221;<\/em> (72).<\/p>\n<p style=\"text-align: justify;\">Inoltre si deve considerare che <em>&#8220;<\/em>[&#8230;]<em> non tutta la spesa pubblica \u00e8 destinata a finalit\u00e0 &#8220;sociali&#8221;: nel 1985 la spesa per prestazioni sociali ha costituito soltanto il 31 per cento della spesa totale del settore pubblico; n\u00e9 \u00e8 vero che la crescita della spesa pubblica complessiva sia interamente imputabile a spesa &#8220;sociale&#8221;: dal 1976 al 1985 l\u2019incremento della spesa per prestazioni sociali <\/em>[&#8230;] <em>ha rappresentato solo il 30 per cento dell\u2019incremento della spesa complessiva&#8221;<\/em> (73).<\/p>\n<p style=\"text-align: justify;\">Infine va chiarito che contrastare l\u2019assistenzialismo non significa negare l\u2019assistenza: vi sono innumerevoli spese, secondo Antonio Martino, che potrebbero essere ridotte, garantendo una diminuzione della spesa totale, senza dover incidere sulle spese realmente assistenziali.<\/p>\n<p style=\"text-align: justify;\">Riflettendo su queste affermazioni dell\u2019autore, \u00e8 naturale chiedersi per qual motivo i nostri governanti, dovendo ridurre la spesa pubblica, scelgano costantemente di contrarre i costi assistenziali, che, come si \u00e8 visto, sono meno di un terzo del totale. Si potrebbe dubitare che essi vogliano, premendo in questo modo sull\u2019opinione pubblica, esercitare una difesa preventiva, ricattatoria e non dichiarata dello statalismo.<\/p>\n<p style=\"text-align: justify;\">Antonio Martino non affronta soltanto problemi di diritto tributario e di economia politica, ma anche temi di diritto costituzionale e di psicologia sociale, come quello dell\u2019invidia, offrendo al lettore un lavoro scientifico e ricco di informazioni. La vivacit\u00e0 dell\u2019esposizione rende lo studio piacevole, mentre l\u2019oggettiva situazione della fiscalit\u00e0 italiana ne conferma l\u2019attualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Concludendo, \u00e8 giusto riconoscere l\u2019idealit\u00e0, che traspare in ogni pagina e che testimonia un gusto per la verit\u00e0 e un coraggioso anticonformismo, e ringraziare l\u2019autore per l\u2019aiuto che offre a quanti sperano che <em>&#8220;la saviezza dei savi perir\u00e0 e l\u2019intelligenza degli intelligenti si oscurer\u00e0&#8221;<\/em> (74), e a quanti intendono rispondere positivamente alla domanda posta a titolo del capitolo conclusivo: <em>&#8220;Perch\u00e9 non noi?&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>NOTE<\/strong><\/p>\n<p style=\"text-align: justify;\">(1) Cfr. Antonio Martino, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, con una <em>Introduzione<\/em> di Victor Uckmar, Studio Tesi, Udine 1987, pp. X-206; la frase cit. \u00e8 a p. 4.<\/p>\n<div style=\"text-align: justify;\">(2) Cfr. <em>&#8220;Marcia dei Contribuenti&#8221;<\/em>, in <em>Cristianit\u00e0<\/em>, anno XIV, n. 139-140, novembre-dicembre 1986.<\/div>\n<div style=\"text-align: justify;\">(3) Cfr. A. Martino, <em>Fisco: anarchia o legalit\u00e0 costituzionale?<\/em>, CREA, Roma 1986; e il mio <em>Il fisco fra anarchia e legalit\u00e0 costituzionale<\/em>, in <em>Cristianit\u00e0<\/em>, anno XIV, n. 139-140, cit.<\/div>\n<div style=\"text-align: justify;\">(4) Cfr. V. Uckmar, <em>Introduzione<\/em>, cit., pp. VII-IX.<\/div>\n<div style=\"text-align: justify;\">(5) Cit. in A. Martino, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., p. 11.<\/div>\n<div style=\"text-align: justify;\">(6) <em>Ibid<\/em>., p. 104.<\/div>\n<div style=\"text-align: justify;\">(7) <em>Ibid<\/em>., p. 121.<\/div>\n<div style=\"text-align: justify;\">(8) <em>Ibid<\/em>., p. 123.<\/div>\n<div style=\"text-align: justify;\">(9) <em>Ibid<\/em>., p. 20.<\/div>\n<div style=\"text-align: justify;\">(10) <em>Ibid<\/em>., pp. 19-20.<\/div>\n<div style=\"text-align: justify;\">(11) <em>Ibid<\/em>., pp. 32-33.<\/div>\n<div style=\"text-align: justify;\">(12) <em>Ibid<\/em>., p. 34.<\/div>\n<div style=\"text-align: justify;\">(13) Cfr. Milton Friedman, <em>A New Holiday<\/em>, in <em>Newsweek<\/em>, 5-8-1974; A. Martino, <em>Il giorno dell\u2019indipendenza personale<\/em>, in <em>il Giornale nuovo<\/em>, 21-4-1976; e Idem, <em>Per la ricostruzione economica dell\u2019Italia<\/em>, in <em>Nuovi studi politici<\/em>, n. 2, 1976.<\/div>\n<div style=\"text-align: justify;\">(14) A. Martino, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., p. 36.<\/div>\n<div style=\"text-align: justify;\">(15) Cfr. Idem, <em>Non basta dirsi pi\u00f9 ricchi<\/em>, in <em>La Stampa<\/em>, 17-2-1987.<\/div>\n<div style=\"text-align: justify;\">(16) Idem, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., p. 39.<\/div>\n<div style=\"text-align: justify;\">(17) Idem, <em>L\u2019economia clandestina ci ha salvato dal baratro<\/em>, in <em>il Giornale nuovo<\/em>, 19-11-1978; per un\u2019analisi pi\u00f9 approfondita del problema, cfr. Idem, <em>Measuring Italy\u2019s Underground Economy<\/em>, in <em>Policy Review<\/em>, primavera 1981, pp. 87-106; sull\u2019aleatoriet\u00e0 e sull\u2019arbitrariet\u00e0 delle stime del PIL sommerso, cfr., fra altri, Mario Deaglio, <em>Economia sommersa e analisi economica<\/em>, Giappichelli, Torino 1985, p. 114; e la mia recensione, in <em>Quaderni di &#8220;Cristianit\u00e0&#8221;<\/em>, anno II, n. 4, primavera 1986, pp. 83-88.<\/div>\n<div style=\"text-align: justify;\">(18) A. Martino, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., p. 40.<\/div>\n<div style=\"text-align: justify;\">(19) Antonio Pedone, <em>Il tesoro nascosto<\/em>, in <em>il Mondo<\/em>, 16-2-1987.<\/div>\n<div style=\"text-align: justify;\">(20) A. Martino, <em>Noi e il fisco. La crescita della fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., pp. 42-43.<\/div>\n<div style=\"text-align: justify;\">(21) <em>Ibid<\/em>., p. 43.<\/div>\n<div style=\"text-align: justify;\">(22) <em>Ibid<\/em>., p. 44.<\/div>\n<div style=\"text-align: justify;\">(23) Cit. <em>ibid<\/em>., p. 46.<\/div>\n<div style=\"text-align: justify;\">(24) <em>Ibid.<\/em>, p. 61.<\/div>\n<div style=\"text-align: justify;\">(25) <em>Ibid<\/em>., p. 63.<\/div>\n<div style=\"text-align: justify;\">(26) <em>Ibidem<\/em>.<\/div>\n<div style=\"text-align: justify;\">(27) <em>Ibid<\/em>., p. 64.<\/div>\n<div style=\"text-align: justify;\">(28) <em>Ibid<\/em>., p. 65.<\/div>\n<div style=\"text-align: justify;\">(29) <em>Ibid<\/em>., p. 68.<\/div>\n<div style=\"text-align: justify;\">(30) <em>Ibid<\/em>., p. 73.<\/div>\n<div style=\"text-align: justify;\">(31) <em>Ibid<\/em>., p. 76.<\/div>\n<div style=\"text-align: justify;\">(32) <em>Ibid<\/em>., p. 79.<\/div>\n<div style=\"text-align: justify;\">(33) <em>Ibid<\/em>., p. 80.<\/div>\n<div style=\"text-align: justify;\">(34) <em>Ibid<\/em>., p. 82.<\/div>\n<div style=\"text-align: justify;\">(35) <em>Ibid<\/em>., p. 83.<\/div>\n<div style=\"text-align: justify;\">(36) <em>Ibid<\/em>., p. 84.<\/div>\n<div style=\"text-align: justify;\">(37) <em>Ibid<\/em>., pp. 86-87.<\/div>\n<div style=\"text-align: justify;\">(38) <em>Ibid<\/em>., p. 89.<\/div>\n<div style=\"text-align: justify;\">(39) <em>Ibid<\/em>., p. 21.<\/div>\n<div style=\"text-align: justify;\">(40) <em>Ibid<\/em>., p. 20.<\/div>\n<div style=\"text-align: justify;\">(41) <em>Ibid<\/em>., p. 93; cfr. Helmut Schoek, <em>L\u2019invidia e la societ\u00e0<\/em>, trad. it., Rusconi, Milano 1974.<\/div>\n<div style=\"text-align: justify;\">(42) <em>Ibid<\/em>., p. 132.<\/div>\n<div style=\"text-align: justify;\">(43) <em>Ibid<\/em>., p. 133.<\/div>\n<div style=\"text-align: justify;\">(44) <em>Ibid<\/em>., p. 135.<\/div>\n<div style=\"text-align: justify;\">(45) <em>Ibid<\/em>., p. 47.<\/div>\n<div style=\"text-align: justify;\">(46) <em>Ibidem<\/em>.<\/div>\n<div style=\"text-align: justify;\">(47) <em>Ibid<\/em>., p. 129.<\/div>\n<div style=\"text-align: justify;\">(48) <em>Ibid<\/em>., p. 140.<\/div>\n<div style=\"text-align: justify;\">(49) <em>Ibid<\/em>., p. 141.<\/div>\n<div style=\"text-align: justify;\">(50) <em>Ibid<\/em>., p. 114.<\/div>\n<div style=\"text-align: justify;\">(51) E. Longobardi, <em>Inflazione e progressivit\u00e0 dell\u2019imposta sul reddito in Italia: l\u2019IRPEF dal 1974 al 1984<\/em>, in appendice a Vito Tanzi, <em>Inflazione e imposta personale sul reddito<\/em>, il Mulino, Bologna 1986, pp. 295-296.<\/div>\n<div style=\"text-align: justify;\">(52) Cfr. Giorgio Fu\u00e0 e Emilio Rosini, <em>Troppe tasse sui redditi<\/em>, Laterza, Bari 1985; e la mia recensione in <em>Cristianit\u00e0<\/em>, anno XIII, n. 118, febbraio 1985.<\/div>\n<div style=\"text-align: justify;\">(53) A. Martino, <em>Noi e il fisco. La fiscalit\u00e0 arbitraria: cause, conseguenze, rimedi<\/em>, cit., p. 111.<\/div>\n<div style=\"text-align: justify;\">(54) <em>Ibid<\/em>., p. 110.<\/div>\n<div style=\"text-align: justify;\">(55) <em>Ibidem<\/em>.<\/div>\n<div style=\"text-align: justify;\">(56) Cit. <em>ibid<\/em>., p. 118.<\/div>\n<div style=\"text-align: justify;\">(57) <em>Ibid<\/em>., p. 119.<\/div>\n<div style=\"text-align: justify;\">(58) <em>Ibid<\/em>., p. 121.<\/div>\n<div style=\"text-align: justify;\">(59) <em>Ibid<\/em>., p. 148.<\/div>\n<div style=\"text-align: justify;\">(60) <em>Ibid<\/em>., p. 150.<\/div>\n<div style=\"text-align: justify;\">(61) <em>Ibid<\/em>., p. 153.<\/div>\n<div style=\"text-align: justify;\">(62) Cit. <em>ibid<\/em>, p. 154.<\/div>\n<div style=\"text-align: justify;\">(63) <em>Ibid<\/em>., p. 155.<\/div>\n<div style=\"text-align: justify;\">(64) <em>Ibid<\/em>., pp. 157-158.<\/div>\n<div style=\"text-align: justify;\">(65) <em>Ibid<\/em>., pp. 166-167.<\/div>\n<div style=\"text-align: justify;\">(66) <em>Ibid<\/em>., p. 167.<\/div>\n<div style=\"text-align: justify;\">(67) <em>Ibid<\/em>., p. 169.<\/div>\n<div style=\"text-align: justify;\">(68) Cit. <em>ibid<\/em>., p. 179.<\/div>\n<div style=\"text-align: justify;\">(69) <em>Ibid<\/em>., p. 187.<\/div>\n<div style=\"text-align: justify;\">(70) <em>Ibid<\/em>., p. 180.<\/div>\n<div style=\"text-align: justify;\">(71) <em>Ibid<\/em>., p. 181.<\/div>\n<div style=\"text-align: justify;\">(72) <em>Ibidem<\/em>.<\/div>\n<div style=\"text-align: justify;\">(73) <em>Ibid<\/em>., p. 180.<\/div>\n<div style=\"text-align: justify;\" align=\"justify\">(74) <em>Is<\/em>. 29, 14<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cristianit\u00e0 n. 189 (1991) il problema della fiscalit\u00e0 non \u00e8 soltanto un fatto economico e che, pertanto, non \u00e8 risolvibile con modifiche puramente tecniche della normativa fiscale, ma investe sia il complesso dei rapporti tra lo Stato e i cittadini, sia la concezione delle funzioni e dei limiti dell\u2019attivit\u00e0 di governo: quindi, si tratta di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29026,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[145],"class_list":["post-1619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fisco","tag-fisco-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-10-20T15:43:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-21T15:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"31 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi\",\"datePublished\":\"2005-10-20T15:43:25+00:00\",\"dateModified\":\"2015-12-21T15:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/\"},\"wordCount\":6175,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fisco.jpg\",\"keywords\":[\"fisco\"],\"articleSection\":[\"Fisco\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/\",\"name\":\"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fisco.jpg\",\"datePublished\":\"2005-10-20T15:43:25+00:00\",\"dateModified\":\"2015-12-21T15:32:04+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fisco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fisco.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/","og_locale":"it_IT","og_type":"article","og_title":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-10-20T15:43:25+00:00","article_modified_time":"2015-12-21T15:32:04+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"31 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi","datePublished":"2005-10-20T15:43:25+00:00","dateModified":"2015-12-21T15:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/"},"wordCount":6175,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg","keywords":["fisco"],"articleSection":["Fisco"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/","name":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg","datePublished":"2005-10-20T15:43:25+00:00","dateModified":"2015-12-21T15:32:04+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fisco.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crescita-della-fiscalit-arbitraria-cause-conseguenze-rimedi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La crescita della fiscalit&agrave; arbitraria: cause, conseguenze, rimedi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1619\/revisions"}],"predecessor-version":[{"id":29028,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1619\/revisions\/29028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29026"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}