{"id":1606,"date":"2005-10-20T09:09:59","date_gmt":"2005-10-20T07:09:59","guid":{"rendered":""},"modified":"2016-05-10T18:14:08","modified_gmt":"2016-05-10T16:14:08","slug":"il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/","title":{"rendered":"Il ruolo della grande stampa nel declino morale dell&#8217;Italia"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34025\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg\" alt=\"quotidiani_Italia\" width=\"250\" height=\"147\" \/>Corrispondenza romana <\/strong>n.916<\/div>\n<div style=\"text-align: center;\">dell&#8217;8 ottobre 2005<\/div>\n<p style=\"text-align: justify;\">Dopo l&#8217;avvento alla direzione di Paolo Mieli, il &#8220;Corriere della Sera&#8221; sembra aver imboccato e star percorrendo la via del declino: magari non come vendite, ma senz&#8217;altro come organo di opinione del moderatismo italiano.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">A parte lo spazio sempre maggiore dedicato ai temi &#8220;leggeri&#8221;, se non proprio fatui e scandalistici, la sua concitata presa di posizione a fianco delle punte dell&#8217;odierno rivendicazionismo egualitario, dal referendum sulla cosiddetta procreazione medicalmente assistita fino alle pi\u00f9 sguaiate forme di lotta per la legalizzazione dei &#8220;diritti&#8221; delle minoranze omosessuali, si accoppia con la flebilit\u00e0 con cui d\u00e0 voce ai temi opposti &#8211; a quelli che potremmo definire &#8220;i diritti delle maggioranze&#8221; -: il diritto di aver denaro sufficiente per formarsi una fa-miglia, affittare una casa, mettere al mondo i figli ed istruirli senza troppe ingerenze statali.<\/div>\n<p style=\"text-align: justify;\">Questo squilibrio sembra segnare l&#8217;adesione della grande testata milanese al disegno di indebolire, in nome di un ugualitarismo spinto talora al non sense, la famiglia naturale (struttura ancora troppo gerarchizzata per piacere al pensiero &#8220;debole&#8221;), che \u00e8 portato avanti da tanti altri canali mediatici e da gruppi di azione politica e culturale di diversa natura.<\/p>\n<p style=\"text-align: justify;\">Non sfugge come proprio in questi giorni (e probabilmente proprio in sintonia con l&#8217;imposizione dei modelli di famiglia &#8220;zapateriani&#8221;) siano apparsi numerosi film in cui la famiglia, invece che come prezioso luogo in cui il singolo nasce e si sviluppa, \u00e8 dipinta come una sorta d&#8217;inferno sulla terra.<\/p>\n<p style=\"text-align: justify;\">Il coro che si leva dalla grande stampa (che poi in Italia \u00e8 fatta dal &#8220;La Stampa&#8221;, dal &#8220;Corriere&#8221; e da &#8220;la Repubblica&#8221;) si sta tramutando in un vero e proprio tam-tam assordante e ossessivo. La prassi dello strillo non \u00e8 la sola: a essa fa pendant l&#8217;omissione: su temi, eventi e situazioni che contraddicono la prospettiva evocata il silenzio \u00e8 sovrano. Talora gli stessi organi reputano meglio tacere anche su fatti che si situano nella medesima prospettiva.<\/p>\n<p style=\"text-align: justify;\">In tal senso \u00e8 emblematico il quotidiano di Paolo Mieli, che, sabato 24 settembre, riservava un&#8217;intera pagina all&#8217;intervista della nota coppia di stilisti omosessuali Dolce e Gabbana sui loro problemi affaristico-erotici ma il giorno dopo si dimenticava di informare il lettore (lo ha fatto invece &#8220;Avvenire&#8221;: ma ahim\u00e8, &#8220;Avvenire&#8221; tira meno di un sesto delle copie che tira il &#8220;Corriere&#8221; e non lo leggono nemmeno i preti!) che il disegno di legge repressivo della pedofilia on-line, in discussione in Commissione Giustizia del Senato, aveva cono-sciuto una pesante battuta d&#8217;arresto nella sua potenziale efficacia.<\/p>\n<p style=\"text-align: justify;\">Grazie infatti agli uffici di un esponente del Governo, il giovane ministro delle Pari Opportunit\u00e0 on. Stefania Prestigiacomo, e del leader riconosciuto dell&#8217;omosessualismo organizzato italiano, on. Franco Grillini, nel testo gi\u00e0 approvato alla Camera, sono state introdotte fattispecie limitative della responsabilit\u00e0, per cui la produzione, l&#8217;uso e la diffusione di materiale pedo-pornografico non \u00e8 punibile quando il minore che vi \u00e8 coinvolto ha pi\u00f9 di 13 anni, \u00e8 consenziente e il materiale prodotto si suppone non abbia circolazione.<\/p>\n<p style=\"text-align: justify;\">Se si possono ben immaginare le conseguenze devastanti di un tale &#8220;correttivo&#8221; del testo alla luce dell&#8217;esperienza della &#8220;modica quantit\u00e0&#8221; fatta riguardo agli stupefacenti, e se si pu\u00f2 capire l&#8217;impegno del leader omosessualista, francamente sconcerta che un&#8217;esponente del centro-destra si prodighi nell&#8217;indebolire la repressione di una prassi comunque degradante e nociva. E ancor di pi\u00f9 che ci\u00f2 avvenga senza nessuna presa di misure &#8211; non basta l&#8217;eventuale dissenso &#8211; da parte degli organi del suo partito, n\u00e9 dei leader della coalizione di governo.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 abbondantemente nota per il suo virulento e devastante impegno a favore del &#8220;s\u00ec&#8221; nel referendum abrogativo delle norme che regolano la procreazione assistita, ora, sulla pedofilia, l&#8217;on. Prestigiacomo si ripete &#8211; e si ripeter\u00e0 ancora pochi giorni dopo a &#8220;Matrix&#8221; del 28 settembre con una decisa presa di posizione a favore della &#8220;sperimentazione&#8221;, anticamera della sua somministrazione di massa, del farmaco abortivo Ru486 -, schierandosi a difesa di una concezione della vita umana non solo discutibilissima in s\u00e9, ma del tutto inaccet-tabile dall&#8217;Italia moderata, le cui istanze dovrebbe rappresentare.<\/p>\n<p style=\"text-align: justify;\">Quell&#8217;Italia, cattolica e &#8220;laica&#8221;, che non ama n\u00e9 l&#8217;uccisione degli embrioni, n\u00e9 l&#8217;omosessualismo rivoluzionario, n\u00e9 tanto meno la liberalizzazione della speculazione commerciale sul massacro morale non solo dei bambini ma anche dei pre-adolescenti.<\/p>\n<p style=\"text-align: justify;\">Anche se si cerca di nascondere certe &#8220;disinvolture&#8221;, gli italiani non sono ciechi, n\u00e9 privi di memoria: chiss\u00e0 se nel preparare l&#8217;imminente sfida elettorale i dirigenti del centro-destra si ricorderanno dei rischi che corrono se torneranno a &#8220;imbarcare&#8221; personaggi a dir poco ambigui come la signora ministro delle Pari Opportunit\u00e0? (CR 916\/01 del 08\/10\/05)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza romana n.916 dell&#8217;8 ottobre 2005 Dopo l&#8217;avvento alla direzione di Paolo Mieli, il &#8220;Corriere della Sera&#8221; sembra aver imboccato e star percorrendo la via del declino: magari non come vendite, ma senz&#8217;altro come organo di opinione del moderatismo italiano.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34025,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[1093],"class_list":["post-1606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-stampa-nazionale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il ruolo della grande stampa nel declino morale dell&#039;Italia - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il ruolo della grande stampa nel declino morale dell&#039;Italia - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-10-20T07:09:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-10T16:14:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"293\" \/>\n\t<meta property=\"og:image:height\" content=\"172\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il ruolo della grande stampa nel declino morale dell&#8217;Italia\",\"datePublished\":\"2005-10-20T07:09:59+00:00\",\"dateModified\":\"2016-05-10T16:14:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/\"},\"wordCount\":768,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/quotidiani_Italia.jpg\",\"keywords\":[\"stampa nazionale\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/\",\"name\":\"Il ruolo della grande stampa nel declino morale dell'Italia - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/quotidiani_Italia.jpg\",\"datePublished\":\"2005-10-20T07:09:59+00:00\",\"dateModified\":\"2016-05-10T16:14:08+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/quotidiani_Italia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/quotidiani_Italia.jpg\",\"width\":293,\"height\":172},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il ruolo della grande stampa nel declino morale dell&#8217;Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il ruolo della grande stampa nel declino morale dell'Italia - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/","og_locale":"it_IT","og_type":"article","og_title":"Il ruolo della grande stampa nel declino morale dell'Italia - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-10-20T07:09:59+00:00","article_modified_time":"2016-05-10T16:14:08+00:00","og_image":[{"width":293,"height":172,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il ruolo della grande stampa nel declino morale dell&#8217;Italia","datePublished":"2005-10-20T07:09:59+00:00","dateModified":"2016-05-10T16:14:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/"},"wordCount":768,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg","keywords":["stampa nazionale"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/","name":"Il ruolo della grande stampa nel declino morale dell'Italia - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg","datePublished":"2005-10-20T07:09:59+00:00","dateModified":"2016-05-10T16:14:08+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/quotidiani_Italia.jpg","width":293,"height":172},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-ruolo-della-grande-stampa-nel-declino-morale-dellitalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il ruolo della grande stampa nel declino morale dell&#8217;Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1606"}],"version-history":[{"count":6,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1606\/revisions"}],"predecessor-version":[{"id":34027,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1606\/revisions\/34027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34025"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}