{"id":15931,"date":"2015-01-08T00:00:26","date_gmt":"2015-01-07T23:00:26","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=15931"},"modified":"2015-06-18T10:47:05","modified_gmt":"2015-06-18T08:47:05","slug":"gender-il-fondamento-ideologico-dellalleanza-queer-vegan","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/","title":{"rendered":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-15932\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg\" alt=\"manif_queer_vegan\" width=\"118\" height=\"200\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Corrispondenza romana<\/strong> n.1371 del 30 dicembre 2014<\/p>\n<p style=\"text-align: center;\"><strong>di Lupo Glori<\/strong><\/p>\n<p style=\"text-align: justify;\">Cosa hanno in comune la teoria <em>queer<\/em>, ossia il pensiero <em>gender<\/em> portato alle estreme conseguenze, e l\u2019animalismo vegano, fautore di una dura critica allo specismo, inteso come l\u2019ideologia grazie alla quale pu\u00f2 \u00ab<em>mantenersi e prosperare uno sfruttamento della vita animale sempre pi\u00f9 intensivo e specializzato<\/em>\u00bb (p. 9)? L\u2019attivista animalista canadese, Rasmus Rahbek Simonsen, ce lo spiega nel breve saggio <em>Manifesto Queer Vegan<\/em> (Ortica Editore, Aprilia 2014), a cura di Massimo Filippi e Marco Reggio, auspicando una alleanza ideologica tra i due movimenti in nome della comune battaglia contro le norme e i confini etici posti dal sistema sociale dominante.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Il punto di partenza di tale riflessione sono le elucubrazioni filosofiche e la critica alla societ\u00e0 occidentale antropocentrica di Peter Singer e Tom Regan, ispirate, a loro volta, all\u2019utilitarismo del filosofo inglese Jeremy Bentham (1748-1832). Da qui deriva l\u2019ideologica distinzione tra animali umani e non umani finalizzata a mettere sullo stesso piano gli uomini e le bestie, negando, in un\u2019ottica evoluzionista, l\u2019esistenza di un primato dell\u2019uomo sugli animali e di alcuna differenza di specie.<\/p>\n<p style=\"text-align: justify;\">L\u2019uomo privato dell\u2019anima, della ragione e della libert\u00e0 viene ridotto ad un essere \u201csenziente\u201d al pari degli animali. Lo \u201cspecismo\u201d inteso come teoria volta ad affermare la superiorit\u00e0 della \u201cspecie umana\u201d sugli animali, viene, cos\u00ec, considerato dagli animalisti come un pregiudizio equiparabile al \u201crazzismo\u201d o al \u201csessismo\u201d. Ci\u00f2 che attribuisce dignit\u00e0 di persona ad un essere vivente non sono la ragione e la volont\u00e0, ma la sua capacit\u00e0 di \u201cautocoscienza\u201d e di \u201cdesiderio\u201d.<\/p>\n<p style=\"text-align: justify;\">Una delirante visione che porta il filosofo australiano Singer ad affermare: \u00ab<em>uno scimpanz\u00e9, un cane, un maiale, per esempio, avranno un ben pi\u00f9 alto grado di autocoscienza ed una maggiore capacit\u00e0 di relazioni significative con gli altri rispetto ad un bambino gravemente ritardato o a qualcuno in stato di avanzata vecchiaia<\/em>\u00bb (<em>Liberazione animale<\/em>, LAV, Roma 1987, p. 20).<\/p>\n<p style=\"text-align: justify;\">Se il primo \u201cantispecisimo\u201d, al fine di migliorare la condizione animale, si era limitato a ricercare \u00ab<em>tratti propriamente umani (\u2026) negli animali, trasformando alcuni di loro in una specie di umanoidi incompiuti e marginali<\/em>\u00bb (<em>Manifesto Queer Vegan<\/em>, p. 10), successivamente, il cosiddetto \u201cmovimento di liberazione animale\u201d ha, infatti, compiuto un deciso balzo in avanti, sganciando la propria analisi critica da ogni tipo di riferimento umano.<\/p>\n<p style=\"text-align: justify;\">Da una prospettiva identitaria ed antropocentrica, nella quale il metro di valutazione era appunto l\u2019umano, si \u00e8 passati ad una prospettiva della indistinzione che ha annullato la suddivisione tra <em>l\u2019Umano<\/em> e <em>l\u2019Animale<\/em>, ponendoli su di un unico piano indifferenziato. In questo senso, notano i curatori del saggio nella prefazione: \u00ab<em>oggi le<\/em> <em>componenti pi\u00f9 avvedute del movimento di liberazione animale non intendono tanto definire nuove tassonomie \u2013 \u201cpi\u00f9 umane\u201d (\u2026) quanto piuttosto mostrare la bestialit\u00e0 di ogni tassonomia, una volta che si \u00e8 immersi nella deflagrante (im)potenza del divenire animale<\/em>\u00bb (p. 11).<\/p>\n<p style=\"text-align: justify;\">Secondo Simonsen, oggi, la critica allo \u201cspecismo\u201d, che si identifica nel movimento filosofico del \u201cveganismo\u201d, ha perso la sua purezza e radicalit\u00e0 teorica iniziale, trasformandosi, inconsciamente, da pensiero rivoluzionario a nuovo stile di vita, piegato, anche esso, a tendenze e logiche \u201cistituzionalizzate\u201d. Contro tale visione \u201ceretica\u201d dell\u2019antispecismo l\u2019attivista canadese, nel suo \u201cManifesto\u201d, afferma la necessit\u00e0 di \u00ab<em>sovvertire il significato del termine \u201cvegano\u201d per riportarne alla luce il potenziale straniante, deterritorializzante, perturbante \u2013 in una parola, queer<\/em>\u00bb (p. 13).<\/p>\n<p style=\"text-align: justify;\">In tale ottica, Simonsen propone l\u2019alleanza <em>queer-vegan<\/em>, due mondi, all\u2019apparenza distinti, ma che condividono, in realt\u00e0, le stesse radici teoriche e i medesimi fini ideologici. L\u2019attivista animalista mette infatti in luce le analogie che legano i due movimenti, sottolineando come il movimento femminista-queer abbia seguito un percorso simile a quello intrapreso dall\u2019antispecismo: \u00ab<em>dalla rivendicazione di un\u2019identit\u00e0 egualitaria tra i due sessi, all\u2019esaltazione delle molteplici differenze di genere per concludersi nell\u2019indistinzione rizomatica costituita dall\u2019intreccio di sesso, genere e desiderio\u2026(..)<\/em>\u00bb (p. 14).<\/p>\n<p style=\"text-align: justify;\">Nella prefazione al <em>Manifesto<\/em> i curatori Filippi e Reggio precisano i termini dell\u2019alleanza fra <em>queer<\/em> e <em>vegan<\/em> proposta da Simonsen, specificando come essa non sia un semplice matrimonio di interesse quanto piuttosto, \u00ab<em>un rapporto da perseguire fino alla deflagrazione delle architetture su cui l\u2019\u201dUmano\u201d si \u00e8 eretto. Qui \u00e8 in gioco n\u00e9 pi\u00f9 n\u00e9 meno, il compito di destabilizzare l\u2019idea stessa di categoria, a partire dallo scandalo che si realizza ogniqualvolta una persona si rifiuta di cibarsi di animali o di sottostare alle regole di genere dichiarandosi una forma di vita critica e creativa<\/em>\u00bb (pp. 18-19).<\/p>\n<p style=\"text-align: justify;\">L\u2019originalit\u00e0 e la carica rivoluzionaria di tali prese di posizione critiche nei confronti delle norme e delle prassi stabilite risiede nel rifiuto di costituire nuove identit\u00e0 forti quali il <em>vegano<\/em> o il <em>queer <\/em>per dare vita, al contrario, a nuovi soggetti fluidi e complessi, per definizione, in divenire. Il minimo comune denominatore tra il movimento <em>queer<\/em> e quello <em>vegan<\/em> \u00e8 l\u2019orgogliosa rivendicazione della devianza, intesa come comportamento antisociale e antinormativo: \u00ab<em>Diventare vegani significa imparare, sempre e dovunque, a sfidare e a negare le norme dell\u2019antropocentrismo. Il veganismo queer afferma la devianza.(\u2026) La devianza \u00e8 il fulcro manifesto di questo scritto, ci\u00f2 che assicura l\u2019interconnessione tra queer e vegano<\/em>\u00bb (pp. 34-35).<\/p>\n<p style=\"text-align: justify;\">Simonsen chiarisce il concetto di <em>queer<\/em>, inteso come rifiuto del concetto stesso di identit\u00e0, richiamandosi al pensiero di un\u2019altra attivista dei diritti degli animali, Carmen Dell\u2019Aversano, secondo cui: \u00ab<em>il queer non mira a consolidare o a stabilizzare l\u2019identit\u00e0, meno di tutte la propria; il suo scopo principale \u00e8 invece quello di sviluppare una critica dell\u2019identit\u00e0 che non dovrebbe condurre all\u2019egemonia di identit\u00e0 nuove o alternative, ma alla presa di congedo da questa categoria<\/em>\u00bb (p. 37).<\/p>\n<p style=\"text-align: justify;\">L\u2019animalista canadese critica, inoltre, la pretesa di una parte del movimento vegano di apparire \u201cordinari\u201d rivendicando orgogliosamente la propria anormalit\u00e0 e il proprio rigetto delle norme costituite. Da tali tendenze normalizzanti, secondo l\u2019autore del <em>Manifesto queer-vegan<\/em>, non sono immuni neanche le organizzazioni animaliste pi\u00f9 popolari come la <em>PETA<\/em> (<em>People for the Ethical Treatment of Animals<\/em>) accusate di manipolare il messaggio <em>vegan<\/em>, promuovendo un modello normalizzato piegato alle logiche sociali.<\/p>\n<p style=\"text-align: justify;\">In tal senso, secondo Simonsen, diventare \u201cveri vegani\u201d significa divenire <em>queer<\/em> in tutta la sua \u00ab<em>spregevole differenza<\/em>\u00bb (p. 50), facendo propria la lettura del veganismo del teorico <em>queer<\/em> inglese Lee Edelman, inteso come una forma di resistenza metaforica e materiale all\u2019ordine sociale dominante.<\/p>\n<p style=\"text-align: justify;\">L\u2019autore tenta, infatti, di far dialogare il pensiero vegano con la visione <em>No Future<\/em> di Edelaman e di altri teorici <em>queer<\/em> critici nei confronti della prassi e del linguaggio rivoluzionari ancorati ad un utopico avvenire da realizzare. In questo senso Simonsen, accanto alle forze conservatrici, biasima il progetto rivoluzionario teso a costruire un futuro strutturato sul vecchio schema ideologico eteronormativo.<\/p>\n<p style=\"text-align: justify;\">In tale prospettiva, il veganismo <em>queer<\/em> mette in luce \u00ab<em>il fatto che le strutture simboliche e ideologiche che legittimano il consumo di carne rispecchiano quelle dell\u2019eteronormativit\u00e0<\/em>\u00bb (p. 70); eteronormativit\u00e0 che si propone di stabilire le regole sessuali e alimentari, facendo si che l\u2019omofobia si alimenti di vegefobia, \u00ab<em>dal momento che la scelta di mangiare diversamente, soprattutto per i maschi, viene associata all\u2019effeminatezza e alla carenza di virilit\u00e0<\/em>\u00bb (p. 71). Da tali assunti teorici consegue l\u2019alleanza naturale tra veganismo e teoria <em>queer<\/em> in una ottica critica alle \u00ab<em>spinte sociali normalizzanti<\/em>\u00bb (p. 71).<\/p>\n<p style=\"text-align: justify;\">L\u2019alleanza tra pensiero <em>queer<\/em> e antispecismo si fonda, dunque, sulla reciproca condivisione della \u201cdevianza\u201d intesa come negazione della normalit\u00e0. In tale prospettiva, l\u2019onnivorismo e l\u2019eterosessualit\u00e0 vengono considerati concetti normali in quanto \u201cnaturalizzati\u201d dalla societ\u00e0 occidentale attraverso la loro ripetizione incessante nel tempo.<\/p>\n<p style=\"text-align: justify;\">Sia i <em>queer<\/em> che i vegani sono promotori di una cosiddetta \u201cetica negativa\u201d che va ad infrangere schemi di esistenza consolidati. Se l\u2019essere <em>queer<\/em> contrasta il valore assoluto della riproduzione andando contro il progetto sessuale naturale, il veganismo, secondo Simonsen, \u00ab<em>mette in crisi un sistema fondato sulla negazione del valore delle vite non umane<\/em>\u00bb. Teorici <em>queer<\/em> e vegani, accomunati dal loro interesse per la devianza, \u00ab<em>incarnano una volont\u00e0 ostinata di perturbare e intralciare il funzionamento sociale delle norme sessuali, di genere e alimentari<\/em>\u00bb (p. 76).<\/p>\n<p style=\"text-align: justify;\">Una visione che nega esplicitamente il concetto stesso di natura umana affermando come \u00ab<em>la barriera ontologica ed esistenziale eretta tra l\u2019umano e il non umano \u00e8 inaccettabile<\/em>\u00bb (p. 82).<\/p>\n<p style=\"text-align: justify;\">In conclusione del suo manifesto Simonsen scopre le carte rivelando le estreme conseguenze delle sue deliranti teorie: \u00ab<em>A mio modo di vedere, l\u2019etica vegana dovrebbe immaginare e istituire comunit\u00e0 fondate sulla condivisione di spazi materiali ed affettivi all\u2019interno delle specie e tra di loro<\/em>\u00bb (p. 85); parole che lasciano spazio alle pi\u00f9 perverse interpretazioni. Una volta messa da parte ogni criterio valutativo per potere giudicare la realt\u00e0 in maniera logica e coerente, anche il comportamento pi\u00f9 aberrante diviene possibile ed accettabile.<\/p>\n<p style=\"text-align: justify;\">La verit\u00e0 non \u00e8 pi\u00f9 un dato oggettivo, conosciuto attraverso l\u2019adesione dell\u2019intelletto al reale, quanto un dato soggettivo, conosciuto attraverso un processo di costruzione progressiva in continuo divenire. In questo caos schizofrenico, fondato su una \u201crivoluzione permanente\u201d, la societ\u00e0 \u00e8 inevitabilmente destinata ad implodere ed autodissolversi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza romana n.1371 del 30 dicembre 2014 di Lupo Glori Cosa hanno in comune la teoria queer, ossia il pensiero gender portato alle estreme conseguenze, e l\u2019animalismo vegano, fautore di una dura critica allo specismo, inteso come l\u2019ideologia grazie alla quale pu\u00f2 \u00abmantenersi e prosperare uno sfruttamento della vita animale sempre pi\u00f9 intensivo e specializzato\u00bb &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":15932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[1292,1293],"class_list":["post-15931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideologia-del-gender","tag-queer","tag-vegan","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-07T23:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-18T08:47:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"164\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d\",\"datePublished\":\"2015-01-07T23:00:26+00:00\",\"dateModified\":\"2015-06-18T08:47:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/\"},\"wordCount\":1484,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/manif_queer_vegan.jpg\",\"keywords\":[\"queer\",\"vegan\"],\"articleSection\":[\"Ideologia del gender\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/\",\"name\":\"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/manif_queer_vegan.jpg\",\"datePublished\":\"2015-01-07T23:00:26+00:00\",\"dateModified\":\"2015-06-18T08:47:05+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/manif_queer_vegan.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/manif_queer_vegan.jpg\",\"width\":164,\"height\":278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/","og_locale":"it_IT","og_type":"article","og_title":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-01-07T23:00:26+00:00","article_modified_time":"2015-06-18T08:47:05+00:00","og_image":[{"width":164,"height":278,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d","datePublished":"2015-01-07T23:00:26+00:00","dateModified":"2015-06-18T08:47:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/"},"wordCount":1484,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg","keywords":["queer","vegan"],"articleSection":["Ideologia del gender"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/","name":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg","datePublished":"2015-01-07T23:00:26+00:00","dateModified":"2015-06-18T08:47:05+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/12\/manif_queer_vegan.jpg","width":164,"height":278},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gender-il-fondamento-ideologico-dellalleanza-queer-vegan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Gender. Il fondamento ideologico dell\u2019alleanza \u201cQueer \u2013 Vegan\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/15931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=15931"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/15931\/revisions"}],"predecessor-version":[{"id":15933,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/15931\/revisions\/15933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/15932"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=15931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=15931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=15931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}