{"id":1591,"date":"2005-10-18T17:32:30","date_gmt":"2005-10-18T15:32:30","guid":{"rendered":""},"modified":"2016-03-10T13:02:19","modified_gmt":"2016-03-10T12:02:19","slug":"diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/","title":{"rendered":"Diritto naturale e diritto positivo nell&#8217;enciclica &quot;Veritatis splendor"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-31546\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg\" alt=\"Veritatis_cover\" width=\"124\" height=\"200\" \/>pubblicato in <strong>Cristianit\u00e0<\/strong> n.230-231 (1994)<\/div>\n<p style=\"text-align: center;\">di <strong>Mauro Ronco<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1. La &#8220;giusta misura&#8221; platonica<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel dialogo <em>Il Politico<\/em> Platone si ripromette di cogliere la trama e l\u2019ordito che la vera scienza politica viene tessendo, nella ricerca dinamica del bene comune, sul fondamento del riconoscimento in comune del Bene (1).<\/p>\n<p style=\"text-align: justify;\">Socrate e i suoi interlocutori mostrano di conoscere con precisione le caratteristiche delle varie forme costituzionali in cui si manifesta l\u2019esercizio del potere politico, dal comando di uno solo al dominio dei pochi, al potere della moltitudine, ciascuna forma con le sue possibili varianti, a seconda che sia diffuso l\u2019uso della costrizione ovvero il potere si eserciti prevalentemente previo il consenso dei sudditi, a seconda che l\u2019ordinamento si basi su leggi scritte ovvero si regga sulle consuetudini antiche.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Tutti i partecipanti al dialogo concordano sul principio che non possono e non debbono servire alla individuazione del valore delle costituzioni le circostanze contingenti che il potere sia esercitato dai pochi o dai molti, che prevalga la libera accettazione, ovvero sia pi\u00f9 rilevante il peso della costrizione, che vi sia nello Stato una condizione generalizzata di ricchezza ovvero la povert\u00e0 caratterizzi la vita del maggior numero.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che decide essenzialmente della qualit\u00e0, buona o cattiva, \u00e8 il possesso in chi governa \u2014 chiunque esso sia: uno solo, pochi, ovvero molte persone \u2014 di una scienza e di un\u2019arte, analoghe alla scienza e all\u2019arte medica, intese alla conoscenza teoretica e alla concreta applicazione del giusto potere, cio\u00e8 del potere politico esercitato secondo giustizia.<\/p>\n<p style=\"text-align: justify;\">Alla domanda: <em>&#8220;<\/em>[&#8230;]<em> dobbiamo forse pensare che una di queste costituzioni sia retta, se definita con questi termini: <\/em>uno<em>, <\/em>pochi<em>, <\/em>molti<em> (con <\/em>ricchezza<em> e <\/em>povert\u00e0<em>, <\/em>coazione<em> e <\/em>spontaneit\u00e0<em>); e se le avvenga d\u2019essere con leggi scritte o senza leggi?&#8221;<\/em>, il Forestiero di Elea \u2014 il principale interlocutore del dialogo platonico \u2014 risponde: <em>&#8220;Ed \u00e8 appunto questo che dobbiamo comprendere, ch\u00e9 il carattere distintivo di tali costituzioni non pu\u00f2 essere n\u00e9 i <\/em>pochi<em> n\u00e9 i <\/em>molti<em> n\u00e9 la <\/em>spontaneit\u00e0<em> n\u00e9 il <\/em>coatto<em>, n\u00e9 la <\/em>povert\u00e0<em> n\u00e9 la <\/em>ricchezza<em>, ma deve consistere in una <\/em>scienza<em>&#8220;<\/em> (2).<\/p>\n<p style=\"text-align: justify;\">Relativizzando pi\u00f9 oltre, nel corso del dialogo, la portata della distinzione fra le varie forme di governo, Platone sottolinea che monarchia, potere di pochi e potere di molti possono essere, o meno, orientati al bene e al giusto.<\/p>\n<p style=\"text-align: justify;\">Il Forestiero rileva anzitutto che anche la democrazia, cos\u00ec come la monarchia e il governo dei pochi, pu\u00f2 degenerare: <em>&#8220;Dalla forma monarchica risulta il governo regio e la tirannide; dal governo dei non molti abbiamo detto che risulta l\u2019aristocrazia, augurale nel suo nome, e l\u2019oligarchia. Quanto poi al governo dei molti, poich\u00e9 allora lo ritenevamo semplice, gli davamo il nome di democrazia, ma anche questo ora va considerato come doppio&#8221;<\/em> (3). Invero, non v\u2019\u00e8 ragione alcuna per cui anche la democrazia non vada sottoposta al comune criterio di giudizio: <em>&#8220;<\/em>[&#8230;]<em> ch\u00e9 il governare secondo le leggi e contro le leggi \u00e8 comune a questa come alle altre costituzioni&#8221;<\/em> (4).<\/p>\n<p style=\"text-align: justify;\">Quanto, poi, al rapporto fra le varie forme di costituzione, il Forestiero osserva: <em>&#8220;La monarchia, dunque, accoppiata a buone prescrizioni scritte che diciamo leggi, \u00e8 la migliore delle sei costituzioni; senza leggi per\u00f2 \u00e8 la forma pi\u00f9 penosa e quella in cui si vive peggio&#8221;<\/em>; <em>&#8220;Quanto poi al governo dei non molti<\/em> \u2014 prosegue \u2014<em>, come il poco \u00e8 medio fra l\u2019uno e la massa, cos\u00ec riterremo tale governo quale medio fra l\u2019una e l\u2019altra costituzione; ed infine riterremo il governo di massa debole in tutto ed incapace di far nulla di grande, in bene o in male che sia, nei confronti degli altri, ch\u00e9 in esso le regole del comando sono distribuite fra troppa gente e frammentariamente. Ecco perch\u00e9 tale governo, fra i varii tipi di costituzioni che si reggono su leggi, \u00e8 il peggiore, mentre \u00e8 il migliore fra tutti quelli che si reggon senza leggi&#8221;<\/em> (5).<\/p>\n<p style=\"text-align: justify;\">Gli studiosi contemporanei di diritto costituzionale \u2014 e gli uomini politici che ai primi si ispirano \u2014 ritengono di rintracciare in complessi sistemi di ingegneria costituzionale la soluzione di molti problemi attinenti alla vita politica; \u00e8 singolare, per\u00f2, che essi non prestino alcuna attenzione alla costellazione dei fini del vivere associato. Eppure, il fallimento dei vari progetti di ingegneria costituzionale dovrebbe indurre a comprendere che la democrazia \u2014 come forma di governo \u2014, cos\u00ec come ogni altro tipo di regime, non pu\u00f2 essere assunta come principio aggregante la comunit\u00e0. Invero, quando si assume la forma di governo a origine e fine della comunit\u00e0, si determina il vuoto politico, ossia si costituisce un governo imbelle \u2014 forte con i poveri e debole con i potenti \u2014 e si contribuisce alla disgregazione della societ\u00e0 (6).<\/p>\n<p style=\"text-align: justify;\">Secondo Platone, coloro che \u2014 tiranni o democratici \u2014 pretendono di comandare senza piegarsi ad apprendere e a praticare la scienza e l\u2019arte del bene non sono dei veri uomini politici, ma dei faziosi; <em>&#8220;<\/em>[&#8230;] <em>e poich\u00e9 si fan guida di grandissime, false immagini, tali sono essi medesimi, e poich\u00e9 sono ad un tempo insigni mimi e ciarlatani, divengono fra i sofisti i sofisti pi\u00f9 grandi&#8221;<\/em> (7).<\/p>\n<p style=\"text-align: justify;\">Il problema della vera scienza politica consiste, dunque, nel fare in modo che gli uomini politici non siano <em>&#8220;mimi e ciarlatani&#8221;<\/em>, &#8220;veri sofisti&#8221;: e ci\u00f2 avviene soltanto se essi formano il proprio giudizio e indirizzano le loro azioni sul fondamento della <em>&#8220;giusta misura&#8221;<\/em> (8) e in vista della realizzazione di ci\u00f2 che \u00e8 giusto. Non diversa \u00e8 la tesi della dottrina politica della Chiesa.<\/p>\n<p style=\"text-align: justify;\">Riaffermando fermamente che la potest\u00e0 di comandare proviene da Dio, Papa Leone XIII, nell\u2019enciclica <em>Diuturnum<\/em>, del 20 giugno 1881, proclamava la legittimit\u00e0 di ciascuna delle varie forme di governo, purch\u00e9 l\u2019ordinamento sia giusto e rivolto al comune vantaggio: <em>&#8220;Importa per\u00f2 notare qui che coloro i quali siano per esser preposti alla pubblica cosa, possano in talune circostanze venir eletti per volont\u00e0 e deliberazione della moltitudine, senza che a ci\u00f2 sia contraria o ripugni la dottrina cattolica. Colla quale scelta tuttavia si designa il Principe, ma non si conferiscono i diritti del principato: non si d\u00e0 l\u2019imperio, ma si stabilisce da chi deve essere amministrato. \u2014 N\u00e9 qui si fa questione dei modi del pubblico reggimento: poich\u00e9 non vi \u00e8 alcuna ragione, perch\u00e9 la Chiesa non approvi il principato d\u2019uno o di molti, purch\u00e9 esso sia giusto e rivolto al comune vantaggio. Perci\u00f2, salva la giustizia, non s\u2019impedisce ai popoli di procacciarsi quel genere di reggimento, che meglio convenga alla loro indole, o alle istituzioni ed ai costumi dei loro maggiori&#8221;<\/em> (9).<\/p>\n<p style=\"text-align: justify;\">Affinch\u00e9, per\u00f2, la legge sia giusta occorre l\u2019individuazione della giusta misura: cio\u00e8 di un parametro oggettivo alla cui stregua il tessitore \u2014 cui Platone assimila, con perspicua metafora, l\u2019uomo politico (10) \u2014 sappia gerarchizzare e armonizzare tutte le &#8220;misure&#8221; particolari, definite dall\u2019affermarsi e consolidarsi nella vita sociale dei valori e degli interessi delle persone e dei gruppi che compongono la societ\u00e0.<\/p>\n<p style=\"text-align: justify;\">Diametralmente contrario a qualsivoglia teoria etica che, con terminologia moderna, potremmo definire &#8220;teleologica&#8221;, sia essa di tipo &#8220;consequenzialistico&#8221; o di tipo &#8220;proporzionalistico&#8221;, secondo cui il criterio del bene si ricaverebbe dal bilanciamento delle conseguenze degli atti ovvero dall\u2019assetto dei valori e degli interessi \u2014 in termini di soddisfazione del maggior numero \u2014 dopo il compimento dell\u2019azione (11), Platone suggerisce come necessario per rintracciare il giusto diritto il metodo della comparazione di ciascun bene, prima e pi\u00f9 ancora che con ogni altro bene particolare, con il criterio del giusto.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;E dunque bisogna porre che due siano questi modi di essere e queste distinzioni del grande e del piccolo, e non dobbiamo <\/em>[&#8230;]<em> considerarli soltanto nel loro rapporto reciproco, ma, come si \u00e8 detto appena sopra, dobbiamo piuttosto, da un lato distinguere il loro reciproco rapporto, dall\u2019altro lato anche quello in cui si trovano con il giusto mezzo&#8221;<\/em> (12).<\/p>\n<p style=\"text-align: justify;\">Il metodo adottato dalla giurisprudenza costituzionalistica contemporanea in tema di aborto, cos\u00ec come in moltissimi altri settori dell\u2019esperienza giuridica, corrisponde a quello criticato da Platone, poich\u00e9 si esaurisce nel porre a confronto fra loro i due valori \u2014 il grande e il piccolo \u2014, senza procedere all\u2019indispensabile comparazione di ciascun valore con la giusta misura, ovvero con il criterio del diritto. Cos\u00ec la vita del feto, pur esso &#8220;valore&#8221;, secondo il Giudice supremo italiano che pronunci\u00f2 la sentenza del 1975, come vita di chi ancora non sarebbe compiutamente vita \u2014 <em>&#8220;il piccolo&#8221;<\/em> \u2014, dovrebbe soccombere di fronte alla salute della madre, come interesse di chi gi\u00e0 possiede la capacit\u00e0 di azionare giudizialmente la sua pretesa \u2014 <em>&#8220;il grande&#8221;<\/em> \u2014 (13): vita del feto e salute della donna \u2014 il <em>&#8220;piccolo&#8221;<\/em> e il <em>&#8220;grande&#8221;<\/em> \u2014 sono posti a confronto fra loro con esclusivo riguardo al bilanciamento dei costi sociali ricollegabili al sacrificio dell\u2019uno e dell\u2019altro, senza alcuna attenzione al rapporto reciproco di ciascuno di essi con il criterio morale che definisce in radice lecita o illecita la condotta che volontariamente attenta a ciascun bene.<\/p>\n<p style=\"text-align: justify;\">Secondo Platone, se si ammettesse che il pi\u00f9 grande a nient\u2019altro stia in relazione se non al pi\u00f9 piccolo, e si misconoscesse la necessit\u00e0 del confronto con la giusta misura, allora sarebbe annientata la possibilit\u00e0 stessa del diritto e della politica, cos\u00ec come di qualsivoglia altra arte (14).<\/p>\n<p style=\"text-align: justify;\">Come il giudizio relativo alla perfezione del prodotto di ciascuna arte concerne il superamento o la carenza della giusta misura, s\u00ec che pu\u00f2 dirsi che l\u2019opera d\u2019arte in tanto esiste in quanto \u00e8 presupposta la giusta misura, cos\u00ec ugualmente il diritto e la politica esistono sul presupposto che il legislatore e l\u2019uomo politico ispirino la legislazione e la propria condotta al criterio del giusto e del bene comune.<\/p>\n<p style=\"text-align: justify;\">Senza attenzione, in capo a chi dirige e orienta la cosa pubblica, a tale criterio, diritto e politica sono annientati: vi potranno essere strategia, amministrazione, giurisprudenza e retorica, ovvero metodologia raffinata dell\u2019esercizio della forza e dell\u2019astuzia, gestione impegnata della dimensione economica della vita associata, legislazione abbondante e incessante applicazione coattiva delle leggi e dei regolamenti, manipolazione instancabile delle coscienze attraverso l\u2019uso dei mezzi di comunicazione di massa, ma non sussisteranno diritto e politica, come dimensioni della vita associata caratterizzate dalla forza dinamica di rintracciare, definire, garantire e promuovere il bene di tutti in comune.<\/p>\n<p style=\"text-align: justify;\">Vi sono due modalit\u00e0 diverse di misurare: l\u2019una costituita dalle <em>&#8220;arti che misurano il numero, la lunghezza, l\u2019altezza, la larghezza, la velocit\u00e0 in rapporto ai loro contrarii&#8221;<\/em> e l\u2019altra formata dalle <em>&#8220;arti che si riferiscono alla giusta misura, al conveniente, all\u2019opportuno, al doveroso, in una parola a tutto ci\u00f2 che ha per sua sede naturale il mezzo fra gli estremi&#8221;<\/em> (15): la riduzione delle arti di questo secondo tipo a quelle del primo tipo e la conseguente scomparsa del criterio del diritto, con la perdita dell\u2019idea di ci\u00f2 che \u00e8 dovuto, \u00e8 all\u2019origine e alla base della dis-societ\u00e0, in cui viviamo, stracolma di leggi, di regolamenti, di decreti e di circolari interpretative, ma del tutto priva dell\u2019idea e della realt\u00e0 del diritto, come criterio del dovuto, e, in conseguenza di ci\u00f2, del giusto.<\/p>\n<p style=\"text-align: justify;\">Molti contemporanei si stupiscono che la dilatazione della dimensione regolamentativa (16), attraverso la riscrittura di ogni rapporto sociale in termini di dover essere giuridico, non rechi con s\u00e9 l\u2019ordine dei rapporti intersoggettivi e la pace delle parti tra loro, delle parti con il tutto e di quest\u2019ultimo con esse, bens\u00ec accresca obiettivamente il conflitto sociale e diffonda l\u2019atteggiamento litigioso come il modo consueto di rapportarsi del singolo agli altri soggetti dell\u2019ordinamento.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0, quanto pi\u00f9 il reale \u00e8 visto privo di qualit\u00e0 e sempre pi\u00f9 \u00e8 assimilato a massa da misurarsi con le unit\u00e0 di calcolo delle scienze quantitative, tanto pi\u00f9 esso \u00e8 incapace di comunicare messaggi di intrinseca normativit\u00e0 e sempre pi\u00f9 viene assoggettato alla legge dettata dalla decisione, arbitraria e variabile, dell\u2019uomo che detiene l\u2019uso della forza.<\/p>\n<p style=\"text-align: justify;\">Poich\u00e9 lo statuto del diritto \u00e8 la giusta misura \u2014 cio\u00e8 la legge morale e, a fondamento di questa, la legge eterna di Dio impressa nella realt\u00e0 creata e partecipata alla ragione dell\u2019uomo \u2014, l\u2019ordinamento che rimuove il riferimento alla giusta misura annienta se stesso come ordinamento giuridico, erigendo al suo posto, in una vana opera di sostituzione, l\u2019indefinita variet\u00e0 delle decisioni particolari, che illegittimamente pretendono la qualifica della giuridicit\u00e0, sul fondamento della loro coercitivit\u00e0. Ma tutto ci\u00f2 non vale a creare diritto, bens\u00ec soltanto ad approfondire la dissociazione delle parti tra loro e ad accrescere nel corpo sociale il sentimento della costrizione e dell\u2019oppressione.<\/p>\n<p style=\"text-align: justify;\"><strong>2. Il diritto naturale<\/strong><\/p>\n<p style=\"text-align: justify;\">Nell\u2019enciclica <em>Veritatis splendor<\/em>, Papa Giovanni Paolo II esprime esemplarmente l\u2019insegnamento tradizionale della Chiesa in ordine all\u2019integrazione armonica fra le inclinazioni naturali, come sono manifestate all\u2019uomo dalla dimensione corporea, e l\u2019ordine razionale, colto dalla ragione assistita dalla grazia di Dio (17).<\/p>\n<p style=\"text-align: justify;\">Richiamandosi espressamente all\u2019<em>Istruzione &#8220;Donum vitae&#8221; su il rispetto della vita umana nascente e la dignit\u00e0 della procreazione<\/em>, della Congregazione per la Dottrina della Fede, emessa in data 22 febbraio 1987 (18), il Sommo Pontefice sottolinea come le inclinazioni naturali anticipino e suggeriscano i princ\u00ecpi normativi che la ragione compiutamente definisce alla luce del destino eterno cui ciascun uomo \u00e8 chiamato dall\u2019Amore di Dio.<\/p>\n<p style=\"text-align: justify;\">Nella realt\u00e0 corporea \u00e8 inscritta la legge naturale: <em>&#8220;<\/em>[&#8230;] <em>essa si riferisce alla natura propria e originale dell\u2019uomo, alla &#8220;natura della persona umana&#8221;, che \u00e8 <\/em>la persona stessa nell\u2019unit\u00e0 di anima e di corpo<em>, nell\u2019unit\u00e0 delle sue inclinazioni di ordine sia spirituale che biologico e di tutte le altre caratteristiche specifiche necessarie al perseguimento del suo fine&#8221;<\/em> (19). Come sottolinea l\u2019istruzione <em>Donum vitae<\/em>, la legge morale <em>&#8220;<\/em>[&#8230;]<em> non pu\u00f2 essere concepita come normativit\u00e0 semplicemente biologica, ma deve essere definita come l\u2019ordine razionale secondo il quale l\u2019uomo \u00e8 chiamato dal Creatore a dirigere e a regolare la sua vita e i suoi atti e, in particolare, a usare e disporre del proprio corpo&#8221;<\/em> (20).<\/p>\n<p style=\"text-align: justify;\">Non vi sono <em>&#8220;valori spirituali&#8221;<\/em>, <em>&#8220;valori sentimentali&#8221;<\/em>, <em>&#8220;valori attinenti alla sfera della corporeit\u00e0&#8221;<\/em>, separati gli uni dagli altri, misurabili secondo i calcoli delle scienze quantitative, che il legislatore avrebbe il compito di massimizzare secondo la legge della maggior quantit\u00e0 per il maggior numero.<\/p>\n<p style=\"text-align: justify;\">Operando in un modo siffatto si prescinderebbe del tutto dal tener conto della giusta misura, costituita dalla legge naturale, come legge che si riferisce alla <em>&#8220;natura della persona umana&#8221;<\/em>, limitandosi alla comparazione tra grandezze meramente quantitative, con l\u2019inevitabile annientamento del diritto. Nessun bene \u2014 neppure la vita umana \u2014 possiede un valore assoluto, un valore, cio\u00e8, che prescinda dal significato morale in riferimento al bene della persona nella sua integralit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Insegna Papa Giovanni Paolo II nell\u2019enciclica <em>Veritatis splendor<\/em> che il fondamento del dovere di rispettare la vita umana sta nella dignit\u00e0 della persona e non semplicemente nell\u2019inclinazione naturale a conservare la vita fisica: <em>&#8220;Cos\u00ec la vita umana, pur essendo un bene fondamentale dell\u2019uomo, acquista un significato morale in riferimento al bene della persona che deve essere sempre affermata per se stessa: mentre \u00e8 sempre moralmente illecito uccidere un essere umano innocente, pu\u00f2 essere lecito, lodevole o persino doveroso dare la propria vita (cf. <\/em>Gv<em> 15, 13) per amore del prossimo o per testimonianza verso la verit\u00e0&#8221;<\/em> (21).<\/p>\n<p style=\"text-align: justify;\">Il diritto \u00e8 suggerito dall\u2019esame attento e rispettoso della realt\u00e0 fisica, biologica, psicologica, poich\u00e9 nel reale \u00e8 rimasta impressa l\u2019impronta di Dio creatore. Il suo criterio \u00e8 la legge eterna di Dio. Nell\u2019enciclica <em>Veritatis splendor<\/em> il Sommo Pontefice ribadisce in modo perentorio la dottrina tradizionale della Chiesa a riguardo dell\u2019essenziale subordinazione della ragione e della legge umana alla Sapienza di Dio e alla sua legge (22).<\/p>\n<p style=\"text-align: justify;\">Il primo riferimento dell\u2019enciclica \u00e8 alla <em>Dichiarazione sulla libert\u00e0 religiosa &#8220;Dignitatis Humanae&#8221;<\/em>, 3, ove \u00e8 ricordato che <em>&#8220;<\/em>[&#8230;] <em>norma suprema della vita umana \u00e8 la stessa legge divina, eterna, oggettiva e universale, per mezzo della quale Dio con un disegno di sapienza e amore ordina, dirige e governa il mondo intero e le vie della comunit\u00e0 umana. E Dio rende partecipe l\u2019uomo di questa sua legge, cosicch\u00e9 l\u2019uomo, per soave disposizione della provvidenza divina, possa conoscere sempre pi\u00f9 l\u2019immutabile verit\u00e0&#8221;<\/em> (23).<\/p>\n<p style=\"text-align: justify;\">Il Concilio rinvia alla dottrina classica sulla legge eterna di Dio. Sant\u2019Agostino la definisce come <em>&#8220;la ragione o la volont\u00e0 di Dio che comanda di conservare l\u2019ordine naturale e proibisce di turbarlo&#8221;<\/em> (24), san Tommaso la identifica con <em>&#8220;la ragione della divina sapienza che muove tutto al fine dovuto&#8221;<\/em> (25).<\/p>\n<p style=\"text-align: justify;\">E la Sapienza di Dio si prende cura degli uomini in modo diverso rispetto agli esseri che non sono persone: non semplicemente operando <em>&#8220;&#8221;dall\u2019esterno&#8221;<\/em>, <em>attraverso le leggi della natura fisica, ma &#8220;dal di dentro&#8221;<\/em>, <em>mediante la ragione che, conoscendo col lume naturale la legge eterna di Dio, \u00e8 perci\u00f2 stesso in grado di indicare all\u2019uomo la giusta direzione del suo libero agire&#8221;<\/em> (26).<\/p>\n<p style=\"text-align: justify;\">S\u00ec che l\u2019uomo \u00e8 chiamato da Dio <em>&#8220;a partecipare alla sua provvidenza&#8221;<\/em>, poich\u00e9 egli, partecipando con la sua ragione alla legge eterna di Dio, \u00e8 capace di guidare il mondo, tanto delle creature inanimate, quanto delle persone umane, attraverso la sua ragionevole e responsabile cura.<\/p>\n<p style=\"text-align: justify;\">Questo \u00e8 l\u2019orizzonte eterno della legge naturale, espressione umana della legge eterna di Dio. Secondo san Tommaso, la creatura razionale \u00e8 soggetta in modo pi\u00f9 eccellente alla divina provvidenza rispetto alle altre creature, <em>&#8220;<\/em>[&#8230;] <em>in quanto anche essa diventa partecipe della provvidenza, provvedendo a se stessa e agli altri: perci\u00f2 si ha in essa una partecipazione della ragione eterna, grazie alla quale ha una naturale inclinazione all\u2019atto ed al fine dovuti: tale partecipazione della legge eterna nella creatura razionale \u00e8 chiamata legge naturale&#8221;<\/em> (27).<\/p>\n<p style=\"text-align: justify;\"><strong>3. La nozione di diritto naturale<\/strong><\/p>\n<p style=\"text-align: justify;\">Papa Giovanni Paolo II afferma solennemente nell\u2019enciclica <em>Veritatis splendor<\/em> che la Chiesa ha assunto nel proprio insegnamento morale la dottrina tomistica di legge naturale (28). Il Pontefice Regnante richiama espressamente i princ\u00ecpi essenziali della dottrina politica e giuridica della Chiesa, siccome nitidamente espressi da Papa Leone XIII nell\u2019enciclica <em>Libertas praestantissimum<\/em>, secondo cui tanto la ragione individuale quanto la legge della comunit\u00e0 politica sono essenzialmente subordinate alla Sapienza di Dio e alla sua legge (29).<\/p>\n<p style=\"text-align: justify;\">Il fondamento della normativit\u00e0 della ragione umana sta nella sua partecipazione alla legge eterna di Dio. Per Papa Leone XIII, infatti, <em>&#8220;<\/em>[&#8230;]<em> questo medesimo comando e divieto dell\u2019umana ragione non ha forza di legge, se non perch\u00e9 voce ed interprete di una ragione pi\u00f9 alta, da cui la ragione e libert\u00e0 nostra assolutamente dipendono&#8221;<\/em> (30).<\/p>\n<p style=\"text-align: justify;\">La forza della legge \u2014 secondo la dottrina della Chiesa \u2014 risiede nella sua autorit\u00e0 di imporre dei doveri, di conferire dei diritti e di dare la sanzione a certi comportamenti (31). <em>&#8220;Ora<\/em> \u2014 ricorda Papa Giovanni Paolo II citando Papa Leone XIII \u2014 <em>tutto ci\u00f2 non potrebbe esistere nell\u2019uomo, se fosse egli stesso a darsi, quale legislatore supremo, la norma delle sue azioni&#8221;<\/em> (32).<\/p>\n<p style=\"text-align: justify;\">Ne consegue che <em>&#8220;<\/em>[&#8230;] <em>la legge naturale \u00e8 la stessa legge eterna, ossia la stessa eterna ragione di Dio creatore e reggitore del mondo, inserita nelle ragionevoli creature, e motrice di queste agli atti debiti ed al fine&#8221;<\/em> (33). La forza della legge \u2014 il carattere della normativit\u00e0 \u2014 risiede nell\u2019autorit\u00e0 di imporre doveri, conferire diritti e garantire la sanzione degli uni e degli altri. Il fondamento della normativit\u00e0 sta nella partecipazione della legge dell\u2019uomo alla legge di Dio, cos\u00ec come il fondamento dell\u2019autorit\u00e0 dell\u2019uomo sta nel partecipare all\u2019autorit\u00e0 di Dio, secondo il principio per cui ogni autorit\u00e0 sulla terra proviene da Dio.<\/p>\n<p style=\"text-align: justify;\">Papa Leone XIII ribadisce nell\u2019enciclica <em>Diuturnum<\/em>, fondando il suo insegnamento sull\u2019autorit\u00e0 delle Scritture, la tesi tradizionale della Chiesa secondo cui <em>&#8220;<\/em>[&#8230;] <em>il diritto di comandare deriva da Dio, come dal suo naturale e necessario principio&#8221;<\/em> (34). A Pilato, che ostentava il proprio potere giudiziario, Ges\u00f9 Nostro Signore rispose: <em>&#8220;Non avresti potest\u00e0 alcuna contro di me, se ci\u00f2 non ti fosse dato dall\u2019alto&#8221; <\/em>(35). Come l\u2019uomo non potrebbe comandare e imporre alcunch\u00e9 all\u2019altro uomo se il suo potere non partecipasse al potere di Dio, cos\u00ec la forza della legge \u2014 la sua normativit\u00e0 \u2014 risiede nella partecipazione alla legge eterna di Dio.<\/p>\n<p style=\"text-align: justify;\">Teoria politica e teoria giuridica sono \u2014 nella dottrina della Chiesa \u2014 indissolubilmente congiunte nel riconoscimento del primato di Dio sull\u2019uomo e della eminente libert\u00e0 della persona umana: \u00e8 conforme alla natura razionale e libera dell\u2019uomo che egli sia obbligato in coscienza a prestare rispetto e obbedienza alla legge soltanto se e nella misura in cui essa partecipi della razionalit\u00e0 che la rende congrua rispetto alla legge eterna di Dio.<\/p>\n<p style=\"text-align: justify;\">Gli ordinamenti moderni non sono, propriamente parlando, ordinamenti giuridici \u2014 o lo sono soltanto in modo residuale e materiale, per quanto riguarda il contenuto di una parte delle norme che li compongono, nella misura in cui esse sono destinate comunque a regolare secondo le esigenze della giustizia la convivenza civile degli uomini \u2014; non sono ordinamenti giuridici <em>formaliter<\/em> perch\u00e9 privi della nota della normativit\u00e0, in quanto non sono incardinati nella legge naturale, che \u00e8 la stessa legge eterna di Dio, insita negli esseri dotati di ragione.<\/p>\n<p style=\"text-align: justify;\">V\u2019\u00e8, invero, stretta analogia tra il significato della libert\u00e0 rispettivamente per ciascun uomo e per la comunit\u00e0 sociale e politica. Insegna Papa Leone XIII: <em>&#8220;Poich\u00e9 ci\u00f2 che in ciascun uomo opera la ragione e la legge naturale, \u00e8 similmente operato nella societ\u00e0 dalla legge umana promulgata a comun bene dei cittadini. Delle umane leggi alcune cadono su cose intrinsecamente buone o cattive, comandando quelle e vietando queste, aggiuntavi la debita sanzione. Ed \u00e8 chiaro che tali comandi o divieti non hanno origine dall\u2019umana societ\u00e0: la quale come non crea la natura umana, cos\u00ec non crea il bene che conviene, n\u00e9 il male che ripugna alla natura medesima: precedono invece la stessa societ\u00e0, e son dettami della legge naturale, e perci\u00f2 della legge eterna&#8221;<\/em> (36).<\/p>\n<p style=\"text-align: justify;\">Estremamente significativo appare il fenomeno \u2014 cui assistiamo con crescente intensit\u00e0 nel momento attuale \u2014, di smarrimento, da parte degli ordinamenti contemporanei, della stessa normativit\u00e0 materiale, come indifferenza dello Stato rispetto alla regola del giusto o addirittura come positivo contrasto delle leggi con il criterio della giustizia.<\/p>\n<p style=\"text-align: justify;\">L\u2019attenzione \u00e8 attirata, tra tutti, dai casi della &#8220;legalizzazione&#8221; dell\u2019aborto, alla cui stregua lo Stato ha tolto la protezione dovuta alla vita innocente nel grembo materno, e della &#8220;legalizzazione&#8221; delle convivenze omosessuali, su cui si \u00e8 pronunciato il Parlamento Europeo l\u20198 febbraio 1994 (37), che costituirebbe la conclusione coerente di un lungo processo di aggressione contro la famiglia sul piano giuridico.<\/p>\n<p style=\"text-align: justify;\">Per quanto preoccupanti siano i singoli casi \u2014 e tra tutti i pi\u00f9 gravi sono la negazione del diritto alla vita e la negazione dell\u2019istituto familiare come unione d\u2019amore indissolubile di due persone di sesso diverso per la generazione e l\u2019educazione dei figli \u2014 va ricordato che ancora pi\u00f9 lacerante \u00e8 la ferita inferta dagli Stati moderni al corpo sociale attraverso la negazione del fondamento del principio della normativit\u00e0 nell\u2019autorit\u00e0 della legge eterna di Dio.<\/p>\n<p style=\"text-align: justify;\">Questo solco \u00e8 stato scavato progressivamente, nazione per nazione, con una serie di atti, di valore disuguale, ma ciascuno diretto contro il legame necessario tra la legge dello Stato e la legge morale.<\/p>\n<p style=\"text-align: justify;\">La stagione culturalmente pi\u00f9 significativa, politicamente pi\u00f9 violenta e giuridicamente pi\u00f9 incisiva in tale processo e, dunque, determinante per tutta la storia dell\u2019Occidente europeo e, poi, del mondo intero, \u00e8 quella dell\u2019affermarsi e del dispiegarsi della rivoluzione detta francese, tanto nella fase &#8220;interna&#8221;, quanto nella fase di espansione al di l\u00e0 dei confini della terra di Francia, soprattutto attraverso l\u2019opera militare e di legislatore di Napoleone Bonaparte: fu quella la stagione in cui venne proclamato legislativamente e attuato praticamente il principio, diametralmente opposto a quello della dottrina della Chiesa, secondo cui sarebbe l\u2019uomo, o l\u2019assemblea degli uomini, competente a darsi, quale legislatore supremo, la norma delle sue azioni (38).<\/p>\n<p style=\"text-align: justify;\">Al termine di questa fase storica, contrassegnata dall\u2019annientamento del principio della normativit\u00e0, che in Italia si sviluppa attraverso il dispiegamento e la vittoria storica del cosiddetto &#8220;risorgimento&#8221;, che, sotto pretesto della realizzazione dell\u2019unit\u00e0 d\u2019Italia, svincola la legge dell\u2019uomo dalla legge di Dio e intronizza una falsa idea di libert\u00e0 (39), Papa Leone XIII, con l\u2019enciclica <em>Libertas praestantissimum<\/em>, espone in modo organico la dottrina politica e giuridica della Chiesa, sottolineando la subordinazione essenziale della ragione e della legge umana alla Sapienza di Dio e alla sua legge, nonch\u00e9 il vero significato della libert\u00e0 umana: provvidenzialmente l\u2019Autorit\u00e0 magisteriale della Chiesa ripropone, in una vera e propria Summa politica di fronte al successo della rivoluzione, a futura memoria, i princ\u00ecpi fondamentali dell\u2019ordine giuridico e politico.<\/p>\n<p style=\"text-align: justify;\"><strong>4. Le conseguenze dell\u2019abbandono della &#8220;giusta misura&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Platone ne <em>Il Politico<\/em>, con profonda intuizione, osservava che la trascuratezza nei confronti della relazione di ciascuna cosa con la giusta misura porterebbe all\u2019&#8221;annientamento&#8221; della politica, come di qualsivoglia altra arte. Gli ordinamenti post-rivoluzionari, a cominciare da quelli liberali, intronizzano positivisticamente il principio del primato assoluto della legge dello Stato indipendentemente dal suo contenuto e, prima ancora e soprattutto, indipendentemente dal suo fondamento nella legge eterna di Dio.<\/p>\n<p style=\"text-align: justify;\">Il fondamento della normativit\u00e0 \u00e8 cos\u00ec radicalmente negato e il diritto annientato in modo coerentemente consequenziale. Provoca stupore, in queste condizioni, non l\u2019approvazione progressiva, in tutti gli ordinamenti, di norme <em>materialiter<\/em> contrarie al criterio del giusto, bens\u00ec la lentezza del processo e la resistenza opposta dalle societ\u00e0 civili al rovesciamento degli assi del reale. Invero, l\u2019annientamento del diritto, realizzatosi con la negazione della partecipazione della legge umana alla legge naturale che \u00e8 la legge eterna di Dio, anticipa e pre-contiene integralmente lo svuotamento del contenuto giuridico materiale dei vari ordinamenti statali.<\/p>\n<p style=\"text-align: justify;\">Nella prima met\u00e0 del secolo XX la dottrina &#8220;pura&#8221; del diritto ha tratto le conclusioni teoretiche del processo compiuto, in una prospettiva cui non era affatto estraneo \u2014 attraverso la critica a qualsivoglia tentativo di relazionare la forma del dover essere al suo contenuto \u2014 il progetto inteso e sradicare dagli ordinamenti quanto <em>materialiter<\/em> continuava a sussistere in essi come diritto.<\/p>\n<p style=\"text-align: justify;\">Assumendo l\u2019ordinamento come un <em>&#8220;sistema di norme generali ed invidivuali connesse fra di loro in base al principio che il diritto regola la propria creazione&#8221; <\/em>(40), quindi affermando che <em>&#8220;una norma appartiene a quell\u2019ordinamento giuridico soltanto perch\u00e9 \u00e8 stata creata in conformit\u00e0 al dettato di un\u2019altra norma dello stesso ordinamento&#8221;<\/em> (41), Hans Kelsen pretende di escludere dall\u2019orizzonte del diritto ogni riferimento a ci\u00f2 che \u00e8 estraneo al puro processo normativo, e, in particolare, ogni riferimento al contenuto delle singole norme, secondo una valutazione concernente la loro conformit\u00e0, o difformit\u00e0, rispetto a ci\u00f2 che \u00e8 giusto.<\/p>\n<p style=\"text-align: justify;\">Il processo di formalizzazione del diritto \u2014 coincidente con la separazione tematica tra normazione e giustizia \u2014 sfocia nella rivelazione del fondamento reale, anche se occultato, dell\u2019ordinamento giuridico moderno; in tanto \u00e8 ipotizzabile l\u2019esistenza di un diritto puro, come mero processo di normazione positiva, indipendentemente dal suo contenuto, in quanto sia valida la cosiddetta norma fondamentale, la <em>Grundnorm<\/em>, la quale dovrebbe costituire l\u2019unit\u00e0 di quel sistema di norme. Senonch\u00e9, tale norma fondamentale in realt\u00e0 non esiste, ma \u00e8 soltanto postulata ipoteticamente per mascherare il soggetto \u2014 colui che detiene ed effettivamente esercita il potere \u2014 che sta alla base del processo di normazione positiva (42).<\/p>\n<p style=\"text-align: justify;\">La conclusione di Hans Kelsen \u00e8 coerente con il principio di separazione tra normazione e giustizia: l\u2019efficacia \u00e8 la condizione <em>sine qua non<\/em> della validit\u00e0 delle singole norme; l\u2019ordinamento \u00e8 valido se \u00e8 &#8220;efficace&#8221;, cio\u00e8 se le norme dell\u2019ordinamento sono in generale obbedite da chi \u00e8 soggetto (43).<\/p>\n<p style=\"text-align: justify;\">Il grido empio \u00e8 alla fine proclamato apertamente: il diritto non \u00e8 ci\u00f2 che gli uomini per generazioni e generazioni hanno chiamato diritto, bens\u00ec \u00e8 esclusivamente potere, forza, coercizione, adeguatezza nel piegare le volont\u00e0 e nell\u2019uniformizzare i comportamenti. L\u2019equivalenza tra normazione e potere segna l\u2019annientamento del diritto e dell\u2019autorit\u00e0 politica.<\/p>\n<p style=\"text-align: justify;\">V\u2019\u00e8 corrispondenza in Hans Kelsen tra la negazione del diritto e la costituzione di una forma politica totalmente priva di riferimento all\u2019autorit\u00e0: come, nella dottrina della Chiesa, l\u2019autorit\u00e0 viene da Dio e la legge umana si radica nella legge eterna di Dio, partecipata <em>ab origine<\/em> alla ragione dell\u2019uomo, cos\u00ec, nella dottrina &#8220;pura&#8221; \u2014 cio\u00e8, empia \u2014, del diritto, l\u2019autorit\u00e0 non esiste, riducendosi alla mera designazione, di volta in volta, da parte della massa, organizzata secondo la legge del numero, di chi esercita la coercizione, e la legge umana si identifica nella forma del dovere \u2014 indipendentemente dal suo contenuto \u2014, che sussiste in virt\u00f9 del potere di chi comanda. Secondo il giurista viennese la democrazia \u00e8 la migliore forma di governo perch\u00e9 essa costituirebbe il pi\u00f9 efficace strumento di traduzione del relativismo etico sul piano giuridico (44).<\/p>\n<p style=\"text-align: justify;\">Sostiene, invero, Hans Kelsen, in <em>Vom Wesen und Wert der Demokratie<\/em>: <em>&#8220;Se io mi pronuncio a favore della democrazia, lo faccio esclusivamente <\/em>[&#8230;]<em> a causa <\/em>[&#8230;]<em> del legame che esiste fra una democrazia e una teoria relativista&#8221;<\/em> (45). In <em>Foundations of Democracy<\/em>, Hans Kelsen afferma: <em>&#8220;Che i giudizi di valore abbiano una validit\u00e0 soltanto relativa \u2014 principio basilare del relativismo filosofico \u2014 implica che opposti giudizi di valore non siano esclusi n\u00e8 logicamente n\u00e8 moralmente. Uno dei princ\u00ecpi fondamentali della democrazia \u00e8 che ognuno deve rispettare l\u2019opinione politica degli altri, giacch\u00e9 tutti sono uguali e liberi. <\/em>[&#8230;]<em> Se si riconosce <\/em>[&#8230;]<em> che solo i valori relativi sono accessibili alla conoscenza ed alla volont\u00e0 umana, allora \u00e8 giustificato imporre un ordinamento sociale ad individui riluttanti solo se tale ordinamento \u00e8 in armonia con il maggior numero possibile di individui uguali, cio\u00e8 con la volont\u00e0 della maggioranza&#8221;<\/em> (46).<\/p>\n<p style=\"text-align: justify;\">Il principio maggioritario, assunto in modo assoluto e senza alcun vincolo contenutistico, esprime puntualmente l\u2019applicazione alla politica della legge quantitativa, che pretende di misurare il bene e il male con lo stesso metro con cui si misurano la lunghezza, l\u2019altezza, la velocit\u00e0 e le altre grandezze meramente quantitative. La democrazia assoluta costituisce il tentativo di trattare la <em>res publica<\/em> con un criterio di misura meramente quantitativo: il numero pi\u00f9 elevato decide in ogni situazione concreta della prevalenza di valori di volta in volta opposti. Nessun riferimento alla giusta misura \u00e8 possibile, poich\u00e9 il numero costituisce criterio della validit\u00e0 della normazione.<\/p>\n<p style=\"text-align: justify;\">Rescisso, sul piano individuale, il rapporto di dipendenza della libert\u00e0 dalla verit\u00e0 \u2014 rapporto che, come ricorda Papa Giovanni Paolo II, \u00e8 stato espresso nel modo pi\u00f9 limpido e autorevole dalle parole di Cristo: <em>&#8220;Conoscerete la verit\u00e0, e la verit\u00e0 vi far\u00e0 liberi&#8221;<\/em> (<em>Gv<\/em>. 8, 32) (47) \u2014, sul piano politico e giuridico la contraddittoriet\u00e0 delle opzioni individuali, postulata come radicalmente insanabile, proprio per l\u2019assenza di partecipazione della ragione dell\u2019uomo alla <em>ratio<\/em> universale della legge eterna di Dio e per il carattere affatto opinabile delle scelte di ciascuno, viene artificialmente composta attraverso la legge cieca del numero.<\/p>\n<p style=\"text-align: justify;\">La legge dello Stato, in tale modo, da strumento pratico che esprime e rivela il diritto, garantendo a tutti i membri della comunit\u00e0 politica i benefici inerenti alla naturale socialit\u00e0 dell\u2019uomo, diventa essa stessa fonte esclusiva del diritto, trovando il fondamento della sua validit\u00e0 nel rispetto formale delle procedure previste per la sua entrata in vigore e nell\u2019efficacia che riposa sulla forza (48).<\/p>\n<p style=\"text-align: justify;\">La dialettica vitale tra legge e diritto, nello sforzo inesauribile di adeguare la prima al secondo, rivelativa della profondit\u00e0 etica e metafisica della dimensione giuridica e della centralit\u00e0 della virt\u00f9 della giustizia nella vita sociale, svanisce progressivamente e cede il posto a una sequenza meramente temporale \u2014 tra ci\u00f2 che appare prima e ci\u00f2 che appare dopo \u2014, che appiattisce la vita associata sull\u2019unica dimensione di quel che sembra, in ciascun momento storico e per la generazione presente, socialmente utile e vantaggioso.<\/p>\n<p style=\"text-align: justify;\"><strong>5. L\u2019enciclica &#8220;Veritatis splendor&#8221;<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel dialogo platonico <em>Il Politico<\/em>, il Forestiero, a un certo punto, si domanda perch\u00e9 mai sia necessaria l\u2019opera legislativa se la legge non \u00e8 una cosa al massimo grado giusta. La legge, infatti, proprio per la sua generalit\u00e0 e astrattezza, non potrebbe mai comprendere con esattezza quanto \u00e8 migliore e insieme pi\u00f9 giusto per tutti, impartendo le sue prescrizioni con assoluta giustizia (49).<\/p>\n<p style=\"text-align: justify;\">Le leggi sono come appunti che un medico o un maestro di ginnastica, accingendosi a compiere un viaggio e a star lontano, per un tempo piuttosto lungo, dalle persone che ha in cura, scriverebbe per i propri malati o allievi, ritenendo che costoro non ricorderebbero i suoi precetti: ma la forza delle leggi non sta nel loro presentarsi come precetti, bens\u00ec nella loro idoneit\u00e0 a realizzare sempre una perfetta giustizia, secondo la ragione e l\u2019arte, s\u00ec non soltanto da proteggere i cittadini, ma anche da farli <em>&#8220;<\/em>[&#8230;] <em>da peggiori che erano<\/em> [&#8230;]<em>, per quanto \u00e8 possibile, migliori&#8221;<\/em> (50).<\/p>\n<p style=\"text-align: justify;\">La legge della comunit\u00e0 politica non \u00e8 mai qualcosa di massimamente e assolutamente giusto, proprio perch\u00e9 \u00e8 la legge dell\u2019uomo, e, dunque, \u00e8 sempre perfettibile e bisognosa di adeguarsi all\u2019ideale della giustizia, cos\u00ec come l\u2019uomo, nello stato di pellegrinaggio sulla terra, pu\u00f2 migliorare costantemente s\u00e9 stesso, e non raggiunge mai lo stato di perfezione. La legge \u00e8 come un ap-punto, come un viatico per il viaggio che la societ\u00e0 instancabilmente compie: il suo modello \u00e8 la legge eterna di Dio, la sua condizione di legittimit\u00e0 \u00e8 il radicarsi in quella, senza pretendere di esaurirla. L\u2019indifferenza verso di essa \u2014 o, peggio ancora, il suo rifiuto \u2014 segna l\u2019annientamento del diritto.<\/p>\n<p style=\"text-align: justify;\">Senonch\u00e9, il grido empio da molto tempo lanciato si \u00e8 fatto mentalit\u00e0 e costume: il diritto non esiste realmente; esso \u00e8 mera forma che copre il potere; il fondamento del diritto non \u00e8 la legge naturale bens\u00ec la idoneit\u00e0 del complesso di leggi che compongono l\u2019ordinamento d\u2019imporsi coercitivamente nei confronti della generalit\u00e0 dei soggetti. Il processo di svuotamento dell\u2019ordinamento da ci\u00f2 che permane <em>materialiter<\/em> come diritto progredisce nel tempo, attentando via via ai fondamenti del vivere associato, dal diritto alla vita, anzitutto, come diritto che tutti gli altri implica e presuppone, a tutti gli altri diritti fondamentali.<\/p>\n<p style=\"text-align: justify;\">Non soltanto e non tanto appare necessario, in questa condizione, ribadire la doverosit\u00e0, per l\u2019ordinamento statuale, di rispettare i diritti fondamentali e di conformarsi al diritto naturale, quanto e soprattutto affermare ci\u00f2 che da molto tempo \u00e8 andato smarrito, cio\u00e8 il legame di dipendenza della libert\u00e0 \u2014 sia dell\u2019uomo come singolo, sia dell\u2019uomo come membro della comunit\u00e0 giuridica \u2014 dalla verit\u00e0. L\u2019enciclica <em>Veritatis splendor<\/em> di Papa Giovanni Paolo II interpreta, al tramonto del secolo XX e nell\u2019attesa dell\u2019alba del terzo millennio cristiano, i segni dei tempi, additando ai singoli uomini e alle societ\u00e0 articolate in Stati non tanto quali siano i comportamenti da tenere in questa o in quell\u2019altra occasione, quanto soprattutto lo statuto della vera libert\u00e0 dell\u2019uomo, che non \u00e8 l\u2019assoluto, da cui promanano come sorgente i valori (51), ma <em>&#8220;segno altissimo dell\u2019immagine divina&#8221;<\/em> (52), che in tanto si attua e conduce l\u2019uomo alla perfezione, in quanto si sottopone al primato della verit\u00e0 (53).<\/p>\n<p style=\"text-align: justify;\">La domanda morale \u2014 insegna il Sommo Pontefice \u2014 non pu\u00f2 prescindere dalla questione della libert\u00e0, giacch\u00e9, se <em>&#8220;<\/em>[&#8230;] <em>non si d\u00e0 morale senza libert\u00e0&#8221;<\/em> (54) \u2014 potendo <em>&#8220;l\u2019uomo <\/em>[&#8230;]<em> volgersi al bene soltanto nella libert\u00e0&#8221;<\/em> (55) \u2014, non esiste vera libert\u00e0 se non nell\u2019adesione della volont\u00e0 alla verit\u00e0: <em>&#8220;Se esiste il diritto di essere rispettati nel proprio cammino di ricerca della verit\u00e0, esiste ancor prima l\u2019obbligo morale grave per ciascuno di cercare la verit\u00e0 e di aderirvi una volta conosciuta&#8221;<\/em> (56)! Non compete all\u2019uomo il potere di decidere del bene e del male, poich\u00e9 la sua libert\u00e0 <em>&#8220;<\/em>[&#8230;] <em>deve arrestarsi di fronte all\u2019&#8221;albero della conoscenza del bene e del male&#8221;, essendo chiamata ad accettare la legge morale che Dio d\u00e0 all\u2019uomo&#8221;<\/em> (57).<\/p>\n<p style=\"text-align: justify;\">La legge di Dio non comprime la libert\u00e0 dell\u2019uomo, a guisa di un ostacolo che dall\u2019esterno soffochi le potenze dell\u2019anima, ma costituisce l\u2019alveo nel quale essa trova alimento per la sua perfezione, s\u00ec da renderlo migliore da peggiore che fosse, secondo la sintesi platonica, ricordata. Il conflitto tra la libert\u00e0 e la legge non sussiste ontologicamente e metafisicamente, perch\u00e9 la legge morale \u00e8 la legge intrinseca della creatura voluta da Dio a sua immagine, e perch\u00e9 la libert\u00e0 \u00e8 la libera adesione dell\u2019uomo alla legge della propria realizzazione e perfezione.<\/p>\n<p style=\"text-align: justify;\">Il conflitto tra la libert\u00e0 e la legge \u2014 continua Papa Giovanni Paolo II \u2014 \u00e8 artificiosamente provocato da quelle <em>&#8220;dottrine che attribuiscono ai singoli individui o ai gruppi sociali la facolt\u00e0 di <\/em>decidere del bene e del male<em>&#8220;<\/em> (58), come se la libert\u00e0 umana potesse <em>&#8220;creare i valori&#8221;<\/em> e godesse di un <em>&#8220;primato sulla verit\u00e0, al punto che la verit\u00e0 stessa sarebbe considerata una creazione della libert\u00e0&#8221;<\/em> (59).<\/p>\n<p style=\"text-align: justify;\">Tutta l\u2019attenzione possibile va attirata sulla rigorosa analogia, espressamente enunciata dal Sommo Pontefice, tra i singoli individui e i gruppi sociali nella relazione rispettiva con la verit\u00e0. Come la pretesa del singolo di <em>&#8220;creare&#8221;<\/em> autonomamente <em>&#8220;valori&#8221;<\/em> si esprime nella teorizzazione della <em>&#8220;<\/em>completa sovranit\u00e0 della ragione<em> nell\u2019ambito delle norme morali relative al retto ordinamento della vita in questo mondo&#8221;<\/em> (60), nella relazione fra <em>&#8220;un <\/em>ordine etico<em>, che avrebbe origine umana e valore solo <\/em>mondano<em>, e un <\/em>ordine della salvezza<em>, per il quale avrebbero rilevanza solo alcune intenzioni ed atteggiamenti interiori circa Dio e il prossimo&#8221;<\/em> (61), cos\u00ec la pretesa delle societ\u00e0 di &#8220;valorizzare&#8221; autonomamente, con segni di volta in volta positivi o negativi, a seconda delle convenienze contingenti del gruppo dei governanti o del maggior numero, ora questi ora quegli interessi, si esprime nella teorizzazione della &#8220;purezza&#8221; dell\u2019ordinamento giuridico e nella separazione assoluta di quest\u2019ultimo, che avrebbe origine umana e valore solo mondano, dall\u2019ordine morale, che riguarderebbe esclusivamente i singoli, nelle loro opzioni etiche affatto autonome e indifferenti.<\/p>\n<p style=\"text-align: justify;\">L\u2019intreccio concettuale e lo sviluppo storico che ha condotto alla separazione dell\u2019ordine politico e giuridico dall\u2019ordine etico e quest\u2019ultimo dall\u2019ordine religioso \u00e8 assai complesso e articolato. L\u2019orizzonte intenzionale \u00e8 sempre quello dell\u2019orgoglioso rifiuto di obbedire al comando di non mangiare del frutto dell\u2019albero del bene e del male, come pretesa di sostituire un ordine completamente e autonomamente umano all\u2019ordine voluto da Dio, e, al limite, se ci\u00f2 fosse possibile, di creare un &#8220;altro&#8221; mondo al posto di quello creato da Dio.<\/p>\n<p style=\"text-align: justify;\">Sul piano storico, la separazione dell\u2019ordine politico e giuridico dall\u2019ordine etico, che si realizza in modo compiuto \u2014 <em>formaliter<\/em> \u2014, con la teorizzazione della sovranit\u00e0 assoluta dapprima del principe e poi della legge (62), promuove e fomenta la tendenza alla separazione dell\u2019ordine etico, valido per il singolo individuo, dall\u2019ordine etico oggettivo, fondato sulla legge naturale e valido universalmente per ciascun uomo e in ogni tempo.<\/p>\n<p style=\"text-align: justify;\">Il singolo uomo, infatti, trova nell\u2019indifferenza o, addirittura, nella contrariet\u00e0 del modello legale al principio morale, alimento pedagogico e sostegno psicologico all\u2019orgoglioso rifiuto di far valere anche per s\u00e9, come legge di carattere universale, la legge morale che si presenta alla sua coscienza. Per altro verso, la frantumazione dell\u2019ordine etico oggettivo in una miriade di universi soggettivi di &#8220;valori&#8221; (63), tanti quanto sono, al limite, gli individui, tende a rendere irreversibile la frattura fra ordine giuridico e ordine etico: la relazione armonica tra essi diventa, infatti, tanto pi\u00f9 incomprensibile, quanto pi\u00f9 \u00e8 radicata la convinzione circa la relativit\u00e0 e la variabilit\u00e0 dei &#8220;valori&#8221; etici.<\/p>\n<p style=\"text-align: justify;\">Trova origine, in questa situazione, la particolare difficolt\u00e0, nel tempo presente, della presentazione, e della successiva realizzazione, di una proposta politica conforme ai postulati del diritto naturale cristiano. Invero, la proclamazione della doverosit\u00e0 del rispetto, da parte dello Stato, della legge morale, appare, alla mentalit\u00e0 della maggior parte dei nostri contemporanei, doppiamente inaccettabile: una prima volta, essa sarebbe oppressiva, perch\u00e9 violerebbe la libert\u00e0 di ogni singolo uomo, che in tanto sarebbe libero in quanto elaborasse da s\u00e9 stesso una propria costellazione di &#8220;valori&#8221;; una seconda volta, il rispetto legislativo della legge morale violerebbe la libert\u00e0 di tutti coloro, costituiscano essi maggioranza o minoranza, che si sono costruiti un universo di valori diverso e contraddittorio rispetto ai princ\u00ecpi del diritto naturale.<\/p>\n<p style=\"text-align: justify;\">Molto spesso anche coloro che aderiscono <em>materialiter<\/em> al dettame della legge morale si sentono a disagio nella presentazione e nell\u2019attuazione di una proposta politica conforme al diritto naturale, poich\u00e9 hanno smarrito tanto il senso dell\u2019oggettivit\u00e0 e dell\u2019universalit\u00e0 della legge morale, quanto il senso della vera libert\u00e0, che risiede nell\u2019adesione alla legge naturale, che \u00e8 legge altres\u00ec dell\u2019uomo, in quanto <em>ab origine<\/em> partecipata da Dio alla ragione umana.<\/p>\n<p style=\"text-align: justify;\"><strong>6. Verit\u00e0 morale e martirio<\/strong><\/p>\n<p style=\"text-align: justify;\">Il Sommo Pontefice, cui ben \u00e8 presente il desolante quadro delle legislazioni degli Stati contemporanei, soprattutto in tema di tutela del diritto alla vita e dei diritti fondamentali della famiglia (64), assume nell\u2019enciclica <em>Veritatis splendor<\/em> nuovamente dalle fondamenta il tema del rapporto fra libert\u00e0 dell\u2019uomo e verit\u00e0, fra primato della legge di Dio e legittima autonomia dell\u2019uomo. <em>&#8220;La <\/em>vera autonomia morale<em> dell\u2019uomo <\/em>\u2014 proclama Papa Giovanni Paolo II \u2014<em> non significa affatto il rifiuto, bens\u00ec l\u2019accoglienza della legge morale, del comando di Dio. <\/em>[&#8230;]<\/p>\n<p style=\"text-align: justify;\">La libert\u00e0 dell\u2019uomo e la legge di Dio s\u2019incontrano e sono chiamate a compenetrarsi tra loro<em>, nel senso della libera obbedienza dell\u2019uomo a Dio e della gratuita benevolenza di Dio all\u2019uomo. E pertanto l\u2019obbedienza a Dio non \u00e8, come taluni credono, un\u2019<\/em>eteronomia<em>, come se la vita morale fosse sottomessa alla volont\u00e0 di un\u2019onnipotenza assoluta, esterna all\u2019uomo e contraria all\u2019affermazione della sua libert\u00e0. In realt\u00e0, se eteronomia della morale significasse negazione dell\u2019autodeterminazione dell\u2019uomo o imposizione di norme estranee al suo bene, essa sarebbe in contraddizione con la rivelazione dell\u2019Alleanza e dell\u2019Incarnazione redentrice. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Una simile eteronomia non sarebbe che una forma di alienazione, contraria alla sapienza divina ed alla dignit\u00e0 della persona umana.<\/em> <em>&#8220;Alcuni parlano, a giusto titolo, di <\/em>teonomia<em>, o di <\/em>teonomia partecipata<em>, perch\u00e9 la libera obbedienza dell\u2019uomo alla legge di Dio implica effettivamente la partecipazione della ragione e della volont\u00e0 umane alla sapienza e alla provvidenza di Dio. Proibendo all\u2019uomo di mangiare &#8220;dell\u2019albero della conoscenza del bene e del male&#8221;, Dio afferma che l\u2019uomo non possiede originariamente in proprio questa &#8220;conoscenza&#8221;, ma solamente vi partecipa mediante la luce della ragione naturale e della rivelazione divina, che gli manifestano le esigenze e gli appelli della sapienza eterna. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>La legge quindi deve dirsi un\u2019espressione della sapienza divina: sottomettendosi ad essa, la libert\u00e0 si sottomette alla verit\u00e0 della creazione. Per questo occorre riconoscere nella libert\u00e0 della persona umana l\u2019immagine e la vicinanza di Dio, che \u00e8 &#8220;presente in tutti&#8221; (cf. <\/em>Ef<em> 4, 6); allo stesso modo, bisogna confessare la maest\u00e0 del Dio dell\u2019universo e venerare la santit\u00e0 della legge di Dio infinitamente trascendente. <\/em>Deus semper maior<em>&#8221; <\/em>(65).<\/p>\n<p style=\"text-align: justify;\">Dopo aver illustrato, nel capitolo secondo dell\u2019enciclica \u2014 che reca come titolo l\u2019appello di san Paolo ai Romani (<em>Rm<\/em>. 12, 2) <em>&#8220;Non conformatevi alla mentalit\u00e0 di questo mondo&#8221;<\/em> \u2014 la relazione inscindibile tra verit\u00e0 e libert\u00e0, e aver sottoposto a critica le opinioni teologiche che mettono in discussione, erodono o addirittura negano tale fondamentale legame, Papa Giovanni Paolo II passa a trattare nel capitolo terzo, intitolato con la frase di san Paolo nella prima lettera ai Corinti (<em>1 Cor<\/em>. 1, 17) <em>&#8220;Perch\u00e9 non venga resa vana la croce di Cristo&#8221;<\/em> \u2014 profili pi\u00f9 propriamente pastorali, mostrando come una rinnovata coscienza dei fedeli in ordine alla vera natura del bene morale sia indispensabile per la fioritura della nuova evangelizzazione e per lo stesso rinnovamento della vita sociale e politica.<\/p>\n<p style=\"text-align: justify;\">Per illuminare i cristiani in ordine ai loro doveri di fronte al dettame inviolabile della legge morale, il Papa addita anzitutto l\u2019esempio dei martiri, che hanno testimoniato con l\u2019effusione del sangue la santit\u00e0 della legge di Dio e il suo primato su qualsivoglia potenza umana, alla luce del <em>&#8220;rispetto incondizionato che si deve alle esigenze insopprimibili della dignit\u00e0 personale di ogni uomo&#8221;<\/em> (66), esigenze che proscrivono senza eccezione alcuna il compimento di atti intrinsecamente cattivi. La testimonianza dei martiri dell\u2019Antico e del Nuovo Testamento rammenta alla mente e ricorda al cuore che la salvezza individuale e la pace sociale risiedono nell\u2019obbedienza perfetta alla verit\u00e0 e all\u2019assolutezza dell\u2019ordine morale.<\/p>\n<p style=\"text-align: justify;\">Dalla casta Susanna che, resistendo alla pressione impura dei due giudici ingiusti, sceglie per se la <em>&#8220;parte migliore&#8221;<\/em>, preferendo <em>&#8220;cadere innocente <\/em>[&#8230;]<em> che peccare davanti al Signore&#8221;<\/em> (<em>Dn.<\/em> 13, 22-23), a Giovanni Battista che, alle soglie del Nuovo Testamento, rifiuta <em>&#8220;<\/em>[&#8230;] <em>di tacere la legge del Signore e di venire a compromesso col male&#8221;<\/em>, immolando <em>&#8220;la sua vita per la verit\u00e0 e la giustizia&#8221;<\/em> (cfr. <em>Mc<\/em>. 6, 17-29); dai primi seguaci di Cristo, a cominciare dal diacono Stefano (cfr. <em>At.<\/em> 6, 8-7, 60) e dall\u2019apostolo Giacomo (cfr. <em>At.<\/em> 12, 1-2), <em>&#8220;che sono morti martiri per confessare la loro fede e il loro amore al Maestro e per non rinnegarlo&#8221;<\/em> agli innumerevoli testimoni fino ai giorni nostri, <em>&#8220;nel martirio come affermazione dell\u2019inviolabilit\u00e0 dell\u2019ordine morale risplendono <\/em>\u2014 secondo le parole di Papa Giovanni Paolo II \u2014<em> la santit\u00e0 della legge di Dio e insieme l\u2019intangibilit\u00e0 della dignit\u00e0 personale dell\u2019uomo, creato a immagine e somiglianza di Dio&#8221;<\/em> (67).<\/p>\n<p style=\"text-align: justify;\">Deve rappresentare per i cristiani motivo di confusione e costituire per tutta la societ\u00e0 stimolo alla conversione la constatazione drammatica che, laddove si \u00e8 dispiegata un tempo con maggior frutto la parola rivelata di Dio \u2014 nell\u2019Europa cristiana e nell\u2019Italia culla del Papato \u2014 qui viene rigettato con sistematica protervia il fondamento morale dell\u2019ordine giuridico.<\/p>\n<p style=\"text-align: justify;\">Il dialogo vitale fra fede e ragione \u2014 che ha permesso ai nostri padri di comprendere che la legge non \u00e8 uno strumento eteronomo di coercizione del volere, bens\u00ec la via per realizzare la piena libert\u00e0 dell\u2019uomo, siccome la legge eterna di Dio \u00e8 partecipata alla ragione dell\u2019uomo \u2014 deve essere ricostruito con rinnovato entusiasmo come condizione indispensabile per la nostra personale salvezza e per l\u2019instaurazione di un ordine giuridico e sociale conforme al piano di Dio sulla storia dell\u2019uomo.<\/p>\n<div align=\"center\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1590\" target=\"_blank\">vai alle note<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>pubblicato in Cristianit\u00e0 n.230-231 (1994) di Mauro Ronco 1. La &#8220;giusta misura&#8221; platonica Nel dialogo Il Politico Platone si ripromette di cogliere la trama e l\u2019ordito che la vera scienza politica viene tessendo, nella ricerca dinamica del bene comune, sul fondamento del riconoscimento in comune del Bene (1). Socrate e i suoi interlocutori mostrano di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31546,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11],"tags":[484,1097],"class_list":["post-1591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto","category-dottrina-sociale","tag-diritto-naturale","tag-veritatis-splendor","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diritto naturale e diritto positivo nell&#039;enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diritto naturale e diritto positivo nell&#039;enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-10-18T15:32:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-10T12:02:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"177\" \/>\n\t<meta property=\"og:image:height\" content=\"285\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"37 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Diritto naturale e diritto positivo nell&#8217;enciclica &quot;Veritatis splendor\",\"datePublished\":\"2005-10-18T15:32:30+00:00\",\"dateModified\":\"2016-03-10T12:02:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/\"},\"wordCount\":7404,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/Veritatis_cover.jpg\",\"keywords\":[\"diritto naturale\",\"Veritatis splendor\"],\"articleSection\":[\"Diritto\",\"Dottrina sociale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/\",\"name\":\"Diritto naturale e diritto positivo nell'enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/Veritatis_cover.jpg\",\"datePublished\":\"2005-10-18T15:32:30+00:00\",\"dateModified\":\"2016-03-10T12:02:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/Veritatis_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/Veritatis_cover.jpg\",\"width\":177,\"height\":285},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diritto naturale e diritto positivo nell&#8217;enciclica &quot;Veritatis splendor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diritto naturale e diritto positivo nell'enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/","og_locale":"it_IT","og_type":"article","og_title":"Diritto naturale e diritto positivo nell'enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-10-18T15:32:30+00:00","article_modified_time":"2016-03-10T12:02:19+00:00","og_image":[{"width":177,"height":285,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"37 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Diritto naturale e diritto positivo nell&#8217;enciclica &quot;Veritatis splendor","datePublished":"2005-10-18T15:32:30+00:00","dateModified":"2016-03-10T12:02:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/"},"wordCount":7404,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg","keywords":["diritto naturale","Veritatis splendor"],"articleSection":["Diritto","Dottrina sociale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/","name":"Diritto naturale e diritto positivo nell'enciclica &quot;Veritatis splendor - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg","datePublished":"2005-10-18T15:32:30+00:00","dateModified":"2016-03-10T12:02:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/Veritatis_cover.jpg","width":177,"height":285},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/diritto-naturale-e-diritto-positivo-nellenciclica-veritatis-splendor-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Diritto naturale e diritto positivo nell&#8217;enciclica &quot;Veritatis splendor"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1591"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1591\/revisions"}],"predecessor-version":[{"id":31547,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1591\/revisions\/31547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31546"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}