{"id":1548,"date":"2005-10-10T12:26:47","date_gmt":"2005-10-10T10:26:47","guid":{"rendered":""},"modified":"2016-02-05T20:34:33","modified_gmt":"2016-02-05T19:34:33","slug":"i-giorni-del-condom","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/","title":{"rendered":"I giorni del condom"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-30401\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg\" alt=\"fedelt\u00e0_anti-aids\" width=\"250\" height=\"121\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg 323w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids-300x144.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>Pubblicato su<strong> Tempi <\/strong>n.41<\/div>\n<div style=\"text-align: center;\">del 6 ottobre 2005<\/div>\n<p style=\"text-align: justify;\"><em>La fedelt\u00e0 di coppia, e non i profilattici, hanno abbassato l&#8217;aids.lo confermano gli studi scientifici, ignorati dalla grande stampa che continua a fare propaganda ideologica<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Casadei Rodolfo<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Diffamate pure l&#8217;Uganda con le vostre denunce di un presunto boicottaggio dei condom, continuate a lanciare le vostre accuse grottesche contro i papi, tirate in ballo George W. Bush e la destra religiosa americana.<\/div>\n<p style=\"text-align: justify;\">Cari giornalisti liberal, le vostre campagne di stampa potranno sempre nascondere la verit\u00e0 ma non riusciranno a cancellarla: fedelt\u00e0 di coppia, astinenza sessuale, riduzione del numero dei part-ner sono molto pi\u00f9 importanti nella lotta all&#8217;Aids che non la disponibilit\u00e0 e l&#8217;uso dei profilattici.<\/p>\n<p style=\"text-align: justify;\">Gli studi scientifici che evidenziano questa verit\u00e0 si accumulano, ma sulle pagine del New York Times, di Le Monde, dell&#8217;Economist c&#8217;\u00e8 spazio soltanto per i rapporti di Human Rights Watch e per le dichiarazioni di Stephen Lewis, il canadese rappresentante speciale dell&#8217;Onu per l&#8217;Aids in Africa, che incolpano il governo ugandese di avere quasi eliminato il condom dalle campagne di prevenzione dell&#8217;Aids per fare un piacere al presidente Bush e ai suoi programmi basati sull&#8217;astinenza.<\/p>\n<p style=\"text-align: justify;\">I capi di accusa sono: penuria di profilattici distribuiti gratuitamente che avrebbe costretto i consumatori a ricavare condom di fortuna da sacchetti di plastica per l&#8217;immondizia (!), caro-prezzi dei profilattici in vendita, negazione delle informazioni sull&#8217;utilizzo dei condom ai bambini delle scuole elementari (!), eccessiva pubblicit\u00e0 delle campagne per l&#8217;astinenza sessuale promosse da Janet Museveni, la moglie del presidente, una cristiana evangelica molto attiva.<\/p>\n<p style=\"text-align: justify;\">Inutilmente ministri e ambasciatori ugandesi hanno cercato di spiegare che la penuria c&#8217;era stata a causa del ritiro dal mercato di un prodotto che presentava seri problemi, che 65 milioni di profilattici erano nel frattempo diventati disponibili e altri 80 milioni sarebbero arrivati.<\/p>\n<p style=\"text-align: justify;\">Avendo fatto l&#8217;errore di premettere alle loro dichiarazioni che \u00abs\u00ec, noi riconosciamo che i condom riducono il rischio ma riconosciamo anche che non lo eliminano\u00bb, e avendo dietro di s\u00e9 un presidente come Yoweri Museveni che al summit dell&#8217;Onu sull&#8217;Aids a Bangkok nel 2004 aveva detto di preferire \u00abrelazioni ottimali basate sull&#8217;amore e la fiducia alla diffidenza istituzionalizzata, che \u00e8 l&#8217;ambito del condom\u00bb, sono stati trattati come mentecatti.<\/p>\n<p style=\"text-align: justify;\">Le Monde ha sentenziato che il successo dell&#8217;Uganda nel ridurre il tasso di positivit\u00e0 dal 15 per cento degli adulti nel 1992 al 6 per cento di oggi, unico paese africano fino ad oggi a riuscire nell&#8217;impresa, \u00absi fonda sull&#8217;utilizzo dei preservativi\u00bb. Ma cos\u00ec non \u00e8. Leggere per credere.<\/p>\n<p style=\"text-align: justify;\"><strong>PROFILATTICI: NESSUNO \u00c8 PERFETTO<\/strong><\/p>\n<p style=\"text-align: justify;\">Una delle accuse formulate nei confronti di Janet Museveni \u00e8 di aver fatto affiggere manifesti in cui si afferma che i condom riducono il rischio di contrarre l&#8217;Aids soltanto dell&#8217;80 per cento, mentre il condom sarebbe molto pi\u00f9 sicuro di cos\u00ec. In realt\u00e0 il dato \u00e8 esatto, esso proviene da uno studio americano (Weller S., Davis K., <em>Condom effectiveness in reducing heterosexual HIV transmission<\/em>) revisionato dall&#8217;autorevole Cochrane Library. Tale studio prende in considerazione l&#8217;utilizzo &#8220;adeguato&#8221; del condom, cio\u00e8 un utilizzo continuato (tutte le volte che c&#8217;\u00e8 un rapporto sessuale) ma non necessariamente appropriato.<\/p>\n<p style=\"text-align: justify;\">Il profilattico \u00e8 un metodo di prevenzione dell&#8217;Aids abbastanza efficace quando ci si riferisce all&#8217;utilizzo &#8220;perfetto&#8221;, cio\u00e8 quando lo si utilizza sempre e nel modo migliore: allora il suo tasso di efficacia per quanto riguarda la trasmissione dell&#8217;Hiv \u00e8 del 96 per cento su base annua (che vuol pur sempre dire che ci saranno 4 contagi nel corso di un anno); ma scende all&#8217;87 per cento quando si passa all&#8217;utilizzo &#8220;tipico&#8221;, cio\u00e8 l&#8217;utilizzo non continuato (a volte s\u00ec, a volte no) e non appropriato (condom danneggiati, entrati in contatto con fluidi corporei, indossati troppo tardi, ecc.); questi sono i numeri che J. Trussell e K. Yost producono in un loro citatissimo studio, fondato sul presupposto di soggetti che abbiano 83 rapporti sessuali all&#8217;anno (media americana).<\/p>\n<p style=\"text-align: justify;\">Proiettati su dieci anni, questi numeri sono molto allarmanti: fra gli utilizzatori &#8220;tipici&#8221; il tasso di infezione raggiungerebbe il 75-78 per cento nell&#8217;arco di un decennio. Alla recente conferenza Onu di Rio de Janeiro Ward Cates di Family Health International (una Ong americana favorevole ai condom) ha mostrato le diapositive con queste proiezioni senza che nessuno obiettasse.<\/p>\n<p style=\"text-align: justify;\">Ma, si dir\u00e0, tutto il problema sta nell&#8217;aiutare la gente a passare dall&#8217;utilizzo &#8220;tipico&#8221; a quello &#8220;perfetto&#8221;. Pi\u00f9 facile a dirsi che a farsi! E inoltre l&#8217;accento sul condom pu\u00f2 avere risultati opposti a quelli attesi. Lo dimostra uno studio ugandese fresco di stampa, apparso sul numero di settembre della rivista scientifica <em>Journal of Acquired Immune Deficiency Syndromes<\/em> sotto il titolo <em>Increasing Condom Use Without Reducing Hiv Risk,<\/em> cio\u00e9 &#8220;Aumentare l&#8217;utilizzo del condom senza ridurre il rischio dell&#8217;Hiv&#8221;.<\/p>\n<p style=\"text-align: justify;\">Gli studiosi hanno selezionato due gruppi di giovani maschi ugandesi; hanno addestrato i primi all&#8217;utilizzo perfetto del condom e li hanno forniti di coupon per ritirarli gratis presso strutture di facile accesso; hanno comunicato solo informazioni generali sull&#8217;Aids e fornito altrettanti coupon ai secondi. All&#8217;inizio e alla fine dell&#8217;esperimento ai due gruppi \u00e8 stato chiesto di compilare un identico questionario sulle loro attivit\u00e0 sessuali, per raffrontare i comportamenti prima e dopo l&#8217;intervento.<\/p>\n<p style=\"text-align: justify;\">Ci si attendeva che i primi rivelassero comportamenti meno esposti al rischio del contagio che non i secondi. \u00c8 risultato il contrario. I membri del primo gruppo hanno s\u00ec utilizzato i loro coupon in misura maggiore di quelli del secondo, ma nel contempo hanno aumentato l&#8217;intensit\u00e0 della loro attivit\u00e0 sessuale, incluso il numero dei partner (che sono passati da 2,13 a 2,44 mentre quelli del secondo diminuivano da 2,20 a 2,03) e non hanno diminuito le occasioni di sesso non protetto (31,9 per cento di rispondenti sia prima che dopo l&#8217;intervento).<\/p>\n<p style=\"text-align: justify;\">Risultato: \u00abL&#8217;astinenza da rapporti con partner occasionali \u00e8 aumentata nel gruppo &#8220;generico&#8221; ma \u00e8 diminuita nel gruppo &#8220;istruito&#8221;. Il risultato netto \u00e8 che un numero leggermente maggiore di uomini nel gruppo &#8220;istruito&#8221; ha dichiarato rapporti sessuali non protetti con partner occasionali nel questionario finale in confronto agli uomini del gruppo &#8220;generico&#8221;&#8230; non c&#8217;\u00e8 dunque nessuna prova statistica di un beneficio dell&#8217;intervento in termini di cambiamento di comportamenti sessuali a rischio, come quello rappresentato dal sesso non protetto con partner occasionali\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>NON RESTA CHE RIDURRE IL NUMERO DEI PARTNER<\/strong><\/p>\n<p style=\"text-align: justify;\">Esistono invece lavori scientifici che dimostrano la preminenza di fedelt\u00e0 di coppia, astinenza sessuale e riduzione del numero dei partner nel successo ugandese contro l&#8217;Aids. Vedi per esempio il bel libro di Edward C. Green, Rethinking Aids Prevention: Learning from successes in developing countries (2003).<\/p>\n<p style=\"text-align: justify;\">\u00abGreen &#8211; spiega Paolo Bonfanti, infettivologo del Luigi Sacco di Milano &#8211; descrive, fornendo non opinioni ma dati epidemiologici, come per anni il mondo scientifico e politico abbia ignorato ci\u00f2 che la realt\u00e0 dell&#8217;Aids in Africa continuava a suggerire: gli unici paesi che hanno mostrato una inversione di tendenza circa la diffusione della malattia sono quelli che hanno adottato programmi di Primary Behavior Change, cio\u00e8 cambiamento dei comportamenti a rischio, mentre l&#8217;applicazione di modelli di prevenzione basati unicamente sull&#8217;uso del condom non ha prodotto gli effetti sperati.<\/p>\n<p style=\"text-align: justify;\">Green spiega che campagne di prevenzione basate sull&#8217;utilizzo del preservativo sono appropriate laddove la malattia si diffonde prevalentemente in gruppi ad alto rischio, come ad esempio gli omosessuali nei paesi occidentali. Dove invece la diffusione epidemica interessa tutta la popolazione sessualmente attiva, ed \u00e8 il caso dell&#8217;Africa sub-sahariana, tale modello preventivo non pu\u00f2 essere efficace\u00bb. Sulla stessa linea troviamo due importanti articoli scientifici usciti nel 2004.<\/p>\n<p style=\"text-align: justify;\">Il primo, Partner reduction is crucial for balanced &#8220;ABC&#8221; approach to Hiv prevention, \u00e8 apparso sul British Medical Journal e spiega, come dice il titolo, che nell&#8217;approccio ugandese incentrato sul triplice messaggio &#8220;astieniti, oppure sii fedele al tuo partner, oppure usa un condom&#8221; i risultati migliori in termini di prevenzione li ha prodotti il secondo dei tre imperativi.<\/p>\n<p style=\"text-align: justify;\">A met\u00e0 degli anni Novanta in Uganda l&#8217;uso sistematico del profilattico era salito al 20 per cento fra le donne e al 30 per cento fra gli uomini, ma \u00abin un&#8217;epidemia cos\u00ec capillarmente diffusa questi livelli di utilizzo del condom erano ancora relativamente modesti, e l&#8217;uso sistematico non significa l&#8217;uso corretto e continuato necessario per prevenire l&#8217;infezione da Hiv.<\/p>\n<p style=\"text-align: justify;\">Pertanto, anche se l&#8217;uso del condom ha probabilmente contribuito, \u00e8 improbabile che da esso dipenda la drammatica flessione dei tassi di infezione fra la fine degli anni Ottanta e l&#8217;inizio degli anni Novanta\u00bb. Pi\u00f9 importante la riduzione del numero dei partner: \u00abLe indagini del Programma globale sull&#8217;Aids hanno rilevato che la proporzione di uomini che si sono accompagnati a una o pi\u00f9 partner occasionali nell&#8217;anno precedente \u00e8 scesa dal 35 per cento al 15 per cento fra il 1989 e il 1995, e fra le donne dal 16 per cento al 6 per cento\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il condom non viene affatto demonizzato, ma la sua promozione \u00e8 analizzata con estremo realismo: \u00abAnche se gli studi di proiezione hanno mostrato che i condom riducono il rischio dell&#8217;80-90 per cento circa quando vengono usati sempre, nella vita reale essi sono spesso usati in modo errato e incostante. Pertanto non dovrebbero essere pubblicizzati in una maniera che generi eccessiva sicurezza di s\u00e9 o comportamenti rischiosi\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>COS&#8217;HANNO FATTO VERAMENTE IN UGANDA<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;altro articolo di peso che insiste sugli stessi punti \u00e8 apparso su Science del 30 aprile 2004 sotto il titolo Population-Level Hiv Declines and Behavioral Risk Avoidance in Uganda, autori Rand L. Stoneburner e Daniel Low-Beer. \u00abUn&#8217;importante e spesso trascurata misura di cambiamento del comportamento in Uganda fra il 1989 e il 1995 &#8211; si legge nell&#8217;articolo &#8211; \u00e8 stata una riduzione del 60 per cento delle persone che dichiaravano di aver avuto rapporti occasionali nell&#8217;anno precedente, sia fra le popolazioni urbane che fra quelle rurali.<\/p>\n<p style=\"text-align: justify;\">La percentuale di persone che hanno dichiarato rapporti occasionali \u00e8 stata molto pi\u00f9 alta in Malawi e Zambia nel 1996 e in Kenya nel 1998 che in Uganda nel 1995. Bench\u00e8 fosse aumentato dal 1989, il tasso di utilizzo del condom nei rapporti occasionali nel 1995 in Uganda non era sostanzialmente differente da quello degli altri paesi africani. Invece la percentuale di giovani fra i 15 e i 19 anni che si astenavano dal sesso era pi\u00f9 alta, essendo cresciuta sostanzialmente fra il 1989 e il 1995.<\/p>\n<p style=\"text-align: justify;\">Questi dati suggeriscono che la riduzione del numero dei partner sessuali e l&#8217;astinenza fra i giovani non sposati (particolarmente maschi delle aree urbane) anzich\u00e9 l&#8217;uso dei condom sono stati i fattori rilevanti nella riduzione dell&#8217;incidenza dell&#8217;Hiv\u00bb. Per Stoneburner e Low-Beer \u00e8 appurato che il ruolo del profilattico \u00e8 stato secondario: \u00abI condom furono una componente minore della strategia originaria&#8230;<\/p>\n<p style=\"text-align: justify;\">Il diffuso sostegno alla distribuzione di condom attraverso tecniche di marketing sociale, i test volontari e il counseling, il migliorato trattamento delle infezioni trasmesse per via sessuale sono venute in gran parte dopo che il declino dei tassi di incidenza e di prevalenza dell&#8217;Hiv era gi\u00e0 iniziato\u00bb.<\/p>\n<p style=\"text-align: justify;\">Che la riduzione dei tassi di incidenza dell&#8217;Hiv in Uganda sia cominciata prima della promozione dei profilattici su larga scala lo ha confermato quest&#8217;anno un altro studio, dedicato al distretto di Rakai (il pi\u00f9 colpito di tutto il paese), presentato nel febbraio scorso alla XII Conferenza sui retrovirus e le infezioni opportunistiche da Maria Wawer della Columbia University. Allora, chi \u00e8 l&#8217;oscurantista e chi \u00e8 che si appoggia sull&#8217;evidenza scientifica?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato su Tempi n.41 del 6 ottobre 2005 La fedelt\u00e0 di coppia, e non i profilattici, hanno abbassato l&#8217;aids.lo confermano gli studi scientifici, ignorati dalla grande stampa che continua a fare propaganda ideologica di Casadei Rodolfo<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[1088],"class_list":["post-1548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aids","tag-condom","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I giorni del condom - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I giorni del condom - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-10-10T10:26:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-05T19:34:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"323\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I giorni del condom\",\"datePublished\":\"2005-10-10T10:26:47+00:00\",\"dateModified\":\"2016-02-05T19:34:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/\"},\"wordCount\":1864,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fedelt\u00e0_anti-aids.jpg\",\"keywords\":[\"condom\"],\"articleSection\":[\"Aids\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/\",\"name\":\"I giorni del condom - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fedelt\u00e0_anti-aids.jpg\",\"datePublished\":\"2005-10-10T10:26:47+00:00\",\"dateModified\":\"2016-02-05T19:34:33+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fedelt\u00e0_anti-aids.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/10\\\/fedelt\u00e0_anti-aids.jpg\",\"width\":323,\"height\":156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-giorni-del-condom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I giorni del condom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I giorni del condom - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/","og_locale":"it_IT","og_type":"article","og_title":"I giorni del condom - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-10-10T10:26:47+00:00","article_modified_time":"2016-02-05T19:34:33+00:00","og_image":[{"width":323,"height":156,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I giorni del condom","datePublished":"2005-10-10T10:26:47+00:00","dateModified":"2016-02-05T19:34:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/"},"wordCount":1864,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg","keywords":["condom"],"articleSection":["Aids"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/","name":"I giorni del condom - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg","datePublished":"2005-10-10T10:26:47+00:00","dateModified":"2016-02-05T19:34:33+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/10\/fedelt\u00e0_anti-aids.jpg","width":323,"height":156},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-giorni-del-condom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I giorni del condom"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1548"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1548\/revisions"}],"predecessor-version":[{"id":30402,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1548\/revisions\/30402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30401"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}