{"id":1470,"date":"2005-09-22T17:12:42","date_gmt":"2005-09-22T15:12:42","guid":{"rendered":""},"modified":"2016-04-11T09:03:52","modified_gmt":"2016-04-11T07:03:52","slug":"altamura-la-strage-delle-innocenti","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/","title":{"rendered":"&#8221;Altamura. La strage delle innocenti&#8221;."},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32548\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg\" alt=\"Altamura\" width=\"250\" height=\"161\" \/>Pubblicato in <strong>Cristianit\u00e0<\/strong> n. 287-288, anno XXVII, marzo-aprile 1999<\/div>\n<p style=\"text-align: center;\"><em>Un falso storico contro l\u2019Insorgenza italiana<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Oscar Sanguinetti<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>1. Il fatto<\/strong><\/div>\n<p style=\"text-align: justify;\">Il <em>Corriere della Sera<\/em> di mercoled\u00ec 17 febbraio 1999 ha pubblicato con ampio risalto sulla prima delle sue pagine culturali un articolo di Maria Antonietta Macciocchi dal titolo <em>Altamura. La strage delle innocenti<\/em> (1).<\/p>\n<p style=\"text-align: justify;\">Nell\u2019articolo \u00e8 narrato un fatto di sangue che sarebbe accaduto duecento anni or sono, nel corso della guerra civile che nella prima met\u00e0 del 1799 vide contrapposte le popolazioni del Regno di Napoli &#8211; inquadrate in gran parte nell\u2019esercito della Santa Fede, guidato dal cardinale Fabrizio Ruffo dei duchi di Baranello (1744-1827), vicario generale di re Ferdinando IV di Borbone (1751-1825) &#8211; e i rivoluzionari francesi, affiancati dalle milizie della giacobina Repubblica Napoletana, proclamata il 21 gennaio dello stesso anno.<\/p>\n<p style=\"text-align: justify;\">Secondo la studiosa, le truppe sanfediste avrebbero perpetrato, nel corso del saccheggio seguito all\u2019espugnazione della citt\u00e0 pugliese di Altamura, roccaforte giacobina, nel maggio 1799, lo <em>&#8220;stupro di massa&#8221;<\/em> e il massacro di quaranta religiose di clausura, di cui non viene specificato l\u2019ordine di appartenenza, ma che sarebbero orsoline, secondo le fonti di cui si \u00e8 avvalsa.<\/p>\n<p style=\"text-align: justify;\"><strong>2. La narrazione.<\/strong><\/p>\n<p style=\"text-align: justify;\">Maria Antonietta Macciocchi nasce il 22 luglio 1922 a Isola del Liri, in provincia di Frosinone; nel 1942 aderisce al Partito Comunista Italiano e nel 1950 si laurea in storia dell\u2019arte all\u2019Universit\u00e0 La Sapienza di Roma. Sposa il giornalista Alberto Jacoviello, dal quale poi divorzier\u00e0. Dal 1956 al 1961 dirige il settimanale comunista <em>Noi donne<\/em> e dal 1961 al 1968 la rivista, sempre comunista, <em>Vie nuove<\/em>; \u00e8 quindi corrispondente de <em>l\u2019Unit\u00e0<\/em>, l\u2019organo ufficiale del Partito Comunista Italiano, da Algeri, da Bruxelles e da Parigi.<\/p>\n<p style=\"text-align: justify;\">Nel 1968 \u00e8 eletta deputata nelle file del PCI. Nel 1971 entra in dissenso con la linea ufficiale del partito, che di conseguenza non la ricandida al Parlamento. Nel 1972 si trasferisce a Parigi, dove consegue il dottorato in scienze politiche alla Sorbona e ottiene un lettorato all\u2019universit\u00e0 di Parigi VIII a Vincennes. Nel 1977 lascia il PCI e aderisce al Partito Radicale, nelle cui liste \u00e8 eletta nel 1979 sia alla Camera dei Deputati, sia al Parlamento Europeo.<\/p>\n<p style=\"text-align: justify;\">\u00c8 ancora parlamentare europea dal 1984 al 1989 con la Sinistra Indipendente. Collabora attualmente con i quotidiani <em>Corriere della Sera<\/em>, <em>Le Monde<\/em>, di Parigi, e <em>El Pa\u00eds<\/em>, di Madrid. \u00c8 promotrice della Convenzione di Venezia degli intellettuali europei e nel 1986 riceve dal governo francese l\u2019<em>Ordre des Arts et des Lettres<\/em>.<\/p>\n<p style=\"text-align: justify;\">Ha pubblicato una quindicina di libri &#8211; per lo pi\u00f9 su temi interni al movimento rivoluzionario italiano ed europeo -, gli ultimi dei quali dedicati alle due maggiori esponenti femminili della Repubblica Napoletana, Eleonora de Fonseca Pimentel (1752-1799) e Luisa Sanfelice (1764-1800), entrambe vittime della <em>&#8220;ferocia misogina dei crocesegnati&#8221;<\/em>, ovvero dei sanfedisti (2).<\/p>\n<p style=\"text-align: justify;\">Prendendo spunto dal clamore suscitato da una sentenza della Corte di Cassazione relativa a un caso di stupro e sfavorevole alla vittima &#8211; sentenza definita senza mezzi termini <em>&#8220;sgangherata e beffarda&#8221;<\/em> -, la scrittrice introduce il tema, connesso al primo, del duecentesimo anniversario dei moti repubblicani di Altamura, del quale sono in corso rievocazioni da parte di un comitato locale, e di uno <em>&#8220;stupro di massa consumato dalle bande dei sanfedisti contro le suore di clausura del Monastero del Soccorso&#8221; <\/em>di quella citt\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019iniziativa nasce dalla scoperta fortuita, nel fondo <em>Ginguen\u00e9<\/em> (3) della Biblioteca Richelieu di Parigi, del diario manoscritto relativo al saccheggio della citt\u00e0 pugliese, in cui l\u2019episodio dello stupro sarebbe narrato con efferati particolari. L\u2019episodio sarebbe divenuto oggetto dell\u2019attenzione della scrittrice non solo perch\u00e9 giudicato particolarmente grave e odioso e perch\u00e9 ne ricorre il secondo centenario, ma anche in quanto suonerebbe come l\u2019ennesima conferma della tesi femminista secondo cui la violenza sessuale sulle donne, e in generale l\u2019oppressione dell\u2019elemento femminile, sarebbero un dato strutturale della societ\u00e0 occidentale, da cui le interessate dovrebbero emanciparsi attraverso un\u2019azione politica e sociale organizzata.<\/p>\n<p style=\"text-align: justify;\">Secondo questa prospettiva, lungo i secoli si sarebbe attuato un ininterrotto <em>&#8220;martirio delle donne&#8221;<\/em>, di cui sarebbero responsabili non soltanto il maschio <em>uti singulus<\/em>, ma anche e soprattutto le leggi, il &#8220;sistema&#8221;, ovvero le istituzioni sociali e religiose. Alla radice di tale oppressione plurisecolare sarebbe una ideologia &#8220;maschilista&#8221;, misogina e illiberale, che risalirebbe in ultima analisi alla cultura e alla mentalit\u00e0 cattoliche &#8211; o, forse, a una concezione del cristianesimo &#8220;deviata&#8221; in quanto istituzionalizzata &#8211; e al potere esercitato dalla Chiesa sulle coscienze.<\/p>\n<p style=\"text-align: justify;\">Questa mentalit\u00e0 sarebbe particolarmente radicata in correnti ideologiche considerate come avverse pregiudizialmente alla modernit\u00e0, di cui il sanfedismo sarebbe l\u2019estrema manifestazione (4). La figura del cardinale Ruffo (5) e quella di re Ferdinando IV di Borbone, che rappresentano rispettivamente il &#8220;sacerdozio&#8221; e il &#8220;dispotismo&#8221;, ovvero i due cardini della repressione istituzionale, vengono cos\u00ec percepite come gli emblemi della pi\u00f9 bieca repressione anti-femminile.<\/p>\n<p style=\"text-align: justify;\">La responsabilit\u00e0 del &#8220;martirio&#8221; di Altamura e delle esecuzioni di numerosi &#8220;patrioti&#8221;, vittime della giustizia borbonica dopo la caduta della Repubblica Napoletana &#8211; in particolare le donne, due volte martiri, della libert\u00e0 e della condizione femminile -, viene attribuita in ultima istanza alla Chiesa e al Papa. Pertanto la Macciocchi, che pure si dichiara favorevole alla <em>&#8220;rievangelizzazione del mondo&#8221;<\/em> &#8211; che equivarrebbe curiosamente solo a <em>&#8220;una Chiesa riconciliata con il Vangelo&#8221;<\/em> e non a un mondo riconciliato con la Chiesa, quindi con il Vangelo -, si sente autorizzata a domandare pressantemente a Papa Giovanni Paolo II, definito un <em>&#8220;Papa colossale&#8221; <\/em>(6), di aggiungere l\u2019eccidio delle <em>&#8220;innocenti&#8221;<\/em> di Altamura alla lista degli atti di contrizione che la Chiesa sarebbe prossima a compiere in occasione del Giubileo dell\u2019anno 2000.<\/p>\n<p style=\"text-align: justify;\">Questo gesto, inoltre, dovrebbe essere accompagnato dalla condanna ufficiale del cardinale calabrese, reo di aver insignito del nome di <em>&#8220;Esercito della Santa Fede un\u2019accozzaglia di assassini e di stupratori&#8221;<\/em>, troppo a lungo <em>&#8220;difeso da una fitta rete di complicit\u00e0 che passa per gli intellettuali borbonici, i fascisti e persino la Chiesa&#8221;<\/em>. La condanna dovrebbe essere estesa a re Ferdinando IV <em>&#8220;<\/em>[&#8230;] <em>che allag\u00f2 del sangue delle sue vittime tutta Napoli&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Considerazioni storiche<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019episodio di Altamura e il modo con cui \u00e8 affrontato dalla Macciocchi si prestano ad alcuni rilievi, sia sul piano della verit\u00e0 dei fatti &#8211; ovvero sul piano storico, con la sua premessa di metodologia storiografica -, sia su quello politico ed etico in generale. Va premesso che la Macciocchi aveva gi\u00e0 fatto menzione tanto delle suore di Altamura &#8211; senza per\u00f2 citare come fonte il diario anonimo parigino, che peraltro avrebbe gi\u00e0 dovuto conoscere -, quanto del <em>mea culpa<\/em> cattolico nella sua opera su Luisa Sanfelice, pubblicata nel 1998 (7).<\/p>\n<p style=\"text-align: justify;\"><strong><em>3.1. Le fonti a disposizione<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Sotto il profilo storico, il fatto rievocato &#8211; oltre a essere tutt\u2019altro che inedito &#8211; poggia su basi molto fragili, se non del tutto inesistenti. Non risulta infatti dalla stragrande maggioranza delle fonti che vi sia stato ad Altamura nel 1799 un eccidio di religiose, tanto meno con le modalit\u00e0 particolarmente efferate denunciate. L\u2019unico dato certo \u00e8 che ad Altamura vi sono stati un assedio e una battaglia, culminati con l\u2019espugnazione della citt\u00e0 murata da parte dei &#8220;crociati&#8221; e con il saccheggio &#8211; non esente da tutte le intuibili forme di violenza privata proprie della rappresaglia -, che venne peraltro temperato proprio dal cardinale Ruffo e dai suoi ufficiali. Inoltre, non risulta che esistano rami claustrali delle orsoline, n\u00e9 che vi sia mai stato un convento di tale ordine in citt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Queste riserve sono state espresse da uno storico di Altamura, Giuseppe Castelli &#8211; i cui antenati furono fra i difensori della citt\u00e0 in occasione dell\u2019assedio sanfedista del 1799 -, che in un articolo sul quotidiano <em>Avvenire<\/em> ha precisato che dall\u2019abbondante documentazione esistente &#8211; fra cui tutto quanto pubblicato in occasione del primo centenario dei fatti, non escluse le dichiarazioni di testimoni oculari, raccolti molti anni prima &#8211; non risulta alcun fatto nei termini riferiti dalla Macciocchi (8).<\/p>\n<p style=\"text-align: justify;\">Fra le fonti disponibili figurano non poche cronache locali del tempo, anzitutto i resoconti di Gian Carlo Berarducci (1762-1837) e del sacerdote Vitangelo Bisceglia (1749-1817), pubblicati dallo storico Giuseppe Ceci (1863-1938) nel 1900 (9). Il primo, pi\u00f9 laconico, si limita ad affermare che nel sacco di Altamura <em>&#8220;si contano <\/em>[&#8230;] <em>due monache, una morta e l\u2019altra ferita&#8221; <\/em>(10); il secondo precisa che <em>&#8220;<\/em>[&#8230;] <em>il cardinale Ruffo, per risparmiare le claustrali dalle violenze, ordin\u00f2 che fossero uscite <\/em>[<em>sic<\/em>] <em>dalla citt\u00e0, ed avessero occupata la casa di Montecalvario, dove con esse furono trasportate molte dame&#8221; <\/em>(11).<\/p>\n<p style=\"text-align: justify;\">Il curatore precisa in una nota al testo: <em>&#8220;Talune <\/em>[donne]<em> per minacce, altre co\u2019 doni presi dal saccheggio, altre lusingate da promesse di matrimonio, si prestarono alle infami voglie&#8221; <\/em>(12); parla per\u00f2 di <em>&#8220;prostituzione&#8221;<\/em> e non di violenze, e non dice nulla sulle religiose. Medesima impostazione ha l\u2019abate Domenico Sacchinelli (1766-1844), il quale, scrivendo nel 1836, sostiene che <em>&#8220;<\/em>[&#8230;]<em> le donne Altamurane (facendo le dovute eccezioni) produssero all\u2019armata Cristiana quegli stessi effetti, che un tempo cagionarono ai soldati di Annibale le donne Capuane&#8221; <\/em>(13).<\/p>\n<p style=\"text-align: justify;\">Nel 1899, in occasione del primo centenario del sacco di Altamura, il senatore pugliese Ottavio Serena (1837-1914) d\u00e0 alle stampe un saggio su <em>Altamura nel 1799<\/em>, non favorevole al cardinale Ruffo, che non fa cenno alcuno dell\u2019episodio raccontato dalla Macciocchi e pubblica l\u2019importante relazione del parroco della cattedrale di Altamura, che, attingendo ai registri parrocchiali, riporta i nomi di tutte le vittime del saccheggio del 10 maggio &#8211; in totale <em>trentasette<\/em>, cio\u00e8 tre di meno delle asserite vittime religiose &#8211; e la precisa indicazione:<em> &#8220;Ora in Altamura non vi fu mai un monastero di Orsoline; le monache Clarisse del Soccorso prima dell\u2019assalto abbandonarono il monastero&#8221; <\/em>(14).<\/p>\n<p style=\"text-align: justify;\">Inoltre, nell\u2019appendice documentaria sono edite le <em>Notizie<\/em> di un <em>Anonimo altamurano<\/em>, il quale, a proposito delle <em>&#8220;Signore Monache di Clausura d\u2019ambi i Monasteri del Soccorso e S. Chiara&#8221; <\/em>(15), scrive che il cardinale <em>&#8220;<\/em>[&#8230;]<em> ordin\u00f2 che trasportate fossero nelle rispettive abitazioni ed ivi fossero custodite&#8221;<\/em> (16); quindi <em>&#8220;<\/em>[&#8230;]<em> anche le clausure delle monache sacrate se ne uscirono, e lasciarono in abbandono gli Monasteri e si ritirarono tutte unite in casa sicura di un Signore con guardia permessa dal Ruffo&#8221;<\/em> (17).<\/p>\n<p style=\"text-align: justify;\">Lo stesso anonimo cronista altamurano, testimone dei fatti, \u00e8 ripreso senza riserve dallo storico degli anni 1930 Massimo Lelj (1888-1962) &#8211; di orientamento sfavorevole ai sanfedisti e in genere piuttosto ben documentato &#8211; al capitolo XI della sua opera <em>La Santa Fede. La spedizione del cardinale Ruffo (1799) <\/em>(18).<\/p>\n<p style=\"text-align: justify;\">Infine, la tesi della protezione richiesta dalle religiose al cardinale \u00e8 confermata dal tenente colonnello borbonico Domenico Petromasi, commissario di guerra presso l\u2019armata sanfedista ed estensore di una cronaca della riconquista del Regno di Napoli, che \u00e8 testimone oculare senz\u2019altro interessato dei fatti, ma fondamentalmente equilibrato e onesto nel suo resoconto (19).<\/p>\n<p style=\"text-align: justify;\"><strong><em>3.2. Le fonti utilizzate<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Se mancano testimonianze tali da accreditare la versione della Macciocchi, a smentire la realt\u00e0 dell\u2019eccidio, per la loro intrinseca debolezza e inattendibilit\u00e0, sono proprio le fonti utilizzate dalla scrittrice. Francamente non basta un diario &#8211; anche se manoscritto e inedito, e per di pi\u00f9 letto dalla studiosa <em>&#8220;quasi tremante&#8221;<\/em> &#8211; per stabilire la verit\u00e0 di un fatto storico.<\/p>\n<p style=\"text-align: justify;\">Tanto pi\u00f9 se il cronista non \u00e8 testimone oculare dei fatti e, come traspare dai toni &#8220;apocalittici&#8221; utilizzati, si tratta di un <em>&#8220;giovane che si era battuto&#8221;<\/em>, quindi di un militante rivoluzionario, di un giacobino, ossia di una persona pregiudizialmente avversa per ragioni ideologiche ai sanfedisti.<\/p>\n<p style=\"text-align: justify;\">Inoltre la prosa del cronista non convince: \u00e8 troppo stranamente simile a quella di una qualunque delle gazzette giacobine del periodo, per le quali era pi\u00f9 importante combattere la &#8220;battaglia delle idee&#8221; che riferire la verit\u00e0. Basta aprirne una a caso, a Napoli come a Brescia o a Milano, per accorgersi che le vicende dell\u2019Insorgenza sono generalmente riferite negli stessi termini e con i medesimi toni, faziosi e altamente emotivi, dell\u2019anonimo. Quanto ai <em>&#8220;testi pi\u00f9 solidi&#8221;<\/em> cui la studiosa dice di essersi rifatta, sono molto dubbi il loro valore e la loro attendibilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Tutti sono marcatamente favorevoli alla Rivoluzione: Jules Michelet (1798-1874), anticlericale e partigiano a oltranza dell\u2019Ottantanove (20); Carlo Botta (1766-1837), ex giacobino, autore di un\u2019ampia sintesi della storia d\u2019Italia che si avvale spesso di fonti di dubbio valore (21); Pietro Colletta (1775-1831), prima seguace di Gioacchino Murat (1767-1815), poi carbonaro, autore di una <em>Storia del Reame di Napoli dal 1734 al 1825<\/em>, sulla quale lo stesso curatore esprime il seguente giudizio: <em>&#8220;Quella del Colletta \u00e8 una delle opere che maggiormente hanno bisogno di chiarimenti e di delucidazioni per esser ricca di errori, o voluti dall\u2019autore per motivi di ordine politico o personale, o da attribuire alle fonti da lui usate&#8221; <\/em>(22); Vincenzo Cuoco (1770-1823), gi\u00e0 protagonista della Repubblica Napoletana (23); Adolf Wilhelm Theodor Stahr (1805-1876), autore di <em>Die Republikaner in Neapel<\/em>, &#8220;I repubblicani a Napoli&#8221;, il cui anonimo traduttore precisa che <em>&#8220;l\u2019opera che pubblichiamo<\/em>[<em>,..<\/em>]<em> tradotta dal tedesco,<\/em> <em>appartiene a quel genere commisto di vero e di falso del quale pi\u00f9 si piacque questo secolo e che romanzo-storico vien detto&#8221;<\/em> (24).<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec non si capisce se la scena descritta da Stahr, nella quale il diacono cardinale Ruffo &#8211; che, ammette per inciso lo studioso, <em>&#8220;<\/em>[&#8230;] <em>sentiva talora qualche piccolo accenno di umanit\u00e0&#8221;<\/em> (25) &#8211; celebra la Messa al campo, sia una forzatura romanzesca oppure l\u2019autore &#8211; non alieno da studi presso facolt\u00e0 teologiche protestanti &#8211; alluda a una partecipazione del cardinale stesso alla Messa nel suo limitato ruolo ministeriale (26).<\/p>\n<p style=\"text-align: justify;\">La sorpresa maggiore, per\u00f2, deriva dalla consultazione delle opere di Giovanni La Cecilia (1801-1880), perch\u00e9 si constatata che gran parte del testo della Macciocchi, sia fra virgolette sia in parafrasi, come pure <em>tutti<\/em> gli autori citati come fonti autorevoli e pi\u00f9 solide, sono ripresi letteralmente da un volume del polemista napoletano (27).<\/p>\n<p style=\"text-align: justify;\">In particolare, la descrizione della truculenta scena dell\u2019eccidio non \u00e8 tratta dalle pagine dell\u2019anonimo &#8220;parigino&#8221;, che sarebbe stato senz\u2019altro pi\u00f9 autorevole, ma, <em>senza avvertirne il lettore<\/em>, dalla prosa dello scrittore mazziniano, confidando forse sul fatto che, siccome lo stile dei due autori \u00e8 affine, il lettore inavvertito non se ne accorga.<\/p>\n<p style=\"text-align: justify;\">Anche La Cecilia, comunque, non suffraga il fatto specifico con alcuna &#8220;pezza d\u2019appoggio&#8221;, anzi ricorre al discorso diretto (28), come se si trattasse di una parentesi romanzata nella narrazione. Ci\u00f2 avvalora l\u2019ipotesi che sia una interpolazione dell\u2019autore, fatta quanto meno a scopo narrativo, di spunti forniti da altri.<\/p>\n<p style=\"text-align: justify;\">Del resto, La Cecilia, carbonaro e poi mazziniano, \u00e8 un militante a tempo pieno, un &#8220;rivoluzionario di professione&#8221; &#8211; in una nota del volume confida di credere che <em>&#8220;<\/em>[&#8230;] <em>il papato fu ed \u00e8 il flagello d\u2019Italia&#8221;<\/em> (29) -, non uno storico ma un propagandista e un uomo d\u2019azione, giudicato da Alessandro Galante Garrone come autore di <em>&#8220;pittoresche romanzature&#8221; <\/em>(30) e una <em>&#8220;testa calda&#8221;<\/em> (31).<\/p>\n<p style=\"text-align: justify;\">Il libro in questione colpisce immediatamente per la sua scarsa scientificit\u00e0. La versione dei fatti \u00e8 inattendibile, le fonti citate sparute e quasi mai di prima mano, l\u2019apparato critico nullo, il linguaggio inadeguato a un\u2019opera storica. Lo studio, quindi, si colloca all\u2019interno del genere letterario del &#8220;romanzo d\u2019appendice&#8221; &#8211; molto in voga nell\u2019Ottocento e in verit\u00e0 mai tramontato -, piuttosto che in quello storiografico.<\/p>\n<p style=\"text-align: justify;\">La Cecilia si sforza di trasmettere della monarchia borbonica di Napoli l\u2019immagine di un regime corrotto e inetto, che si avvale di ogni bassezza e di agenti spregevoli &#8211; per esempio, del cardinale Ruffo dice che manteneva un<em> &#8220;Harem di corrotte femmine&#8221;<\/em> (32) &#8211; pur di conservare il potere.<\/p>\n<p style=\"text-align: justify;\">Per rafforzare questo quadro La Cecilia non esita a far dipingere <em>ad hoc<\/em> ben cinquanta illustrazioni a colori, che raffigurano scene fra le pi\u00f9 inverosimili &#8211; ma efficaci -, come quella del capitano borbonico Gennaro Rivelli, aiutante di campo del cardinale e particolarmente inviso a La Cecilia, che offre a Ruffo le teste mozzate di una madre incinta e della bambina strappatale dal ventre, al fine d\u2019intascare due volte la taglia posta dal re sulle teste dei giacobini (33).<\/p>\n<p style=\"text-align: justify;\">In un\u2019epoca in cui non esisteva la televisione, si pu\u00f2 intuire come queste scene s\u2019imprimessero nell\u2019immaginario del lettore e dessero vita ad altrettante leggende. Pubblicato alla vigilia dell\u2019invasione garibaldina del Regno di Napoli &#8211; e ripreso da non pochi scrittori politici &#8220;nazionali&#8221; che, evidentemente, lo hanno trovato utile (34) -, \u00e8 difficile non vedere il volume come un lavoro di propaganda, inteso a &#8220;preparare il terreno&#8221; alle camicie rosse di Giuseppe Garibaldi (1807-1882).<\/p>\n<p style=\"text-align: justify;\">Questa \u00e8 l\u2019opera da cui la Macciocchi trae il succo della sua argomentazione: quando si trattano temi delicati e complessi come quello evocato, che stanno a cuore a molti, sia favorevoli che contrari, sarebbe per\u00f2 opportuno fondare la propria argomentazione su &#8220;pezze d\u2019appoggio&#8221; un po\u2019 meno fragili e screditate.<\/p>\n<p style=\"text-align: justify;\">Per completezza di quadro, occorre esprimere non poche riserve sullo stile. In una persona di cultura, e in particolare in uno storico, i gi\u00e0 segnalati toni altamente emotivi &#8211; verrebbe spontaneo scrivere &#8220;che rasentano l\u2019isteria&#8221; &#8211; di cui risente pesantemente la prosa dell\u2019illustre pubblicista sono stonature fatali.<\/p>\n<p style=\"text-align: justify;\">Alcuni passaggi meritano di essere riportati: <em>&#8220;Su Parigi l\u2019aria era fredda, pioveva, mentre continuavo a decifrare quasi tremante il manoscritto che avevo messo sul leggio. Tutto sembrava silenzio&#8221;<\/em>; il diario scoperto a Parigi \u00e8 un <em>&#8220;eccezionale testo&#8221;<\/em>, scritto <em>&#8220;con una calligrafia limpida e una prosa poderosa&#8221;<\/em>; la folla di Altamura che ascolta la rievocazione della stessa studiosa \u00e8 <em>&#8220;fitta, bella e severa, assiepata davanti al monumento della Libert\u00e0&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">Frasi a effetto, che scadono per\u00f2 in autentiche contumelie e &#8220;clave ideologiche&#8221; quando, passando ai fatti storici, la Macciocchi descrive l\u2019esercito della Santa Fede come un insieme di <em>&#8220;bande&#8221;<\/em> o di <em>&#8220;orde&#8221;<\/em>,<em> &#8220;un\u2019accozzaglia di banditi e di stupratori&#8221;<\/em>, ignorando o dimenticando che con il cardinale Ruffo &#8211; <em>&#8220;un vero bandito&#8221;<\/em>, che <em>&#8220;si abbeverava di sangue&#8221;<\/em> &#8211; combattevano reparti dell\u2019esercito regolare napoletano.<\/p>\n<p style=\"text-align: justify;\">Oppure quando lascia cadere attributi enigmatici sui sanfedisti, come quando &#8211; riprendendo acriticamente un tema caro a La Cecilia &#8211; ricorda che il <em>&#8220;mostro&#8221;<\/em> Gennaro Rivelli, aiutante di campo di Ruffo, era stato <em>&#8220;meni\u00f1o&#8221;<\/em>, ovvero <em>&#8220;fratello di latte&#8221;<\/em> di re Ferdinando, lasciando intendere velatamente che il capo sanfedista e il re avessero condiviso chiss\u00e0 quali turpitudini (35).<\/p>\n<p style=\"text-align: justify;\">Oppure ancora quando, per accentuare la corresponsabilit\u00e0 del cardinale nei massacri, parla di una <em>&#8220;piena assoluzione della Chiesa&#8221;<\/em> che Ruffo avrebbe impartito ai suoi accoliti prima di lanciarli al massacro e al saccheggio, cosa da intendersi eventualmente nel senso di mancata o ridotta sanzione giudiziaria, civile o ecclesiastica, e non certo di assoluzione sacramentale, l\u2019autentica <em>&#8220;piena assoluzione della Chiesa&#8221;<\/em>, dato che, essendo solo diacono, <em>&#8220;in virt\u00f9 del <\/em>[suo] <em>sacro ministero&#8221;<\/em>, il cardinale non poteva assolvere proprio nessuno.<\/p>\n<p style=\"text-align: justify;\">Certo la riconquista borbonica del Regno di Napoli avviene e culmina in un quadro di guerra civile, che causa profonde divisioni e odi. Essa costa sangue, come in genere tutte le guerre civili, ma nel 1799 la popolazione \u00e8 tutta con il re. E non si pu\u00f2 dimenticare che gli &#8220;illuminati&#8221; dirigenti della Repubblica Napoletana &#8211; in via di &#8220;beatificazione laica&#8221; &#8211; nei nove mesi della loro permanenza al potere comminarono migliaia di condanne, nel tentativo di &#8220;purificare&#8221; la repubblica proprio dallo spirito sanfedista.<\/p>\n<p style=\"text-align: justify;\">Come meravigliarsi che vi siano state vendette, anche sanguinose, da parte degli avversari? Del resto, proprio ad Altamura, come riferisce Lelj, i giacobini assediati, prima di fuggire ingloriosamente, avevano passato a fil di spada circa cinquanta realisti, politici e ostaggi, fra i quali pi\u00f9 di un ambasciatore inviato dai sanfedisti (36).<\/p>\n<p style=\"text-align: justify;\">Di queste rappresaglie il cardinale Ruffo, come ormai \u00e8 riconosciuto unanimamente, fu sempre, sia durante la guerra, che soprattutto dopo, moderatore intransigente, indipendentemente dal fallimento dei suoi tentativi di opporsi al re e ai britannici. In conclusione, sotto il profilo storico quello della Macciocchi sembra un modo di accostarsi ai fatti scorretto e dilacerante, che rischia di risvegliare artificialmente passioni civili del tutto fuori luogo.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 questo il metodo giusto per iniziare una serena e fondata revisione della storia italiana e per ricostruire una memoria comune del nostro popolo, sulla quale fondare &#8211; come \u00e8 pressante necessit\u00e0 &#8211; nuove regole di convivenza civile.<\/p>\n<p style=\"text-align: justify;\"><strong>4. Considerazioni politiche<\/strong><\/p>\n<p style=\"text-align: justify;\">Tutti questi elementi lasciano intravedere la trama di fondo, rigidamente ideologica, in cui l\u2019intervento si situa. La storia, lo studio dei fatti del passato, in questa prospettiva, diventa puramente strumentale a obiettivi extra-storici, in genere politici o, nel caso della studiosa, funzionali a una militanza ideologica che talora va oltre la politica.<\/p>\n<p style=\"text-align: justify;\">Rievocare un massacro di monache, vero o falso che sia, per la Macciocchi serve solo alla &#8220;prassi&#8221;, cio\u00e8 a &#8220;mettere in azione&#8221; persone e gruppi umani &#8211; quanto meno il comitato delle sue <em>&#8220;amiche&#8221;<\/em> di Altamura &#8211; in una prospettiva assunta apoditticamente e pregiudizialmente &#8211; verrebbe da dire &#8220;metafisicamente&#8221; &#8211; come buona, ovvero il trionfo del femminismo.<\/p>\n<p style=\"text-align: justify;\">E se i fatti scarseggiano o sono dubbi o mancano del tutto, tanto peggio per i fatti! Bastano quattro frasi di un romanzo d\u2019appendice e un diario ideologizzato e i fatti si piegano al <em>wishful thinking<\/em> o alla &#8220;volont\u00e0 di potenza&#8221; di chi scrive. E in questo la studiosa sembra davvero non avere dimenticato le sue radici culturali marxiste&#8230;<\/p>\n<p style=\"text-align: justify;\">Quest\u2019ultimo tratto suggerisce alcune riflessioni di tipo generale, che si traducono in altrettanti quesiti. Con tanti tragici casi umani davanti agli occhi, come mai questo interesse per una categoria femminile, normalmente non particolarmente in auge negli ambienti femministi?<\/p>\n<p style=\"text-align: justify;\">E perch\u00e9 un interesse che si spinge fino a rivendicare le doti delle religiose, quando si dimentica che cosa ne \u00e8 stato &#8211; non solo delle doti, ma dei monasteri stessi, soprattutto nel Mezzogiorno &#8211; in altre condizioni e sotto altri regimi, giudicati invece con favore o comunque meno sgradevoli di quello borbonico restaurato, come le repubbliche giacobine o lo Stato italiano post-unitario?<\/p>\n<p style=\"text-align: justify;\">\u00c8 proprio vero che, quando si tratta di &#8220;fare rivoluzione&#8221;, marxisti o femministe non guardano tanto per il sottile quanto alla &#8220;materia prima&#8221; disponibile. L\u2019illustre esponente progressista si sofferma sulla &#8220;pagliuzza&#8221; sanfedista, peraltro non provata, e dimentica l\u2019enorme &#8220;trave&#8221; costituita dagl\u2019innumerevoli eccidi &#8211; di uomini e di donne, anche religiose &#8211; e dai saccheggi con i quali i francesi e le milizie giacobine hanno funestato per anni regioni e province intere in Italia &#8211; e in tutta Europa -, soprattutto nel Mezzogiorno, dove infieriscono per oltre quindici anni (37).<\/p>\n<p style=\"text-align: justify;\">E sempre nella predetta metafora evangelica, sarebbe da chiedere alla studiosa da che parte si situano i massacri di migliaia di religiosi e di religiose perpetrati dai comunisti e dagli anarchici durante la guerra civile spagnola, quando monache e frati vennero uccisi non perch\u00e9 ricchi di famiglia o perch\u00e9 di piacevole aspetto &#8211; ma quale &#8220;misoginia&#8221; si pu\u00f2 imputare ai <em>&#8220;crocesegnati&#8221;<\/em> nella versione dei fatti della Macciocchi? &#8211; e neppure sotto l\u2019influsso del delirio da saccheggio, ma, freddamente, <em>in quanto religiosi<\/em>, e nessuno si cur\u00f2 che fossero <em>&#8220;innocenti&#8221;<\/em> o meno, per riallacciarsi al titolo dell\u2019articolo.<\/p>\n<p style=\"text-align: justify;\">E come non ricordare, da ultimo, l\u2019annientamento di intere chiese e comunit\u00e0 religiose &#8211; certamente composte da un\u2019alta percentuale di donne &#8211; attraverso la deportazione nel GuLag in tutti i paesi sovietizzati a partire dal 1918? Ha letto la Macciocchi quale fu per esempio la sorte dei religiosi russi deportati nel <em>Lager<\/em> delle isole Solovki a nord-est di Leningrado, nel Mar Bianco, ai limiti del Circolo Polare Artico, di cui solo recentemente &#8211; dopo ottant\u2019anni dal martirio &#8211; sono state ricostruite le indicibili sofferenze (38)?<\/p>\n<p style=\"text-align: justify;\">Riguardo, infine, al tema della Chiesa e del perdono: certo, la Chiesa e il Papa, quando imperativi di verit\u00e0 lo hanno richiesto, non hanno esitato e non esiteranno a rivedere la propria interpretazione consueta di vicende storiche, che hanno visto un cattivo comportamento da parte di cristiani. Cos\u00ec, se l\u2019eccidio di Altamura fosse autentico, esso potrebbe di certo finire nel novero di tali vicende.<\/p>\n<p style=\"text-align: justify;\">Non risulta invece che i responsabili di almeno ottanta milioni di vittime &#8211; uomini e donne, laici e religiosi -, a fianco dei quali ha militato per anni e forse ancora milita la Macciocchi, abbiano ancora in qualche forma chiesto perdono del loro operato. Quale senso ha, in questa prospettiva oggettivamente mutila e &#8220;squilibrata&#8221;, avanzare arrogantemente richieste come quelle formulate, se non cercare di sfruttare furbescamente &#8211; o marxisticamente &#8211; tutte le opportunit\u00e0, tutte le &#8220;contraddizioni&#8221; &#8211; reali o create ad arte &#8211; offerte dalla situazione, sforzandosi nel caso specifico di &#8220;arruolare&#8221; alla propria causa, sempre pi\u00f9 in crisi, le forze ideali dell\u2019avversario?<\/p>\n<p style=\"text-align: justify;\"><strong>5. Considerazioni finali<\/strong><\/p>\n<p style=\"text-align: justify;\">Concludendo, un ultimo appunto merita la sede in cui la Macciocchi ha potuto divulgare le sue tesi, pi\u00f9 consone a testate di parte che non al pi\u00f9 diffuso quotidiano italiano. Come mai questo ha ospitato sulla sua prima pagina culturale un contributo cos\u00ec discutibile e gli ha concesso tanto spazio? Semplice ricerca dello <em>scoop<\/em>? &#8220;Simpatia&#8221; di fondo per le tesi? Autorevolezza della scrittrice? O forse un &#8220;segnale&#8221; alla Chiesa e ai vescovi italiani, troppo &#8220;schierati&#8221; in occasione della battaglia parlamentare sulla legge relativa alla procreazione assistita?<\/p>\n<p style=\"text-align: justify;\">Comunque &#8211; tornando a orizzonti maggiori, cio\u00e8 nell\u2019ottica della storia come deposito di esperienze per la politica e come ricostruzione del passato che, se non spiega il presente, almeno lo fonda -, si deve registrare il fatto che, dopo le dichiarazioni d\u2019inesistenza dell\u2019Insorgenza e\/o quelle di perfetta conoscenza dei fatti a essa relativi, si \u00e8 prodotto anche un nuovo tipo di attacco a un momento essenziale della storia degli italiani: il falso storico.<\/p>\n<p style=\"text-align: justify;\"><strong>Note:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(1)<\/strong> Cfr. Maria Antonietta Macciocchi, <em>Altamura. La strage delle innocenti<\/em>, in <em>Corriere della Sera<\/em>, 17-2-1999, p. 33. Tutte le citazioni senza rimando sono tratte da questo articolo.<br \/>\n<strong>(2)<\/strong> Cfr. Eadem, <em>Cara Eleonora. Passione e morte della Fonseca Pimentel nella Rivoluzione Napoletana<\/em>, Mondadori, Milano 1996; ed Eadem, <em>L\u2019amante della Rivoluzione. La vera storia di Luisa Sanfelice e della Repubblica Napoletana del 1799<\/em>, Mondadori, Milano 1998. Sulla scrittrice vedi <em>I deputati dell\u2019ottavo parlamento repubblicano<\/em>, La Navicella, Roma 1979, <em>sub nomine<\/em>;<em> Le donne italiane. Il chi \u00e8 del \u2019900<\/em>, a cura di Miriam Mafai, Rizzoli, Milano 1993, p. 272; e <em>Who\u2019s who in Italy<\/em>, Sutter\u2019s international red series, Milano 1998, vol. II, pp. 1147-1148.<br \/>\n<strong>(3)<\/strong> Pierre Louis Ginguen\u00e9 (1748-1816) fu letterato rivoluzionario e uomo politico &#8211; ambasciatore presso la corte sabauda nel 1798 &#8211; nonch\u00e9 autore di una <em>Storia letteraria dell\u2019Italia <\/em>in 10 volumi, scritta fra il 1811 e il 1819, in collaborazione con il giacobino Francesco Saverio Salfi (1759-1832). Fece parte della corrente culturale degli <em>&#8220;id\u00e9ologues&#8221;<\/em>; cadde in disgrazia presso Napoleone Bonaparte (1769-1821) per essersi rifiutato di accettare la nuova costituzione del 1799.<br \/>\n<strong>(4)<\/strong> Sulla Santa Fede vedi Francesco Pappalardo, <em>1799: la crociata della Santa Fede<\/em>, in <em>Quaderni di &#8220;Cristianit\u00e0&#8221;<\/em>, anno II, n. 3, inverno 1985, pp. 34-50, rielaborato in Idem, <em>1799. Rivoluzione e Contro-Rivoluzione nel Regno di Napoli<\/em>, Istituto per la Storia delle Insorgenze, <em>pro manuscripto<\/em>, Milano 1999; e Idem,<em> Il sanfedismo<\/em>, in IDIS. Istituto per la Dottrina e l\u2019Informazione Sociale, <em>Voci per un &#8220;Dizionario del Pensiero Forte&#8221;<\/em>, a cura di Giovanni Cantoni e con una presentazione di Gennaro Malgieri, Cristianit\u00e0, Piacenza 1997, pp. 215-220. <strong><br \/>\n(5)<\/strong> Su di lui, cfr. Giovanni Ruffo, <em>Il cardinale rosso<\/em>, Calabria Letteraria Editrice, Soveria Mannelli (Catanzaro) 1998.<br \/>\n<strong>(6)<\/strong> Soprattutto &#8211; e forse solo &#8211; perch\u00e9 autore della <em>&#8220;magnifica frase, quella sul genio delle donne&#8221;<\/em> legato in qualche modo &#8211; non \u00e8 ben chiaro il senso della frase della Macciocchi &#8211; alla <em>&#8220;mulieris dignitatem&#8221;<\/em>, la lettera apostolica di Papa Giovanni Paolo II sulla dignit\u00e0 e la vocazione della donna, pubblicata nel 1988 in occasione dell\u2019Anno Mariano.<br \/>\n<strong>(7)<\/strong> Cfr. M. A. Macciocchi, <em>L\u2019amante della Rivoluzione. La vera storia di Luisa Sanfelice e della Repubblica Napoletana del 1799<\/em>, cit., rispettivamente alle pp. 204-209 e 224-227.<br \/>\n<strong>(8)<\/strong> Cfr. Giuseppe Castelli,<em> Troppe leggende sul cardinale Ruffo<\/em>, in <em>Avvenire. Quotidiano d\u2019ispirazione cattolica<\/em>, 25-2-1999; cfr. pure Giovanni Formicola, <em>Altamura, gli errori di Maria Antonietta Macciocchi<\/em>, in <em>Roma<\/em>, 7-3-1999.<br \/>\n<strong>(9)<\/strong> Cfr. <em>Cronache di fatti del 1799<\/em>, a cura di G. Ceci, Tip. Vecchi, Andria (Bari) 1900.<br \/>\n<strong>(10)<\/strong> <em>Diario di Gian Carlo Berarducci<\/em>, in <em>Cronache di fatti del 1799<\/em>, cit., pp. 1-279 (p. 121).<br \/>\n<strong>(11)<\/strong> <em>Memorie storiche contenenti la serie degli avvenimenti che hanno avuto luogo nella citt\u00e0 di Altamura dal principio della rivoluzione fino all\u2019ingresso e dimora dell\u2019armata regia e cristiana nella medesima, vale a dire dal principio di Gennaio 1799 per tutto il mese di Maggio dello stesso anno, scritte nel tempo istesso da un testimonio di vista<\/em>, in <em>Cronache di fatti del 1799<\/em>, cit., pp. 281-399 (p. 391).<br \/>\n<strong>(12)<\/strong> <em>Ibid<\/em>., p. 393, nota 2.<br \/>\n<strong>(13)<\/strong> <em>Memorie storiche sulla vita del Cardinale Fabrizio Ruffo, con osservazioni sulle opere di Cuoco, di Botta e di Colletta. Edizione seconda,<\/em> Tip. Poliglotta, Roma 1895, p. 161.<br \/>\n<strong>(14)<\/strong> Cfr. Ottavio Serena, <em>Altamura nel 1799<\/em>, Casa Editrice Italiana, Roma 1899, p. 79, nota 1.<br \/>\n<strong>(15)<\/strong> <em>Ibid<\/em>., p. 23 dell\u2019appendice.<br \/>\n<strong>(16)<\/strong> <em>Ibidem<\/em>.<br \/>\n<strong>(17)<\/strong> <em>Ibidem<\/em>.<br \/>\n<strong>(18)<\/strong> Cfr. Massimo Lelj, <em>La Santa Fede. La spedizione del cardinale Ruffo (1799)<\/em>, Mondadori, Milano 1936, pp. 127-147.<br \/>\n<strong>(19)<\/strong> Cfr. Domenico Petromasi, <em>Alla riconquista del regno. La marcia del cardinale Ruffo dalle Calabrie a Napoli<\/em>, Editoriale il Giglio, Napoli 1994 (prec. ed. Manfredi, Napoli 1801), p. 71.<br \/>\n<strong>(20)<\/strong> Su di lui vedi Paul Vialleneix, <em>Jules Michelet<\/em>, in <em>L\u2019albero della rivoluzione. Le interpretazioni della Rivoluzione francese<\/em>, a cura di Bruno Bongiovanni e Luciano Guerci, Einaudi, Torino 1989, pp. 481-490.<br \/>\n<strong>(21)<\/strong> Su di lui vedi Walter Maturi (1902-1961), <em>Interpretazioni del Risorgimento. Lezioni di storia della storiografia<\/em>, Einaudi, Torino 1962, pp. 36-91.<br \/>\n<strong>(22)<\/strong> Nino Cortese (1896-1972), in Pietro Colletta, <em>Storia del Reame di Napoli dal 1734 al 1825, <\/em>3 voll., Libreria Scientifica Editrice, Napoli 1956-1957, vol. I, p. XII. Colletta, comunque, descrivendo il saccheggio di Altamura, accenna <em>in meno di una riga<\/em> a <em>&#8220;<\/em>[&#8230;] <em>un convento di vergini profanato&#8221; <\/em>(<em>ibid<\/em>., vol. II, p. 64). Sull\u2019opera di Colletta, vedi il giudizio del <em>Dizionario di Storiografia <\/em>(Bruno Mondadori, Milano 1996, p. 222), secondo cui <em>&#8220;<\/em>[&#8230;] <em>quest\u2019opera storico-memorialistica fu largamente discussa e si rivel\u00f2 un importante strumento politico contro la monarchia borbonica&#8221;<\/em>.<br \/>\n<strong>(23)<\/strong> A proposito di Altamura Cuoco parla <em>&#8220;di cadaveri intrisi di sangue&#8221;<\/em> (Vincenzo Cuoco, <em>Saggio storico sulla rivoluzione di Napoli del 1799, <\/em>a cura di N. Cortese, Vallecchi, Firenze 1926, p. 270), ma \u00e8 smentito dal curatore dell\u2019edizione, che precisa: <em>&#8220;La citt\u00e0 fu data al saccheggio; ma, contrariamente a ci\u00f2 che dice il Cuoco, \u00e8 da avvertire che gli abitanti abbandonarono interamente il paese, al momento della resa&#8221; <\/em>(<em>ibid.<\/em>, p. 271, nota 2). Su di lui vedi Stefano Nutini, <em>Vincenzo Cuoco<\/em>, in <em>L\u2019albero della rivoluzione. Le interpretazioni della Rivoluzione francese<\/em>, cit., pp. 152-158.<br \/>\n<strong>(24)<\/strong> Adolf Wilhelm Theodor Stahr, <em>I repubblicani di Napoli. Romanzo storico<\/em>, 2 voll., G. Lobetti-Bodoni, Pinerolo (Torino) 1854, vol. I, p. I. Stahr, storico prussiano dell\u2019antichit\u00e0 greca e romana, scrittore assai prolifico, dopo un viaggio in Italia, in Svizzera e a Parigi, intrapreso nel 1845 e durato un anno &#8211; a Roma fra l\u2019altro conobbe la sua futura consorte, la letterata Fanny Lewald (1811-1889) -, pubblic\u00f2 alcuni volumi di ricordi di viaggio: <em>Ein Jahr in Italien<\/em> [<em>Un anno in Italia<\/em>, 1847], <em>Herbstmonate in Italien<\/em> [<em>Mesi d\u2019autunno in Italia<\/em>, 1860] e <em>Herbsmonate in Oberitalien<\/em> [<em>Mesi d\u2019autunno in Italia settentrionale<\/em>, 1866], nonch\u00e9 &#8211; unico suo lavoro di epoca moderna &#8211; <em>Die Republikaner in Neapel<\/em>, apparso nel 1849 a Berlino, un <em>romanzo<\/em> storico dedicato alla Repubblica Napoletana del 1799 e, in particolare, alla figura dello storico e militante repubblicano Colletta. Su Stahr vedi <em>Allgemeine Deutsche Biographie<\/em>, 56 voll., Dunder &amp; Humblot, Lipsia 1874-1912, vol. 35, 1893, pp. 403-406.<br \/>\n<strong>(25)<\/strong> <em>Ibid<\/em>., vol. II, p. 115.<br \/>\n<strong>(26)<\/strong> Cfr. <em>ibid<\/em>., vol. II, p. 113.<br \/>\n<strong>(27)<\/strong> Cfr. Giovanni La Cecilia, <em>Storie segrete delle famiglie reali o misteri della vita intima dei Borboni di Francia, di Spagna, di Parma, di Napoli e della famiglia Absburgo-Lorena d\u2019Austria e di Toscana per Giovanni La-Cecilia<\/em> [<em>sic<\/em>], 4 voll., Tip. Toscana Cecchi, Genova-Firenze 1859, vol. II, <em>I Borboni di Napoli<\/em>.<br \/>\n<strong>(28)<\/strong> Un esempio: <em>&#8220;Ol\u00e0 (disse <\/em>[il capitano Rivelli, indicato quale <em>leader<\/em> degli stupratori assassini]<em>) mie tenere colombe, cessate dal guaire e andate a provvedere e qui recate quanto avete di meglio di cibi e di vini&#8221;<\/em> (<em>ibid<\/em>., p. 386).<br \/>\n<strong>(29)<\/strong> <em>Ibid<\/em>., pp. 294-295, nota 1.<br \/>\n<strong>(30)<\/strong> Alessandro Galante Garrone, <em>Filippo Buonarroti e i rivoluzionari dell\u2019Ottocento (1828 -1837)<\/em>, 2a ed., Einaudi, Torino 1975, p. 170.<br \/>\n<strong>(31)<\/strong> <em>Ibid<\/em>., p. 175. Lo storico torinese, riguardo ad altra opera storica di La Cecilia, le <em>Memorie storico-politiche dal 1820 al 1876. Risorgimento italiano<\/em> (5 voll., Artero, Roma 1876-1878), dice trattarsi di <em>&#8220;<\/em>[&#8230;] <em>opera notoriamente screditata nel campo storico per le sue gravi inesattezze e fantasiose invenzioni <\/em>[&#8230;] <em>spesso accolta come verit\u00e0 sacrosanta, anche per penuria estrema d\u2019altre sicure fonti&#8221;<\/em> (<em>ibid<\/em>., p. 199, nota 16).<br \/>\n<strong>(32)<\/strong> G. La Cecilia, <em>op. cit.<\/em>, p. 271.<br \/>\n<strong>(33)<\/strong> Cfr. <em>ibid<\/em>., inserto a pp. 430-431.<br \/>\n<strong>(34)<\/strong> Cfr., per esempio, Giovanni Firrao, <em>Cenni storici sulla citt\u00e0 di Altamura e i suoi avvenimenti. Dalla sua origine al 1860<\/em>, Borsella, Cantatore e Soci, Andria (Bari) 1880, che riprende con ampio risalto da La Cecilia il tema della violenza alle religiose. Su di lui lo storico Serena esprime il seguente giudizio: <em>&#8220;<\/em>[&#8230;] <em>il Firrao, seguendo ciecamente le storie segrete di Giovanni La Cecilia, ripete cose che possono trovar luogo in un romanzo, <\/em>[&#8230;]<em> ma non in una vera e propria narrazione storica&#8221;<\/em> (<em>op<\/em>. <em>cit<\/em>., p. 79, nota 1).<br \/>\n<strong>(35)<\/strong> Il rapporto fra i due &#8220;fratelli di latte&#8221; &#8211; la madre di Rivelli, Agnese, era stata balia del piccolo Ferdinando &#8211; \u00e8 descritto con maggiore obiettivit\u00e0 in Giuseppe Campolieti, <em>Il re lazzarone. Ferdinando IV di Borbone, amato dal popolo e condannato dalla storia<\/em>, Mondadori, Milano 1999, pp. 10 e 22-23, che tratta anche della deformazione della figura del re e di Rivelli operata da La Cecilia.<br \/>\n<strong>(36)<\/strong> Cfr. M. Lelj, <em>op<\/em>. <em>cit<\/em>., p. 134. <strong><br \/>\n(37)<\/strong> Cfr., fra l\u2019altro, Marcello Veneziani, <em>1799: Massacri in Puglia come nel Kosovo d\u2019oggi<\/em>, ne <em>il Giornale<\/em>, 1-4-1999. Il giornalista e scrittore si sofferma in particolare sui massacri giacobini di Andria e di Trani, che costarono alcune migliaia di vittime fra gl\u2019insorgenti e i semplici civili e qualche centinaio tra i francesi. L\u2019articolo polemizza <em>en passant <\/em>con quello della Macciocchi su Altamura.<br \/>\n<strong>(38)<\/strong> Cfr. Jurij Brodskij, <em>Solovki. Le isole del martirio. Da monastero a primo lager sovietico<\/em>, con una prefazione di Vittorio Strada, con illustrazioni, La Casa di Matriona, Milano 1998.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato in Cristianit\u00e0 n. 287-288, anno XXVII, marzo-aprile 1999 Un falso storico contro l\u2019Insorgenza italiana di Oscar Sanguinetti<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32548,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[99,96],"tags":[1052,1051],"class_list":["post-1470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insorgenze","category-storia-italiana","tag-altamura","tag-insorgenze-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;&#039;Altamura. La strage delle innocenti&#039;&#039;. - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;&#039;Altamura. La strage delle innocenti&#039;&#039;. - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-22T15:12:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-11T07:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"27 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"&#8221;Altamura. La strage delle innocenti&#8221;.\",\"datePublished\":\"2005-09-22T15:12:42+00:00\",\"dateModified\":\"2016-04-11T07:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/\"},\"wordCount\":5466,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Altamura.jpg\",\"keywords\":[\"Altamura\",\"insorgenze\"],\"articleSection\":[\"Insorgenze\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/\",\"name\":\"''Altamura. La strage delle innocenti''. - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Altamura.jpg\",\"datePublished\":\"2005-09-22T15:12:42+00:00\",\"dateModified\":\"2016-04-11T07:03:52+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Altamura.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Altamura.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altamura-la-strage-delle-innocenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8221;Altamura. La strage delle innocenti&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"''Altamura. La strage delle innocenti''. - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/","og_locale":"it_IT","og_type":"article","og_title":"''Altamura. La strage delle innocenti''. - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-09-22T15:12:42+00:00","article_modified_time":"2016-04-11T07:03:52+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"27 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"&#8221;Altamura. La strage delle innocenti&#8221;.","datePublished":"2005-09-22T15:12:42+00:00","dateModified":"2016-04-11T07:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/"},"wordCount":5466,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg","keywords":["Altamura","insorgenze"],"articleSection":["Insorgenze","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/","name":"''Altamura. La strage delle innocenti''. - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg","datePublished":"2005-09-22T15:12:42+00:00","dateModified":"2016-04-11T07:03:52+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Altamura.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altamura-la-strage-delle-innocenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"&#8221;Altamura. La strage delle innocenti&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":32549,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1470\/revisions\/32549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32548"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}