{"id":1452,"date":"2005-09-22T09:13:54","date_gmt":"2005-09-22T07:13:54","guid":{"rendered":""},"modified":"2014-11-11T10:41:49","modified_gmt":"2014-11-11T09:41:49","slug":"mitrokhin-cos-il-kgb-finanzi-allende","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/","title":{"rendered":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13038 alignright\" alt=\"Allende\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg\" width=\"193\" height=\"250\" \/><\/a>Corriere della sera<\/strong> 17 settembre 2005<\/div>\n<p style=\"text-align: center;\">ANTICIPAZIONE<\/p>\n<p style=\"text-align: justify;\">Il secondo volume sui documenti trafugati dall\u2019archivista russo <em>E l\u2019Urss faceva affari con la giunta militare argentina<\/em><\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"font-size: 12.222222328186px; text-align: justify;\">Molto si \u00e8 scritto sulle operazioni segrete condotte in Cile dalla Cia per provocare la caduta del presidente socialista Salvador Allende, abbattuto l\u201911 settembre 1973 dal colpo di Stato del generale Augusto Pinochet.<\/p>\n<p style=\"font-size: 12.222222328186px; text-align: justify;\">Ben poco si sa invece dell\u2019attivit\u00e0 parallela svolta nel Paese andino dallo spionaggio sovietico per sostenere Unidad Popular, il fronte delle sinistre. Ora per\u00f2 dalle carte riservate del Kgb giunge una novit\u00e0 importante: lo stesso Allende, a quanto pare, era un contatto confidenziale degli agenti di Mosca, dai quali ricevette ingenti somme di denaro.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">La rivelazione si trova nel secondo volume dedicato dallo storico inglese Christopher Andrew ai documenti del Kgb copiati e trafugati in Occidente dall\u2019archivista Vasilij Mitrokhin, morto nel gennaio del 2004. Il libro, che parla delle imprese compiute dalle spie sovietiche in Asia, Africa e America Latina, esce quasi simultaneamente in Italia (da Rizzoli), Usa e Gran Bretagna.<\/p>\n<p style=\"text-align: justify;\">Il capitolo sul Cile si apre negli anni Cinquanta, quando Allende, socialista alleato dei comunisti, fu avvicinato da un uomo del Kgb, Svjatoslav Kuznetsov, cui assicur\u00f2 \u00abla sua disponibilit\u00e0 a collaborare su basi confidenziali e a fornire tutto l\u2019appoggio necessario\u00bb. Il cileno in realt\u00e0, nota Andrew, \u00abnon corrispondeva a nessuno stereotipo di leader marxista\u00bb: massone dai gusti aristocratici, amante del lusso e delle belle donne, era visto con diffidenza dai comunisti ortodossi, che gli attribuivano \u00absimpatie maoiste\u00bb. Tuttavia aveva un grande seguito tra le masse popolari e, proprio per il suo stile di vita borghese, appariva rassicurante ai ceti medi progressisti.<\/p>\n<p style=\"text-align: justify;\">Sconfitto alle elezioni presidenziali nel 1964, nella tornata del 1970 Allende venne favorito dalla frattura del fronte moderato, diviso tra un candidato democristiano e uno di destra. Cia e Kgb investirono parecchi quattrini in quel turno elettorale, ma va ricordato che i fondi di Mosca andarono perlopi\u00f9 al Pc di Luis Corval\u00e1n.<\/p>\n<p style=\"text-align: justify;\">Comunque Allende prevalse nel voto popolare, sia pure con la maggioranza relativa e per uno scarto esiguo, poi venne eletto dal Parlamento: il Kgb rivendic\u00f2 parte del merito per il successo e continu\u00f2 a sovvenzionare il presidente, che s\u2019incontrava e consultava spesso con Kuznetsov. I problemi iniziarono quando Mosca invi\u00f2 a Santiago l\u2019ambasciatore Aleksandr Basov, che pretendeva l\u2019esclusiva dei rapporti con Allende. Il conflitto tra i due russi \u00e8 emblematico della rivalit\u00e0 fra servizi segreti sovietici e ministero degli Esteri che caratterizz\u00f2 l\u2019epoca della Guerra Fredda.<\/p>\n<p style=\"text-align: justify;\">Intanto la dura reazione di Washington all\u2019elezione di Allende induceva il Cremlino a pi\u00f9 miti consigli. Jurij Andropov, capo del Kgb, osserv\u00f2 che gli americani non interferivano nell\u2019Est europeo e quindi, in ossequio alla spartizione del mondo, l\u2019Urss in America Latina doveva procedere con cautela: su questo Mosca si trov\u00f2 in perenne attrito con Fidel Castro, smanioso invece di esportare la rivoluzione in tutto il continente.<\/p>\n<p style=\"text-align: justify;\">D\u2019altronde il leader cileno aveva poco in comune con il dittatore cubano: \u00abSecondo il Kgb &#8211; scrive Andrew &#8211; il difetto fondamentale di Allende era la sua indisponibilit\u00e0 a far uso della forza contro gli avversari\u00bb. Forse anche per questo le somme stanziate dall\u2019Urss in Cile furono piuttosto basse, rispetto agli enormi aiuti economici destinati a Cuba e pi\u00f9 tardi al Nicaragua sandinista, per non parlare dell\u2019Egitto di Nasser.<\/p>\n<p style=\"text-align: justify;\">L\u2019epilogo \u00e8 noto. Colto di sorpresa dal golpe di Pinochet, nonostante i moniti delle spie di Mosca, Allende non fece appello alla resistenza popolare e prefer\u00ec sacrificarsi (quasi sicuramente si suicid\u00f2 mentre il suo palazzo veniva bombardato) per \u00abevitare un bagno di sangue\u00bb ancor pi\u00f9 orrendo.<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 in generale l\u2019America Latina si dimostr\u00f2 un ambiente inospitale per il Kgb, non soltanto perch\u00e9 situato nella sfera d\u2019influenza americana, ma anche perch\u00e9 difficile da comprendere. Castro prese il potere senza alcun appoggio da parte dell\u2019Urss: fu poi lui a contattare di sua iniziativa i sovietici, che ne fecero la loro testa di ponte, ma lo considerarono sempre un eterodosso dalle ambizioni eccessive. E non parliamo di Ernesto Guevara, accusato di ignorare \u00abi principi basilari del marxismo-leninismo\u00bb. La morte del Che in Bolivia, nell\u2019ottobre del 1967, vide scendere in piazza a Mosca solo pochi studenti latinoamericani, mentre a Washington, nel covo del nemico, gli resero omaggio oltre 50 mila attivisti di sinistra.<\/p>\n<p style=\"text-align: justify;\">Paradossalmente l\u2019Urss trov\u00f2 invece una tacita sintonia con i generali argentini. Mentre scatenava sulle atrocit\u00e0 di Pinochet un\u2019intensa campagna propagandistica, con tanto di documenti falsificati, il Kgb prefer\u00ec tacere sui delitti ancor pi\u00f9 gravi della giunta di Buenos Aires. Un silenzio, osserva Andrew, tutt\u2019altro che disinteressato: \u00abNel 1980, l\u201980 per cento delle esportazioni di grano argentino era destinato all\u2019Unione Sovietica\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il libro di <strong>Christopher Andrew<\/strong> e <strong>Vasilij Mitrokhin<\/strong> <em>\u00abL\u2019archivio Mitrokhin. Una storia globale della guerra fredda da Cuba al Medio Oriente\u00bb<\/em> (Rizzoli, pp. 604, 26) sar\u00e0 in vendita dal 21 settembre<\/p>\n<p style=\"text-align: justify;\">_______________________<\/p>\n<p><strong>leggi anche:<\/strong><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1452\">Mitrokhin: cos\u00ec il Kgb finanzi\u00f2 Allende<\/a><\/p>\n<p><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=13029\">Il crollo del mito di Allende<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corriere della sera 17 settembre 2005 ANTICIPAZIONE Il secondo volume sui documenti trafugati dall\u2019archivista russo E l\u2019Urss faceva affari con la giunta militare argentina * * * Molto si \u00e8 scritto sulle operazioni segrete condotte in Cile dalla Cia per provocare la caduta del presidente socialista Salvador Allende, abbattuto l\u201911 settembre 1973 dal colpo di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,84],"tags":[892,891],"class_list":["post-1452","post","type-post","status-publish","format-standard","hentry","category-filosofia-del-comunismo","category-urss","tag-cile","tag-salvador-allende","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-22T07:13:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-11-11T09:41:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende\",\"datePublished\":\"2005-09-22T07:13:54+00:00\",\"dateModified\":\"2014-11-11T09:41:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/\"},\"wordCount\":825,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Allende.jpg\",\"keywords\":[\"Cile\",\"Salvador Allende\"],\"articleSection\":[\"Comunismo\",\"URSS\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/\",\"name\":\"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Allende.jpg\",\"datePublished\":\"2005-09-22T07:13:54+00:00\",\"dateModified\":\"2014-11-11T09:41:49+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Allende.jpg\",\"contentUrl\":\"http:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Allende.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/mitrokhin-cos-il-kgb-finanzi-allende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/","og_locale":"it_IT","og_type":"article","og_title":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-09-22T07:13:54+00:00","article_modified_time":"2014-11-11T09:41:49+00:00","og_image":[{"url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg","type":"","width":"","height":""}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende","datePublished":"2005-09-22T07:13:54+00:00","dateModified":"2014-11-11T09:41:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/"},"wordCount":825,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg","keywords":["Cile","Salvador Allende"],"articleSection":["Comunismo","URSS"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/","name":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#primaryimage"},"thumbnailUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg","datePublished":"2005-09-22T07:13:54+00:00","dateModified":"2014-11-11T09:41:49+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#primaryimage","url":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg","contentUrl":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Allende.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/mitrokhin-cos-il-kgb-finanzi-allende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Mitrokhin: cos&igrave; il Kgb finanzi&ograve; Allende"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1452"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1452\/revisions"}],"predecessor-version":[{"id":13044,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1452\/revisions\/13044"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}