{"id":1387,"date":"2005-09-11T00:00:00","date_gmt":"2005-09-10T22:00:00","guid":{"rendered":""},"modified":"2016-01-23T12:43:21","modified_gmt":"2016-01-23T11:43:21","slug":"un-indagine-sulla-soppressione-degli-ordini-religiosi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/","title":{"rendered":"Un&#8217; indagine sulla soppressione degli ordini religiosi"},"content":{"rendered":"<div style=\"text-align: center;\" align=\"center\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29686\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg\" alt=\"Cavour\" width=\"157\" height=\"200\" \/><\/a>Articolo pubblicato su<strong> Il Corriere del Sud<\/strong> n. 3<\/div>\n<div style=\"text-align: center;\" align=\"center\">1 febbraio &#8211; 15 febbraio 2002<\/div>\n<p style=\"text-align: justify;\"><em>Si sperava di finanziare con il ricavato di quegli espropri le nuove guerre contro il Papa e soprattutto contro l\u2019Austria<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Roberto Cavallo<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">&#8220;Il naufragio dei chiostri. Conventi di Terra d&#8217;Otranto tra restaurazione borbonica e soppressione sabauda&#8221;: \u00e8 il titolo del libro (Besa Editore) con cui Oronzo Mazzotta getta un po\u2019 di luce, con dati d&#8217;archivio alla mano, su un capitolo scarsamente conosciuto della nostra storia risorgimentale.<\/div>\n<p style=\"text-align: justify;\">Anche in Italia tutto comincia con la Rivoluzione francese e con la conseguente invasione napoleonica della Penisola. Si attua, negli staterelli giacobinizzati, una prosecuzione della legislazione che in Francia aveva colpito la Chiesa cattolica. Soltanto nella Terra d&#8217;Otranto, che \u00e8 poi l&#8217;ambito geografico preso in considerazione dal libro, Gioacchino Murat nel 1809 cancell\u00f2 165 conventi sia maschili che femminili (quasi l&#8217;86% del totale!): &#8220;Mand\u00f2 a casa oltre 900 religiosi, sacerdoti e laici, e ne incamer\u00f2 tutti i beni, mobili ed immobili&#8221;.<\/p>\n<p style=\"text-align: justify;\">Con la restaurazione borbonica venne sottoscritto nel 1818 il concordato di Terracina tra la S.Sede e il Regno delle Due Sicilie. Con tale trattato una parte dei beni sottratti agli ordini religiosi vennero restituiti alla Chiesa, anche se molte case e terreni erano gi\u00e0 stati alienati a privati cittadini e dunque erano diventati difficilmente recuperabili.<\/p>\n<p style=\"text-align: justify;\">Era comunque un&#8217;indubbia inversione di tendenza, e quantunque lo spirito dell&#8217;illuminismo e del giurisdizionalismo non lasciasse del tutto immune la corte napoletana, veniva sancita e garantita di fatto la piena libert\u00e0 religiosa per le comunit\u00e0 cattoliche meridionali.<\/p>\n<p style=\"text-align: justify;\">Il Mazzotta sottolinea nel suo libro come il popolo reclamasse a gran voce il ripristino dei conventi soppressi.<\/p>\n<p style=\"text-align: justify;\">All&#8217;indomani della conquista del Sud e della conseguente Unit\u00e0 d&#8217;Italia, l&#8217;operazione della soppressione dei conventi si ripet\u00e9 in modo speculare rispetto a quella francese, medesime essendone le motivazioni ideologiche.<\/p>\n<p style=\"text-align: justify;\">Il 17 febbraio 1861 Eugenio di Savoia, luogotenente del Regno, dichiarava decaduto il concordato di Terracina del 1818 ed estendeva alle province napoletane la legislazione ecclesiastica sabauda del 1855. Beni immobili e mobili furono minuziosamente inventariati e passati al bilancio dello Stato.<\/p>\n<p style=\"text-align: justify;\">Si sperava, fra l&#8217;altro, di finanziare con il ricavato di quegli espropri le nuove guerre contro il Papa e soprattutto contro l&#8217;Austria che i governi sabaudi andavano progettando; ma gli introiti derivati dalle vendite dei beni ecclesiastici furono ben inferiori a quelli preventivati in bilancio. Chi si avvantaggi\u00f2 di tutta quell&#8217;operazione, che conobbe non pochi momenti drammatici, fu una ristretta cerchia di proprietari e latifondisti, spesso investiti dal Governo di tutte le pubbliche cariche, che con poche lire fecero man bassa dei beni ecclesiastici.<\/p>\n<p style=\"text-align: justify;\">Fu solo la Chiesa con i suoi religiosi a perdere? Sicuramente no.<\/p>\n<p style=\"text-align: justify;\">I terreni della Chiesa erano generalmente concessi in affitto o in enfiteusi, con rare eccezioni di conduzione diretta. A fronte di entrate sicure, i monasteri si accontentavano di canoni modesti e, specie nel caso dell&#8217;enfiteusi, pi\u00f9 che altro simbolici. La figura giuridica dell&#8217;enfiteusi prevedeva inoltre il progressivo miglioramento del fondo.<\/p>\n<p style=\"text-align: justify;\">La soppressione del latifondo ecclesiastico seguita dal nuovo governo unitario, invece che favorire il frazionamento agrario, allarg\u00f2 il latifondo borghese. Scrive il Mazzotta in proposito: &#8220;I piccoli proprietari furono di fatto impossibilitati a comprare anche i piccoli lotti. Se erano terre di prima classe, con l&#8217;assegnazione al migliore offerente, la concorrenza lievitava il prezzo di base fino a somme che, nonostante la rateizzazione, erano proibitive per chi non aveva capitali.<\/p>\n<p style=\"text-align: justify;\">A basso prezzo rimanevano i piccoli lotti di terre scadenti che non garantivano una rendita tale che permettesse di onorare le rate concordate. Era logico che questo tipo di terre non interessando, per opposti motivi, n\u00e9 gli speculatori borghesi e neppure i piccoli proprietari, rimanessero al demanio. Chi trasse vantaggio dai beni della Chiesa, anche questa volta, come nella soppressione francese, non fu lo Stato, ma i privati che disponevano di una forte liquidit\u00e0&#8221;.<\/p>\n<p style=\"text-align: justify;\">Come nel resto d&#8217;Europa, la vittoria del liberalismo economico si accompagnava all&#8217;affermazione della borghesia, che nell&#8217;Italiameridionale era rappresentata soprattutto da quella agraria. Alle spoliazioni dei beni della Chiesa si un\u00ec anche una forte azione governativa a sostegno del protestantesimo, per completare cos\u00ec il programma anticattolico conformemente ai principi massonici, che in quegli anni ispiravano la politica italiana. Ma sia pure affamato e costretto all&#8217;emigrazione verso le Americhe, il popolo meridionale, e italiano in generale, conserver\u00e0 la millenaria fede religiosa cattolica, reale contrassegno della propria identit\u00e0 nazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su Il Corriere del Sud n. 3 1 febbraio &#8211; 15 febbraio 2002 Si sperava di finanziare con il ricavato di quegli espropri le nuove guerre contro il Papa e soprattutto contro l\u2019Austria di Roberto Cavallo<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,101,24,96],"tags":[2406,404],"class_list":["post-1387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-risorgimento","category-storia","category-storia-italiana","tag-risorgimento","tag-storia-italiana-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un&#039; indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un&#039; indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-10T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-23T11:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"199\" \/>\n\t<meta property=\"og:image:height\" content=\"253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Un&#8217; indagine sulla soppressione degli ordini religiosi\",\"datePublished\":\"2005-09-10T22:00:00+00:00\",\"dateModified\":\"2016-01-23T11:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/\"},\"wordCount\":734,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Cavour.jpg\",\"keywords\":[\"Risorgimento\",\"storia italiana\"],\"articleSection\":[\"Chiesa\",\"Risorgimento\",\"Storia\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/\",\"name\":\"Un' indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Cavour.jpg\",\"datePublished\":\"2005-09-10T22:00:00+00:00\",\"dateModified\":\"2016-01-23T11:43:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Cavour.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Cavour.jpg\",\"width\":199,\"height\":253},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-indagine-sulla-soppressione-degli-ordini-religiosi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un&#8217; indagine sulla soppressione degli ordini religiosi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un' indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/","og_locale":"it_IT","og_type":"article","og_title":"Un' indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-09-10T22:00:00+00:00","article_modified_time":"2016-01-23T11:43:21+00:00","og_image":[{"width":199,"height":253,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Un&#8217; indagine sulla soppressione degli ordini religiosi","datePublished":"2005-09-10T22:00:00+00:00","dateModified":"2016-01-23T11:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/"},"wordCount":734,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg","keywords":["Risorgimento","storia italiana"],"articleSection":["Chiesa","Risorgimento","Storia","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/","name":"Un' indagine sulla soppressione degli ordini religiosi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg","datePublished":"2005-09-10T22:00:00+00:00","dateModified":"2016-01-23T11:43:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Cavour.jpg","width":199,"height":253},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-indagine-sulla-soppressione-degli-ordini-religiosi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Un&#8217; indagine sulla soppressione degli ordini religiosi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1387"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1387\/revisions"}],"predecessor-version":[{"id":29687,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1387\/revisions\/29687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29686"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}