{"id":1366,"date":"2005-09-09T00:00:00","date_gmt":"2005-09-08T22:00:00","guid":{"rendered":""},"modified":"2015-11-02T11:06:27","modified_gmt":"2015-11-02T10:06:27","slug":"la-verit-su-galileo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/","title":{"rendered":"La verit&agrave; su Galileo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27113\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg\" alt=\"Galileo\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>Fogli,<\/strong> n. 90, Anno XI, settembre 1984<\/div>\n<p style=\"text-align: center;\">di<strong> Rino Cammilleri<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">I secoli futuri, se ci saranno, definiranno questo nostro tempo come &#8220;l&#8217;eta&#8217; della retorica&#8221;. o &#8220;del falso storico&#8221;, se preferite. Prendiamo ad esempio Galileo: il solo nome evoca nella mente dei piu&#8217; l&#8217; &#8220;oscurantismo&#8221; della Chiesa e dei &#8220;lumi&#8221; della Scienza.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Ce l&#8217;hanno inculcato fin dai banchi dell&#8217;asilo il &#8220;martirio&#8221; di Galileo a opera della &#8220;sanguinaria&#8221; Inquisizione, l&#8217; &#8220;eppur si muove&#8221; finale, la terra che gira attorno al sole e via blaterando. Hanno voglia gli storici <em>veri <\/em>(non i commediografi comunisti come Bertolt Brecht o i cinematografari come Liliana Cavani) e i filosofi del calibro di un Popper di dirci che Galileo aveva <em>torto<\/em>, e che la ragione stava tutta dalla parte di Bellarmino.<\/div>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Macche&#8217;. Si continua con la retorica.Il famigerato processo? Dopo vent&#8217;anni di insistenze e certificati medici da parte dell&#8217;inquisito, fu celebrato con mille scuse per il grande Galileo, che intanto stava alloggiato in una villa sul Pincio con servitori, leccato e lisciato dal Papa e dai Cardinali. L&#8217; &#8220;eppur si muove!&#8221;? Mai detto. La condanna? Dire una volta alla settimana i sette salmi penitenziali per tre anni (subito commutata). A Galileo la trappola gliel&#8217;avevano &#8220;montata&#8221; i suoi colleghi, stufi della sua arroganza (Galileo li insultava apertamente tutte le volte che poteva) e gelosi delle sue entrature vaticane (furono gli astronomi gesuiti a difenderlo quando annuncio&#8217; le sue scoperte).<\/p>\n<p style=\"text-align: justify;\">L&#8217;intolleranza ecclesiastica nella Controriforma? Ma Galileo convive <em>more uxorio <\/em>con una sguattera che non volle sposare mai (se ne vergognava) e che gli diede quattro figli, tra cui due suore, tutti registrati come N.N.. E nessun ecclesiastico glielo rimprovero&#8217; mai. Le scoperte di Galileo? Nel campo della fisica, non certo in quello dell&#8217;astronomia. Che la terra girasse attorno al sole l&#8217;aveva gia&#8217; detto Copernico. Il cannocchiale l&#8217;aveva scoperta un ottico olandese (e c&#8217;e&#8217; chi sostiene che l&#8217;invenzione fosse addirittura di un domenicano pisano medievale).<\/p>\n<p style=\"text-align: justify;\">Allora, cos&#8217;era tutta questa storia attorno a Galileo? Il fatto era che lui il cannocchiale l&#8217;aveva puntato verso e il cielo e aveva scoperto i satelliti di Giove: giravano attorno a un&#8217;altra cosa, quindi non tutto girava attorno alla terra. Bene, questo al tempo lo sapevano tutti: era un&#8217;ipotesi matematica che si studiava tranquillamente nelle universita&#8217;. Solo che Galileo pretendeva che la Chiesa mutasse le Scritture, specialmente nel passo in cui si dice che Giosue&#8217; fermo&#8217; il sole.<\/p>\n<p style=\"text-align: justify;\">I colleghi fecero girare certe sue lettere in cui si sfidava la Chiesa a pronunciarsi e la cosa fini&#8217; in tribunale. Tutto qui. La Chiesa si preoccupo&#8217; subito delle implicazioni <em>etiche <\/em>della cosa. E aveva ragione, perche&#8217; oggi conosciamo i guasti che puo&#8217; causare la Scienza quando sfugge di mano. Cambiava qualcosa nella nostra vita se era il sole a girare attorno alla terra?No.<\/p>\n<p style=\"text-align: justify;\">Ma sarebbe cambiato si&#8217;, ed e&#8217; cambiato (tutto), da quando la Scienza ha preso il posto della Religione, cosa che a Galileo importava piu&#8217; della teoria copernicana. Ma la retorica si e&#8217; impadronita dell&#8217;evento (ricomposto subito, peraltro, dai protagonisti, che non diedero alla cosa tutta l&#8217;importanza che oggi le si da&#8217;), facendo di Galileo il campione della Ragione.<\/p>\n<p style=\"text-align: justify;\">Ma il &#8220;razionalismo&#8221; stava invece tutto dalla parte della Chiesa, visto che Galileo e l&#8217;intera sua Accademia dei Lincei avevano piu&#8217; a cuore la magia, l&#8217;alchimia, l&#8217;ermetismo, l&#8217;esoterismo (una mostra parigina tutti questi panni sporchi li ha messi in piazza dal 12 dicembre all&#8217;8 gennaio), e i fantomatici Rosacroce. Cosi&#8217; come tutto il gotha della cosiddetta Scienza dell&#8217;epoca: Bacone, Newton, Cartesio, Copernico, Boyle, Grozio, Keplero.<\/p>\n<p style=\"text-align: justify;\">E poi Campanello e Giordano Bruno, che per vivere, faceva anche la spia. Si e&#8217; scoperto recentemente: grazie a lui Elisabetta &#8220;la grande&#8221; mando&#8217; a morte migliaia di cattolici inglesi. Ma credete che tutto cio&#8217; finira&#8217; nei libri di scuola? Scordatevelo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fogli, n. 90, Anno XI, settembre 1984 di Rino Cammilleri &nbsp; I secoli futuri, se ci saranno, definiranno questo nostro tempo come &#8220;l&#8217;eta&#8217; della retorica&#8221;. o &#8220;del falso storico&#8221;, se preferite. Prendiamo ad esempio Galileo: il solo nome evoca nella mente dei piu&#8217; l&#8217; &#8220;oscurantismo&#8221; della Chiesa e dei &#8220;lumi&#8221; della Scienza. Ce l&#8217;hanno inculcato &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27113,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,93,22],"tags":[919,468,261],"class_list":["post-1366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-inquisizione","category-scienza","tag-galileo-galilei","tag-inquisizione-2","tag-scienza-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La verit&agrave; su Galileo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La verit&agrave; su Galileo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-08T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-02T10:06:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La verit&agrave; su Galileo\",\"datePublished\":\"2005-09-08T22:00:00+00:00\",\"dateModified\":\"2015-11-02T10:06:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/\"},\"wordCount\":650,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Galileo.jpg\",\"keywords\":[\"Galileo Galilei\",\"inquisizione\",\"scienza\"],\"articleSection\":[\"Chiesa\",\"Inquisizione\",\"Scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/\",\"name\":\"La verit&agrave; su Galileo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Galileo.jpg\",\"datePublished\":\"2005-09-08T22:00:00+00:00\",\"dateModified\":\"2015-11-02T10:06:27+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Galileo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Galileo.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verit-su-galileo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La verit&agrave; su Galileo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La verit&agrave; su Galileo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/","og_locale":"it_IT","og_type":"article","og_title":"La verit&agrave; su Galileo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-09-08T22:00:00+00:00","article_modified_time":"2015-11-02T10:06:27+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La verit&agrave; su Galileo","datePublished":"2005-09-08T22:00:00+00:00","dateModified":"2015-11-02T10:06:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/"},"wordCount":650,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg","keywords":["Galileo Galilei","inquisizione","scienza"],"articleSection":["Chiesa","Inquisizione","Scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/","name":"La verit&agrave; su Galileo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg","datePublished":"2005-09-08T22:00:00+00:00","dateModified":"2015-11-02T10:06:27+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Galileo.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verit-su-galileo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La verit&agrave; su Galileo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1366"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1366\/revisions"}],"predecessor-version":[{"id":27114,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1366\/revisions\/27114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27113"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}