{"id":134,"date":"2004-11-15T11:32:46","date_gmt":"2004-11-15T10:32:46","guid":{"rendered":""},"modified":"2025-04-06T17:06:34","modified_gmt":"2025-04-06T15:06:34","slug":"contro-il-silenzio-assenso-alla-donazione-di-organi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/","title":{"rendered":"Contro il silenzio-assenso alla donazione di organi"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/alleanzacattolica.org\/indici-cristianita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cristianit\u00e0<\/a><\/strong> n.249 (1996)<\/p>\n\n\n\n<p class=\"has-text-align-center\">di<strong>&nbsp;Alfredo Mantovano<\/strong><\/p>\n\n\n\n<p>Il 30 novembre 1995 il Senato ha approvato la proposta di legge n. 3509, contenente\u00a0<em>Norme per la manifestazione di volont\u00e0 per il prelievo di organi, tessuti e cellule per il trapianto terapeutico<\/em>, e la proposta \u00e8 stata trasmessa il giorno successivo alla Camera dei Deputati. Una delle disposizioni del testo che ha sollevato le maggiori preoccupazioni \u00e8 quella del 4\u00b0 comma dell\u2019articolo 2, che prevede il silenzio-assenso. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg\" alt=\"\" class=\"wp-image-28425\" style=\"width:339px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Il meccanismo che lo regola \u00e8 il seguente: nei tre mesi dall\u2019entrata in vigore della legge le unit\u00e0 sanitarie locali &#8211; cos\u00ec si legge nell\u2019articolato, anche se le USL con tale denominazione non esistono pi\u00f9 &#8211; notificano agli assistiti l\u2019invito a manifestare la volont\u00e0 di donare gli organi; i destinatari sono tenuti a rispondere nei successivi tre mesi recandosi nei locali dell\u2019ente, e la loro risposta viene annotata sulla tessera sanitaria: la mancata annotazione equivale a consentire l\u2019espianto.<\/p>\n\n\n\n<p>Il primo problema che porrebbe la norma, se fosse approvata in via definitiva, \u00e8 di ordine pratico, e attiene all\u2019individuazione delle modalit\u00e0 per garantire che in novanta giorni si realizzino cinquanta e pi\u00f9 milioni di valide notifiche, posto che gli ufficiali giudiziari e i messi sono gi\u00e0 insufficienti per provvedere alle notifiche che riguardano atti giudiziari e amministrativi, e che la dizione&nbsp;<em>&#8220;nelle forme di legge&#8221;<\/em>, adoperata dalla proposta per qualificare il sistema delle notifiche stesse, non specifica se le forme siano quelle del codice di procedura penale, del codice di procedura civile oppure delle leggi amministrative, e che cosa accade se il domicilio \u00e8 inesatto, incompleto o sconosciuto; non si tratta di questioni superficiali, perch\u00e9, se \u00e8 vero &#8211; per esempio &#8211; che il processo penale assicura, con un sistema molto articolato, che l\u2019imputato sia messo a conoscenza dell\u2019esistenza di un processo a suo carico, s\u00ec che all\u2019emissione di un decreto d\u2019irreperibilit\u00e0 si perviene soltanto dopo vane ricerche da parte degli organi allo scopo incaricati, non si comprende per quale ragione non debba valere un rigore simile, se non superiore, nell\u2019ipotesi in cui siano in gioco beni ancora pi\u00f9 importanti della libert\u00e0 personale.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale-1024x668.jpg\" alt=\"\" class=\"wp-image-45314\" style=\"width:388px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale-1024x668.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale-300x196.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale-768x501.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/12\/medici_sanit\u00e0_ospedale.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p>Invece, il tutto si traduce nella concreta assenza di garanzie per scongiurare il rischio di una presunzione di consenso conseguente alla completa ignoranza dell\u2019interessato, che magari ha avuto il solo torto di cambiare residenza senza informare l\u2019azienda sanitaria locale di appartenenza. Per tacere che l\u2019annotazione del dissenso sul libretto sanitario non tutela dall\u2019espianto coatto; infatti, il 2\u00b0 comma dell\u2019articolo 8 stabilisce che, nell\u2019impossibilit\u00e0 di&nbsp;<em>&#8220;prendere visione della tessera sanitaria&#8221;<\/em>&nbsp;o&nbsp;<em>&#8220;di accedere ai dati&#8221;<\/em>&nbsp;relativi al consenso o al dissenso manifestati, tali consenso o dissenso possono essere sostituiti all\u2019occorrenza dalla testimonianza del coniuge, dei figli o dei genitori, s\u00ec che a chi dissente conviene circolare con il libretto sanitario bene in evidenza, per impedire che altri decidano per lui.<\/p>\n\n\n\n<p>Perplessit\u00e0, per dire il meno, attengono anche alla fissazione a sedici anni dell\u2019et\u00e0 minima per la valida manifestazione di volont\u00e0, quando la capacit\u00e0 di agire si acquista al diciottesimo anno di et\u00e0; alla mancanza di garanzie di riservatezza in ordine all\u2019espressione del consenso e del dissenso &#8211; il che lascia spazio, per esempio, alla possibile strumentalizzazione della notizia in occasione del conferimento di incarichi pubblici a chi abbia a suo tempo esplicitato il dissenso &#8211; e all\u2019autorizzazione a che genitori e tutori consentano la donazione al posto dei figli minori di sedici anni o degli interdetti, quasi che gli organi di costoro siano&nbsp;<em>res familiae<\/em>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/medico_paziente.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/03\/medico_paziente.jpg\" alt=\"\" class=\"wp-image-37449\" style=\"width:385px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Perplessit\u00e0, ancora, riguardano l\u2019obbligo, che l\u2019articolo 4 del testo, al 3\u00b0 comma, pone a carico dei&nbsp;<em>&#8220;medici di medicina generale&#8221;<\/em>, d\u2019informare i pazienti&nbsp;<em>&#8220;sulle misure adottate con la presente legge e su tutta la tematica dei trapianti&#8221;<\/em>. Il grado d\u2019insidiosit\u00e0 della norma dipende dal tipo di risposta all\u2019interrogativo sul taglio dell\u2019informazione che la proposta sollecita; infatti, l\u2019indipendenza professionale verrebbe compromessa se si considerasse il medico vincolato all\u2019elencazione pura e semplice delle procedure e a un acritico stimolo alla donazione, con la preclusione dell\u2019esposizione contestuale delle eventuali riserve nutrite in materia. La previsione, contenuta nella stessa norma, della vigilanza dell\u2019ordine professionale sull\u2019adempimento di quell\u2019obbligo apre la prospettiva a un procedimento disciplinare nell\u2019ipotesi in cui ragioni di coscienza prevalgano sulle esortazioni rivolte ai pazienti a dichiararsi donatori.<\/p>\n\n\n\n<p>Pi\u00f9 in generale, \u00e8 discutibile la stessa ammissibilit\u00e0 dell\u2019istituto del silenzio-assenso in una materia di tale delicatezza. Infatti, finora il silenzio-assenso \u00e8 stato utilizzato esclusivamente nei rapporti fra privato e pubblica amministrazione, in casi limitati e circoscritti, caratterizzati dalla semplicit\u00e0 del procedimento e del contenuto del provvedimento. La legge lo ha configurato come una sorta di&nbsp;<em>fictio juris<\/em>: l\u2019inerzia dell\u2019ente pubblico diventa un semplice fatto sul cui presupposto si basa la previsione legislativa per esigenze di rapidit\u00e0 e per dare espansione alle posizioni soggettive dei privati, garantite costituzionalmente, che chiedono un provvedimento alla pubblica amministrazione.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/12\/ricerca_biomedica.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/12\/ricerca_biomedica.jpg\" alt=\"\" class=\"wp-image-41860\" style=\"width:417px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>Cos\u00ec avviene per gli interventi edilizi di manutenzione straordinaria, per l\u2019iscrizione di cooperative nel registro prefettizio, per l\u2019esecuzione di nuove opere in prossimit\u00e0 del demanio marittimo, e cos\u00ec via: il decorso di un termine variante, a seconda dei casi, fra i novanta e i centoventi giorni dalla presentazione dell\u2019istanza \u00e8 idoneo a far ritenere formato il provvedimento; cos\u00ec non avviene, al contrario, per procedimenti amministrativi pi\u00f9 articolati, come quelli di programmazione urbanistica, che esigono l\u2019esercizio del potere discrezionale della pubblica amministrazione.<\/p>\n\n\n\n<p>Chiunque \u00e8 in grado di apprezzare quanto un istituto del genere, che conosce tali limiti e cautele, si presti a valere su un terreno cos\u00ec coinvolgente sul piano personale come quello dei trapianti, nel quale si valuta non gi\u00e0 una condotta inerte dell\u2019ente pubblico, ma la mancata scelta di un essere umano che pu\u00f2 ignorare del tutto i termini della questione, e comunque pu\u00f2 nutrire ragioni d\u2019incertezza o di perplessit\u00e0, non risolvibili in termini tassativi, sulla sorte di s\u00e9 stesso e del proprio corpo. La valutazione va eseguita peraltro alla stregua della tendenza &#8211; affermatasi negli ultimi decenni &#8211; di valorizzazione del consenso informato del paziente al trattamento del medico, e in particolare a interventi rischiosi, pur se a scopi terapeutici: una tendenza con la quale la proposta passata al Senato confligge radicalmente perch\u00e9 per gli espianti prescinde addirittura dal consenso, e anzi lo presume.<\/p>\n\n\n\n<p>S\u2019impone una rilettura dell\u2019articolato alla Camera. N\u00e9 si obietti che in questo modo si umilia l\u2019esortazione alla solidariet\u00e0 di fronte alle possibilit\u00e0 di salvare vite umane con il trapianto di organi vitali. \u00c8 vita anche quella di colui che viene di volta in volta individuato come donatore: il quale in ogni caso, quand\u2019anche non vi fossero dubbi sulla definitivit\u00e0 della sua morte &#8211; ma non mancano dubbi relativi all\u2019accertamento basato sul doppio elettroencefalogramma eseguito con l\u2019intervallo delle sei ore, secondo le norme contenute nella legge n. 578 del 29 dicembre 1993 e nel decreto di attuazione del ministro della Sanit\u00e0 n. 582 del 22 agosto 1994 -, non pu\u00f2 essere espropriato forzatamente di parti del corpo. A meno che non si scambi la solidariet\u00e0 per quel collettivismo di stampo scandinavo che include la disponibilit\u00e0 della vita delle persone, e in particolare di quelle pi\u00f9 deboli, perch\u00e9 incapaci di opporsi.<\/p>\n\n\n\n<p>Ma questa \u00e8 la medesima solidariet\u00e0 da carnefice in base alla quale, come sta avvenendo in alcuni paesi dell\u2019Europa Settentrionale, agli ammalati anziani e difficili vengono sospese assistenza e cure mediche per ragioni economiche e per far posto alle terapie verso i pi\u00f9 giovani e i meno infermi<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Cristianit\u00e0 n.249 (1996) di&nbsp;Alfredo Mantovano Il 30 novembre 1995 il Senato ha approvato la proposta di legge n. 3509, contenente\u00a0Norme per la manifestazione di volont\u00e0 per il prelievo di organi, tessuti e cellule per il trapianto terapeutico, e la proposta \u00e8 stata trasmessa il giorno successivo alla Camera dei Deputati. Una delle disposizioni del testo &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28425,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2388,526],"class_list":["post-134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","tag-bioetica","tag-donazione-organi","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-15T10:32:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-06T15:06:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Contro il silenzio-assenso alla donazione di organi\",\"datePublished\":\"2004-11-15T10:32:46+00:00\",\"dateModified\":\"2025-04-06T15:06:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/\"},\"wordCount\":1253,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/silenzio-assenso.jpg\",\"keywords\":[\"Bioetica\",\"donazione organi\"],\"articleSection\":[\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/\",\"name\":\"Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/silenzio-assenso.jpg\",\"datePublished\":\"2004-11-15T10:32:46+00:00\",\"dateModified\":\"2025-04-06T15:06:34+00:00\",\"description\":\"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/silenzio-assenso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/silenzio-assenso.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/contro-il-silenzio-assenso-alla-donazione-di-organi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contro il silenzio-assenso alla donazione di organi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica","description":"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/","og_locale":"it_IT","og_type":"article","og_title":"Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica","og_description":"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-15T10:32:46+00:00","article_modified_time":"2025-04-06T15:06:34+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Contro il silenzio-assenso alla donazione di organi","datePublished":"2004-11-15T10:32:46+00:00","dateModified":"2025-04-06T15:06:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/"},"wordCount":1253,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg","keywords":["Bioetica","donazione organi"],"articleSection":["Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/","name":"Contro il silenzio-assenso alla donazione di organi - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg","datePublished":"2004-11-15T10:32:46+00:00","dateModified":"2025-04-06T15:06:34+00:00","description":"Contro il silenzio-assenso alla donazione di organi, una disposizione di difficile applicazione secondo il disposto legislativo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/silenzio-assenso.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/contro-il-silenzio-assenso-alla-donazione-di-organi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Contro il silenzio-assenso alla donazione di organi"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=134"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/134\/revisions"}],"predecessor-version":[{"id":62446,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/134\/revisions\/62446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28425"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}