{"id":1273,"date":"2005-09-05T00:00:00","date_gmt":"2005-09-04T22:00:00","guid":{"rendered":""},"modified":"2015-11-26T12:49:20","modified_gmt":"2015-11-26T11:49:20","slug":"bisanzio-o-la-civilt-cristiana-romano-orientale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/","title":{"rendered":"Bisanzio o la civilt&agrave; cristiana romano-orientale"},"content":{"rendered":"<div style=\"text-align: center;\">I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale<\/div>\n<p style=\"text-align: center;\"><strong>Voci per un dizionario del pensiero forte<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-28071\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg\" alt=\"Bisanzio\" width=\"250\" height=\"139\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg 301w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio-300x166.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">di <strong>Marco Tangheroni<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>1. L\u2019impero romano d\u2019Oriente fra barbari e arabi musulmani<\/strong><\/div>\n<p style=\"text-align: justify;\">L\u2019immagine prevalente di Bisanzio, del suo impero e della sua civilt\u00e0 \u00e8 quella ereditata dall\u2019Illuminismo, da autori come Charles de Secondat di La Br\u00e8de e di Montesquieu (1689-1755) ed Edward Gibbon (1737-1794): trionfo del dispotismo e dell\u2019oscurantismo religioso, controversie tanto sottili quanto inutili, raffinatezza estenuata e fine a s\u00e9 stessa, sostanziale immobilit\u00e0 della sua storia.<\/p>\n<p style=\"text-align: justify;\">Si tratta di un\u2019immagine deformata, che non rende giustizia al ruolo avuto per un millennio da questa sopravvivenza dell\u2019impero romano cristianizzato: fino alla sua scomparsa, gli imperatori bizantini si proclamano sempre <em>&#8220;re dei Romani&#8221;<\/em>. Nel 476 finisce l\u2019impero romano d\u2019Occidente, dopo che Roma \u00e8 stata saccheggiata prima, nel 410, dai visigoti di Alarico (395-410) e poi, nel 455, dai vandali di Genserico (428-477); ma la parte orientale dell\u2019impero sopravvive attorno a Costantinopoli, la Nuova Roma creata dall\u2019imperatore Costantino I il Grande (324-337) dove sorgeva la vecchia Bisanzio, in posizione decisiva per il controllo degli stretti che separano l\u2019Europa e l\u2019Asia.<\/p>\n<p style=\"text-align: justify;\">La minaccia germanica, che non era stata inferiore in Oriente &#8211; basti ricordare la terribile sconfitta subita dall\u2019imperatore Valente (364-378) a opera dei goti ad Adrianopoli nel 378 -, sta allontanandosi, mentre resta, ai confini orientali, la minacciosa e da sempre ostile presenza dell\u2019impero sassanide, erede dei parti. Anzi, all\u2019imperatore Giustiniano (527-565) \u00e8 possibile concepire e in qualche misura attuare un programma di riconquista della parte occidentale dell\u2019impero: con una rapida campagna annienta il regno vandalo e riprende l\u2019Africa Settentrionale; con una guerra quasi ventennale elimina la presenza ostrogota in Italia; infine, rioccupa vasti territori iberici lungo la costa mediterranea.<\/p>\n<p style=\"text-align: justify;\">Ma gi\u00e0 nel 568 &#8211; o 569 &#8211; i longobardi invadono l\u2019Italia, che rimane, dopo ripetuti conflitti, divisa in due parti, una sotto i nuovi sovrani germanici, l\u2019altra ancora integrata nell\u2019impero, la cui presenza nell\u2019Italia Meridionale si protrarr\u00e0 fino al secolo XI. Gi\u00e0 vivente Giustiniano, vecchie e nuove minacce si ripresentano ai confini settentrionali e orientali; unni e avari premono a nord, mentre il re sassanide Cosroe I il Grande (531-579) scatena nuove offensive in Mesopotamia e in Armenia.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, le preoccupazioni delle diverse guerre non impediscono a Giustiniano di completare l\u2019imponente opera di sistemazione delle leggi e del sapere giuridico, che pu\u00f2 ben essere riassunta con le parole che Dante Alighieri (1265-1321) attribuisce all\u2019imperatore nel canto VI del <em>Paradiso<\/em>: <em>&#8220;dalle leggi tolsi il troppo e il vano&#8221;<\/em>; sar\u00e0 questa, dal secolo XI, la base della rinascita del diritto romano e della formazione del diritto comune della Cristianit\u00e0 Occidentale.<\/p>\n<p style=\"text-align: justify;\">Ma ben pi\u00f9 gravi sono le conseguenze dell\u2019espansione araba, la quale, subito dopo la morte del fondatore dell\u2019islam, il profeta Maometto (570 ca.-632), si abbatte sull\u2019impero persiano, che viene annientato e completamente assorbito, e sull\u2019impero bizantino, il quale, in una ottantina di anni, perde tutte le province africane, la Palestina, la Siria e parte dell\u2019Asia Minore; seguir\u00e0, nel secolo IX, la conquista della Sicilia.<\/p>\n<p style=\"text-align: justify;\">La stessa Costantinopoli, assediata, viene salvata nel 717 dall\u2019imperatore Leone III (717-741), fondatore della dinastia isaurica; la sua vittoria &#8211; gli arabi tolgono l\u2019assedio dopo un anno, nell\u2019agosto del 718 &#8211; <em>&#8220;<\/em>[&#8230;]<em> per l\u2019Islam<\/em> &#8211; scrive Charles Diehl (1859-1944) &#8211;<em>, fu un grande disastro: un avvenimento d\u2019un\u2019importanza ben diversa dalla vittoria riportata quindici anni pi\u00f9 tardi (732) da Carlo Martello nelle pianure di Poitiers. Lo slancio arabo era definitivamente spezzato, e i pii Bizantini potevano a giusto titolo andar orgogliosi di vedere Dio e la Vergine proteggere sempre fedelmente la Citt\u00e0 e l\u2019impero cristiano&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\">La dinastia isaurica, per\u00f2, scatena la lotta contro il culto delle immagini &#8211; iconoclastia -, aprendo una grave crisi religiosa che dura vari decenni, fino al 780, quando Irene &#8211; da quell\u2019anno reggente per il figlio Costantino VI (780-797 ca.), poi imperatrice (797-802) &#8211; pone temporaneamente fine a tale politica. Mentre in Occidente, nell\u2019anno 800, viene restaurato il Sacro Romano Impero con l\u2019incoronazione di Carlo Magno (800-814), in Oriente l\u2019imperatore Niceforo (802-811) riprende la politica iconoclasta, con nuovi gravi conflitti interni.<\/p>\n<p style=\"text-align: justify;\">Essa dura fino all\u2019843, quando un concilio, presieduto dal nuovo patriarca san Metodio (843-847), restaura il culto delle immagini. Tuttavia, in un contesto storico in cui rari e poco consistenti sono i rapporti fra Occidente e Oriente, la Chiesa di Roma e la Chiesa Greca si allontanano sempre pi\u00f9. Gi\u00e0 con il patriarca di Costantinopoli Fozio (858-867 e 877-886), tanto colto quanto ambizioso, vi sono ripetute rotture con il papato, proprio negli anni in cui i santi Cirillo (827 ca.-869) e Metodio (825 ca.-885) iniziano l\u2019opera di evangelizzazione degli slavi.<\/p>\n<p style=\"text-align: justify;\">Si arriver\u00e0 alla rottura definitiva con il patriarca Michele Cerulario (1043-1058) che rifiuta d\u2019incontrare i legati pontifici, arrivati nella capitale imperiale per risolvere diverse questioni alla base degli attriti esistenti; essi allora, il 16 luglio 1054, depongono sull\u2019altare della basilica di Santa Sofia una bolla di scomunica alla quale Michele reagisce con una contro-scomunica, riuscendo a trascinare con s\u00e9 anche i patriarchi di Gerusalemme, di Antiochia e di Alessandria: <em>&#8220;Se lo scisma accrebbe notevolmente l\u2019autorit\u00e0 del patriarcato di Costantinopoli sui tre patriarchi e sul mondo slavo <\/em>&#8211; nota il bizantinologo Silvio Giuseppe Mercati (1877-1963) &#8211;<em>, dal punto di vista politico fu esiziale all\u2019impero bizantino, in quanto fu preclusa ogni possibilit\u00e0 d\u2019intesa durevole tra Bisanzio e l\u2019Occidente e rese pi\u00f9 difficili gli aiuti dei Latini contro la minaccia turca&#8221;<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>2. Apogeo e crisi<\/strong><\/p>\n<p style=\"text-align: justify;\">Frattanto l\u2019impero bizantino conosce il suo apogeo sotto gli imperatori della dinastia macedone, fondata da Basilio I (867-886). Accanto a una profonda riorganizzazione sociale, istituzionale e militare, viene ripresa vittoriosamente la lotta contro gli arabi: nel 960 viene riconquistata Creta, in Asia il confine \u00e8 riportato al Tigri e all\u2019Eufrate e l\u2019Italia Meridionale \u00e8 riportata sotto il controllo imperiale, grazie al successo del Garigliano del 915, cui seguir\u00e0, nel 1018, la vittoria di Canne su una rivolta pugliese.<\/p>\n<p style=\"text-align: justify;\">Ma, soprattutto, viene definitivamente liquidato l\u2019impero bulgaro dopo una guerra trentennale, dal 986 al 1018. Una notevole prosperit\u00e0 economica e una fase di splendore letterario e artistico caratterizzano questi secoli. Dopo il Mille, per\u00f2, mentre la Cristianit\u00e0 latina conosce una vigorosa ripresa economica, demografica, urbana e culturale, l\u2019impero si trova ad affrontare nuove difficolt\u00e0 interne, collegate anche alle lotte dinastiche, ed esterne: mentre a Occidente i normanni eliminano ogni residua presenza bizantina nell\u2019Italia Meridionale e attaccano l\u2019Epiro, in Oriente i turchi selgiuchidi conquistano, dopo la battaglia di Mantzikiert del 1071, l\u2019Armenia e la Cappadocia, giungendo, infine, davanti a Costantinopoli con la presa di Crisopoli del 1079.<\/p>\n<p style=\"text-align: justify;\">Le crisi favoriscono l\u2019ascesa al trono di una grande famiglia feudale, i Comneni, con Alessio I (1081-1118). Sotto il regno di questo sovrano si svolge la prima crociata (1096-1099), che mostra quanto difficili siano ormai i rapporti fra bizantini e latini: i territori siriani e palestinesi riconquistati dai crociati, non sostenuti dai bizantini, sono organizzati in Stati &#8220;franchi&#8221; e l\u2019arcivescovo di Pisa Daiberto (1089 ca.-1105) diventa patriarca latino di Gerusalemme (1099-1107).<\/p>\n<p style=\"text-align: justify;\">Verso la fine del secolo l\u2019impero entra in una gravissima crisi: mentre nel 1182 un moto xenofobo nella capitale porta al massacro dei latini presenti, pi\u00f9 spesso la debolezza politica costringe gli imperatori a larghe concessioni verso i mercanti stranieri; rinasce un impero bulgaro, i cui territori vanno da Belgrado al Mar Nero, alle lotte dinastiche si sommano le ribellioni feudali, una delle quali, nel 1185, porta al potere la dinastia degli Angeli; corruzione e pressione fiscali crescono di pari passo.<\/p>\n<p style=\"text-align: justify;\">Nel 1202 i crociati, radunati a Venezia, non potendo far fronte agli impegni finanziari presi con la Serenissima per il trasporto marittimo, si pongono al servizio dei suoi obbiettivi, prima espugnando Zara, che si era messa sotto la protezione del regno di Ungheria ribellandosi alla citt\u00e0 lagunare, poi minacciando la stessa Costantinopoli.<\/p>\n<p style=\"text-align: justify;\">Quando il giovane imperatore Alessio IV (1203-1204), che aveva fatto larghissime promesse ai crociati e a Venezia, viene ucciso da un sollevamento popolare, i crociati attaccano Costantinopoli, che \u00e8 conquistata e saccheggiata il 12 aprile 1204. Viene creato l\u2019impero latino di Oriente, sotto Baldovino di Fiandra (1204-1206 ca.), ma molti territori sono assegnati ad altri signori occidentali e a Venezia, mentre in diverse aree nascono Stati greci che reclamano l\u2019eredit\u00e0 dell\u2019impero bizantino.<\/p>\n<p style=\"text-align: justify;\">Uno di questi &#8211; l\u2019impero di Nicea &#8211; prevale sugli altri e nel 1261, anche grazie al sostegno genovese, restaura l\u2019impero con Michele VIII (1259-1282), fondatore della dinastia dei Paleologi, che governa per quasi due secoli, fino alla sua fine. Lotte religiose, conflitti sociali, rivolte cittadine come quella di Tessalonica che si costituisce in repubblica indipendente (1342-1347), ristrettezze finanziarie, pressioni bulgare e serbe oltre che turche, caratterizzano l\u2019ultima fase dell\u2019esistenza ormai millenaria dell\u2019impero.<\/p>\n<p style=\"text-align: justify;\">Pi\u00f9 volte gli imperatori negoziano con Roma la riunificazione delle Chiese per eliminare un grosso ostacolo a un maggiore impegno delle potenze occidentali di fronte all\u2019avanzata sempre pi\u00f9 inarrestabile dei turchi ottomani; ma ogni volta parti consistenti e turbolente del clero greco e anche dei laici si oppongono violentemente a tale indirizzo.<\/p>\n<p style=\"text-align: justify;\">Grazie anche al viaggio dell\u2019imperatore Giovanni VIII (1425-1448) in Occidente il Concilio di Firenze, nel quale il papato fa ampie concessioni, pu\u00f2, nel 1439, proclamare la riunificazione delle due Chiese; ma le correnti anti-romane non ne accettano il risultato e i disordini religiosi sono forti anche negli ultimi anni, bench\u00e9 la minaccia turca incomba ormai sulla stessa capitale. I principali esponenti della corrente unionista passano direttamente alla Chiesa di Roma, come Giovanni Bessarione, futuro cardinale (1403-1472).<\/p>\n<p style=\"text-align: justify;\"><strong>3. L\u2019aiuto della Cristianit\u00e0 latina<\/strong><\/p>\n<p style=\"text-align: justify;\">La Cristianit\u00e0 latina, spesso distratta rispetto a quanto accade in Oriente, fa comunque due grossi sforzi anti-turchi: ma essi sono segnati da altrettante disfatte, quella di Nicopoli nel 1396 e quella della Varna nel 1444. Peraltro pochi sono i difensori occidentali di Costantinopoli quando, all\u2019inizio di aprile del 1453, Maometto II (1451-1481) l\u2019assedia con forze enormemente superiori, sia in uomini che in armamento, a quelle dei difensori: il contingente pi\u00f9 significativo \u00e8 quello genovese, che giunge prima dell\u2019inizio dell\u2019assedio, mentre Venezia era da decenni impegnata prevalentemente nella politica italiana.<\/p>\n<p style=\"text-align: justify;\">La resistenza \u00e8 accanita, ricca di episodi eroici. Alla vigilia dell\u2019assalto decisivo <em>&#8220;<\/em>[&#8230;] <em>i cristiani, Greci e Latini assieme <\/em>&#8211; scrive Georg Ostrogorsky (1902-1976) &#8211;<em>, celebravano in Santa Sofia la loro ultima funzione religiosa. Dopo la funzione i soldati tornarono ai loro posti e fino a tarda notte l\u2019imperatore ispezion\u00f2 le fortificazioni&#8221;<\/em>. Il giorno dopo, 29 maggio 1453, vinte le ultime resistenze, i turchi s\u2019impadroniscono di Costantinopoli, dando il via al saccheggio e ai massacri. L\u2019ultimo imperatore, Costantino XI Dragaz\u00e8s (1449-1453), muore eroicamente, dando a Bisanzio una fine degna della sua grandezza. Quindi Maometto II entra in citt\u00e0 e va in Santa Sofia a ringraziare il Dio dell\u2019islam.<\/p>\n<p style=\"text-align: justify;\">Nato con la fondazione costantiniana della capitale, l\u2019impero muore praticamente con essa: il despotato di Morea e l\u2019impero di Trebisonda sopravvivono pochissimi anni; Atene \u00e8 conquistata nel 1456. Di questo impero non possiamo e non dobbiamo dimenticare la plurisecolare funzione di bastione contro l\u2019islam, l\u2019altezza delle sue espressioni spirituali, letterarie e artistiche, il contributo alla diffusione del cristianesimo e all\u2019organizzazione del prima informe mondo slavo, la trasmissione all\u2019Occidente di tanta parte della cultura greca, classica, ellenistica e cristiana.<\/p>\n<p style=\"text-align: justify;\"><strong>Per approfondire:<\/strong> vedi la sintesi di Charles Diehl, <em>Storia dell\u2019impero bizantino<\/em>, trad. it., Edizioni Orientalia Christiana, Roma 1977; pi\u00f9 ampiamente Georg Ostrogorsky, <em>Storia dell\u2019impero bizantino<\/em>, trad. it., Einaudi, Torino 1993; quanto alla civilt\u00e0 e alle strutture di lunga durata, vedi dello stesso Ch. Diehl, <em>La civilt\u00e0 bizantina<\/em>, trad. it., Garzanti, Milano 1962; sulla mentalit\u00e0 e sulla vita quotidiana, Alain Ducellier, <em>Il dramma di Bisanzio<\/em>, trad. it., Liguori, Napoli 1980; e <em>L\u2019uomo bizantino<\/em>, a cura di Guglielmo Cavallo, Laterza, Bari 1994.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I.D.I.S. &#8211; Istituto per la Dottrina e l&#8217;Informazione Sociale Voci per un dizionario del pensiero forte di Marco Tangheroni<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28071,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[954],"class_list":["post-1273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storia","tag-bisanzio","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-04T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-26T11:49:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"301\" \/>\n\t<meta property=\"og:image:height\" content=\"167\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Bisanzio o la civilt&agrave; cristiana romano-orientale\",\"datePublished\":\"2005-09-04T22:00:00+00:00\",\"dateModified\":\"2015-11-26T11:49:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/\"},\"wordCount\":1962,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Bisanzio.jpg\",\"keywords\":[\"Bisanzio\"],\"articleSection\":[\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/\",\"name\":\"Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Bisanzio.jpg\",\"datePublished\":\"2005-09-04T22:00:00+00:00\",\"dateModified\":\"2015-11-26T11:49:20+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Bisanzio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/09\\\/Bisanzio.jpg\",\"width\":301,\"height\":167},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/bisanzio-o-la-civilt-cristiana-romano-orientale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bisanzio o la civilt&agrave; cristiana romano-orientale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/","og_locale":"it_IT","og_type":"article","og_title":"Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-09-04T22:00:00+00:00","article_modified_time":"2015-11-26T11:49:20+00:00","og_image":[{"width":301,"height":167,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Bisanzio o la civilt&agrave; cristiana romano-orientale","datePublished":"2005-09-04T22:00:00+00:00","dateModified":"2015-11-26T11:49:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/"},"wordCount":1962,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg","keywords":["Bisanzio"],"articleSection":["Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/","name":"Bisanzio o la civilt&agrave; cristiana romano-orientale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg","datePublished":"2005-09-04T22:00:00+00:00","dateModified":"2015-11-26T11:49:20+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/09\/Bisanzio.jpg","width":301,"height":167},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/bisanzio-o-la-civilt-cristiana-romano-orientale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Bisanzio o la civilt&agrave; cristiana romano-orientale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1273"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1273\/revisions"}],"predecessor-version":[{"id":28072,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1273\/revisions\/28072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28071"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}