{"id":1196,"date":"2005-08-17T00:00:00","date_gmt":"2005-08-16T22:00:00","guid":{"rendered":""},"modified":"2016-01-04T11:53:16","modified_gmt":"2016-01-04T10:53:16","slug":"guernica","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/","title":{"rendered":"Guernica"},"content":{"rendered":"<div style=\"text-align: center;\">\u00a9<strong> <em>Le cose della vita<\/em><\/strong>, San Paolo, Milano 1995, p. 240.<\/div>\n<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-29170\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg\" alt=\"Guernica\" width=\"300\" height=\"168\" \/><\/a><\/div>\n<p style=\"text-align: center;\">di <strong>Vittorio Messori<\/strong><\/p>\n<p style=\"text-align: justify;\">Da buon spagnolo, Pablo Ruiz Biasco y Picasso amava le corride. Fu, dunque, sconvolto dalla tragica morte di un suo beniamino, il famoso torero Joselito. Per celebrarne la memoria, mise in cantiere un&#8217;enorme tela d\u00ec 8 metri per 3 e mezzo, che grem\u00ec di figure tragicamente atteggiate, a colori luttuosi. Finita che l&#8217;ebbe, la chiam\u00f2 <em>En muerte del torero Joselito.<\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Correva per\u00f2 il 1937, in Spagna infuriava la guerra civile e il governo anarco-socialcomunista si rivolse a Picasso per avere da lui un quadro per il padiglione repubblicano all&#8217;Esposizione Universale in programma a Parigi per l&#8217;anno dopo<\/div>\n<p style=\"text-align: justify;\">&gt;Il Picasso (che diventer\u00e0, non a caso, uno degli artisti pi\u00f9 ricchi della storia) ebbe una pensata geniale: fece qualche modifica alla tela per il torero, la ribattezz\u00f2 <em>Guernica <\/em>(dal nome della citt\u00e0 basca bombardata dall&#8217;aviazione tedesca e italiana) e la vendette al governo &#8220;popolare&#8221; per la non modicaa cifra di 300.000 pesetas dell&#8217;epoca. Qualcosa come qualche miliardo &#8211; pare due o tre &#8211; di lire di oggi, che furono vcrsati da Stalin attraverso il Comintern.<\/p>\n<p style=\"text-align: justify;\">Contento Picasso, ovviamente; contenti anche i socialcomunisti, che di quel quadro di tori e toreri fecero un simbolo che \u00e8 giunto sino a noi ed \u00e8 continuamente riprodotto, con emozione, come simbolo della protesta dell&#8217;umanit\u00e0 civile contro la barbarie nazi-fascista. Stando a molti critici d&#8217;arte, Guernica \u00e8 il pi\u00f9 celebre quadro del secolo.<\/p>\n<p style=\"text-align: justify;\">E, ci\u00f2, grazie proprio alla &#8220;sponsorizzazione&#8221; da parte delle sinistre, a cominciare dai <em>liberals<\/em> occidentali: la tela picassiana ebbe una sala tutta per s\u00e9 al <em>Metropolitan Museum<\/em> di New York e vide milioni di &#8221;pellegrini&#8221; sfilare in religioso silenzio.<\/p>\n<p style=\"text-align: justify;\">Si arriva al grottesco di interpretazioni come quella &#8211; un esempio a caso tra mille &#8211; della pur pregevole enciclopedia <em>Rizzoli-Larousse <\/em>che alla tela dedica oltre venti., fitte righe, nelle quali si dice, tra l&#8217;altro: &#8220;Motivo centrale, l&#8217;angoscia della testa del cavallo che sovrasta il duro lastricato dei cadaveri: in alto, a sinistra, l&#8217;antico simbolo della violenza, il Minotauro&#8221;<\/p>\n<p style=\"text-align: justify;\">Ora, il presunto &#8220;Minotauro&#8221; altre non \u00e8 che il toro che uccise Joselito; e il cavallo \u00e8 quello del <em>picad\u00f2r, <\/em>sventrato nell&#8217;arena dallo stesso animale. Una storia, dunque, di tauromachia. dove la &#8220;protesta civile&#8221;, la &#8220;passione politica&#8221; non c&#8217;entrano nulla, se non, forse, in qualche particolare aggiunto per rifilare il quadro, a suon di miliardi, alle generose <em>Izquierdas <\/em>iberiche.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 occuparsi di <\/strong><em><strong>Guernica?<\/strong> <\/em>Ma perch\u00e9, in epoca di riletture della storia dopo il crollo delle menzogne ideologiche, \u00e8 ora di andare a vedere che ci sia davvero dietro tante storie edificanti sulle quali comunisti e simpatizzanti avevano costruito un mito sul quale era terroristicamente proibito indagare. Se il quadro di Picasso \u00e8 una sorta di truffa, non si pu\u00f2 certo dire che la verit\u00e0 trionfi nella realt\u00e0 che gli ha dato il nome.<\/p>\n<p style=\"text-align: justify;\">Da un controllo, anche su libri di storia &#8220;cattolici&#8221;, risulta che ci\u00f2 che \u00e8 accettato da tutti \u00e8 quanto segue: &#8220;Guernica era una cittadina sacra ai baschi, perch\u00e9 sotto un suo albero i re di Spagna giuravano di rispettare le libert\u00e0 della regione. Durante la guerra civile, malgrado fosse indifesa e non rappresentante un obiettivo militare, il 26 aprile 1937 fu distrutta da un selvaggio bombardamento dell&#8217;aviazione tedesca che voleva sperimentare nuove tecniche e nuovi velivoli.<\/p>\n<p style=\"text-align: justify;\">Per sadismo, fu scelto il luned\u00ec, giorno di mercato: ci furono, cos\u00ec, ben 1654 morti e 889 feriti, tutti vecchi, bambini, donne, perch\u00e9 gli uomini erano a combattere contro Franco&#8221;. Una &#8220;verit\u00e0&#8221; codificata una volta per sempre anche nella <em>Storia della guerra civile spagnola <\/em>(stampata, in Italia, da Einaudi) di Hugh Thomas. \u00c8 significativo che questo storico, nella edizione &#8220;rivista&#8221; della sua <em>Storia, <\/em>abbia poi ridotto a 200 il numero dei morti: 1454in meno da una ristampa all&#8217;altra. E senza dare spiegazioni\u2026<\/p>\n<p style=\"text-align: justify;\">La realt\u00e0 \u00e8 del tutto diversa, come hanno stabilito anche commissioni internazionali di inchiesta. Come and\u00f2 davvero lo si sa da decenni, ma la forza della propaganda sembra ancora invincibile.<\/p>\n<p style=\"text-align: justify;\"><strong>Guernica costituiva<\/strong> un normale obiettivo militare, come ben sapeva anche il governo rosso&#8221; che vi aveva installato pezzi contraerei e scavato sette rifugi collettivi. In effetti, la citt\u00e0 era sede di due importanti fabbriche, d&#8217;armi leggere e di bombe d&#8217;aviazione. Inoltre era nodo stradale e ferroviario per i repubblicani che combattevano a una dozzina di chilometri dalla citt\u00e0, che rigurgitava di soldati e di mezzi militari.<\/p>\n<p style=\"text-align: justify;\">Non si dimentichi che l&#8217;importanza strategica di Guernica veniva anche dalle fortificazioni che i baschi vi avevano costruito (la cintura di ferro&#8221;, come la chiamavano) per marcare l&#8217;indipendenza della loro regione nei confronti delle altre etnie spagnole. Non era affatto, dunque, il &#8220;bucolico, sacro villaggio dove mercanti e villici portavano pacificamente le loro povere cose&#8221;, per dirla con Thomas.<\/p>\n<p style=\"text-align: justify;\">Alcuni bombardieri (di vecchio tipo) inviati dalla Germania e 18 aerei, tra pesanti e leggeri, del Corpo di spedizione italiano, nel pomeriggio di quel 26 aprile 1937 fecero alcuni passaggi per distruggere il ponte di Renteria, sul fiume Oca e ostacolare cos\u00ec i movimenti dei repubblicani.<\/p>\n<p style=\"text-align: justify;\">La maggioranza dell&#8217;esplosivo italo-tedesco cadde sul nodo stradale attorno al ponte e solo alcune bombe sulla citt\u00e0: su 39 crateri individuati dalla ricognizione aerea, solo 7 risultano nell&#8217;abitato. I morti accertati &#8211; anche da accurati controlli all\u2019anagrafe &#8211; furono 93, cui \u00e8 forse da aggiungere qualcun altro tra soldati isolati. Quasi la met\u00e0 di quei 93 mor\u00ec per il crollo di un rifugio appena costruito ma evidentemente inadeguato: Forse, gli appalti truccati esistevano anche tra i baschi &#8220;rossi&#8221;\u2026<\/p>\n<p style=\"text-align: justify;\">In ogni caso, non si supera il centinaio, com&#8217;\u00e8 provato da ripetute indagini sull&#8217;anagrafe della citt\u00e0, che contava 5.000 abitanti in tutto: bilancio tragico ma, purtroppo, di <em>routine <\/em>nella pi\u00f9 sanguinosa guerra civile della storia che, alla fine, cont\u00f2 quasi un milione di morti. In Ogni caso, si \u00e8 abissalmente lontani dai 1654 caduti (e 889 feriti) che sono entrati nella leggenda sempre ripetuta.<\/p>\n<p style=\"text-align: justify;\">E si \u00e8 ben lontani anche dalle migliaia di cadaveri che furono il tragico prezzo da pagare &#8211; in quella lotta spietata &#8211; per la conquista di tanti altri obiettivi militari, \u00c9 vero che documenti fotografici e cinematografici mostrano la citt\u00e0 semidiroccata. Ma questo perch\u00e9 (come dimostr\u00f2 una commissione internazionale; e come Fu appurato persino dal tribunale di Norimberga che giudic\u00f2 i generali nazisti) prima di ritirarsi i socialcomunisti e gli anarchici cosparsero di benzina tutto ci\u00f2 che poterono e vi diedero fuoco Non un solo cratere di bomba fu trovato tra le rovine bruciate del centro storico.<\/p>\n<p style=\"text-align: justify;\">Fu provato, inoltre, che i minatori anarchici delle Asturie. fuggendo, fecero saltare con la dinamite, di cui disponevano in abbondanza, molti edifici per creare ostacoli alle truppe franchiste.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma come nacque <\/strong>la leggenda giunta sino a noi, malgrado le risultanze delle inchieste internazionali e il lavoro &#8211; inascoltato, per lo pi\u00f9 &#8211; di qualche storico con il rispetto della sua professione? All&#8217;inizio della manipolazione della verit\u00e0 c\u2019\u00e8 un corrispondente di guerra inglese, George L. Steer, il quale, pur non essendo sul posto quel giorno, sped\u00ec da Bilbao (dopo essersi accordato con tre colleghi e connazionali per non smentirsi a vicenda) una cronaca fantasiosa al suo giornale di Londra.<\/p>\n<p style=\"text-align: justify;\">Da soldati baschi, Steer (che secondo molti apparteneva allo spionaggio inglese) aveva appreso che il luned\u00ec, a Guernica, si teneva un affollato mercato; e poich\u00e9 quel 26 aprile era, appunto, un luned\u00ec, lavor\u00f2 di fantasia immaginando le inermi massaie e i vecchi contadini spappolati dalle bombe tedesche (tra l&#8217;altro, visto che il miro esige &#8220;cattivi&#8221; che lo siano davvero, da allora, parlando di Guernica, si disse solo dei tedeschi, tacendo degli italiani che furono invece presenti in forze sul ponte con tre moderni bombardieri S79 e con 15 caccia CR32).<\/p>\n<p style=\"text-align: justify;\">Per tornare al corrispondente inglese e ai colleghi che gli tenevano bordone: non sapevano che il mercato quel luned\u00ec non si era svolto, poich\u00e9 il Delegato militare del governo basco lo aveva vietato, temendo appunto azioni di guerra. In ogni caso, non avrebbe potuto essere colpito, visto che il mercato terminava sul mezzogiorno e l&#8217;azione italo-tedesca si svolse a partire dalle 16.15.<\/p>\n<p style=\"text-align: justify;\">Della corrispondenza Fantasiosa di Steer e dei colleghi si impadronirono subito due propagande: quella anarco-comunista, naturalmente; ma anche quella britannica, poich\u00e9 il nuovo governo di Chamberlain doveva convincere l&#8217;opinione pubblica della necessit\u00e0 di affrontare grandi spese per il riarmo, vista la barbarie tedesca e la potenza delle sue armi (da qui, l&#8217;invenzione che Guernica fosse stata colpita da modernissimi velivoli). Il lucroso falso di Picasso complet\u00f2 la leggenda che tutti, sino a qui, hanno preso per storia vera.<\/p>\n<p style=\"text-align: justify;\">_________________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a style=\"font-size: 12px;\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1179\">Il mito di Guernica<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a9 Le cose della vita, San Paolo, Milano 1995, p. 240. di Vittorio Messori Da buon spagnolo, Pablo Ruiz Biasco y Picasso amava le corride. Fu, dunque, sconvolto dalla tragica morte di un suo beniamino, il famoso torero Joselito. Per celebrarne la memoria, mise in cantiere un&#8217;enorme tela d\u00ec 8 metri per 3 e mezzo, &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,24],"tags":[900,2404],"class_list":["post-1196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guerra-di-spagna","category-storia","tag-guernica","tag-guerra-di-spagna","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guernica - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guernica - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-08-16T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-04T10:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Guernica\",\"datePublished\":\"2005-08-16T22:00:00+00:00\",\"dateModified\":\"2016-01-04T10:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/\"},\"wordCount\":1405,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Guernica.jpg\",\"keywords\":[\"Guernica\",\"Guerra di Spagna\"],\"articleSection\":[\"Guerra di Spagna\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/\",\"name\":\"Guernica - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Guernica.jpg\",\"datePublished\":\"2005-08-16T22:00:00+00:00\",\"dateModified\":\"2016-01-04T10:53:16+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Guernica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Guernica.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/guernica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guernica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guernica - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/","og_locale":"it_IT","og_type":"article","og_title":"Guernica - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-08-16T22:00:00+00:00","article_modified_time":"2016-01-04T10:53:16+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Guernica","datePublished":"2005-08-16T22:00:00+00:00","dateModified":"2016-01-04T10:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/"},"wordCount":1405,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg","keywords":["Guernica","Guerra di Spagna"],"articleSection":["Guerra di Spagna","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/","name":"Guernica - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg","datePublished":"2005-08-16T22:00:00+00:00","dateModified":"2016-01-04T10:53:16+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Guernica.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/guernica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Guernica"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1196"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1196\/revisions"}],"predecessor-version":[{"id":29171,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1196\/revisions\/29171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29170"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}