{"id":1190,"date":"2005-08-15T11:30:05","date_gmt":"2005-08-15T09:30:05","guid":{"rendered":""},"modified":"2016-03-11T09:01:15","modified_gmt":"2016-03-11T08:01:15","slug":"lo-spinello-debutta-a-11-anni","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/","title":{"rendered":"Lo spinello debutta a 11 anni"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-31661\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg\" alt=\"bambini_droga\" width=\"250\" height=\"161\" \/>Pubblicato su <strong>Avvenire<\/strong> il 9 giugno 2005<\/div>\n<p style=\"text-align: justify;\"><em>Sono adolescenti, fanno sport e vanno bene a scuola, ma non sanno rinunciare alla \u201ccanna\u201d e alle pasticche. Negli ultimi 5 anni l\u2019et\u00e0 media si \u00e8 abbassata fortemente.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Pino Ciociola<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Si &#8220;bruciano&#8221; senza sapersene nemmeno accorgere. Persino gi\u00e0 a 11 anni. Una bella canna o una bella impasticcata, magari di sabato sera &#8211; tanto \u00abnon fa troppo male\u00bb, tanto soldi in tasca ne hanno &#8211; cos\u00ec i problemi e\/o la noia sembrano risolversi: cervello e carattere, intanto, cominciano a liquefarsi. La situazione \u00e8 \u00abdrammatica\u00bb. E cos\u00ec l&#8217;ha fatta conoscere ieri mattina la Federserd (Federazione italiana degli operatori e dei dipartimenti e dei servizi delle dipendenze) riunita a congresso.<\/div>\n<p style=\"text-align: justify;\">Raccontando che la droga gira ormai anche fra i banchi delle prime medie, che lo spinello lo fumano ragazzini insospettabili che hanno bei voti e fanno s ort, e che sempre pi\u00f9 spesso si tratta ragazzine. A proposito, neppure lo spinello \u00e8 pi\u00f9 quello di una volta, quello degli anni&#8217; 70, quando conteneva al massimo il 2% di sostanza attiva: oggi ce n&#8217;\u00e8 fino al 15 \/16%, col risultato di provocare effetti allucinogeni che prima non si producevano.<\/p>\n<p style=\"text-align: justify;\">Un quadro angosciante confermato dal direttore generale del Dipartimento nazionale contro le tossicodipendenze presso la presidenza del Consiglio, Andrea Fantoma: \u00abNegli ultimi cinque anni l&#8217;et\u00e0 media di assunzione si \u00e8 abbassata vertiginosamente &#8211; ha spiegato, anticipando alcuni dati della prossima &#8220;Relazione annuale al Parlamento sulle tossicodipendenze&#8221; -. \u00c8 poi aumentato l&#8217;uso di amfetamine e, anche qui, gli assuntori sono giovani e giovanissimi. Di fronte a questo scenario; profondamente cambiato, occorre trovare soluzioni articolate per fornire risposte adeguate\u00bb. Il punto \u00e8 che l&#8217;allarme viene lanciato da molto tempo.<\/p>\n<p style=\"text-align: justify;\">Fra luglio 1990 e dicembre 2000, ad esempio, erano stati segnalati ai Prefetti dalle forze dell&#8217;ordine (per detenzione di sostanze stupefacenti per uso personale) 22.620 minorenni. Oppure si leggeva nella Relazione 1997 dell\u2019Osservatorio europeo delle droghe e delle tossicodipendenze&#8221; di Lisbona (l&#8217;agenzia dell&#8217;Ue) che \u00abin alcuni Paesi dell&#8217;Unione un numero senza precedenti di ragazzi di et\u00e0 sempre pi\u00f9 giovane ha iniziato a usare droghe sintetiche (&#8230;)\u00bb.<\/p>\n<p style=\"text-align: justify;\">E veniva sottolineata \u00abla facilit\u00e0 con cui il consumo di droghe sintetiche oltrepassa i confini nazionali\u00bb. Tutto questo senza dimenticare che, fra gli operatori pubblici e privati (cio\u00e8 Sert e Comunit\u00e0 terapeutiche), le prime grosse preoccupazioni sull&#8217;et\u00e0 in discesa di chi assume sostanze stupefacenti risalgono almeno al 1993, durante la prima Conferenza nazionale sulle tossicodipendenze a Palermo.<\/p>\n<p style=\"text-align: justify;\">Sono passati dodici anni. E adesso uno dei risultati \u00e8 questo: \u00abCi sono in Calabria ragazzini, ma anche ragazzine, di 11,12 anni che fumano marijuana e cannabis e quando arrivano a 14 o 15 sono dipendenti dall&#8217;eroina e dalla cocaina. Tanto da chiedere aiuto al Sert. E al mattino, prima di recarsi a scuola, passano e ritirano la loro terapia\u00bb, raccontava ieri Bernardo Grande, sociologo, direttore del Sert e del Dipartimento delle dipendenze della Asl 7 di Catanzaro.<\/p>\n<p style=\"text-align: justify;\">Ma non crediate c&#8217;entrino fattori geografici. \u00abSi \u00e8 abbassata a 13, 14 anni l&#8217;et\u00e0 del primo contatto con la cannabis &#8211; diceva Edo Polidori, responsabile del Sert di Faenza &#8211; perch\u00e9 in realt\u00e0 si stanno modificando in termini assoluti i costumi, i valori, il modo di affrontare la vita. E di conseguenza anche il rapporto che i giovanissimi hanno con le sostanze che possono dare dipendenza, legali o illegali, \u00e8 cambiato. Si \u00e8 &#8220;normalizzato&#8221;\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ultima conferma. Hashish e marijuana sono gli stupefacenti maggiormente consumati dai giovani. Lo sottolinea l&#8217;indagine Espad Italia 2003, condotta dal Cnr e presentata sempre ieri al Congresso della Federserd. Un\u2019indagine su 27.392 ragazzi tra 15 e 19 anni, e alla quale viene fuori che appunto la sostanza pi\u00f9 utilizzata \u00e8 l&#8217;hashish-marijuana: tra i maschi (32,7%) e tra le femmine (22,9%). Al secondo posto c&#8217;\u00e8 la cocaina (6,3% maschi e 3% femmine). Al terzo l\u2019 eroina &#8220;fumata&#8221; (3,5% ragazzi e 2% ragazze), modalit\u00e0 meno invasiva della siringa, ma anche meno riconducibile al &#8220;tossico di strada&#8221;. Non manca infine l&#8217;ecstasy: ne prendono il 3,8% di maschi e l&#8217;1,6% di femmine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato su Avvenire il 9 giugno 2005 Sono adolescenti, fanno sport e vanno bene a scuola, ma non sanno rinunciare alla \u201ccanna\u201d e alle pasticche. Negli ultimi 5 anni l\u2019et\u00e0 media si \u00e8 abbassata fortemente. di Pino Ciociola<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31661,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[917],"class_list":["post-1190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-droga","tag-spinello","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-08-15T09:30:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-11T08:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Lo spinello debutta a 11 anni\",\"datePublished\":\"2005-08-15T09:30:05+00:00\",\"dateModified\":\"2016-03-11T08:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/bambini_droga-1.jpg\",\"keywords\":[\"spinello\"],\"articleSection\":[\"Droga\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/\",\"name\":\"Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/bambini_droga-1.jpg\",\"datePublished\":\"2005-08-15T09:30:05+00:00\",\"dateModified\":\"2016-03-11T08:01:15+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/bambini_droga-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/bambini_droga-1.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lo-spinello-debutta-a-11-anni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo spinello debutta a 11 anni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/","og_locale":"it_IT","og_type":"article","og_title":"Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-08-15T09:30:05+00:00","article_modified_time":"2016-03-11T08:01:15+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Lo spinello debutta a 11 anni","datePublished":"2005-08-15T09:30:05+00:00","dateModified":"2016-03-11T08:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/"},"wordCount":646,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg","keywords":["spinello"],"articleSection":["Droga"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/","name":"Lo spinello debutta a 11 anni - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg","datePublished":"2005-08-15T09:30:05+00:00","dateModified":"2016-03-11T08:01:15+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/bambini_droga-1.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lo-spinello-debutta-a-11-anni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Lo spinello debutta a 11 anni"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"predecessor-version":[{"id":31662,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1190\/revisions\/31662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31661"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}