{"id":1181,"date":"2005-08-12T11:23:14","date_gmt":"2005-08-12T09:23:14","guid":{"rendered":""},"modified":"2015-11-19T16:42:17","modified_gmt":"2015-11-19T15:42:17","slug":"cina-gli-operai-fuggono-dal-partito","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/","title":{"rendered":"Cina, gli operai fuggono dal partito"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27935\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg\" alt=\"Cina-operai\" width=\"250\" height=\"168\" \/><\/a>pubblicato su \u00a0<strong>Il Corriere della Sera<\/strong><\/div>\n<div style=\"text-align: center;\">del 10 maggio 2005<\/div>\n<p style=\"text-align: center;\">di\u00a0<strong>Fabio Cavalera<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">PECHINO &#8211; Alla scuola che forma i dirigenti comunisti lo ammettono. Il partito \u00e8 alle prese con una severa crisi di identit\u00e0 e di fiducia. \u00c8 una crisi che a medio-lungo termine minac\u00adcia l&#8217;equilibrio della societ\u00e0 cinese. La realt\u00e0, del resto, non pu\u00f2 essere negata. Un documento &#8211; la radiografia della Cina del 2004 pubblicata da poco dalla Accademia delle scienze, l&#8217;istituto di analisi che affianca il governo &#8211; contiene affermazioni inusuali.<\/div>\n<p style=\"text-align: justify;\">Leggiamone un paio: \u00abSebbene i membri del comitato politico centrale parlino spesso di servire il popolo o di agire per il bene del popolo spesso occupano il loro posto senza un senso di responsabilit\u00e0 per il popolo\u00bb. E ancora: \u00abRiguardo la rettitudine nei comportamenti politici, l\u2019atteggiamento dei membri del comitato \u00e8 piuttosto ambiguo e complicato\u00bb.<\/p>\n<p style=\"text-align: justify;\">Dietro ai pesanti silenzi o dietro ai titoli del \u201cQuotidiano del popolo\u201d del tipo \u00abmantenere il ruolo avanzato degli iscritti del Pcc\u00bb o \u00abvalorizzare il grande spirito dei lavoratori modello\u00bb si nasconde una profonda inquietudine. Cos\u00ec profonda che le strutture del partito hanno cominciato a interrogarsi sul futuro che le attende. La ragione di tale inquietudine \u00e8 che la capacit\u00e0 di interpretare i nuovi sentimenti della societ\u00e0 cinese si \u00e8 indebolita e ha raggiunto livelli di guardia. C&#8217;\u00e8 innanzitutto uno scontro di generazioni.<\/p>\n<p style=\"text-align: justify;\">Dice l&#8217;analisi della Accademia delle scienze: \u00abLe opinioni dei nuovi membri del partito sembrano non essere del tutto conformi a quelle dei vecchi membri del comitato politico centrale\u00bb. Ma poi si aggiungono tensioni inedite alla rigidit\u00e0 burocratica della organizzazione. Rivela la \u201cradiografia che il 20 per cento dei quadri dirigenti del partito chiede maggiore democrazia interna. E che il 45,5 per cento dei quadri comunisti ritiene essenziale la riforma del sistema politico e del sistema istituzionale.<\/p>\n<p style=\"text-align: justify;\">Il partito unico, il padrone della Cina, \u00e8 davanti a una realt\u00e0 che si presenta, secondo quanto afferma un dirigente della scuola dei dirigenti, con diverse facce. Le possiamo cos\u00ec riassumere: 1) calano le adesioni nel mondo operaio e contadino; 2) all&#8217;opposto crescono &#8211; e di molto &#8211; le iscrizioni fra gli imprenditori e nelle file della neo alta borghesia cittadina; 3) infine il ceto medio urbano, \u00abceto medio conservatore di tipo occidentale\u00bb (lo definiscono in questo modo i sociologi della Accademia) con il quale il partito aveva stretto un patto di scambio &#8211; nuove libert\u00e0 di mercato contro stabilit\u00e0 sociale &#8211; si sta allontanando dalla politica perch\u00e9 non sente rappresentate le sue spe\u00adranze di tranquilla opulenza.<\/p>\n<p style=\"text-align: justify;\">I segnali di allarme sono sparsi ma tanti. Duri i capitoli di accusa, sostenuti anche dentro il partito. Le idee contano poco. Conta ben altro. \u00c8 il partito delle auto blu. Alla ultima as\u00adsemblea nazionale del popolo un delegato si \u00e8 alzato per ammonire che le spese destinate alle auto di rappresentanza stanno esplodendo. \u00c8\u2019 il partito delle poltrone. I genitori invitano i figli a iscriversi al partito solo perch\u00e9 regala un impiego. \u00c8 il partito degli imprenditori che sfidano il mercato e hanno bisogno di appoggi influenti. Ed \u00e8 il partito della corruzione.<\/p>\n<p style=\"text-align: justify;\">Circolano nell&#8217;apparato comunista alcuni numeri che fotografano il suo stato di salute morale. Da otto anni in qua, dopo il quindicesimo congresso, il partito ha scoperto un caso di corruzione al mese a livello ministeriale, un caso di corruzione al giorno a livello centrale medio-al\u00adto, quindici casi di corruzione al giorno a livello distrettuale. Una cifra enorme \u00abCome \u00e8 possibile reggere l&#8217;urto della modernizzazione che richiede capacit\u00e0 di mediazione se si perde di vista l&#8217;interesse generale e si pensa al conto in banca?\u00bb. Domanda che in tanti si pongono.<\/p>\n<p style=\"text-align: justify;\">Quei sessantotto milioni di iscritti ingannano. Il numero in termini assoluti appare altissimo, in termini percentuali (5 per cento della popolazione) dimostra invece sia la natura dirigistica del partito sia la disaffezione fra i ceti medi e le tradizionali aree di adesione. Gi\u00e0 nel 2003 il Pcc era vecchio (solo il 15 per cento degli iscritti aveva meno di 35 anni). Un iscritto su due era operaio o contadino. Il 17 per cento era composto da colletti bianchi, il 21 per cento da militari e funzionari dello Stato. Ma negli ul\u00adtimi due anni le percentuali si sono differenziate e il modello fondato a Shanghai nel luglio 1921 \u00e8 ora definitivamente superato.<\/p>\n<p style=\"text-align: justify;\">Sia nella composizione sociale sia nei valori che rappresenta. Ci sono tre dati che consolidano queste considerazioni. Proven\u00adgono da una ricerca svolta dal dipartimento lavoro del comitato centrale del Pcc, dalla associazione della industria e del commercio, dalla associazione per la ricerca sulle aziende private. Il primo dato dice che un imprenditore su tre ha la tessera del Partito comunista.<\/p>\n<p style=\"text-align: justify;\">Il secondo dato afferma che fra le maggiori spese a carico delle aziende private vi sono quelle catalogate come \u00abpubbliche relazioni e buon rapporto con i funzionari gover\u00adnativi\u00bb. Traduciamolo con \u00abcorruzioni\u00bb. Il terzo dato sottolinea come 9 imprenditori su 10 spingano per \u00abprotezione del patrimonio privato\u00bb.<\/p>\n<p style=\"text-align: justify;\">I tre dati confermano che il Partito comunista cinese ha conservato la sua funzione di perno del sistema ma che la testa e il cuore sono stati trapiantati. Il risultato finale \u00e8 (accerchiamento esterno e il grave disagio interno. Premono e protestano gli operai e i contadini. Premono i ceti medi disillusi.<\/p>\n<p style=\"text-align: justify;\">Premono gli imprenditori che utilizzano la politica per tornaconto personale. \u00c8 un processo intenso quello che sta scuotendo la politica cinese, una volta segreta e inaccessibile, oggi un po&#8217; meno. Deng Xiaping aveva riconosciuto il diritto alla ricchezza spezzando il dogmatismo dell&#8217;uguaglianza. Oggi la modernizzazione si \u00e8 tal\u00admente spinta in l\u00e0 da rendere attuale un dubbio: quanto riuscir\u00e0 a durare la versione autoritaria di un partito al quale la globalizzazione ha estirpato i geni delle origini ma al quale sta offrendo, seppure minacciati dalla degenerazione delle corruzioni e dal vecchio assolutismo, inediti germogli di democrazia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>pubblicato su \u00a0Il Corriere della Sera del 10 maggio 2005 di\u00a0Fabio Cavalera<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,32,108],"tags":[2395,139],"class_list":["post-1181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-filosofia-del-comunismo","category-paesi-e-continenti","tag-cina","tag-comunismo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-08-12T09:23:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-19T15:42:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Cina, gli operai fuggono dal partito\",\"datePublished\":\"2005-08-12T09:23:14+00:00\",\"dateModified\":\"2015-11-19T15:42:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/\"},\"wordCount\":953,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Cina-operai.jpg\",\"keywords\":[\"Cina\",\"comunismo\"],\"articleSection\":[\"Cina\",\"Comunismo\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/\",\"name\":\"Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Cina-operai.jpg\",\"datePublished\":\"2005-08-12T09:23:14+00:00\",\"dateModified\":\"2015-11-19T15:42:17+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Cina-operai.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/Cina-operai.jpg\",\"width\":274,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/cina-gli-operai-fuggono-dal-partito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cina, gli operai fuggono dal partito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/","og_locale":"it_IT","og_type":"article","og_title":"Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-08-12T09:23:14+00:00","article_modified_time":"2015-11-19T15:42:17+00:00","og_image":[{"width":274,"height":184,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Cina, gli operai fuggono dal partito","datePublished":"2005-08-12T09:23:14+00:00","dateModified":"2015-11-19T15:42:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/"},"wordCount":953,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg","keywords":["Cina","comunismo"],"articleSection":["Cina","Comunismo","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/","name":"Cina, gli operai fuggono dal partito - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg","datePublished":"2005-08-12T09:23:14+00:00","dateModified":"2015-11-19T15:42:17+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/Cina-operai.jpg","width":274,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/cina-gli-operai-fuggono-dal-partito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Cina, gli operai fuggono dal partito"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1181"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1181\/revisions"}],"predecessor-version":[{"id":27936,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1181\/revisions\/27936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27935"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}