{"id":11614,"date":"2014-10-16T00:00:57","date_gmt":"2014-10-15T22:00:57","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=11614"},"modified":"2015-06-17T09:44:43","modified_gmt":"2015-06-17T07:44:43","slug":"la-grande-confusione-delle-unioni-civili","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/","title":{"rendered":"La grande confusione delle \u00abunioni civili\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-11615 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg\" alt=\"civil_union\" width=\"250\" height=\"162\" \/><\/a>La nuova Bussola quotidiana<\/strong>,<\/p>\n<p style=\"text-align: center;\">15 ottobre 2014<\/p>\n<p style=\"text-align: center;\">di<strong> Massimo Introvigne<\/strong><\/p>\n<p style=\"text-align: justify;\">Il fatto che il Sinodo dei vescovi &#8211; anche nella relazione che riassume i lavori della prima settimana &#8211; insista sull&#8217;accoglienza delle persone omosessuali, menzionando pure che dal \u00abprezioso\u00bb mutuo sostegno che due persone omosessuali si danno derivano diritti e doveri, ha portato alcuni vescovi italiani &#8211; da monsignor Mogavero al cardinale Scola, ognuno evidentemente con il suo stile e le sue idee &#8211; a intervenire con aperture di varia natura alle \u00abunioni civili\u00bb tra persone dello stesso sesso, purch\u00e9 non le si chiami \u00abmatrimonio\u00bb. Chi legge i giornali ha l&#8217;impressione che i vescovi, Renzi, Berlusconi ormai remino tutti nella stessa direzione. Ma non \u00e8 proprio cos\u00ec, e un minimo di chiarezza \u00e8 obbligatorio.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Comincio con il ricordare al paziente lettore che presiedo un comitato che si chiama \u00abS\u00ec alla famiglia\u00bb di cui fanno parte &#8211; aderendo ai suoi comitati locali &#8211; una quarantina di associazioni cattoliche e non cattoliche, le quali hanno sottoscritto un manifesto, lodato anche da diversi vescovi italiani e pubblicato sul sito del Pontificio Consiglio per la Famiglia, che pone su questa materia due paletti.<\/p>\n<p style=\"text-align: justify;\">Ricordando che, come insegna il \u00abCatechismo della Chiesa Cattolica\u00bb le persone omosessuali devono essere accolte \u00abcon rispetto, compassione, delicatezza\u00bb evitando \u00abogni marchio di ingiusta discriminazione\u00bb, abbiamo inteso chiudere le porte di \u00abS\u00ec alla famiglia\u00bb a chi non si riconosce nell&#8217;atteggiamento del \u00abCatechismo\u00bb &#8211; che pu\u00f2 essere evidentemente condiviso anche da non cattolici &#8211; e nell&#8217;invito di Papa Francesco a non giudicare le persone in quanto persone.<\/p>\n<p style=\"text-align: justify;\">Nello stesso tempo, affermando nel manifesto un \u00abno\u00bb al \u00abmatrimonio\u00bb omosessuale e a \u00abunioni civili\u00bb para-matrimoniali, che al \u00abmatrimonio\u00bb omosessuale non sono l&#8217;alternativa ma il battistrada, abbiamo pure escluso dall&#8217;ambito del nostro comitato chi sostiene che servono in Italia leggi sul modello delle \u00abcivil union\u00bb mandate in pensione in Inghilterra nel 2013 dopo avere svolto il loro lavoro, cio\u00e8 appunto preparare la strada al \u00abmatrimonio\u00bb omosessuale introdotto in quell&#8217;anno.<\/p>\n<p style=\"text-align: justify;\">Con poche eccezioni, nella Chiesa e &#8211; cosa meno importante, ma politicamente non irrilevante, nel centro-destra italiano &#8211; sembra che oggi tutti o quasi siano contrari al \u00abmatrimonio\u00bb omosessuale e nello stesso tempo favorevoli alle \u00abunioni civili\u00bb. Senonch\u00e9, a leggere interviste e interventi, si scopre che parlando di \u00abunioni civili\u00bb i diversi prelati e politici parlano ciascuno di una cosa diversa. Quando capita cos\u00ec, vuol dire che siamo di fronte a una parola insidiosa.<\/p>\n<p style=\"text-align: justify;\">Che cosa significa \u00abunioni civili\u00bb? Nell\u2019intervista a Ferruccio de Bortoli, pubblicata sul \u00abCorriere della Sera\u00bb del 5 marzo 2014, Papa Francesco a una domanda su cosa pensasse delle unioni civili ha risposto: \u00abIl matrimonio \u00e8 fra un uomo e una donna. Gli Stati laici vogliono giustificare le unioni civili per regolare diverse situazioni di convivenza, spinti dall\u2019esigenza di regolare aspetti economici fra le persone, come ad esempio assicurare l\u2019assistenza sanitaria. Si tratta di patti di convivenza di varia natura, di cui non saprei elencare le diverse forme. Bisogna vedere i diversi casi e valutarli nella loro variet\u00e0\u00bb. Premesso che un\u2019intervista non \u00e8 assolutamente Magistero, neppure ordinario, de Bortoli a differenza di Scalfari sembrerebbe non avere inventato nulla, e il testo rivela almeno la \u00abmens\u00bb del Pontefice.<\/p>\n<p style=\"text-align: justify;\">Il Papa ribadisce anzitutto che il matrimonio \u00e8 solo fra un uomo e una donna, il che \u2013 almeno nella Chiesa, con poche eccezioni \u2013 non sembra essere in discussione. Quanto alle \u00abunioni civili\u00bb il Papa ci dice in sostanza che l\u2019espressione \u00e8 come una scatola: bisogna aprirla e guardarci dentro, perch\u00e9 ci sono cose diverse, le \u00abdiverse forme\u00bb da esaminare e vedere una per una. Dalle convivenze \u2013 anche omosessuali \u2013 derivano diritti e doveri: il Papa parla di \u00abaspetti economici\u00bb ma cita poi l\u2019\u00abassistenza sanitaria\u00bb, intendendo evidentemente non l\u2019INPS \u2013 non c\u2019\u00e8 un INPS speciale per gli omosessuali \u2013 ma la possibilit\u00e0 di assistere in ospedale il convivente.<\/p>\n<p style=\"text-align: justify;\">Come la nostra testata ha spiegato molte volte, con elenchi puntigliosi, questi diritti in Italia sono gi\u00e0 garantiti dalla normativa vigente. Ne mancano solo tre: adottare bambini, avere assicurata una quota di legittima in caso di successione, e godere della pensione di reversibilit\u00e0.<\/p>\n<p style=\"text-align: justify;\">L\u2019adottare bambini \u00e8 una delle chiavi di tutto, ma perfino i sondaggi di \u00abRepubblica\u00bb ci dicono che la maggioranza degli italiani sono contrari, per cui \u2013 una volta inserita, come vogliono Renzi e Berlusconi, la possibilit\u00e0 per la coppia \u00abcivilunita\u00bb di adottare i figli di uno dei due \u00abciviluniti\u00bb \u2013 ci penseranno poi verosimilmente i giudici ad allargare l&#8217;adozione a tutti i bambini invocando il principio di uguaglianza. La legittima, se ci sono figli di uno dei due omosessuali \u00abciviluniti\u00bb, pone delicati problemi anche costituzionali. Alla pensione di reversibilit\u00e0 si opporr\u00e0 a corpo morto l\u2019INPS per ragioni di cassa, tanto che anche alcuni dei pi\u00f9 attivi sostenitori delle unioni civili pensano di cassare almeno provvisoriamente la richiesta. Tutto il resto \u2013 assistenza in ospedale, in carcere, subentro nel contratto di locazione \u2013 nelle leggi italiane c\u2019\u00e8 gi\u00e0.<\/p>\n<p style=\"text-align: justify;\">Si vuole fare un testo unico, con eventuali piccoli aggiustamenti, o creare dei contratti-tipo che i conviventi potrebbero sottoscrivere tra loro e dei quali, come di ogni contratto, lo Stato prenderebbe atto? Se ne pu\u00f2 parlare, senza fretta e senza dimenticare per ogni passaggio gli elementi problematici. Forse \u00e8 questo che intendono alcuni vescovi quando usano l&#8217;espressione \u00abunioni civili\u00bb.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2, se diamo retta al Papa e apriamo la scatola a sorpresa della politica italiana su cui c&#8217;\u00e8 scritto \u00abunioni civili\u00bb, non ci troviamo testi unici e contratti-tipo ma una cosa diversa: la \u00abcivil union\u00bb inglese che ispira il disegno di legge Cirinn\u00e0 oppure la \u00abEingetragene Lebenspartnerschaft\u00bb in vigore in Germania di cui ora &#8211; dopo avere a lungo evocato il modello inglese &#8211; parla Renzi.<\/p>\n<p style=\"text-align: justify;\">Sono due modelli aperti ai soli omosessuali. La \u00abcivil union\u00bb inglese era, come abbiamo mostrato altre volte su questo giornale, una cosa uguale in tutto e per tutto al matrimonio tranne che nel nome: e il nome \u00e8 stato cambiato facilmente dopo qualche anno, quando tutti si erano abituati alla cosa. Il modello tedesco originariamente non includeva le adozioni, ma per il resto \u00e8 anch\u2019esso molto simile ai matrimoni: resiste al cambiamento di nome in matrimonio per la benemerita opposizione dei democristiani bavaresi, ma non si sa per quanto.<\/p>\n<p style=\"text-align: justify;\">Quanto alle adozioni, ci hanno pensato &#8211; come ci penserebbero in Italia &#8211; i giudici, prima inducendo il governo a includere la possibilit\u00e0 di adottare il figlio biologico di uno dei partner omosessuali \u00abciviluniti\u00bb, quindi &#8211; con una sentenza del 2013, che ha portato a una modifica legislativa del 2014 &#8211; permettendo alla coppia dello stesso sesso la cosiddetta \u00abadozione successiva\u00bb, cio\u00e8 l&#8217;adozione da parte di entrambi i partner del figlio gi\u00e0 adottato da uno solo di loro.<\/p>\n<p style=\"text-align: justify;\">Pendono ora di fronte alla Corte Costituzionale tedesca casi che potrebbero aprire alle coppie omosessuali \u00abcivilunite\u00bb la possibilit\u00e0 di adottare figli senza alcuna condizione o limitazione. \u00c8 vero che la Germania \u00e8 pi\u00f9 ricca di noi, ma nel 2009 i giudici hanno imposto anche lo stesso regime pensionistico per le coppie omosessuali rispetto a quelle formate da un uomo e da una donna. I nostri giudici non avrebbero di per s\u00e9 bisogno dell&#8217;esempio tedesco per sapere come, una volta aperte le porte, l&#8217;attivismo giudiziario pu\u00f2 rapidamente equiparare le \u00abunioni civili\u00bb ai matrimoni in tutto tranne che nel nome: ma ne faranno certamente tesoro.<\/p>\n<p style=\"text-align: justify;\">La cerimonia \u00e8 una delle chiavi \u2013 non l\u2019unica, ma importante, e tanto importante per i sociologi \u2013 per distinguere se si tratta di constatare che fra due persone dello stesso sesso che convivono sono stati almeno implicitamente stipulati quei \u00abpatti di convivenza\u00bb di cui parla il Papa, da cui far discendere \u00abdiritti economici\u00bb, o se si vuole creare il \u00abmatrimonio\u00bb omosessuale con il nome provvisorio di \u00abunione civile\u00bb.<\/p>\n<p style=\"text-align: justify;\">Nulla pi\u00f9 della cerimonia solenne identica a quella del matrimonio fra un uomo e una donna &#8211; abiti bianchi, musica, solennit\u00e0, le stesse forme &#8211; diffonde nel corpo sociale l\u2019idea che il \u00abmatrimonio\u00bb omosessuale ci sia gi\u00e0, per quanto lo si chiami provvisoriamente \u00abunione civile\u00bb. La legge inglese voleva la cerimonia \u00abidentica\u00bb al matrimonio, con dure sanzioni per chi sgarrava. E i progetti del PD comprendono la cerimonia, che anzi alcuni esponenti di quel partito hanno definito la loro linea del Piave. Mi permetto d&#8217;insistere anch&#8217;io, come il PD: non sottovalutiamo la cerimonia. Vedrete, sar\u00e0 la via pedagogica italiana al \u00abmatrimonio\u00bb omosessuale.<\/p>\n<p style=\"text-align: justify;\">Abbiamo dunque chiarito come sotto la dicitura \u00abunioni civili\u00bb passano in Europa e nel mondo cose diverse. L&#8217;ambiguit\u00e0 dell&#8217;espressione dovrebbe indurre chi \u00e8 contrario al \u00abmatrimonio\u00bb omosessuale a non usarla per indicare testi unici sui diritti e doveri delle convivenze o contratti-tipo. Tuttavia il linguaggio ha le sue dinamiche, alle quali dopo un po&#8217; diventa molto difficile opporsi. Se l&#8217;espressione \u00abunioni civili\u00bb diventer\u00e0 di uso corrente anche tra i vescovi, ci sar\u00e0 utile l\u2019intervista del Papa a de Bortoli e il suo riferimento a diverse categorie di cose che qualcuno chiama con lo stesso nome di \u00abunioni civili\u00bb e che vanno distinte ed esaminate una per una.<\/p>\n<p style=\"text-align: justify;\">Se mi si consente di tornare al manifesto di \u00abS\u00ec alla famiglia\u00bb, l\u00ec le associazioni firmatarie hanno incluso un \u00abs\u00ec al riconoscimento che da ogni convivenza derivano diritti e doveri, applicando le norme in vigore che in Italia gi\u00e0 tutelano ampiamente i conviventi, anche omosessuali, in materia di ospedali, carceri, subentro nei contratti d\u2019affitto, ove necessario introducendo ulteriori aggiustamenti pratici di tipo amministrativo o civile\u00bb.<\/p>\n<p style=\"text-align: justify;\">Preferiremmo che le persone bene orientate, e certamente i nostri vescovi, non chiamassero gli \u00abaggiustamenti pratici\u00bb \u2013 compresi i testi unici e i contratti-tipo \u2013 \u00abunioni civili\u00bb, perch\u00e9 ogni uso dell&#8217;espressione aumenta la confusione. Sappiamo per\u00f2 che ci sono battaglie contro il linguaggio corrente che difficilmente possono essere vinte. Ci permettiamo allora di chiedere, ogni volta che sentiamo qualcuno ripetere \u00abs\u00ec alle unioni civili, no al &#8220;matrimonio&#8221; omosessuale\u00bb, che cosa intende esattamente per \u00abunioni civili\u00bb.<\/p>\n<p style=\"text-align: justify;\">Qualcuno che ha le idee chiare c&#8217;\u00e8. Intervistato da \u00abLa Stampa\u00bb sul suo invito a cena in casa Berlusconi, Vladimir Luxuria ha spiegato che per lui le unioni civili alla tedesca servono a preparare la strada alla rapida introduzione in Italia del \u00abmatrimonio\u00bb omosessuale, chiamato con questo nome e con diritto illimitato all&#8217;adozione. A qualunque vescovo o politico di centro-destra che ripete il \u00abmantra\u00bb secondo cui le unioni civili sono alternative al \u00abmatrimonio\u00bb tra persone dello stesso sesso, si ha il diritto e forse anche il dovere di chiedere se conosce bene i precedenti inglese e tedesco, e per quali ragioni le cose in Italia, una volta aperto il vaso di Pandora, dovrebbero andare diversamente dall&#8217;Inghilterra, dalla Germania, e da quanto prevede e auspica Luxuria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nuova Bussola quotidiana, 15 ottobre 2014 di Massimo Introvigne Il fatto che il Sinodo dei vescovi &#8211; anche nella relazione che riassume i lavori della prima settimana &#8211; insista sull&#8217;accoglienza delle persone omosessuali, menzionando pure che dal \u00abprezioso\u00bb mutuo sostegno che due persone omosessuali si danno derivano diritti e doveri, ha portato alcuni vescovi &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":11615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[415],"class_list":["post-11614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-omosessualit","tag-matrimonio-gay","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-15T22:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-17T07:44:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"267\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La grande confusione delle \u00abunioni civili\u00bb\",\"datePublished\":\"2014-10-15T22:00:57+00:00\",\"dateModified\":\"2015-06-17T07:44:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/\"},\"wordCount\":1756,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/civil_union.jpg\",\"keywords\":[\"matrimonio gay\"],\"articleSection\":[\"Omosessualit&agrave;\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/\",\"name\":\"La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/civil_union.jpg\",\"datePublished\":\"2014-10-15T22:00:57+00:00\",\"dateModified\":\"2015-06-17T07:44:43+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/civil_union.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/civil_union.jpg\",\"width\":267,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-grande-confusione-delle-unioni-civili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La grande confusione delle \u00abunioni civili\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/","og_locale":"it_IT","og_type":"article","og_title":"La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2014-10-15T22:00:57+00:00","article_modified_time":"2015-06-17T07:44:43+00:00","og_image":[{"width":267,"height":189,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La grande confusione delle \u00abunioni civili\u00bb","datePublished":"2014-10-15T22:00:57+00:00","dateModified":"2015-06-17T07:44:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/"},"wordCount":1756,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg","keywords":["matrimonio gay"],"articleSection":["Omosessualit&agrave;"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/","name":"La grande confusione delle \u00abunioni civili\u00bb - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg","datePublished":"2014-10-15T22:00:57+00:00","dateModified":"2015-06-17T07:44:43+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/10\/civil_union.jpg","width":267,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-grande-confusione-delle-unioni-civili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La grande confusione delle \u00abunioni civili\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/11614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=11614"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/11614\/revisions"}],"predecessor-version":[{"id":26392,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/11614\/revisions\/26392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/11615"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=11614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=11614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=11614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}