{"id":1152,"date":"2005-08-02T18:04:41","date_gmt":"2005-08-02T16:04:41","guid":{"rendered":""},"modified":"2016-03-02T09:13:34","modified_gmt":"2016-03-02T08:13:34","slug":"la-crociata-questa-sconosciuta","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/","title":{"rendered":"La crociata, questa sconosciuta"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31268\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg\" alt=\"crociate\" width=\"250\" height=\"152\" \/>di<strong> Adolfo Morganti<\/strong><\/div>\n<p><strong>1. Usi contemporanei del termine Crociata<\/strong><\/p>\n<p style=\"text-align: justify;\">Affrontare con seriet\u00e0 scientifica il tema della Crociata, uno dei tanti episodi di cui apparentemente tutto \u00e8 noto, \u00e8 reso difficile prima di tutto dall\u2019utilizzo che di questo termine ha fatto e continua a fare la cultura contemporanea. Un utilizzo carico di enfasi contrapposte, che come giustamente nota Franco Cardini (1), consente immediatamente di comprenderne l\u2019impostazione filosofico-politica di fondo.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Da un lato oggi abbiamo la Crociata come &#8220;guerra santa&#8221;, doverosa e meritoria, contro un obiettivo meritevole di essere distrutto, sia essa la fame nel mondo, la lebbra o una &#8220;incarnazione del male&#8221; come Saddam Hussein o Slobodan Milosevic; d\u2019altra parte, in allocuzioni quali &#8220;non facciamone una Crociata&#8221; la si interpreta all\u2019opposto come un\u2019esagerata, rigida ed ingiusta reazione in difesa di interessi o posizioni precostituite. Ovviamente questo peso linguistico tende a proiettarsi sulla nostra comprensione del fatto storico, ed entrambi gli utilizzi si rivelano fuorvianti.<\/p>\n<p style=\"text-align: justify;\">Scopo di questo incontro \u00e8 di far comprendere le linee generali di un fenomeno solo apparentemente noto, e di seguirle l\u2019eco fino ad oggi.<\/p>\n<p style=\"text-align: justify;\"><strong>2. La realt\u00e0 del tempo: la Crociata sconosciuta.<\/strong><\/p>\n<p style=\"text-align: justify;\">Prima di tutto va detto che al tempo delle Crociate questo termine, oggi entrato nell\u2019uso comune (appunto: &#8220;Crociata&#8221;), non esisteva: i Crociati del 1096-1099, cos\u00ec come quelli del XIII secolo, non erano a conoscenza di star partecipando ad una Crociata; parallelamente, anche nelle fonti arabe del tempo non si ha traccia dell\u2019utilizzo di questo termine.<\/p>\n<p style=\"text-align: justify;\">Anzi, a dire la verit\u00e0 il mondo musulmano ben poco si accorse dell\u2019immenso significato che le Crociate ebbero per i cristiani del tempo, limitandosi a registrare sporadici spostamenti di &#8220;Franchi&#8221;. Il Termine &#8220;Crociata&#8221; \u00e8 assai tardo, pi\u00f9 moderno e soprattutto contemporaneo che medievale.<\/p>\n<p style=\"text-align: justify;\">Le fonti dell\u2019epoca, cui ovviamente dobbiamo rifarci per comprendere come la Cristianit\u00e0 del tempo visse i secoli dell\u2019avventura crociata, parlano invece di <em>peregrinatio<\/em> (&#8220;pellegrinaggio&#8221;), <em>iter<\/em> (&#8220;viaggio in armi&#8221;); dal XII secolo si afferma l\u2019uso del termine <em>passagium<\/em> (&#8220;viaggio attraverso il mare&#8221;), o <em>passagium generale<\/em> quando si indicavano le spedizioni maggiori, indette da un\u2019apposita Bolla pontificia, e che quindi interessavano in via di diritto tutta la Cristianit\u00e0 occidentale. Le 8 Crociate della nostra cronologia scolastica sono appunto <em>passagia generalia<\/em>.<\/p>\n<p style=\"text-align: justify;\">Comunque, le &#8220;Crociate&#8221; furono pi\u00f9 di 8: e la storia di questi &#8220;altri&#8221; movimenti crociati si confonde con quella dei movimenti penitenziali di massa, tipici dello scenario sociale e religioso del XI-XII secolo: si pensi alla cosiddetta &#8220;crociata dei poveri&#8221;, guidata da Pietro l\u2019Eremita e Gualtieri Senza Averi (un nome che \u00e8 una dichiarazione di censo) che si snod\u00f2 parallelamente alla 1\u00b0 Crociata del 1096-1099 e conobbe un esito tragico, anche se i suoi superstiti furono rilevati dalle armate della 1\u00b0 Crociata &#8220;dei Baroni&#8221;, inquadrati nella propria armata e giunsero alla conquista di Gerusalemme, ove Pietro l\u2019Eremita era presente; si ricordi il terribile, successivo episodio della &#8220;crociata dei bambini&#8221;, un movimento penitenziale di massa nato tra i fanciulli europei del tempo, che si mossero a migliaia verso la Terrasanta, inermi, per liberarla con la forza della preghiera: finirono massacrati o schiavi.<\/p>\n<p style=\"text-align: justify;\">Come quest\u2019ultimo episodio dimostra, i <em>passagia<\/em> non furono nemmeno tutte spedizioni armate, mentre al contrario, soprattutto nella prima Crociata, vediamo unirsi agli armati una quantit\u00e0 immensa di pellegrini inermi, che ritengono di potersi avvicinare a Gerusalemme in maniera pi\u00f9 sicura accompagnandosi agli armati in marcia.<\/p>\n<p style=\"text-align: justify;\">I <em>passagia<\/em>, ed anche i <em>passagia generalia<\/em> non ebbero nemmeno tutti come obiettivo la Terra Santa: \u00e8 ben noto a tutti che la cosiddetta IV Crociata si risolse, nel 1204, nella conquista e nel saccheggio di Bisanzio, capitale del Sacro Romano Impero d\u2019Oriente, e nell\u2019istituzione di un effimero Regno Latino di Costantinopoli. Questo saccheggio contro altri cristiani \u00e8 rimasto talmente vivo ancor oggi nella memoria della cristianit\u00e0 ortodossa da rispuntare regolarmente in ogni polemica contraria al dialogo ecumenico con i cattolici.<\/p>\n<p style=\"text-align: justify;\">Viceversa, le fonti dell\u2019epoca utilizzano il termine <em>cruce signati<\/em>, da cui l\u2019aggettivo <em>cruciati<\/em>, per indicare i singoli partecipanti ai <em>passagia. <\/em>Questo perch\u00e9 i pellegrini verso la Terra Santa, armati o inermi che fossero, dopo il Concilio di Clermont dovevano portare obbligatoriamente cucita addosso sulla veste o sul mantello una Croce di stoffa.<\/p>\n<p style=\"text-align: justify;\">Questo dettaglio, apparentemente minore, ci conferma quindi il nesso stretto della Crociata con la lunga storia del pellegrinaggio ai Luoghi Santi, che come sappiamo inizia gi\u00e0 nei primi secoli dopo Cristo e non termina mai, a dispetto delle difficolt\u00e0 e dei pericoli: per comprenderla in profondit\u00e0, pi\u00f9 che come un semplice capitolo di storia militare o di un esempio di protocolonialismo magari a sfondo religioso, \u00e8 quindi necessario ricordarsi sempre la stretta parentela della Crociata con la <span style=\"text-decoration: underline;\">storia della venerazione dei luoghi santi e del pellegrinaggio<\/span>.<\/p>\n<p style=\"text-align: justify;\">E dobbiamo sempre rammentare come l\u2019aspetto armato della Crociata non era affatto, per la mentalit\u00e0 medievale, in contrasto con le elevate finalit\u00e0 spirituali del pellegrinaggio; al contrario, era assai raro che un pellegrinaggio cristiano ai Luoghi Santi di Palestina non avvenisse sotto la protezione, almeno in certi tratti di percorso, delle armi.<\/p>\n<p style=\"text-align: justify;\"><strong>3. Ci\u00f2 che \u00e8 avvenuto prima<\/strong><\/p>\n<p style=\"text-align: justify;\">Inoltre, per comprendere appieno il significato che la Crociata ebbe per gli uomini che la vissero in prima persona, dobbiamo entrare nello spirito di un\u2019intera civilt\u00e0 assediata, la cristianit\u00e0 medievale uscita malamente dalla crisi dell\u2019Impero carolingio, che per secoli pat\u00ec un assedio dall\u2019esterno, primariamente da parte dell\u2019Islam (ma anche da parte delle scorrerie vichinghe), il cui impatto e violenza noi facciamo oggi fatica a comprendere.<\/p>\n<p style=\"text-align: justify;\">Cerchiamo quindi di ricostruire assieme, con l\u2019ausilio di qualche data, le tappe essenziali di questo secolare scontro di civilt\u00e0:<\/p>\n<p style=\"text-align: justify;\">Meno di cinquant\u2019anni dopo l\u2019incoronazione di Carlo Magno, nell\u2019846 una scorreria musulmana saccheggi\u00f2 <strong>Roma<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Nel 902 venne condotta a termine la conquista musulmana della <strong>Sicilia. <\/strong><\/p>\n<p style=\"text-align: justify;\">Nel 940 una banda musulmana giunse ad assalire e distruggere il Monastero di <strong>San Gallo,<\/strong> sito nell\u2019omonimo Cantone, in Svizzera.<\/p>\n<p style=\"text-align: justify;\">Nel 972, un\u2019altra formazione musulmana riusc\u00ec a catturare ed a tenere in ostaggio il monaco <strong>Maiolo<\/strong>, abate di Cluny, figura centrale del monachesimo del tempo, consigliere spirituale e politico di duchi ed Imperatori. Si tratt\u00f2 di un vero colpo per l\u2019intera Cristianit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Nel 981, in Calabria, nella battaglia di <strong>Stilo <\/strong>le truppe musulmane sconfissero l\u2019esercito cristiano guidato dall\u2019Imperatore Sacro e Romano Ottone I. Nel meridione d\u2019Italia per pi\u00f9 di cinquant\u2019anni si ebbe addirittura un Emirato di Bari.<\/p>\n<p style=\"text-align: justify;\">Nel 997 un\u2019altra scorreria musulmana saccheggi\u00f2 il santuario spagnolo di <strong>Santiago<\/strong> di Compostela.<\/p>\n<p style=\"text-align: justify;\">Ma questa pressione non riguardava solamente l\u2019Occidente cristiano: nel 1071 vi fu la grande vittoria dei musulmani selgiuchidi contro l\u2019esercito cristiano bizantino a Manzikert. Fu l\u2019impatto di questa sconfitta a persuadere l\u2019Imperatore d\u2019Oriente a chiedere un aiuto militare al Papa, innescando cos\u00ec il meccanismo che doveva portare alla Crociata.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, di fronte a questa impressionante serie di attacchi al cuore politico e spirituale dell\u2019Europa cristiana dobbiamo anche ricordare che l\u2019Islam non era n\u00e9 fu mai un insieme organico, ma un mosaico di Re corsari, i quali controllavano territori di estensione quantomai eterogenea, sempre in lotta tra loro e con i cristiani.<\/p>\n<p style=\"text-align: justify;\"><strong>4. Inizia la <em>Reconquista<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">A partire all\u2019incirca dall\u2019anno 1000, nel contesto di una generale fioritura economica, sociale e politica dell\u2019Europa che segn\u00f2 tutto il XI secolo, inizi\u00f2 un generale contrattacco della Cristianit\u00e0, che possiamo definire col termine che i cristiani coniarono nelle Spagne: la <em>Reconquista. <\/em>Anch\u2019essa dur\u00f2 quasi un secolo e conobbe una serie di tappe, che \u00e8 bene sintetizzare.<\/p>\n<p style=\"text-align: justify;\">In <strong>Spagna,<\/strong> proprio agli inizi del XI secolo, vengono poste le basi culturali, letterarie ed anche religiose della <em>Reconquista <\/em>dell\u2019Europa occupata dai musulmani. A questo periodo risale infatti la stesura della celeberrima <em>Chanson de Roland<\/em>, in cui \u00e8 evidente la riproposizione esemplare, rivolta prima di tutto a tutta la Cavalleria europea, della figura di Orlando, il Paladino di Carlo Magno, come archetipo del cavaliere cristiano che mette tutto il suo valore al servizio del suo Re e della sua Fede, e muore combattendo contro i mori a Roncisvalle.<\/p>\n<p style=\"text-align: justify;\">In tutto il Medioevo, la storia dei Paladini carolingi, o Materia di Francia, costitu\u00ec assieme alla Materia di Bretagna (il ciclo Graalico-Arturiano) e alla Materia di Roma (la storia romanzata degli antichi eroi romani), il cuore vivente dell\u2019epica cavalleresca europea.<\/p>\n<p style=\"text-align: justify;\">Sempre in Spagna, al tempo di Papa Alessandro II, avviene un passaggio giuridico fondamentale: si inizia ad equiparare la partecipazione personale del Cavaliere cristiano alle ricorrenti spedizioni militari contro i musulmani ad un pellegrinaggio spirituale, ad un <em>iter poenitentiale<\/em>. Conoscendo il senso proprio di questo termine, che gi\u00e0 abbiamo incontrato, possiamo vedere che proprio qui la morte in battaglia contro i nemici di Dio comincia ad essere equiparata in modo sempre pi\u00f9 evidente al martirio.<\/p>\n<p style=\"text-align: justify;\">E giusto per avere un\u2019idea dell\u2019impegno che i cattolici spagnoli dovranno affrontare per portare a termine questa impresa, accontentiamoci di ricordare che la <em>Reconquista<\/em> cattolica delle Spagne terminer\u00e0 solamente <em>quasi cinque secoli dopo<\/em>, nel 1492: lo stesso anno che vide il fortunato viaggio di Colombo nelle Americhe, l\u2019anno convenzionale che apre l\u2019epoca moderna.<\/p>\n<p style=\"text-align: justify;\">Contemporaneamente, nell\u2019<strong>Italia meridionale,<\/strong> all\u2019incirca verso il 1030, avviene un fatto che gi\u00e0 ci cala all\u2019interno del clima sociale della Crociata: in mezzo ad una situazione quasi caotica, tra le costanti minacce musulmane provenienti dalla Sicilia, le tensioni politiche e gli scontri armati tra gli ultimi potentati bizantini e i principati longobardi, i cambiamenti socio-economici provocati dalle nascenti &#8211; come entit\u00e0 cittadine autonome &#8211; citt\u00e0 marinare, una numero a noi sconosciuto, ma che tutte le fonti del tempo concordano nel definire veramente ragguardevole di cavalieri provenienti dal nord Europa, normanni (tra i quali ricordiamo solamente gli Altavilla, destinati alla fortuna che sappiamo, ma in origine di modesto lignaggio), bretoni, dell\u2019Anjou, del Maine, delle Fiandre calano in quelle terre sentendo odore di battaglia, in cerca cio\u00e8 di ingaggio, di una possibile fortuna, comunque sempre di <em>aventure<\/em>.<\/p>\n<p style=\"text-align: justify;\">Sempre in <strong>Italia meridionale,<\/strong> verso il 1060 Roberto il Guiscardo, vassallo della Santa Sede, innalzando cio\u00e8 il vessillo con le Chiavi di Pietro, termina la riconquista di Puglia e Calabria. Si tratta di un dettaglio importante: la Santa Sede concede il Suo simbolo e affida il proprio prestigio a chi, in Suo nome, combatte per la riconquista del territorio italiano occupato dai musulmani.<\/p>\n<p style=\"text-align: justify;\">Quasi contemporaneamente nel 1061 il fratello di Roberto il Guiscardo, Ruggero, inizia la riconquista della Sicilia, che verr\u00e0 condotta a buon fine non molto tempo prima dell\u2019indizione della Prima Crociata. In questo clima di esaltazione guerriera e religiosa le Cronache ci tramandano generosamente molteplici episodi di miracoli operati dagli Arcangeli o dai Santi combattenti, che scendono a combattere con i cristiani contro i nemici della fede, benedicendo con la loro stessa presenza miracolosa la bont\u00e0 della battaglia, e rafforzando all\u2019interno della cultura del tempo la percezione dell\u2019unica battaglia che unisce la cavalleria terrena e quella celeste contro il male, sia esso spirituale o materiale (nel nostro caso i musulmani).<\/p>\n<p style=\"text-align: justify;\"><strong>5. La proclamazione della Prima Crociata.<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 quindi in questo contesto storico e militare che vanno collocati sia i fatti storici che soprattutto l\u2019ideologia, il vissuto popolare della prima Crociata. Questa si comprende in tutta la sua importanza epocale a partire dal primo e poderoso gesto, la sua proclamazione solenne al termine del Concilio di Clermont nel novembre del 1095 da parte di Papa Urbano II.<\/p>\n<p style=\"text-align: justify;\">In quell\u2019occasione il suo appello, conservatoci in cinque versioni di poco pi\u00f9 tardive, si present\u00f2 nelle sue linee generali come un vero e proprio appello che la Chiesa universale rivolgeva in primo luogo all\u2019insieme della Cavalleria europea: quest\u2019appello ottenne un successo veramente strepitoso, tale da generare un fenomeno di ampiezza tale &#8211; appunto la Crociata &#8211; da mutare molti aspetti non solo della cultura, ma anche della vita concreta, materiale quantomeno dei ceti dominanti del continente. Leggendolo oggi possiamo scandirne i momenti fondamentali:<\/p>\n<p style=\"text-align: justify;\"><strong>a.<\/strong> L\u2019Appello del Papa \u00e8 immediatamente rivolto al ceto dei Cavalieri, i <em>milites,<\/em> affinch\u00e9 desistano dalle guerre intestine che ancora, evidentemente continuavano a vessare la Cristianit\u00e0. \u00c8 implicito in queste parole il riferimento alla prolungata opera di <em>educazione ed evangelizzazione<\/em> del ceto militare europeo promosso dalla Chiesa gi\u00e0 dal tempo di Carlo Magno, e che a partire dal X secolo produsse quel movimento di riforma sociale chiamato della <em>tregua dei\u00b8 <\/em>o della<em> pax dei<\/em>.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019appello di Urbano II le pressanti necessit\u00e0 del momento sono colte come un\u2019ulteriore e provvidenziale occasione per proseguire e perfezionare quest\u2019opera di mutamento dei costumi dell\u2019<em>\u00e9lite <\/em>cavalleresca europea. Questo non significa che dall\u2019appello del Papa siano esclusi gli altri ceti. Particolarmente il terzo ceto, quello dei <em>laboratores<\/em>, parteciper\u00e0 massicciamente al clima di fervore religioso che dar\u00e0 vita all\u2019avventura crociata.<\/p>\n<p style=\"text-align: justify;\"><strong>b.<\/strong> Lo scopo immediato di questa mobilitazione generale dei laicato cristiano, ed in primo luogo della Cavalleria europea viene indicato chiaramente: rispondere alla richiesta di soccorso che viene da Oriente (e in ci\u00f2 non si pu\u00f2 che cogliere l\u2019effetto dell\u2019appello che l\u2019Imperatore d\u2019Oriente ha rivolto ai cristiani d\u2019Occidente dopo la tremenda sconfitta di Manzikert), e nello stesso tempo aiutare i fratelli cristiani che in Oriente sono minacciati dai musulmani.<\/p>\n<p style=\"text-align: justify;\">\u00c8 interessante chiedersi di <em>quali <\/em>fratelli cristiani si trattasse. Certamente non i membri delle Chiese orientali, che da secoli vivevano in Terrasanta condividendo lingue, usi e costumi del luogo ed essendo pertanto difficilmente distinguibili dal popolo musulmano: il riferimento \u00e8 quindi esplicitamente rivolto ai pellegrini occidentali che continuavano ad affollare le strade verso Gerusalemme ed i Luoghi Santi. \u00c8 bene ricordare che il movimento dei pellegrini dalle plaghe pi\u00f9 remote dell\u2019Europa verso i Luoghi Santi non si arrest\u00f2 praticamente mai (2).<\/p>\n<p style=\"text-align: justify;\"><strong>c.<\/strong> Papa Urbano II dipinge lo scenario della terra da riconquistare inizialmente come luogo di grandi ricchezze materiali, indicandole implicitamente come premio terreno per i prodi che si impegneranno nell\u2019avventura della riconquista di Gerusalemme. Accanto ad una notazione sociale, che fotografa la condizione non di rado di notevole indigenza di parte del ceto cavalleresco europeo, qui si ha un riflesso di una leggenda di lunga durata, quella dell\u2019Oriente &#8220;favolosamente ricco&#8221;, luogo di meraviglie naturalistiche, di mostruosit\u00e0 e prodigi, terra di Imperi favolosi e, appunto, di sterminate ricchezze naturali.<\/p>\n<p style=\"text-align: justify;\"><strong>d.<\/strong> Infine, l\u2019appello del Pontefice \u00e8 ricco di promesse di vantaggi spirituali, simmetrici rispetto a quelli materiali per coloro che prenderanno la Croce. In termini espliciti ed inequivocabili viene attestato come un siffatto impegno militare al servizio di Dio, la <em>militia Christi,<\/em> sia segno di <em>conversio<\/em>. La morte in battaglia del crociato diviene quindi garanzia del Premio eterno.<\/p>\n<p style=\"text-align: justify;\">Infine, pu\u00f2 essere utile sottolineare come la Crociata fosse vissuta direttamente ed autonomamente dai tre Ceti componenti la Cristianit\u00e0. Nel Medioevo, la Cristianit\u00e0 era concepita come un insieme organico, un riflesso terreno dell\u2019armonia cosmica universale, ed era articolata in tre ceti funzionali gerarchicamente connessi fra di loro: gli <em>oratores<\/em>, coloro che pregano (prima di tutto i monaci e successivamente il clero secolare); i <em>bellatores, <\/em>coloro che difendono in armi la Cristianit\u00e0; i <em>laboratores<\/em>, coloro che lavorano, commerciano, manipolano la materia ed hanno il compito di sostenere i due ceti superiori.<\/p>\n<p style=\"text-align: justify;\">Vi fu quindi una Crociata dei monaci, a dispetto del loro essere impossibilitati a partecipare direttamente ai <em>passagia<\/em> a causa della <em>stabilitas loci<\/em>, il voto di stabilit\u00e0 che li obbligava a risiedere stabilmente all\u2019interno del loro monastero: la loro fu la Crociata della predicazione, in cui l\u2019accento fondamentale pesava sulla grandiosa occasione di <em>conversio mundi<\/em>, di conversione generale che lo sforzo crociato offriva. Non si sottovaluti questo ruolo apparentemente defilato: le motivazioni che spingevano un cavaliere a prendere la Croce quasi sempre si definivano <em>prima<\/em> della partenza, e non durante n\u00e9 dopo.<\/p>\n<p style=\"text-align: justify;\">E vi fu anche una Crociata del &#8220;terzo stato&#8221;: l\u2019appello di Urbano II cadde in un contesto ricco di movimenti religioso-popolari di riforma dei costumi e di conversione (talvolta dai connotati estremi e millenaristici), diffusi sia in Italia che nei territori dell\u2019Impero che nelle Fiandre: il pi\u00f9 celebre di questi movimenti fu senza dubbio la Pataria.<\/p>\n<p style=\"text-align: justify;\">La partecipazione attiva dei <em>laboratores<\/em> allo sforzo crociato fu quindi spontaneo, dilagante, e addirittura anteriore al pi\u00f9 fruttifero ed organizzato sforzo militare del ceto signorile-cavalleresco: \u00e8 nota la vicenda della Crociata popolare guidata da quella singolare figura di predicatore che fu Pietro l\u2019eremita, e che ebbe tra i suoi capi una figura di cavaliere povero passato alla storia col significativo appellativo di Gualtieri &#8220;Senza averi&#8221;.<\/p>\n<p style=\"text-align: justify;\">La Crociata popolare si forma sotto l\u2019onda d\u2019urto emotiva della predicazione popolare, e lungo il proprio viaggio verso la Terrasanta sia nella Mitteleuropa che nei Balcani si scava la strada anche attraverso episodi sanguinosi, come la caccia agli ebrei; giunto in Anatolia questa composita armata verr\u00e0 distrutta dal nemico, ed i superstiti verranno presi in forze dalla &#8220;Crociata dei Baroni&#8221;.<\/p>\n<p style=\"text-align: justify;\">In ogni modo Pietro l\u2019Eremita riuscir\u00e0 a sopravvivere ed a partecipare alla conquista di Gerusalemme del 1099, e proprio durante queste ultime fasi della prima Crociata rimarranno segni precisi della presenza di Confraternite di <em>laboratores<\/em> armati, come quella, avvolta da un alone di leggenda, dei Tafuri.<\/p>\n<p style=\"text-align: justify;\"><strong>6. Cosa <em>non \u00e8<\/em> la Crociata.<\/strong><\/p>\n<p style=\"text-align: justify;\">Da questo rapidissimo <em>excursus<\/em> attorno agli aspetti generali della nascita della Crociata, possiamo quindi iniziare a trarre alcune conclusioni generali, sia pure in negativo, attorno al nostro oggetto di riflessione.<\/p>\n<p style=\"text-align: justify;\"><strong>a.<\/strong> La Crociata non \u00e8 una &#8220;guerra santa&#8221;. Questo termine infatti non esiste nel cristianesimo medievale, mentre esiste nella cultura islamica, ed \u00e8 un aspetto buffo del fraintendimento moderno e contemporaneo della Crociata che essa sia stata definita dagli illuministi con un termine islamico. I <em>passagia generalia<\/em> indetti, come abbiamo visto pi\u00f9 sopra, con tanto di regolare Bolla pontificia, sono invece definibili come delle &#8220;guerre giuste&#8221;, <em>bella iusta<\/em>.<\/p>\n<p style=\"text-align: justify;\">La differenza non \u00e8 affatto da poco. La guerra nella tradizione cristiana antica e medievale non \u00e8 infatti un valore in s\u00e9: il <em>bellum<\/em> pu\u00f2 essere accettato come <em>Iustum<\/em> solamente come <em>extrema ratio<\/em>, in quanto mirante a restaurare una <em>iustitia<\/em> avvertita come infranta da un nemico che, proprio in quanto <em>iniustum<\/em>, lede in primo luogo non i diritti di un monarca terreno, ma lo stesso ordine provvidenziale dell\u2019universo.<\/p>\n<p style=\"text-align: justify;\">Particolarmente San Bernardo, nella sua nota epistola indirizzata ai Cavalieri Templari, agli inizi del secolo XII sottolineer\u00e0 questa differenza, che la maggior parte dei commentatori laicisti moderni e contemporanei preferisce ignorare (3).<\/p>\n<p style=\"text-align: justify;\"><strong>b.<\/strong> La Crociata, inoltre, \u00e8 un pellegrinaggio in armi verso i Luoghi Santi. Non \u00e8 quindi una guerra qualunque, n\u00e9 d\u2019altronde un pellegrinaggio qualunque. Il suo fine ultimo \u00e8 la riconquista di Gerusalemme, <em>umbilicus mundi<\/em>, il Centro spirituale del mondo cristiano, luogo in cui, grazie alla Incarnazione e Morte di Ges\u00f9 Cristo \u00e8 terminato l\u2019esilio dell\u2019umanit\u00e0 tutta nella terra del peccato, dopo la Caduta.<\/p>\n<p style=\"text-align: justify;\">Andando verso Gerusalemme si torna nella Terra Promessa, nel Nuovo Israele, al luogo della primitiva rivelazione di Dio al popolo ebraico, della definitiva manifestazione di Dio sulla terra nell\u2019Incarnazione, nel luogo che vedr\u00e0 la Seconda Venuta di Cristo alla fine dei Tempi, e con ci\u00f2 la definitiva sconfitta del Male e la discesa della Gerusalemme Celeste, cos\u00ec come il cristiano trova scritto nel pi\u00f9 terribile ed enigmatico Libro del Nuovo Testamento, l\u2019<em>Apocalisse<\/em>. \u00c8 esistita dunque persino una dimensione escatologico-apocalittica della Crociata.<\/p>\n<p style=\"text-align: justify;\"><strong>c.<\/strong> Questa dimensione nascosta della Crociata spiega molte cose apparentemente assurde. Ad esempio il venire a Gerusalemme, camminando per anni, combattendo per mesi, per sciogliere un voto e poi ripartire immediatamente per cercare, se le asprezze del cammino lo consentiranno, di ritornare a casa propria.<\/p>\n<p style=\"text-align: justify;\">Questo \u00e8 esattamente quello che fecero la quasi totalit\u00e0 dei pellegrini in armi del 1096-99, e le fonti letterarie ed artistiche del XII secolo sono ricche di riferimenti al modello del ritorno del vecchio crociato a casa, provato ed invecchiato. Chi pensa che la Crociata fosse solamente una colossale occasione di arricchimento individuale si soffermi su questa considerazione: un intero ceto di <em>milites<\/em> europei, che in quanto tale era &#8211; limitatamente all\u2019epoca &#8211; mediamente agiata, si mise in viaggio per anni, in condizioni di difficolt\u00e0 materiali estreme, senza alcuna garanzia nemmeno di riuscire a vedere da lontano le mura di Gerusalemme, il tutto rigorosamente a spese proprie.<\/p>\n<p style=\"text-align: justify;\">Anche coloro che riuscirono a vederle e ad entrare nella Citt\u00e0 Santa rimanendo in vita, una volta sciolto il voto religioso che li aveva portati fino a l\u00ec, entro pochi mesi iniziarono il lungo e non meno pericoloso cammino di ritorno, tant\u2019\u00e8 che i Regni crociati di Terrasanta conobbero immediatamente una gravissima penuria di uomini; infine, malgrado la certezza del saccheggio che Gerusalemme pat\u00ec nel 1099, non abbiamo notizie di significativi arricchimenti riportati in Europa dopo la conquista della Terrasanta.<\/p>\n<p style=\"text-align: justify;\">In termini puramente economici l\u2019avventura in Terrasanta era un pessimo investimento. Quale prospettiva di ricchezza materiale poteva infatti compensare dieci-quindici anni di rischi mortali, sofferenze, combattimenti, lontananza dalla propria terra e dalla propria famiglia? Senza dimenticare il fatto che all\u2019epoca questo lasso di tempo per noi tutto sommato breve esauriva la giovinezza del pellegrino in armi, e lo restituiva alla sua casa sicuramente pi\u00f9 ricco di esperienze, ma altrettanto sicuramente invecchiato e indebolito.<\/p>\n<p style=\"text-align: justify;\"><strong>d. <\/strong>Lo spessore spirituale della Crociata illumina anche un altro aspetto singolare: molti pellegrini in armi, o addirittura disarmati, si aggregavano ai diversi scaglioni di Crociati per riuscire ad arrivare a Gerusalemme, semplicemente per morirvi ed essere sepolti l\u00ec. Poggiare come ultimo gesto della propria vita il proprio corpo sugli stessi luoghi che avevano visto la morte di Cristo, negli stessi luoghi della Resurrezione era un modo per aumentare al massimo la speranza di conoscere <em>post mortem<\/em> la stessa, preziosa sorte. Il numero dei pellegrini che moriva dentro le mura di Gerusalemme fu cos\u00ec elevato da provocare anche problemi logistici legati all\u2019ubicazione dei cimiteri, alla loro suddivisione confessionale etc.<\/p>\n<p style=\"text-align: justify;\"><strong>7. Alcuni temi d\u2019approfondimento:<\/strong><\/p>\n<p style=\"text-align: justify;\">Fino ad ora ci siamo limitati a cercare di tratteggiare il clima culturale e la &#8220;visione del mondo&#8221; che dettero vita alla prima Crociata. Dopo il 1099, per quasi 200 anni si ricre\u00f2 un mondo diverso in Terrasanta, la cui storia \u00e8 troppo complessa per poterla seguire qui nel dettaglio. Ci accontenteremo pertanto di evidenziare alcuni temi solitamente poco illuminati, al fine di instillare qualche curiosit\u00e0 in pi\u00f9.<\/p>\n<p style=\"text-align: justify;\"><strong>a.<\/strong> Dopo la conquista e il saccheggio di Gerusalemme, la presenza dei &#8220;Franchi&#8221; in Terrasanta (cos\u00ec erano chiamati i Crociati europei sia dai Bizantini che dai musulmani) condusse rapidamente alla costruzione di una nuova societ\u00e0. Si tratt\u00f2 di una societ\u00e0 di sintesi, che in tempi molto brevi dovette superare sia le caratteristiche tradizionali della cultura locale, sia le abitudini dei nuovi conquistatori, per creare un nuovo equilibrio economico, sociale e politico in cui &#8211; fatto significativo &#8211; la Chiesa seppe organizzarsi prima e meglio della societ\u00e0 laica: segno tangibile di ci\u00f2 fu la creazione di un Patriarcato latino di Gerusalemme, che oltre ad organizzare <em>ex novo<\/em> una rete capillare di istituzioni ecclesiatiche all\u2019interno del territorio dei nuovi Stati crociati, contribu\u00ec validamente al rinnovo di antichi ed alla creazione di nuovi rapporti con le varie Cristianit\u00e0 orientali ivi esistenti ed operanti.<\/p>\n<p style=\"text-align: justify;\"><strong>b. <\/strong>In questi nuovi Stati, per rispondere alle inedite esigenze create dalla situazione politica e militare, sbocciarono anche alcune esperienze originali la cui importanza rapidamente travalic\u00f2 i confini della Terrasanta, per proiettarsi come una rivoluzione culturale e spirituale in tutta la Cristianit\u00e0: alludo agli Ordini cavallereschi sovranazionali, la quintessenza spirituale e militare del Medioevo cattolico, che nacquero tutti proprio in Terrasanta: l\u2019Ospedale (oggi, dopo alcuni passaggi, Ordine di Malta), l\u2019Ordine del Tempio (o Templare), l\u2019Ordine Teutonico.<\/p>\n<p style=\"text-align: justify;\">Chiunque conosca anche solo i rudimenti della storia letteraria, economica, religiosa e sociale dell\u2019Et\u00e0 di Mezzo europea conosce bene l\u2019immensa importanza che l\u2019esperienza degli Ordini Cavallereschi ebbe per molti secoli, talvolta fino ai giorni nostri. Si rammenti solamente che molti stati sulla carta d\u2019Europa, dal Portogallo a Malta, alla triade Estonia, Lettonia e Lituania nascono direttamente dall\u2019opera di difesa e contrattacco antimusulmana ed antipagana svolta da questi Ordini. Da questa esperienza nasce anche uno dei pi\u00f9 coriacei miti della cultura laico-illuministica europea: il mito templare (4).<\/p>\n<p style=\"text-align: justify;\"><strong>c.<\/strong> I regni crociati di Terrasanta vissero per due secoli con l\u2019attenzione costantemente rivolta al proprio entroterra, territorio musulmano. La cosa singolare \u00e8 che questo prolungato confronto non cre\u00f2 solamente scontri, ma anche diverse modalit\u00e0 di incontro tra culture cos\u00ec differenti. Le testimonianze arabe del tempo ci confermano il paradossale (per noi) clima di tolleranza religiosa che si respirava all\u2019interno dei Regni crociati di Terrasanta, con gli Ordini cavallereschi come primi custodi, ad esempio, del diritto dei pellegrini musulmani di pregare nei Luoghi Santi di Gerusalemme.<\/p>\n<p style=\"text-align: justify;\">Questa progressiva e mutua conoscenza produsse degli effetti di lungo periodo che mal si conciliano con l\u2019idea ottocentesca della Crociata come protocolonialismo oppressore, idea vetusta ma quantomai viva ancor oggi soprattutto a livello divulgativo. Sia esempio di questo particolare, ma vivissimo, &#8220;fascino del Nemico&#8221;, il caso del Saladino. Grande generale curdo al servizio del califfo di Baghdad, il Saladino riconquist\u00f2 nel 1187 Gerusalemme, e contro di lui fi indetta la 3\u00b0 Crociata, che vide la partecipazione diretta e personale dei pi\u00f9 grandi Re della Cristianit\u00e0: l\u2019Imperatore Federico I Barbarossa &#8211; oramai anziano, che muore in viaggio &#8211; Riccardo Cuor di Leone Re d\u2019Inghilterra, Filippo II Re di Francia.<\/p>\n<p style=\"text-align: justify;\">Aldil\u00e0 degli esiti militari della spedizione, dobbiamo ricordare che rapidamente si diffuse nella cultura europea del tempo la leggenda del &#8220;buon Saladino&#8221;, in cui il generale curdo veniva presentato in una luce assai favorevole come sovrano colto, cavalleresco, &#8220;quasi cristiano&#8221;; il testo che maggiormente evidenzia questa interpretazione \u00e8 senz\u2019altro l\u2019<em>Ordene de Chevalerie<\/em>, un poemetto cavalleresco anonimo trecentesco che conobbe una larghissima diffusione.<\/p>\n<p style=\"text-align: justify;\">Nello stesso tempo, \u00e8 difficile non cogliere un\u2019eco di questa leggenda nell\u2019episodio della vita San Francesco in cui il santo assisano va a predicare in Terrasanta e, di fronte al Sultano, sbugiarda i dottori islamici e ne ottiene il plauso (ma non la conversione), e la libert\u00e0 di tornarsene indietro.<\/p>\n<p style=\"text-align: justify;\"><strong>d.<\/strong> Come si \u00e8 accennato pi\u00f9 sopra, non tutte le Crociate furono pellegrinaggi in armi: ricordiamo qui la singolare Crociata diplomatica promossa dall\u2019Imperatore Federico II. Spinto ripetutamente dal papa alla Crociata (Federico II fu addirittura scomunicato per i suoi ritardi), nel 1228-1229, l\u2019Imperatore stipul\u00f2 un accordo diplomatico e pacifico con l\u2019allora Sultano del Cairo, Malik al-Kamil: sulla base di questo accordo una parte di Gerusalemme rientr\u00f2 sotto il controllo cristiano, e da allora Federico II pot\u00e9 con giustificato orgoglio portare anche il titolo di Re di Gerusalemme.<\/p>\n<p style=\"text-align: justify;\">Questo accordo pacifico, tra gentiluomini, resse quindici anni: nel 1244 un\u2019orda di nomadi, sempre musulmani ma d\u2019altra etnia, provenienti dall\u2019interno dell\u2019Asia minore e spinti verso la costa dall\u2019invasione mongola, rioccuparono la citt\u00e0, che da allora rimase in mano musulmana. \u00c8 interessante anche notare come quella soluzione che Federico II e il Sultano del Cairo pattuirono, assomiglia notevolmente alla proposta di garanzia di uno statuto internazionale per la citt\u00e0 di Gerusalemme ed I Luoghi Santi continuamente riproposta col suo noto vigore da S.S. Giovanni Paolo II.<\/p>\n<p style=\"text-align: justify;\"><strong>e.<\/strong> La presenza latina in Terrasanta conobbe il suo crepuscolo, e fu la fine dell\u2019avventura<span style=\"text-decoration: underline;\">:<\/span> dopo una serie di perdite territoriali nel 1291 i Crociati resistevano a preponderanti forze musulmane asseragliati nella cittadella fortificata di San Giovanni d\u2019Acri, nell\u2019attuale Libano. Per una volta, alla fine del gioco, le diverse componenti del mondo cristiano crociati seppero recuperare quell\u2019unit\u00e0 d\u2019intenti che in tempi pi\u00f9 felici era stata rapidamente perduta.<\/p>\n<p style=\"text-align: justify;\">La conquista di S. Giovanni d\u2019Acri cost\u00f2 infatti moltissimo ai musulmani: i difensori cristiani riuscirono a far fuggire la popolazione civile via mare, e combatterono fino all\u2019ultimo, dando prova di un eroismo assolutamente commovente, per non cedere l\u2019ultimo brandello di Terrasanta rimasto cristiano. Alla fine, in quello stesso anno, una tremenda esplosione travolse gli ultimi difensori del castello e una grande quantit\u00e0 di assedianti; a San Giovanni d\u2019Acri morirono con le armi in pugno il Gran Maestro dell\u2019Ordine Templare e quello dell\u2019Ospedale, finalmente spalla a spalla dopo decenni di litigi e dispetti reciproci.<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019avventura della Crociata non termin\u00f2 con la perdita della Terrasanta: rimase intatto ed operativo per decenni il Regno latino di Cipro, l\u2019ultimo Regno Crociato, e la difesa della cintura di isole che da Cipro giungeva alla Grecia occup\u00f2 per secoli i cristiani. L\u2019Ordine dell\u2019Ospedale o di San Giovanni, detto successivamente di Rodi e poi di Malta, continu\u00f2 la propria guerra navale contro i Turchi per secoli, e ci volle Napoleone per riuscire a sloggiare i Cavalieri da quell\u2019isola.<\/p>\n<p style=\"text-align: justify;\">Creta (allora chiamata Candia), giunta alla fine in possesso dei veneziani, resistette ai Turchi fin nel XVI secolo: dopo un epico assedio fu infine espugnata; il responsabile della difesa, il gentiluomo veneziano Marcantonio Bragadin, malauguratamente fu catturato ancora in vita: fu scuoiato vivo e ucciso facendolo rotolare dentro una botte di sale, e la sua pelle, conciata ed imbottita di paglia, sventol\u00f2 a lungo sul pi\u00f9 alto pennone del castello di Candia.<\/p>\n<p style=\"text-align: justify;\"><strong>8. Le Crociate dopo la Terrasanta<\/strong><\/p>\n<p style=\"text-align: justify;\">Pu\u00f2 sembrare un paradosso, ma forse le Crociate, come noi le intendiamo, come urto frontale e dichiarato tra la Cristianit\u00e0 e l\u2019Islam, nacquero tempo dopo la conclusione dell\u2019avventura cristiana in Terrasanta, in piena epoca moderna<\/p>\n<p style=\"text-align: justify;\">Probabilmente la prima vera Crociata nel senso moderno del termine fu la &#8220;Lega Santa&#8221; promossa dal Santo Papa Pio V che condusse alla vittoria di Lepanto (7 ottobre 1571), in cui la flotta turca fu fermata per la prima volta grazie al provvisorio miracolo dell\u2019unit\u00e0 tra i diversi principi e Citt\u00e0 cristiane. \u00c8 vero che se Lepanto fosse andata diversamente, noi oggi saremmo tutto musulmani.<\/p>\n<p style=\"text-align: justify;\">Ma la pressione musulmana sull\u2019Europa, fermata via mare, prosegu\u00ec a lungo via terra, fino a giungere a lambire una delle capitali storiche europee, la cui conquista avrebbe spalancato ai Turchi tutta l\u2019Europa centrale. Il 14 luglio 1683 inizi\u00f2 l\u2019assedio turco di Vienna, che si protrasse fino al 12 settembre dello stesso anno, data in cui, l\u2019esercito musulmano, di quasi un milione di uomini, fu costretto alla ritirata.<\/p>\n<p style=\"text-align: justify;\">La difesa di Vienna ebbe quindi un chiaro significato epocale, come Lepanto: la sua caduta sarebbe stata il prodromo della caduta dell\u2019Europa cristiana; per questo a sua difesa convennero migliaia di uomini d\u2019armi appartenenti a tutti i paesi della Cristianit\u00e0, anche a quello, come la Polonia, i cui rapporti con l\u2019Impero Sacro e Romano non erano stati propriamente idilliaci. In quel frangente alcuni reparti turchi riuscirono ad infiltrarsi anche in Italia, nell\u2019odierno Friuli, e fu la stessa popolazione delle valli carniche a mobilitarsi completamente, fino a distruggere gli invasori.<\/p>\n<p style=\"text-align: justify;\">Attorno all\u2019assedio di Vienna si tramanda un episodio emblematico: nel corso della carica (praticamente suicida) di qualche decina di Ussari alati polacchi, cavalieri che innalzavano sulla schiena lunghe ali bianche, contro il grosso della fanteria turca, questa li scambi\u00f2 per angeli, e si dette a precipitosa fuga a dispetto dell\u2019immensa disparit\u00e0 numerica. Dopo qualche giorno inizi\u00f2 la grande ritirata.<\/p>\n<p style=\"text-align: justify;\">Ma il ripiegamento turco fu ovviamente provvisorio, e dopo diversi anni di continue minacce e scorrerie musulmane ai danni delle popolazioni cristiane dell\u2019odierna Austria, Croazia e Slovenia, il grande generale italiano Eugenio di Savoia, al comando di un grande esercito multinazionale dell\u2019Impero Sacro e Romano, riusc\u00ec a portare il conflitto nei territori occupati dai Turchi, dando il via ad una nuova <em>Reconquista<\/em> che si concluse con l\u2019impresa della liberazione di Belgrado, nell\u2019agosto 1717. Anche qui si tratt\u00f2 di un risultato provvisorio: successivamente Belgrado fu ripresa dai Turchi, e fino alla fine della 1\u00b0 guerra mondiale l\u2019odierna Serbia fu largamente sotto il dominio turco. Ma in questo modo l\u2019espansione musulmana nel sud Europa fu definitivamente fermata.<\/p>\n<p style=\"text-align: justify;\">Un\u2019altra Crociata, coscientemente vissuta come tale, fu quella Vandeana, dal 1793 al 1815. Di fronte agli eccessi ed al furore scristianizzatore dei giacobini, i paesani dell\u2019Ovest della Francia presero le armi in difesa della religione cattolica, del Re in quanto legittima autorit\u00e0, dei propri usi e costumi comunitari: La Crociata vandeana dur\u00f2 pi\u00f9 di 20 anni, e conobbe fasi di inedita crudelt\u00e0: contro questi nuovi crociati contadini i parlamenti della modernit\u00e0 non trovarono nulla di meglio che mettere in atto il primo genocidio della storia (5). Ma questa \u00e8 in effetti la storia di tutte le Insorgenze antigiacobine europee.<\/p>\n<p style=\"text-align: justify;\">Non sembri incredibile, ma proprio il nostro secolo \u00e8 quello in cui pi\u00f9 massiccio e contraddittorio \u00e8 stato l\u2019uso del termine &#8220;Crociata&#8221;: al tempo della 1\u00b0 guerra mondiale (1914-1918), la macchina propagandistica anglo-francese, agit\u00f2 con grande vigore la bandiera della Crociata contro la barbarie tedesca; \u00e8 bene ricordarsi che i tedeschi diventarono il simbolo del Male assoluto (contro cui, appunto, appare lecito intraprendere Crociate) non nel 1939, ma nel 1914.<\/p>\n<p style=\"text-align: justify;\">Al tempo della Guerra Civile spagnola (1936-1939), la lotta contro il comunismo ateo e le sue inedite (per l\u2019Europa occidentale) efferatezze anticristiane, ridette vita all\u2019idea di Crociata, contro la nuova barbarie che proveniva, una volta di pi\u00f9, dall\u2019Oriente; questi riferimenti di lungo periodo furono particolarmente evidenti all\u2019interno di quel complesso fenomeno di volontariato internazionale contro il comunismo che port\u00f2 in Spagna nuovi Crociati anticomunisti da moltissimi paesi europei.<\/p>\n<p style=\"text-align: justify;\">Ma fu all\u2019interno della 2\u00b0 guerra mondiale che il ricorso all\u2019idea di Crociata divenne generalizzato e singolarmente contraddittorio: entrambi gli schieramenti si crearono la propria Crociata, e dal 1941 al 1945 riuscirono a convivere ed a scontrarsi le &#8220;simmetriche Crociate&#8221; dell\u2019Asse contro il bolscevismo (a cui parteciparono, \u00e8 bene ricordarlo, volontari da tutto il mondo, USA e Inghilterra compresi) e degli Alleati in difesa della democrazia.<\/p>\n<p style=\"text-align: justify;\">Dopo il 1945 e la spaccatura dell\u2019Europa in blocchi lo schema retorico della &#8220;Crociata in difesa della democrazia&#8221; fu mantenuto vivo specialmente da parte degli USA non pi\u00f9 ovviamente a carico della Germania nazista, ex-nemico sconfitto ora diventato alleato, ma &#8211; per rimanere in Europa &#8211; degli ex-alleati sovietici, trasformati da preziosi fratelli d\u2019arme in un Impero del Male.<\/p>\n<p style=\"text-align: justify;\">E dopo il crollo del Muro di Berlino?<\/p>\n<p style=\"text-align: justify;\">Le Crociate si moltiplicano ancor pi\u00f9. Oramai siamo abituati a periodiche ed incendiarie dichiarazioni sulla stampa che additano al pubblico ludibrio l\u2019Incarnazione del Male del momento, contro cui implacabile si scaglia la Crociata (oggi si dice: umanitaria) del mondo civile, e contro cui &#8211; beninteso &#8211; tutto \u00e8 lecito, anche il bombardamento quotidiano della popolazione civile. L\u2019altroieri \u00e8 stata la volta dell\u2019Iraq di Saddam Hussein, ieri \u00e8 stato il turno della Serbia di Slobodan Milosevic, ed oggi\u2026 staremo a vedere.<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusione<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel percorso di questa chiacchierata abbiamo notato molti paradossi; concluderemo quindi con l\u2019ultimo della serie. Pi\u00f9 si approfondisce la conoscenza storica del fenomeno dei <em>passagia generalia<\/em>, che solo per abitudine oggi continuiamo a chiamare &#8220;Crociate&#8221;, pi\u00f9 ci si rende conto di quanto la loro realt\u00e0 sia stata distante (a volte un poco, pi\u00f9 spesso radicalmente) dall\u2019immagine che comunemente oggi tutti abbiamo delle Crociate, immagine generata durante il secolo scorso ed imposta pi\u00f9 dalla divulgazione mediale e scolastica che da una sufficiente conoscenza delle fonti.<\/p>\n<p style=\"text-align: justify;\">Accanto alla necessit\u00e0 di conoscere meglio la storia <em>vera<\/em> per non essere ingannati dai demagoghi di qualunque colore, resta quindi da comprendere da dove venga fuori quest\u2019immagine cos\u00ec sicura di s\u00e9 e senza mezzi toni che siamo usi abbattere sul nostro passato. In conclusione possiamo dire che, forse, pi\u00f9 che rispondere ad un\u2019esigenza di interpretazione del passato quest\u2019immagine sia una <em>proiezione<\/em> su di esso di una serie di realt\u00e0 che non sono affatto medievali ma moderne e contemporanee, e stonando singolarmente con l\u2019immagine idilliaca che siamo portati a costruirci del nostro mondo attuale, vengono proiettate all\u2019indietro, su tempi che per maturata convenzione culturale &#8211; e con una simmetrica, massima indifferenza verso la realt\u00e0 dei fatti &#8211; <em>devono<\/em> essere impregnate delle caratteristiche pi\u00f9 negative.<\/p>\n<p style=\"text-align: justify;\">E non \u00e8 affatto strano che le caratteristiche maggiormente negative per una cultura emergano dal suo stesso interno, anzich\u00e9 da un\u2019altra cultura che con la nostra ha ben poco a che fare.<\/p>\n<p style=\"text-align: justify;\">L\u2019unica conclusione possibile \u00e8 quindi un appello alla prudenza e ad un sano disincanto nei confronti delle &#8220;leggende nere&#8221; di cui una cultura povera di punti fermi, ma ricca di sicumera come quella occidentale moderna, continua a nutrirsi quotidianamente.<\/p>\n<p style=\"text-align: justify;\"><strong>Note:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> F. Cardini, Dio lo vuole! Intervista sulla Crociata, Rimini 1994, pp. 9-10.<\/p>\n<div align=\"justify\"><strong>2)<\/strong> Sul tema, vedi F. Mian, Gerusalemme citt\u00e0 santa.Oriente e pellegrini d\u2019Occidente (sec. I-XI), Rimini 1988.<\/div>\n<div align=\"justify\"><strong>3)<\/strong> Vedasi San Bernardo di Chiaravalle, <em>L\u2019Elogio della Nuova Milizia. Ai Cavalieri del Tempio<\/em>, trad. it. a cura di M. Polia, Rimini 1988.<\/div>\n<div align=\"justify\"><strong>4)<\/strong> Attorno al &#8220;mito templare&#8221; vedi introduttivamente F. Cardini, <em>La Nascita dei Templari. Bernardo di Chiaravalle e la Cavalleria mistica<\/em>, Rimini 1999, pp. 147 e segg.<\/div>\n<div align=\"justify\"><strong>5)<\/strong> Sul tema, cfr. R. Secher, <em>Il genocidio vandeano<\/em>, Milano 1989.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>di Adolfo Morganti 1. Usi contemporanei del termine Crociata Affrontare con seriet\u00e0 scientifica il tema della Crociata, uno dei tanti episodi di cui apparentemente tutto \u00e8 noto, \u00e8 reso difficile prima di tutto dall\u2019utilizzo che di questo termine ha fatto e continua a fare la cultura contemporanea. Un utilizzo carico di enfasi contrapposte, che come &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,91,24],"tags":[428,268],"class_list":["post-1152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crociate","category-medioevo","category-storia","tag-crociate-2","tag-medioevo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La crociata, questa sconosciuta - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crociata, questa sconosciuta - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-08-02T16:04:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-02T08:13:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"175\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La crociata, questa sconosciuta\",\"datePublished\":\"2005-08-02T16:04:41+00:00\",\"dateModified\":\"2016-03-02T08:13:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/\"},\"wordCount\":6014,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/crociate-2.jpg\",\"keywords\":[\"crociate\",\"medioevo\"],\"articleSection\":[\"Crociate\",\"Medioevo\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/\",\"name\":\"La crociata, questa sconosciuta - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/crociate-2.jpg\",\"datePublished\":\"2005-08-02T16:04:41+00:00\",\"dateModified\":\"2016-03-02T08:13:34+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/crociate-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/08\\\/crociate-2.jpg\",\"width\":287,\"height\":175},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-crociata-questa-sconosciuta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crociata, questa sconosciuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crociata, questa sconosciuta - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/","og_locale":"it_IT","og_type":"article","og_title":"La crociata, questa sconosciuta - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-08-02T16:04:41+00:00","article_modified_time":"2016-03-02T08:13:34+00:00","og_image":[{"width":287,"height":175,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"30 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La crociata, questa sconosciuta","datePublished":"2005-08-02T16:04:41+00:00","dateModified":"2016-03-02T08:13:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/"},"wordCount":6014,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg","keywords":["crociate","medioevo"],"articleSection":["Crociate","Medioevo","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/","name":"La crociata, questa sconosciuta - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg","datePublished":"2005-08-02T16:04:41+00:00","dateModified":"2016-03-02T08:13:34+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/08\/crociate-2.jpg","width":287,"height":175},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-crociata-questa-sconosciuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La crociata, questa sconosciuta"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":31269,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1152\/revisions\/31269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31268"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}