{"id":115,"date":"2004-11-13T00:00:00","date_gmt":"2004-11-12T23:00:00","guid":{"rendered":""},"modified":"2025-04-01T17:08:36","modified_gmt":"2025-04-01T15:08:36","slug":"il-possibile-conflitto-tra-islam-e-occidente","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/","title":{"rendered":"Il possibile conflitto tra Islam e Occidente"},"content":{"rendered":"\n<p class=\"has-text-align-center\">(titolo redazionale)<\/p>\n\n\n\n<p class=\"has-text-align-center\">Articolo pubblicato su <a href=\"https:\/\/www.edizioniares.it\/studi-cattolici\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Studi cattolici<\/strong> <\/a>dell\u2019aprile 1998<\/p>\n\n\n\n<p><em>Per meglio capire che cosa sia l&#8217;isl\u00e0m alla fine del ventesimo secolo, il giornalista polacco Romanowski ha intervistato Samir Khalil Samir, gesuita egiziano e professore di islamologia all&#8217;universit\u00e0 di Beirut, il quale dal 1975 al 1986 ha insegnato presso il Pontificio Istituto Orientale di Roma.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"175\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg\" alt=\"\" class=\"wp-image-34271\" style=\"width:455px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>In un libro molto discusso e di notevole successo, &#8220;Lo scontro delle civilt\u00e0 e il nuovo ordine mondiale&#8221;, il politologo americano Huntington delinea un possibile scenario di conflitto fra mondo islamico e Occidente, segnalandone i fattori di attrito che ne sarebbero all&#8217;origine, tra i quali: l&#8217;islamizzazione della politica e della cultura nella maggior parte dei Paesi musulmani, la crescita dell&#8217;intolleranza verso le comunit\u00e0 non di fede maomettana, la violenza organizzata di s\u00e9tte estremistiche, la pressione demografica delle popolazioni musulmane e l&#8217;emigrazione verso i Paesi occidentali. Per meglio capire che cosa sia l&#8217;isl\u00e0m alla fine del ventesimo secolo, il giornalista polacco Romanowski ha intervistato Samir Khalil Samir, gesuita egiziano e professore di islamologia all&#8217;universit\u00e0 di Beirut, il quale dal 1975 al 1986 ha insegnato presso il Pontificio Istituto Orientale di Roma.<\/p>\n\n\n\n<p><strong>P. Samir, all&#8217;inizio di questo secolo i cristiani nei Paesi musulmani del Medio Oriente e dell&#8217;Africa settentrionale erano circa il 25% della popolazione; oggi questo numero \u00e8 sceso al 7%. Perch\u00e9 i cristiani nei Paesi islamici stanno scomparendo?<\/strong><\/p>\n\n\n\n<p>I motivi della diminuzione dei cristiani nei Paesi islamici sono vari. I musulmani si moltiplicano pi\u00f9 dei cristiani anzitutto per motivi demografici. Il primo \u00e8 la poligamia, che era assai diffusa in ambiente rurale. Il secondo \u00e8 quello igienico: fino a cinquant&#8217;anni fa, cio\u00e8 prima della diffusione degli antibiotici, la mortalit\u00e0 infantile era molto pi\u00f9 diffusa fra le popolazioni musulmane che nelle popolazioni cristiane (essendo i cristiani spesso pi\u00f9 educati); questo handicap dei musulmani \u00e8 felicemente scomparso oggigiorno. Il terzo \u00e8 dato dal fatto che i cristiani hanno una concezione della famiglia che d\u00e0 pi\u00f9 importanza all&#8217;educazione della prole, e li spinge ad un autocontrollo delle nascite. Le famiglie cristiane, solitamente di pi\u00f9 alto livello culturale, hanno mediamente 3-4 figli, contro gli 8-10 delle famiglie musulmane.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Arabia-Saudita_cristiani_Islam.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"180\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/Arabia-Saudita_cristiani_Islam.jpg\" alt=\"\" class=\"wp-image-57705\" style=\"width:453px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>C\u2019\u00e8 poi una motivazione socio-culturale, ed \u00e8 la pi\u00f9 importante: il cristiano non gode, nel mondo musulmano, della parit\u00e0 con gli altri e della libert\u00e0 come \u00e8 intesa oggi. Vorrei spiegare questo partendo dal Corano. La posizione del cristiano nel mondo islamico \u00e8 contemplata dal Corano e dalla successiva tradizione. Il cristiano \u00e8 una persona che deve pagare imposte particolari, e che, essendo tollerato nella comunit\u00e0 musulmana, rimane sempre in una posizione di subalternit\u00e0. Il Corano (sura IX, versetto 29), usa l\u2019espressione &#8220;umiliazione&#8221; (wa-hum saghirun). L\u2019interpretazione di questa parola dipendeva dai califfi: una volta i cristiani erano obbligati a cedere il passo ai musulmani, altra volta non era loro permesso di usare il cavallo (dovevano usare il mulo).<\/p>\n\n\n\n<p>In ogni caso, il Corano d\u00e0 la possibilit\u00e0 di &#8220;umiliare&#8221; i cristiani. Se un fanatico, un capo villaggio, un uomo politico, vuole colpire i cristiani, pu\u00f2 sempre farlo. Prendiamo alcuni esempi dal\u2019Egitto: se si costruisce una chiesa, essa non pu\u00f2 essere pi\u00f9 alta della moschea; i cristiani non possono utilizzare nelle chiese altoparlanti, mentre tutte le moschee li utilizzano; non si pu\u00f2 portare la croce in luogo pubblico; ai cristiani \u00e8 severamente proibito far conoscere la loro religione, mentre essi stessi sono oggetto di forte islamizzazione, ed altri divieti ancora.<\/p>\n\n\n\n<p><strong>Negli ultimi anni si nota una violenta campagna di persecuzione contro i cristiani nei Paesi abitati dai musulmani: i fedeli vengono uccisi e le chiese sono date alle fiamme. Che cosa sta succedendo oggi nel mondo islamico?<\/strong><\/p>\n\n\n\n<p>Per capire che cos\u2019\u00e8 l\u2019isl\u00e0m bisogna cominciare dall\u2019inizio, cio\u00e8 dal progetto di Maometto volto ad unificare tutte le trib\u00f9 arabe sotto la guida di una sola persona e a creare un impero arabo nella penisola arabica. Questo progetto era l\u00b9aspirazione della trib\u00f9 dei Coreisciti, cui apparteneva Maometto. E Maometto, in modo geniale, \u00e8 riuscito a realizzarlo.Maometto attua il suo progetto a Medina, dove \u00e8 fuggito da La Mecca nel 622. La gente lo accoglie come una persona capace di organizzare la citt\u00e0 per far meglio fronte a La Mecca, la citt\u00e0 rivale.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Mecca.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/04\/Mecca.jpg\" alt=\"\" class=\"wp-image-40211\" style=\"width:463px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>All&#8217;inizio l\u2019attivit\u00e0 di Maometto ha carattere amministrativo e politico: stipula un patto con le tre ricche trib\u00f9 ebraiche presenti a Medina, ma poi le espelle e comincia piccole guerre (in dieci anni condusse quaranta guerre, secondo la prima e pi\u00f9 famosa sua biografia, quella di Ibn Hisci\u00e0m), amministra la citt\u00e0 istituendo un sistema politico, giuridico e fiscale-amministrativo. Il suo grande progetto politico include anche la religione, la fede in un Dio unico. Sul piano religioso recupera tutto quello che pu\u00f2: le antiche tradizioni arabe, la tradizione di Abramo, di Ismaele, elementi di ebraismo e cristianesimo. Dal paganesimo arabo provengono i riti del pellegrinaggio a La Mecca che verranno islamizzati.<\/p>\n\n\n\n<p>L\u2019isl\u00e0m non \u00e8 dunque solo la fede in un unico Dio e la preghiera: possono pensarla cos\u00ec solo quanti ignorano l\u2019isl\u00e0m e proiettano su di esso la propria mentalit\u00e0 cristiana. L\u2019isl\u00e0m \u00e8 una totalit\u00e0 socio-politica, culturale e religiosa. Lo stesso si pu\u00f2 dire della moschea: non \u00e8 una chiesa musulmana, non \u00e8 solo un luogo di preghiera, ma anche di studio e di dibattiti politici. Purtroppo, la maggior parte dei cristiani paragona l\u2019isl\u00e0m al Cristianesimo, pensando che l\u2019isl\u00e0m sia una versione araba del Cristianesimo, leggermente diverso da esso. I cristiani lo fanno con intenzioni buone, convinti che cos\u00ec comportandosi siano pi\u00f9 vicini allo spirito del Vangelo. Invece pensare in tal maniera \u00e8 da ingenui. Perch\u00e9 la prima regola del dialogo \u00e8 rispettare gli altri nelle loro diversit\u00e0, e considerarli per quello che sono, senza pretendere che tutte le religioni siano simili o abbiano lo stesso scopo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea-1024x682.jpg\" alt=\"\" class=\"wp-image-48909\" style=\"width:488px;height:auto\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea-1024x682.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea-300x200.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea-768x512.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_preghiera_moschea.jpg 1700w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n<p>Pertanto, un musulmano va visto come membro del suo movimento socio-politico-cultural-religioso. Se qualcuno si converte all\u2019isl\u00e0m, compie non solo un gesto religioso, ma anche una scelta politica, sociale, culturale, giuridica. Per esempio, i croati sono chiamati tali secondo un criterio etnico, e i serbi pure; invece, un croato o un serbo che si \u00e8 convertito all\u2019isl\u00e0m viene chiamato &#8220;musulmano&#8221;, come se perdesse la sua origine etnica. Voglio ripetere ancora che l\u2019isl\u00e0m \u00e8 un progetto politico che include la religione (come, in senso contrario, il comunismo era un progetto politico che escludeva la religione). L\u2019isl\u00e0m \u00e8 un sistema integrale che pu\u00f2 facilmente scivolare verso il totalitarismo, perch\u00e9 lo scopo dell\u2019uomo politico musulmano, anzi il suo dovere, \u00e8 di sostenere la religione musulmana.<\/p>\n\n\n\n<p>In tutti i Paesi del mondo dove i musulmani diventano maggioranza &#8211; Bosnia, Cecenia, regioni occidentali della Cina, certe zone delle Filippine- essi chiedono l\u2019indipendenza politica. A loro non basta la libert\u00e0 religiosa, proprio perch\u00e9 lo scopo ultimo dell\u2019isl\u00e0m \u00e8 una societ\u00e0 integralmente basata su determinate visioni politiche. Dietro la religione c\u00b9\u00e8 anche un progetto politico. Altri esempi. Il corso di religione per i musulmani in Germania include quasi sempre l\u2019insegnamento della lingua e delle usanze turche, mentre in Francia, quando si insegna l\u2019isl\u00e0m, si insegnano anche la lingua araba e le usanze nord-africane. In tal maniera, i governi europei pagano professori che insegnano non solo una religione, ma anche lingue o culture che non hanno niente a che vedere con al cultura tedesca o francese.<\/p>\n\n\n\n<p>E\u2019 questo, per noi cristiani, il grande problema: essendo l\u2019isl\u00e0m societ\u00e0, cultura e religione, come vivere in un sistema musulmano che ha come fine l\u2019islamizzazione di tutti gli aspetti della vita della societ\u00e0? Adduco qualche esempio. Gi\u00e0 prima dell\u2019alba, gli altoparlanti delle moschee svegliano tutti per la preghiera, proclamando che &#8220;la preghiera vale pi\u00f9 del sonno&#8221;. La radio deve interrompere i programmi e i notiziari per trasmettere le preghiere musulmane.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/moschea.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/moschea.jpg\" alt=\"\" class=\"wp-image-32574\" style=\"width:469px;height:auto\"\/><\/a><\/figure><\/div>\n\n\n<p>A scuola, l\u2019isl\u00e0m \u00e8 materia obbligatoria anche per i non musulmani. Anche nelle scuole private cattoliche, prima di cominciare le lezioni, si deve leggere e commentare qualche brano del Corano. La radio diffonde tutta la giornata passi coranici. La televisione \u00e8 sempre pi\u00f9 islamizzata nei programmi. I film sono spesso ispirati alla storia musulmana, e talvolta hanno finalit\u00e0 chiaramente apologetiche.<\/p>\n\n\n\n<p>Anche nelle minime cose l\u2019isl\u00e0m interferisce. Per esempio, un cristiano in Egitto non pu\u00f2 allevare un maiale, perch\u00e9 ci\u00f2 pu\u00f2 dare fastidio a qualche musulmano. In questo modo chi vive in Egitto deve agire da musulmano, altrimenti viene escluso dalla societ\u00e0. Un cristiano non si accorge nemmeno quando si comporta da musulmano. Come possiamo meravigliarci, allora, che, in questo clima di oppressione e di strangolamento, i copti egiziani diventino musulmani a migliaia ogni anno, oppure emigrino?<\/p>\n\n\n\n<p>Cresce anche il fenomeno dei matrimoni misti. La ragazza cristiana che sposa un musulmano ha teoricamente il diritto di rimanere cristiana. In pratica diventa per\u00f2 impossibile, perch\u00e9 non erediterebbe e i figli sarebbero comunque legalmente musulmani, anche se battezzati. Se inoltre capita un divorzio, i figli sono automaticamente affidati alla &#8220;parte migliore&#8221;, come dice la legge, cio\u00e8 a quella musulmana.<\/p>\n\n\n\n<p>Al contrario, l\u2019isl\u00e0m non consente per legge l\u2019unione tra una musulmana e un cristiano. Il motivo \u00e8 politico. Il matrimonio non \u00e8 un affare d\u2019amore, \u00e8 un progetto di societ\u00e0, di vita, serve anche ad aumentare il numero dei credenti. Capo di questa societ\u00e0 familiare \u00e8 l\u2019uomo. Una donna musulmana non pu\u00f2 sposare un cristiano, perch\u00e9 i figli sarebbero cristiani, salvo che il cristiano non si converta all\u2019isl\u00e0m. Il caso contrario \u00e8 impossibile: un musulmano che si converte al cristianesimo o all\u2019ebraismo deve essere ucciso, in quanto apostata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(titolo redazionale) Articolo pubblicato su Studi cattolici dell\u2019aprile 1998 Per meglio capire che cosa sia l&#8217;isl\u00e0m alla fine del ventesimo secolo, il giornalista polacco Romanowski ha intervistato Samir Khalil Samir, gesuita egiziano e professore di islamologia all&#8217;universit\u00e0 di Beirut, il quale dal 1975 al 1986 ha insegnato presso il Pontificio Istituto Orientale di Roma. In &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34271,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[161],"class_list":["post-115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l&#039;isl\u00e0m una intervista al gesuita Samir Khalil Samir,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l&#039;isl\u00e0m una intervista al gesuita Samir Khalil Samir,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-12T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T15:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"175\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il possibile conflitto tra Islam e Occidente\",\"datePublished\":\"2004-11-12T23:00:00+00:00\",\"dateModified\":\"2025-04-01T15:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/\"},\"wordCount\":1577,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/islam_donne.jpg\",\"keywords\":[\"islam\"],\"articleSection\":[\"Islam\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/\",\"name\":\"Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/islam_donne.jpg\",\"datePublished\":\"2004-11-12T23:00:00+00:00\",\"dateModified\":\"2025-04-01T15:08:36+00:00\",\"description\":\"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l'isl\u00e0m una intervista al gesuita Samir Khalil Samir,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/islam_donne.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2004\\\/11\\\/islam_donne.jpg\",\"width\":287,\"height\":175},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-possibile-conflitto-tra-islam-e-occidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il possibile conflitto tra Islam e Occidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica","description":"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l'isl\u00e0m una intervista al gesuita Samir Khalil Samir,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/","og_locale":"it_IT","og_type":"article","og_title":"Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica","og_description":"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l'isl\u00e0m una intervista al gesuita Samir Khalil Samir,","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2004-11-12T23:00:00+00:00","article_modified_time":"2025-04-01T15:08:36+00:00","og_image":[{"width":287,"height":175,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il possibile conflitto tra Islam e Occidente","datePublished":"2004-11-12T23:00:00+00:00","dateModified":"2025-04-01T15:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/"},"wordCount":1577,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg","keywords":["islam"],"articleSection":["Islam"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/","name":"Il possibile conflitto tra Islam e Occidente - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg","datePublished":"2004-11-12T23:00:00+00:00","dateModified":"2025-04-01T15:08:36+00:00","description":"Il possibile conflitto tra Islam e Occidente. Per meglio capire che cosa sia l'isl\u00e0m una intervista al gesuita Samir Khalil Samir,","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/islam_donne.jpg","width":287,"height":175},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-possibile-conflitto-tra-islam-e-occidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il possibile conflitto tra Islam e Occidente"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/115\/revisions"}],"predecessor-version":[{"id":62438,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/115\/revisions\/62438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34271"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}