{"id":1103,"date":"2005-07-24T00:00:00","date_gmt":"2005-07-23T22:00:00","guid":{"rendered":""},"modified":"2016-04-29T12:31:20","modified_gmt":"2016-04-29T10:31:20","slug":"quando-i-comunisti-rubavano-diversamente","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/","title":{"rendered":"Quando i comunisti rubavano \u201cdiversamente\u201d"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33778\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg\" alt=\"mani_pulite\" width=\"157\" height=\"200\" \/>Articolo pubblicato su <strong>L\u2019Italia Settimanale<\/strong> del 25 agosto 1993<\/div>\n<p style=\"text-align: justify;\"><em>Prima del conto \u201cGabbietta\u201d c\u2019era in Svizzera un altro conto che aveva a che fare con il Pci. Ecco come un\u2019azienda marittima trasferiva i dollari dall\u2019Urss alle Botteghe oscure<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giancarlo Lehner<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La ditta \u201cMaritalia\u201d, con sede a Ravenna, circa vent\u2019anni fa, fu rilevata dal comunista Giovanni Belletti. Un\u2019azienda decotta che invece, consule Belletti, registra un vero e proprio boom economico. Fatto \u00e8 che il Pci introduce \u201cMaritalia\u201d nel giro degli affari sovietici, in specie nei traffici della compagnia marittima del mar d\u2019Azov. Di l\u00ec, raggirando sia il fisco sovietico, sia quello italiano, la \u201cMaritalia\u201dunir\u00e0 l\u2019utile al dilettevole partitico, riuscendo a procurare finanziamenti pi\u00f9 che illeciti al Pci.<\/div>\n<p style=\"text-align: justify;\">La tecnica, illustrata dalla documentazione allegata, \u00e8 un marchingegno complesso e, insieme, solare: i profitti della ditta di Belletti vengono, ogni anno, azzerati a causa di multe e ritardi a svantaggio della compagnia marittima del mar d\u2019Azov. La \u201cMaritalia\u201d guadagna 100, ma fa figurare, con false fatture e multe di comodo, che deve restituire 100 alla partner sovietica. La solla finisce in un conto speciale aperto appositamente presso la Banca per il commercio estero dell\u2019Urss. Ma il denaro, in realt\u00e0, non va a gratificare i sovietici, perch\u00e9 \u00e8 messo a disposizione del Comitato centrale del Pci, il quale indicher\u00e0 il nome della persona, o della ditta autorizzata a incassare il denaro depositato nella Banca sovietica.<\/p>\n<p style=\"text-align: justify;\">Chi \u00e8 che, alla fine del giro, incassa il denaro? E\u2019 tale Marco Cassani, allora membro &#8211; siamo negli anni Settanta e Ottanta \u2013 della amministrazione del Pci. Grazie alla nuova documentazione siamo in grado di fornire sia il numero del conto speciale presso la Banca del commercio estero dell\u2019Urss (n. 77001317 a nome di Giovanni Belletti), sia il nome in codice del conto presso l\u2019Unione Banche Svizzere di Losanna, ove finivano i profitti della \u201cMaritalia\u201d, del tutto esentati da tasse, sia sovietiche, sia italiane (il nome in cifra \u00e8 30728760 T). Insomma prima del conto \u201cGabbietta\u201d, in Svizzera c\u2019era un altro conto che aveva a che fare con Botteghe Oscure. Il documento, che qui pubblichiamo con il nome \u201cChiave\u201d \u00e8 del 1984, ma \u00e8 da notare che la \u201cMaritalia\u201d ha continuato nei suoi affari in Urss, almeno sino al 1989 e che, ancora nel 1991, si distingueva tra gli sponsor pi\u00f9 importanti del festival dell\u2019<em>Unit\u00e0<\/em>, tenutosi in quel di Bologna.<\/p>\n<p style=\"text-align: justify;\"><strong>Il documento<\/strong> \u201cChiave\u201d del 1984 riferisce di una somma trasferita dal conto n. 77001317 (Banca del commercio estero dell\u2019Urss) al conto in cifre 0728760T (Unione Banche Svizzere di Losanna), ammontante a 121 mila dollari statunitensi. Da notare che, secondo gli inquirenti russi, sul conto di Losanna debbono essere transitate somme per un ammontare di almeno un milione di dollari. I documenti parlano da soli e non servono perci\u00f2 ulteriori chiose.<\/p>\n<p style=\"text-align: justify;\">Baster\u00e0 rilevare soltanto he il marchingegno per l\u2019evasione delle tasse, sovietiche ed italiane, non fu opera dei sovietici, ma dell\u2019infinita creativit\u00e0 delinquenziale dei comunisti italiani. Infine, un omaggio ad un ignoto magistrato sovietico, forse finito in qualche manicomio criminale. Il giudice ignoto in questione, infatti, sul finire degli anni Settanta si accorse dell\u2019illecito rapporto tra Compagnia marittima del mar d\u2019Azov e \u201cMaritalia\u201d.<\/p>\n<p style=\"text-align: justify;\">Cominci\u00f2, addirittura, ad allestire un\u2019istruttoria, ma il CC del Pcus, probabilmente su suggerimento del CC del Pci, lo blocc\u00f2 immediatamente, facendogli pagare salata l\u2019ingenua intromissione nel sistema dei finanziamenti illetici ai \u201cfratelli\u201d italiani. Non un omaggio, ma una domanda ai magistrati italiani, che circa un anno fa hanno archiviato il caso \u201cMaritalia\u201d: l\u2019archiviazione fu dettata da qualche amnistia o da che altro?<\/p>\n<p style=\"text-align: justify;\"><strong>Volere \u00e8 Violante.<\/strong> Ecco, noi vorremmo saperne di pi\u00f9, promettendo, da parte nostra, di compiere ogni sforzo per rintracciare, se \u00e8 ancora vivo, il magistrato sovietico he incautamente and\u00f2 a sbattere contro la turgida \u201conest\u00e0\u201d dei comunisti italiani. Se ancora respira, ci faremo raccontare da lui di che lagrime e sangue \u00e8 fatta la moralit\u00e0 delle Botteghe Oscure.<\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: center;\"><strong>DOCUMENTO \u201cMARE\u201d<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Fascicolo speciale<\/p>\n<p style=\"text-align: justify;\">Segretissimo copia n.1<\/p>\n<p style=\"text-align: justify;\">Una delegazione di comunisti italiani, composta da: il membro del CC del Pci deputato al Parlamento Gianni Giadresco, (in russo \u00e8 erroneamente scritto Giadrescu), membro regionale del Pci dell\u2019Emilia Romagna, il membro della commissione finanziaria centrale del Pci, Mario Cassani, il dirigente della ditta <em>Maritalia<\/em> di Ravenna, Giovanni Belletti.<\/p>\n<p style=\"text-align: justify;\">Il 26 luglio 1977, questa delegazione di comunisti italiani ha avuto un incontro nel ministero della Marina mercantile sovietica. Su tale incontro i membri ella delegazione ci hanno riferito che la ditta <em>Maritalia<\/em> impegnata con i servizi\u00a0 di assistenza presso l\u2018amministrazione di Azov, \u00e8 di propriet\u00e0 del partito comunista e ed \u00e8 controllata da Pci. Nel 1976, questa ditta ha guadagnato un profitto di circa 40 milioni di lire italiane corrispondenti a 33.200 rubli-valuta (o rubli-speciali). Gli italiani vorrebbero che questo loro profitto fosse posto fuori di ogni tassazione, per destinarla, cos\u00ec, ai bisogni del Pci.<\/p>\n<p style=\"text-align: justify;\">Per questo scopo, hanno proposto la seguente strada: l\u2019amministrazione dei marittimi del mar d\u2019Azov presenter\u00e0 alla ditta Maritalia falsi conti, per commissioni, spedizioni di <em>container<\/em> con merci sovietiche, falsi conti riguardanti multe per i ritardi subiti dalle navi in attesa nel porto, come compensazione delle perdite per i danni ai containers dell\u2019Amministrazione d\u2019Azov. La ditta <em>Maritalia<\/em> pagher\u00e0 i conti e li invier\u00e0 al conto corrente della Amministrazione d\u2019Azov.<\/p>\n<p style=\"text-align: justify;\">Tali denari cos\u00ec percepiti, l\u2019Amministrazione ei marittimi d\u2019Azov dovr\u00e0 trasferire sul conto aperto specificatamente per tale scopo presso la Banca del commercio estero dell\u2019Urss, a nome delle persone o delle ditte che indicher\u00e0 il CC del Pci. Quindi, tali somme depositate nel conto speciale saranno a disposizione del CC del Pci o delle persone o delle ditte delegate (in russo: plenipotenziarie) del CC del Pci.<\/p>\n<p style=\"text-align: justify;\">E\u2019 necessario sottolineare che siffatta operazione non corrisponde alle leggi finanziarie italiane, n\u00e9 a quelle sovietiche, eppure l\u2019esecuzione di questa operazione, secondo il metodo proposto dalla delegazione italiana, appare possibile. Chiediamo la vostra conferma.<\/p>\n<p style=\"text-align: justify;\">Il ministro della flotta mercantile dell\u2019Urss<br \/>\n<strong>T.B. Gusgenko<\/strong><\/p>\n<p style=\"text-align: justify;\">Il presidente della Banca per il commercio estero dell\u2019Urss<br \/>\n<strong>Yuri A.Ivanov<\/strong><\/p>\n<p style=\"text-align: right;\">5 agosto 1977<\/p>\n<p style=\"text-align: center;\"><strong>_________________________ <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>DOCUMENTO \u201cCHIAVE\u201d<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Banca per il commercio estero dell\u2019Urss\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\">(a penna in corsivo: vista la richiesta fatta)<\/p>\n<p style=\"text-align: center;\">a destra: per conto di Mario Cassan<\/p>\n<div style=\"text-align: center;\">Indirizzo: Mosca<\/div>\n<div><\/div>\n<div>Richiesta del 19 aprile 1984<\/div>\n<p style=\"text-align: justify;\">Eseguire il trasferimento\u2026 via cablo per una somma di 121 mila dollari statunitensi, al nome (in luogo del nome c\u2019\u00e8 il codice in cifra) 30728760T<\/p>\n<p style=\"text-align: justify;\">All\u2019indirizzo dell\u2019Unione delle Banche Svizzere. Losanna. Svizzera<\/p>\n<p style=\"text-align: justify;\">La somma segnata sopra, comprese le spese e la commissione, vi prego di scontare dal mio conto bancario n. 77001317 (\u00e8 il conto di belletti presso la Banca per il commercio estero dell\u2019Urss)<\/p>\n<p style=\"text-align: right;\">19 aprile 1984<\/p>\n<p style=\"text-align: left;\">Firma: <strong>Giovanni Belletti<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>____________________________<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PDS, Vecchio di zecca<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Una questione di buon gusto, a proposito dell\u2019importanza di essere onesti. C\u2019\u00e8, in Italia, un partito vecchio di zecca, con una nuova sigla. Suona \u201cPds\u201d, ma l\u2019eco inesorabilmente ripete \u201cPci\u201d. E\u2019 un problema di etologia comunista, di riflessi condizionati, di istinti, di imprinting. Qual \u00e8, dunque, l\u2019impronta immutabile che fa riconoscere il togliattiano nel pidiessino? <\/em><\/p>\n<p style=\"text-align: justify;\"><em>E\u2019 soprattutto l\u2019ipocrisia, irrefrenabile pulsione a simulare ed a dissimulare, la <\/em>langue de bois<em>, la lingua di legno, l\u2019\u201daltra\u201d comunicazione, che annichilisce tutte le nomali unzioni linguistiche. Ad esempio, in tema di Mani pulite, dopo che quasi centro rami della Quercia si sono trovati implicati, Ochetto, D\u2019Alema e quanti altri fini dicitori di legno continuano, talora anche con toni risentiti, a dirsi onesti, mani piedi e faccine pulite. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>A volte, dinnanzi all\u2019evidenza, riducono la ragion pratica kantiana ad una questione, non di qualit\u00e0, ma di quantit\u00e0: \u201ci partiti di governo rubavano miliardi, noi milioni\u201d. L\u2019etica, insomma, un tanto al chilo, come prova di un\u2019immoralit\u00e0 antica e militante. E\u2019 possibile concedere ai pidiessini la modica quantit\u00e0, non l\u2019etichetta di \u201conesti\u201d. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>Hanno probabilmente rubato somme inferiori, anche perch\u00e9 \u00e8 l\u2019occasione e la posizione che rendono l\u2019uomo pi\u00f9 o meno ladro. Una mezza verit\u00e0, quindi, ma associata ad una dissimulazione all\u2019ennesima potenza: il deficit di refurtiva in patria \u00e8 stato a lungo compensato dai finanziamenti dall\u2019estero. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>E non ci riferiamo soltanto ai circa 48 milioni di dollari ricevuti direttamente dal Pcus, nel periodo che va dal 1970 al 1990 \u2013 il dato \u00e8 ufficiale e fa parte della documentazione in possesso del procuratore russo Valentin Stepankov \u2013 ma anche e soprattutto al fiume di denaro proveniente dalle intermediazioni tra aziende sovietiche (e dei Paesi dell\u2019Europa satellizzata) e ditte italiane, cos\u00ec come dalla miriade di societ\u00e0 di import-export che trafficavano con i \u201cfratelli\u201d dell\u2019Est.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Al fine di verificare l\u2019\u201donest\u00e0\u201d dei comunisti italiani, vale la pena raccontare per esteso e con nuove prove documentarie la vicenda dell\u2019azienda ravennate, denominata \u201cMaritalia\u201d. Il lettore \u00e8 pregato di leggere attentamente e di prendere appunti, perch\u00e9 l\u2019historia \u00e8 tortuosa, almeno quanto la forma mentis degli eredi di Togliatti.<\/em><\/p>\n<p style=\"text-align: center;\"><strong>* \u00a0* \u00a0* <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche: <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1104\">Botteghe Oscure traffici nascosti<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articolo pubblicato su L\u2019Italia Settimanale del 25 agosto 1993 Prima del conto \u201cGabbietta\u201d c\u2019era in Svizzera un altro conto che aveva a che fare con il Pci. Ecco come un\u2019azienda marittima trasferiva i dollari dall\u2019Urss alle Botteghe oscure di Giancarlo Lehner<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[424,876,853],"class_list":["post-1103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunismo-in-italia","tag-comunismo-in-italia-2","tag-mani-pulite","tag-pci","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-23T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-29T10:31:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"199\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Quando i comunisti rubavano \u201cdiversamente\u201d\",\"datePublished\":\"2005-07-23T22:00:00+00:00\",\"dateModified\":\"2016-04-29T10:31:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/\"},\"wordCount\":1456,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/mani_pulite.jpg\",\"keywords\":[\"comunismo in Italia\",\"Mani Pulite\",\"Pci\"],\"articleSection\":[\"Comunismo in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/\",\"name\":\"Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/mani_pulite.jpg\",\"datePublished\":\"2005-07-23T22:00:00+00:00\",\"dateModified\":\"2016-04-29T10:31:20+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/mani_pulite.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/07\\\/mani_pulite.jpg\",\"width\":199,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quando-i-comunisti-rubavano-diversamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quando i comunisti rubavano \u201cdiversamente\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/","og_locale":"it_IT","og_type":"article","og_title":"Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-07-23T22:00:00+00:00","article_modified_time":"2016-04-29T10:31:20+00:00","og_image":[{"width":199,"height":254,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Quando i comunisti rubavano \u201cdiversamente\u201d","datePublished":"2005-07-23T22:00:00+00:00","dateModified":"2016-04-29T10:31:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/"},"wordCount":1456,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg","keywords":["comunismo in Italia","Mani Pulite","Pci"],"articleSection":["Comunismo in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/","name":"Quando i comunisti rubavano \u201cdiversamente\u201d - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg","datePublished":"2005-07-23T22:00:00+00:00","dateModified":"2016-04-29T10:31:20+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/07\/mani_pulite.jpg","width":199,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quando-i-comunisti-rubavano-diversamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Quando i comunisti rubavano \u201cdiversamente\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1103"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1103\/revisions"}],"predecessor-version":[{"id":33780,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1103\/revisions\/33780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33778"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}